{"id":68370,"date":"2007-01-04T00:00:00","date_gmt":"2007-01-04T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2007\/01\/04\/un-avertissement-de-kaletsky-a-gordon-brown\/"},"modified":"2007-01-04T00:00:00","modified_gmt":"2007-01-04T00:00:00","slug":"un-avertissement-de-kaletsky-a-gordon-brown","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2007\/01\/04\/un-avertissement-de-kaletsky-a-gordon-brown\/","title":{"rendered":"Un avertissement de Kaletsky \u00e0 Gordon Brown"},"content":{"rendered":"<p><p>La politique britannique est aujourd&rsquo;hui entr\u00e9e dans une phase d\u00e9licate. Le texte que nous citons beaucoup aujourd&rsquo;hui, du chroniqueur Anatol Kaletsky, <a href=\"http:\/\/business.timesonline.co.uk\/article\/0,,1061-2530313,00.html\" class=\"gen\">4 janvier<\/a> dans le <em>Times<\/em>, est aussi un message \u00e0 <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3543\" class=\"gen\">Gordon Brown<\/a>. <\/p>\n<\/p>\n<p><p>\tKaletsky, adversaire de Blair, est <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2743\" class=\"gen\">coutumier<\/a> du fait (messages cod\u00e9s \u00e0 Gordon Brown) dans ses colonnes ces derniers mois. Dans le cas pr\u00e9sent, il s&rsquo;agit pour Kaletsky d&rsquo;avertir Gordon Brown d&rsquo;\u00e9ventuelles intentions de Tony Blair d&rsquo;impliquer le Royaume-Uni dans une aventure iranienne.<\/p>\n<\/p>\n<p><p>\tDe ce point de vue surtout, la pr\u00e9sence de Blair dans l&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3544\" class=\"gen\">\u00e9ventuelle aventure<\/a> d&rsquo;une coalition regroupant par ailleurs les  USA, Isra\u00ebl et l&rsquo;Arabie Saoudite ne surprendra pas. C&rsquo;est une fa\u00e7on de tenter de ligoter Gordon Brown \u00e0 sa politique militariste et n\u00e9o-imp\u00e9rialiste, et de l&rsquo;attacher au char bondissant et flambant neuf de GW Bush. Ainsi Blair pourrait-il quitter, heureux et vanit\u00e9 satisfaite, le 10 Downing Street.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 4 janvier 2007 \u00e0 10H28<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La politique britannique est aujourd&rsquo;hui entr\u00e9e dans une phase d\u00e9licate. Le texte que nous citons beaucoup aujourd&rsquo;hui, du chroniqueur Anatol Kaletsky, 4 janvier dans le Times, est aussi un message \u00e0 Gordon Brown. Kaletsky, adversaire de Blair, est coutumier du fait (messages cod\u00e9s \u00e0 Gordon Brown) dans ses colonnes ces derniers mois. Dans le cas&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[705,4038,857,2773,5397],"class_list":["post-68370","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-blair","tag-brown","tag-irak","tag-iran","tag-kaletsky"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=68370"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68370\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=68370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=68370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=68370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}