{"id":68440,"date":"2007-01-22T00:00:00","date_gmt":"2007-01-22T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2007\/01\/22\/airbus-via-northrop-grumman-face-a-lincrevable-roc-du-pentagone-lamerican-dream-avec-du-plomb-dans-laile\/"},"modified":"2007-01-22T00:00:00","modified_gmt":"2007-01-22T00:00:00","slug":"airbus-via-northrop-grumman-face-a-lincrevable-roc-du-pentagone-lamerican-dream-avec-du-plomb-dans-laile","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2007\/01\/22\/airbus-via-northrop-grumman-face-a-lincrevable-roc-du-pentagone-lamerican-dream-avec-du-plomb-dans-laile\/","title":{"rendered":"Airbus (via Northrop-Grumman) face \u00e0 l&rsquo;increvable roc du Pentagone : l&rsquo;<em>American Dream<\/em> avec du plomb dans l&rsquo;aile"},"content":{"rendered":"<p><p>Pour l&rsquo;Europe, particuli\u00e8rement pour les Allemands (et aussi, plus ou moins secr\u00e8tement, pour nombre de Fran\u00e7ais), le programme des nouveaux ravitailleurs en vol de l&rsquo;USAF fait figure d&rsquo;Eldorado, d&rsquo;<em>American Dream<\/em> et ainsi de suite. Airbus (EADS, donc principalement les Allemands et les Fran\u00e7ais) concourt pour ce programme \u00e9norme qui pourrait atteindre dans les m\u00e9andres pentagonesques la somme de  $200 milliards, d\u00e9j\u00e0 \u00e9pique avec des p\u00e9rip\u00e9ties qui remontent \u00e0 2000-2001, d\u00e9j\u00e0 soulign\u00e9 de scandales divers. Airbus s&rsquo;est alli\u00e9 avec Northrop-Grumman pour pr\u00e9senter le KC-30, extrapolation de l&rsquo;Airbus 330, contre Boeing.<\/p>\n<\/p>\n<p><p>\tMais les conditions mises par l&rsquo;USAF, qui concernent surtout les prix, font que Northrop-Grumman\/EADS n&rsquo;a gu\u00e8re de chance au point que Northrop-Grumman envisage de se retirer. (L&rsquo;offre Northrop-Grumman,\/EADS est plus ch\u00e8re parce que l&rsquo;avion offert a beaucoup plus de capacit\u00e9s, notamment celle du transport en plus du ravitaillement en vol.)<\/p>\n<\/p>\n<p><p>\t<em>Air Force Daily<\/em> de <a href=\"http:\/\/dc01-cdh-afa03.tranguard.net\/AFA\/\" class=\"gen\">ce jour<\/a> pr\u00e9cise la situation actuelle :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Various news reports Friday said that Northrop Grumman likely would pull out of the KC-X tanker replacement program because the Air Force has decided it doesn&rsquo;t need to alter its final request for proposalnow expected this week. The Northrop-EADS team had been pressing for changes that might offset potential disadvantages of larger size and higher cost of its KC-30 entrant. According to Dow Jones newswires and Business Week.com, the Air Force does not intend to make changes to the RFP, so sealing the fate of the KC-30. A Northrop spokesman told the Mobile (Ala.) Press-Register that the company had not yet made a decision and would await the final RFP. The question is: Can USAF keep this vital program on tract if Northrop does pull out? Key lawmakers, including Sen. Carl Levin and Sen. John McCain, already have warned that the program is in jeopardy without a real competition.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tOn peut toujours voir un complot anti-europ\u00e9en dans l&rsquo;attitude de l&rsquo;USAF. Ce n&rsquo;est pas s\u00fbr mais le contraire non plus Disons que, d&rsquo;un point de vue strictement nationaliste US, la situation est arrangeante. S&rsquo;il n&rsquo;y avait le Congr\u00e8s avec ses mouches du coche type <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1283\" class=\"gen\">McCain<\/a> qui r\u00e9clament une r\u00e9elle comp\u00e9tition, il y a longtemps que Boeing serait choisi.<\/p>\n<\/p>\n<p><p>\tLa logique devrait effectivement favoriser Boeing,  avec l&rsquo;alternative d&rsquo;un nouveau blocage et d&rsquo;un nouveau report de la d\u00e9cision. L&rsquo;USAF veut un nombre-plancher d&rsquo;avions et elle ne veut pas programmer plus d&rsquo;argent dans l&rsquo;\u00e9tat actuel des choses, ce qui favorise automatiquement Boeing. Si elle devait y \u00eatre forc\u00e9e par le Congr\u00e8s, pour pouvoir donner ses chances \u00e0 Northrop-EADS, l&rsquo;USAF avertit qu&rsquo;elle irait prendre l&rsquo;argent dans le programme JSF.<\/p>\n<\/p>\n<p><p>\tQuoi qu&rsquo;il en soit, les <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2777\" class=\"gen\">ambitions transatlantiques<\/a> d&rsquo;EADS rencontrent <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2011\" class=\"gen\">bien des difficult\u00e9s<\/a>. Du point de vue politique, un \u00e9chec d&rsquo;EADS dans le programme KC-X serait un rude coup pour l&rsquo;orientation (effectivement transatlantique) que les Allemands veulent donner \u00e0 EADS.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 22 janvier 2007 \u00e0 16H47<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour l&rsquo;Europe, particuli\u00e8rement pour les Allemands (et aussi, plus ou moins secr\u00e8tement, pour nombre de Fran\u00e7ais), le programme des nouveaux ravitailleurs en vol de l&rsquo;USAF fait figure d&rsquo;Eldorado, d&rsquo;American Dream et ainsi de suite. Airbus (EADS, donc principalement les Allemands et les Fran\u00e7ais) concourt pour ce programme \u00e9norme qui pourrait atteindre dans les m\u00e9andres pentagonesques&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3191,3612,3192,3613,4215,3194,4582],"class_list":["post-68440","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-airbus","tag-american","tag-boeing","tag-dream","tag-eads","tag-pentagone","tag-tankers"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=68440"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68440\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=68440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=68440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=68440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}