{"id":68442,"date":"2007-01-24T00:00:00","date_gmt":"2007-01-24T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2007\/01\/24\/presidentielles-aucun-positionnement-des-candidats-sur-les-etats-unis\/"},"modified":"2007-01-24T00:00:00","modified_gmt":"2007-01-24T00:00:00","slug":"presidentielles-aucun-positionnement-des-candidats-sur-les-etats-unis","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2007\/01\/24\/presidentielles-aucun-positionnement-des-candidats-sur-les-etats-unis\/","title":{"rendered":"<strong><em>Pr\u00e9sidentielles : aucun positionnement des candidats sur les Etats-Unis ?<\/em><\/strong>"},"content":{"rendered":"<p><h3>Les pr\u00e9sidentielles fran\u00e7aises et les USA<\/h3>\n<\/p>\n<p><p>\t24 janvier 2007  Voici un article de Jean-Philippe Immarigeon, auteur de <em>American Parano<\/em>. Il a \u00e9t\u00e9 repris sur <a href=\"http:\/\/fr.news.yahoo.com\/22012007\/326\/presidentielles-aucun-positionnement-des-candidats-sur-les-etats-unis.html\" class=\"gen\">Yahoo.com<\/a> le 22 janvier. Nous lui avons laiss\u00e9 son actualit\u00e9 et la forme qui le signale,  il a \u00e9t\u00e9 mis en ligne la veille du discours sur l&rsquo;\u00e9tat de l&rsquo;Union et nous le mettons nous-m\u00eames en ligne alors que le discours vient d&rsquo;\u00eatre prononc\u00e9.<\/p>\n<\/p>\n<p><p>\t(Nous signalons \u00e9galement <a href=\"http:\/\/americanparano.blog.fr\/\" class=\"gen\">le site d&rsquo;Immarigeon<\/a>, o\u00f9 la politique am\u00e9ricaniste est suivie de fa\u00e7on r\u00e9guli\u00e8re et o\u00f9 cet auteur nous tient au courant de ses activit\u00e9s.)<\/p>\n<\/p>\n<p><p>\tNous avons d\u00e9j\u00e0 cit\u00e9 <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3370\" class=\"gen\">\u00e0 une occasion<\/a> le livre de Jean-Philippe Immarigeon. Nous avons dit l&rsquo;estime o\u00f9 nous tenons cet ouvrage, notamment parce qu&rsquo;il repr\u00e9sente une nouvelle approche critique du ph\u00e9nom\u00e8ne de l&rsquo;am\u00e9ricanisme, d\u00e9barrass\u00e9e des contraintes psychologiques de complexe et de fascination auxquelles les auteurs fran\u00e7ais ont succomb\u00e9 pendant plusieurs d\u00e9cennies, depuis la Deuxi\u00e8me Guerre mondiale principalement. (Immarigeon renoue avec la grande tradition de l&rsquo;approche critique de l&rsquo;am\u00e9ricanisme telle qu&rsquo;elle s&rsquo;\u00e9tait install\u00e9e en France entre les deux guerres mondiales, \u00e9poque la plus f\u00e9conde de l&rsquo;analyse du ph\u00e9nom\u00e8ne. C&rsquo;est durant cette p\u00e9riode que le ph\u00e9nom\u00e8ne de l&rsquo;am\u00e9ricanisme a commenc\u00e9 \u00e0 \u00eatre embrass\u00e9 dans sa totalit\u00e9, comme il doit l&rsquo;\u00eatre \u00e9videmment pour \u00eatre justement appr\u00e9ci\u00e9.)<\/p>\n<h2 class=\"common-article\">Pr\u00e9sidentielles : aucun positionnement des candidats sur les Etats-Unis ?<\/h2>\n<\/p>\n<p><p>\t<strong>Entre l&rsquo;anti-am\u00e9ricanisme conspirationniste de certains et l&rsquo;am\u00e9ricanol\u00e2trie b\u00e9ate des autres, n&rsquo;y a-t-il donc autre chose \u00e0 faire qu&rsquo;attendre le retour d&rsquo;une autre Am\u00e9rique pour que les choses rentrent toutes seules dans l&rsquo;ordre, alors que le monde risque de basculer dans une nouvelle crise ?<\/strong><\/p>\n<\/p>\n<p><p>\tQui sont les plus ridicules, les d\u00e9mocrates am\u00e9ricains qui, apr\u00e8s avoir applaudi \u00e0 la guerre durant cinq ans, semblent d\u00e9couvrir l&rsquo;\u00e9tendue du d\u00e9sastre ou nos responsables politiques qui, \u00e0 l&rsquo;unisson de l&rsquo;opinion, avaient averti de la catastrophe \u00e0 venir mais n&rsquo;en attendent pas moins que les m\u00eames d\u00e9mocrates &#8211; qui furent sourds \u00e0 ces avertissements et vocif\u00e9r\u00e8rent contre la France et les Fran\u00e7ais pour ne pas sembler en reste sur les \u00e9ditorialistes de Fox News, de CNN, du New York Times ou du Wall Street Journal  nous permettent cette fameuse r\u00e9conciliation avec l&rsquo;autre Am\u00e9rique, la vraie Am\u00e9rique ?<\/p>\n<\/p>\n<p><p>\tLorsqu&rsquo;il s&rsquo;agit des Etats-Unis, les Fran\u00e7ais sont, soit frapp\u00e9s d&rsquo;amn\u00e9sie, soit but\u00e9s dans leurs illusions. Le r\u00e9cent num\u00e9ro de L&rsquo;Express titr\u00e9 Ceux qui vont tout changer, pulv\u00e9rise sur ce point les bornes du ridicule. Tous veulent oublier que les injures antifran\u00e7aises de Rice, Cheney et Rumsfeld lors de la guerre d&rsquo;Irak furent relay\u00e9es par les \u00e9lus d\u00e9mocrates de l&rsquo;\u00e9poque ; tous oublient que d\u00e8s le 14 septembre 2001, les pouvoirs de guerre furent donn\u00e9s par un Congr\u00e8s unanime \u00e0 un pr\u00e9sident Bush qui rappela 50.000 r\u00e9servistes, mena\u00e7a les alli\u00e9s r\u00e9calcitrants, justifia l&rsquo;usage de la torture et obtint le m\u00eame soutien parlementaire pour son Patriot Act, constamment renouvel\u00e9 depuis. Selon un sondage New York Times\/CBS au lendemain des attentats, 85 % des Am\u00e9ricains souhaitaient une action arm\u00e9e sans m\u00eame savoir contre qui, et 75 % annon\u00e7aient la justifier a priori quand bien m\u00eame elle entra\u00eenerait le massacre de civils et d&rsquo;innocents. Aujourd&rsquo;hui les m\u00eames, \u00e9lus comme \u00e9lecteurs, sont dans les m\u00eames proportions d&rsquo;un avis contraire.<\/p>\n<\/p>\n<p><p>\tFort bien, r\u00e9jouissons-nous-en, s&rsquo;\u00e9merveille l&rsquo;intelligentsia. Notre presse s&rsquo;est mise de la partie. Elle a saut\u00e9 de joie lorsque la Cour supr\u00eame de Washington a d\u00e9couvert le 29 juin 2006, avec quatre ans et demi de retard, qu&rsquo;il se passait des choses pas jolies \u00e0 Guantanamo : l&rsquo;Am\u00e9rique est de retour ! Mais la m\u00eame presse est rest\u00e9e muette lorsque, quelques semaines plus tard, le Congr\u00e8s, d\u00e9mocrates compris, a remis en forme l\u00e9gislative l&rsquo;arbitraire de la lutte antiterroriste, en int\u00e9grant dans la r\u00e8gle de droit ce qui n&rsquo;\u00e9tait alors qu&rsquo;un \u00e9tat d&rsquo;exception (Military Commissions Act du 17 octobre 2006). Bis repetita pour le rapport Baker, qui contient pourtant tout et son contraire : les Am\u00e9ricains prennent enfin conscience ! Il n&rsquo;a pas fallu 15 jours pour que le rapport soit enterr\u00e9. M\u00eame chose pour la victoire d\u00e9mocrate : on allait voir ce qu&rsquo;on allait voir ! Nancy Pelosi, \u00e9crivait Philippe Labro, est le symbole m\u00eame de la grandeur de l&rsquo;Am\u00e9rique, puisque son \u00e9lection cloue le bec \u00e0 tous les d\u00e9tracteurs (raisonnement dont la logique est d&rsquo;autant plus belle qu&rsquo;elle est totalement incompr\u00e9hensible). On va bien voir ce que va faire le chairman Pelosi mardi soir 23 janvier, lorsque George W. Bush aura prononc\u00e9 juste devant elle le discours annuel sur l&rsquo;\u00e9tat de l&rsquo;Union.<\/p>\n<\/p>\n<p><p>\tSi elle applaudit comme ses amis l&rsquo;ont fait durant cinq ans ? Le mythe am\u00e9ricain est tel que l&rsquo;opinion fran\u00e7aise attendra encore deux ans la victoire de&#8230; de qui ? D&rsquo;une ou d&rsquo;un d\u00e9mocrate, pardi, comme on attendait John Kerry ! Et pour quoi faire, lorsque l&rsquo;on sait que la d\u00e9mocrate Madeleine Albright, ex-secr\u00e9taire d&rsquo;Etat de Clinton, qui consid\u00e8re aujourd&rsquo;hui comme une faute une guerre qu&rsquo;elle a soutenue, mena\u00e7ait \u00e0 l&rsquo;automne 2004 de tra\u00eener en Irak les soldats fran\u00e7ais par la peau des fesses si son poulain battait Bush.<\/p>\n<\/p>\n<p><p>\tLa m\u00eame opinion fran\u00e7aise est en droit de dire aux Am\u00e9ricains, d\u00e9mocrates compris : Cette d\u00e9faite dont nous vous avions averti tr\u00e8s t\u00f4t, vous l&rsquo;avez voulue, vous l&rsquo;avez, il fallait y penser avant. C&rsquo;est un peu le sens de la sortie de Jacques Chirac le 6 janvier dernier devant les ambassadeurs. Mais apr\u00e8s, que fait-on, alors que pendant que nos \u00e9lites d\u00e9boussol\u00e9es par une Am\u00e9rique qu&rsquo;elles ne comprennent pas attendent on ne sait quoi, les Etats-Unis, qui n&rsquo;ont plus d&rsquo;autre objectif que de limiter la casse \u00e0 d\u00e9faut de sauver la face, vont laisser, davantage d&rsquo;ailleurs par b\u00eatise et incomp\u00e9tence que par volont\u00e9 d\u00e9lib\u00e9r\u00e9e, tout l&rsquo;Orient sombrer dans le chaos ? Qui peut me dire, \u00e0 l&rsquo;exception de l&rsquo;alignement atlantiste de Nicolas Sarkosy, quel est le positionnement des autres candidats vis-\u00e0-vis de la politique am\u00e9ricaine dans le contexte de crise internationale majeure que le monde vit ?<\/p>\n<\/p>\n<p><p>\tLe ridicule ne tue pas, sinon pas un \u00e9lu am\u00e9ricain, de quelque bord qu&rsquo;il soit, ne serait plus de ce monde. Mais pas un de nos dirigeants n&rsquo;aurait davantage d&rsquo;esp\u00e9rance de vie, de quelque bord qu&rsquo;il (ou qu&rsquo;elle) soit.<\/p>\n<\/p>\n<p><p>\t<strong>Jean-Philippe Immarigeon<\/strong><\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les pr\u00e9sidentielles fran\u00e7aises et les USA 24 janvier 2007 Voici un article de Jean-Philippe Immarigeon, auteur de American Parano. Il a \u00e9t\u00e9 repris sur Yahoo.com le 22 janvier. Nous lui avons laiss\u00e9 son actualit\u00e9 et la forme qui le signale, il a \u00e9t\u00e9 mis en ligne la veille du discours sur l&rsquo;\u00e9tat de l&rsquo;Union et&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[2917,6133,4607,4134],"class_list":["post-68442","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-americaine","tag-immarigeon","tag-politique","tag-presidentielle"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=68442"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68442\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=68442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=68442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=68442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}