{"id":68469,"date":"2007-01-31T00:00:00","date_gmt":"2007-01-31T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2007\/01\/31\/une-situation-hors-de-controle-et-sa-fatalite-tragique\/"},"modified":"2007-01-31T00:00:00","modified_gmt":"2007-01-31T00:00:00","slug":"une-situation-hors-de-controle-et-sa-fatalite-tragique","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2007\/01\/31\/une-situation-hors-de-controle-et-sa-fatalite-tragique\/","title":{"rendered":"Une situation hors de contr\u00f4le et sa fatalit\u00e9 tragique"},"content":{"rendered":"<p><h2 class=\"common-article\">Une situation hors de contr\u00f4le et sa fatalit\u00e9 tragique<\/h2>\n<\/p>\n<p><p>\t31 janvier 2007  De nombreux \u00e9chos se font entendre, qui vont dans le sens de la possibilit\u00e9, voire de la probabilit\u00e9 d&rsquo;une attaque contre l&rsquo;Iran. Ces \u00e9chos sont organis\u00e9s autour de la m\u00e9sentente entre Am\u00e9ricains et Europ\u00e9ens, les premiers accusant les seconds de n&rsquo;\u00eatre pas assez durs contre l&rsquo;Iran. Si l&rsquo;on parle ici de mesures de pression, notamment \u00e9conomiques, la perspective que tout le monde a \u00e0 l&rsquo;esprit est \u00e9videmment celle d&rsquo;une attaque contre l&rsquo;Iran. La situation en Irak favorise cette possibilit\u00e9.<\/p>\n<\/p>\n<p><p>\tCitons notamment des appr\u00e9ciations de la presse anglo-saxonne, fond\u00e9es sur le th\u00e8me de la m\u00e9sentente transatlantique devant la possibilit\u00e9 d&rsquo;une attaque am\u00e9ricaine. Les habituelles sources officielles sont activ\u00e9es. C&rsquo;est un th\u00e8me classique dans cette sorte de situation, d\u00e9j\u00e0 utilis\u00e9 et d&rsquo;une efficacit\u00e9 toujours renouvel\u00e9e ; il vient toujours \u00e0 point pour entamer une campagne de pr\u00e9paration \u00e0 un conflit.<\/p>\n<\/p>\n<p><p>\t  L&rsquo;article du New York <em>Times<\/em>, repris par l&rsquo;International <em>Herald Tribune<\/em> <a href=\"http:\/\/www.iht.com\/articles\/2007\/01\/30\/africa\/web.0130sanctions.php\" class=\"gen\">hier<\/a>, qui d\u00e9veloppe les habituelles positions critiques, notamment lanc\u00e9es par des officiels US : \u00ab<em>European governments are resisting Bush administration demands that they curtail support for exports to Iran and that they block transactions and freeze assets of some Iranian companies, officials on both sides say. The resistance threatens to open a new rift between Europe and the United States over Iran.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t  La m\u00eame id\u00e9e est reprise par <em>The Guardian<\/em> d&rsquo;<a href=\"http:\/\/www.guardian.co.uk\/iran\/story\/0,,2002329,00.html\" class=\"gen\">aujourd&rsquo;hui<\/a>, cette fois en appuyant sur la possibilit\u00e9 d&rsquo;un d\u00e9veloppement militaire. L&rsquo;id\u00e9e g\u00e9n\u00e9rale repose sur l&rsquo;impatience de l&rsquo;administration GW pour  une attaque de l&rsquo;Iran : \u00ab<em>As transatlantic friction over how to deal with the Iranian impasse intensifies, there are fears in European capitals that the nuclear crisis could come to a head this year because of US frustration with Russian stalling tactics at the UN security council. The clock is ticking, said one European official. Military action has come back on to the table more seriously than before. The language in the US has changed.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t  M\u00eame tonalit\u00e9 dans le <em>Times<\/em> de Londres, (<a href=\"http:\/\/www.timesonline.co.uk\/article\/0,,3-2575797,00.html\" class=\"gen\">aujourd&rsquo;hui<\/a> \u00e9galement), qui d\u00e9veloppe quelques d\u00e9tails selon les lignes habituelles suivies pour pr\u00e9parer l&rsquo;opinion \u00e0 une attaque.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Divisions are emerging in the West&rsquo;s united front towards Iran with fears being voiced over the aggressive military posture adopted by America, while European allies are accused by the US of dragging their feet. A diplomatic source in Washington told The Times: It is difficult to imagine Bush and Cheney leaving office without resolving the Iranian issue, if necessary, by force.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Although the prospect of precipitate action by the US is discounted widely, some Western governments are said to be alarmed at events spiral-ling out of control.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Last week Mr Bush authorised US troops to kill or capture Iranians found operating inside Iraq&rsquo;s borders. This week he reiterated that the US will respond firmly if Iran continues to interfere in Iraq. He emphasised that did not necessarily mean that he was planning to invade Iran and that the US is still pursuing a negotiated settlement through the United Nations to eliminate Tehran&rsquo;s suspected nuclear weapons programme.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>But there are fears that the tough new US approach, which included the arrest this month of five Iranian officials in the Iraqi city of Irbil, could trigger a new confrontation.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Reza Zakeri, the director of strategic studies in the Iranian President&rsquo;s office, has said that Tehran may retaliate by capturing American soldiers. Abducting a US soldier in uniform is less expensive than buying a low-quality product made in China, he said. It would not be difficult to capture blond men with blue eyes wearing a military uniform. It would just be necessary to open a wallet and be generous.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t  Vendredi dernier, en renouvelant ses menaces d&rsquo;une proc\u00e9dure de destitution le d\u00e9put\u00e9 d\u00e9mocrate Kucinich <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3649\" class=\"gen\">annon\u00e7ait<\/a> que l&rsquo;administration lan\u00e7ait sa campagne de pr\u00e9paration \u00e0 une attaque contre l&rsquo;Iran. On ne peut le d\u00e9mentir.<\/p>\n<\/p>\n<p><p>\t  Les mots au Congr\u00e8s de l&rsquo;amiral Fallon, U.S. Navy et nouveau chef du th\u00e9\u00e2tre du Moyen-Orient, ne <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3652\" class=\"gen\">contredisent<\/a> en rien l&rsquo;hypoth\u00e8se de la possibilit\u00e9 d&rsquo;une attaque.<\/p>\n<h3>Sous le regard de Toynbee et de Maistre<\/h3>\n<\/p>\n<p><p>\tPrenez ces deux remarques que nous citons de l&rsquo;article du <em>Times<\/em> et vous avez le r\u00e9sum\u00e9 de la situation actuelle, dans son aspect le plus tragique d&rsquo;une <strong>fatalit\u00e9<\/strong>. Il s&rsquo;agit d&rsquo;observer comment la course \u00e0 l&rsquo;attaque contre l&rsquo;Iran (serait-ce une guerre? La question reste pos\u00e9e) est engag\u00e9e, comment elle se d\u00e9roule irr\u00e9sistiblement :<\/p>\n<\/p>\n<p><p>\t \u00ab<em>A diplomatic source in Washington told The Times: It is difficult to imagine Bush and Cheney leaving office without resolving the Iranian issue, if necessary, by force.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t  \u00ab<em>Although the prospect of precipitate action by the US is discounted widely, some Western governments are said to be alarmed at events spiralling out of control.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tIl y a donc d&rsquo;un c\u00f4t\u00e9 une volont\u00e9 affirm\u00e9e, but\u00e9e et ferm\u00e9e, sans compromission possible, dans le cadre d&rsquo;une situation politique d\u00e9sesp\u00e9r\u00e9e (Bush-Cheney dans leurs derniers retranchements \u00e0 Washington) ; de l&rsquo;autre, l&rsquo;absence <strong>totale<\/strong> de la moindre personnalit\u00e9, de la moindre ligne politique, de la moindre fermet\u00e9 qui puisse opposer un barrage ferme \u00e0 cette volont\u00e9. On parle d&rsquo;une situation hors de contr\u00f4le ; on peut parler d&rsquo;un engrenage fatal, qui pourrait \u00eatre assimil\u00e9 \u00e0 une fatalit\u00e9 ; on pourrait m\u00eame parler d&rsquo;une trag\u00e9die au sens le plus fort, avec un <em>deus ex machina<\/em> menant au terme dramatique qui est in\u00e9luctable. C&rsquo;est le sentiment qui pr\u00e9vaut aujourd&rsquo;hui, p\u00e9riode particuli\u00e8rement sombre \u00e0 cet \u00e9gard, et seul un suppl\u00e9ment inattendu de d\u00e9sordre pourrait le changer,  comme par exemple une intervention d\u00e9cid\u00e9e du Congr\u00e8s am\u00e9ricain (nous nommons cela d\u00e9sordre car c&rsquo;est le cas du point de vue objectif du pouvoir et de son autorit\u00e9 ; le mot d\u00e9sordre est employ\u00e9 comme une illustration, pas n\u00e9cessairement comme un \u00e9v\u00e9nement d\u00e9plorable).<\/p>\n<\/p>\n<p><p>\tLa situation est telle qu&rsquo;on dirait que nous aboutissons \u00e0 l&rsquo;\u00e9quation presque parfaite de la formule de <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=315\" class=\"gen\">Toynbee<\/a> constatant que la puissance technologique de l&rsquo;Occident bloque l&rsquo;alternative d&rsquo;autres mod\u00e8les de civilisation alors que notre civilisation offre par contraste tragique une absence totale de sens. On peut \u00e9crire effectivement que jamais une puissance aussi grande que celle de la civilisation occidentale (celle des USA, sous la direction de GW) n&rsquo;aura \u00e9t\u00e9 d\u00e9ploy\u00e9e avec une aussi compl\u00e8te absence de sens. L&rsquo;id\u00e9e s&rsquo;applique \u00e9videmment sans restriction \u00e0 la situation actuelle. Nul ne sait \u00e0 quoi conduira cette attaque, ni ce qui suivra, ni m\u00eame ce qui peut suivre. La pente est suivie comme on suit une fatalit\u00e9. Toute l&rsquo;habilet\u00e9, toute la sophistication de notre civilisation est dans le d\u00e9tail, la campagne de pr\u00e9paration (d&rsquo;intoxication), pour y mener. Nous savons parfaitement <strong>comment<\/strong> y aller mais nous ignorons absolument <strong>pourquoi<\/strong>.<\/p>\n<\/p>\n<p><p>\tL&rsquo;Europe s&rsquo;inqui\u00e8te, rechigne, parce qu&rsquo;elle se doute de quelque chose ; mais nul ne peut simplement esp\u00e9rer qu&rsquo;elle puisse faire quelque chose, d&rsquo;abord parce qu&rsquo;elle ignore totalement quoi faire. On ne lui a appris qu&rsquo;une chose, \u00e0 cette Europe-l\u00e0 : suivre les USA. Si elle rechigne et h\u00e9site, c&rsquo;est qu&rsquo;elle a peur, ce qui est bien compr\u00e9hensible ; elle ne peut s&#8217;emp\u00eacher de penser confus\u00e9ment, dans le secret d&rsquo;alc\u00f4ve de son cerveau fatigu\u00e9, que ce GW est sans doute un peu marteau. Fine remarque.<\/p>\n<\/p>\n<p><p>\tL&rsquo;Europe est <strong>totalement<\/strong> inexistante, confirmant en cela l&rsquo;\u00e9volution des derni\u00e8res ann\u00e9es. Ses hommes politiques sont \u00e0 mesure. Cet \u00e9v\u00e9nement tombe comme un symbole dans ces heures d&rsquo;alarme : l&rsquo;un des principaux candidats fran\u00e7ais \u00e0 la pr\u00e9sidence est \u00e0 Londres, o\u00f9 il vient prendre des le\u00e7ons du glorieux Tony Blair, dans le domaine de l&rsquo;intelligence et de l&rsquo;honn\u00eatet\u00e9 de l&rsquo;acte politique. (Au moins, Sarko joue cartes sur table. Le provincial visite la capitale. Le <em>Times<\/em> peut faire <a href=\"http:\/\/www.timesonline.co.uk\/article\/0,,3-2575574,00.html\" class=\"gen\">ce titre<\/a> qui va bien \u00e0 Sarko : \u00ab<em>Q<\/em>[uestion]<em>: If you want to be President of France where do you campaign? A<\/em>[nswer]<em>: London<\/em>\u00bb) Les hommes politiques de la p\u00e9riode correspondent en tous points aux caract\u00e8res ignobles de cette p\u00e9riode. Mod\u00e8le standard.<\/p>\n<\/p>\n<p><p>\tAutre grand ancien \u00e0 consulter pour comprendre notre \u00e9poque et l&rsquo;encha\u00eenement de ces \u00e9v\u00e9nements incontr\u00f4l\u00e9s qui est le seul moyen de mettre en cause le syst\u00e8me dont nous sommes prisonniers (car, \u00e9videmment, l&rsquo;attaque contre l&rsquo;Iran, si elle avait lieu, ne ferait qu&rsquo;acc\u00e9l\u00e9rer la chute du syst\u00e8me am\u00e9ricaniste, et les Europ\u00e9ens y auraient donc apport\u00e9 leur contribution paradoxale). Joseph de Maistre parlait <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1618\" class=\"gen\">ainsi<\/a> de la R\u00e9volution fran\u00e7aise et des hommes qui s&rsquo;y agitaient, montrant qu&rsquo;il n&rsquo;\u00e9tait pas m\u00e9content de cet \u00e9v\u00e9nement merveilleux qui participait \u00e0 la d\u00e9structuration d&rsquo;un syst\u00e8me parvenu \u00e0 son terme : <\/p>\n<\/p>\n<p><p>\t\u00ab<em>Dans ses Consid\u00e9rations sur la France&rsquo; (1796), Maistre commence par poser le paradoxe que la R\u00e9volution est un \u00e9v\u00e9nement merveilleux&rsquo; (un moment sublime de l&rsquo;Histoire). Mais la R\u00e9volution fran\u00e7aise, et tout ce qui se passe en Europe dans ce moment, est tout aussi merveilleux que la fructification instantan\u00e9e d&rsquo;un arbre au mois de janvier; cependant les hommes, au lieu d&rsquo;admirer, regardent ailleurs ou d\u00e9raisonnent. L\u00e0-dessus, Maistre ne manque pas d&rsquo;opposer avec une extr\u00eame vigueur le moment sublime de la R\u00e9volution et la m\u00e9diocrit\u00e9 des hommes qui croient l&rsquo;influencer, en fait qui sont emport\u00e9s par elle. On a remarqu\u00e9, avec grande raison, que la R\u00e9volution fran\u00e7aise m\u00e8ne les hommes plus que les hommes la m\u00e8nent. Cette observation est de la plus grande justesse&#8230; [&#8230;] Les sc\u00e9l\u00e9rats m\u00eames qui paraissent conduire la r\u00e9volution, n&rsquo;y entrent que comme de simples instruments; et d\u00e8s qu&rsquo;ils ont la pr\u00e9tention de la dominer, ils tombent ignoblement.<\/em>\u00bb<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une situation hors de contr\u00f4le et sa fatalit\u00e9 tragique 31 janvier 2007 De nombreux \u00e9chos se font entendre, qui vont dans le sens de la possibilit\u00e9, voire de la probabilit\u00e9 d&rsquo;une attaque contre l&rsquo;Iran. Ces \u00e9chos sont organis\u00e9s autour de la m\u00e9sentente entre Am\u00e9ricains et Europ\u00e9ens, les premiers accusant les seconds de n&rsquo;\u00eatre pas assez&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[2870,1294,6384,398,3198,2773,4596,3072,6383],"class_list":["post-68469","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-attaque","tag-cheney","tag-controle","tag-europe","tag-gw","tag-iran","tag-maistre","tag-toynbee","tag-tragique"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=68469"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68469\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=68469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=68469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=68469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}