{"id":68482,"date":"2007-02-03T00:00:00","date_gmt":"2007-02-03T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2007\/02\/03\/les-trois-coups-sont-frappes\/"},"modified":"2007-02-03T00:00:00","modified_gmt":"2007-02-03T00:00:00","slug":"les-trois-coups-sont-frappes","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2007\/02\/03\/les-trois-coups-sont-frappes\/","title":{"rendered":"<strong><em>Les trois coups sont frapp\u00e9s<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Les trois coups sont frapp\u00e9s<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t3 f\u00e9vrier 2007  Au th\u00e9\u00e2tre, on frappe trois coups pour annoncer l&rsquo;ouverture de la pi\u00e8ce. Selon notre symbolique, le rapport IPCC\/GIEC (Intergovernmental Panel on Climate Change\/Groupe Intergouvernemental sur l&rsquo;Evolution du Climat) qui couronne la conf\u00e9rence sur la crise climatique de Paris pourrait r\u00e9sonner comme le troisi\u00e8me coup, apr\u00e8s le <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3300\" class=\"gen\">rapport Stern<\/a> et le <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3627\" class=\"gen\">tournant de Davos<\/a>. Bien s\u00fbr, cette pi\u00e8ce-l\u00e0 est plut\u00f4t une trag\u00e9die, celle de la crise climatique ; et notre classification est symbolique, pour l&rsquo;avantage de l&rsquo;image.<\/p>\n<\/p>\n<p><p>\t(Cette symbolique effectivement pratique pour l&rsquo;image de la chose pourrait \u00eatre contest\u00e9e. On pourrait y ajouter un quatri\u00e8me coup frapp\u00e9, celui de l&rsquo;intervention du fameux <em>Bulletin of Atomics Scientists<\/em> annon\u00e7ant le <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3607\" class=\"gen\">17 janvier<\/a> qu&rsquo;il lie au danger nucl\u00e9aire qui menace l&rsquo;esp\u00e8ce, qu&rsquo;il suit depuis 1947, le danger du r\u00e9chauffement climatique.  Cette position du <em>Bulletin<\/em> symbolise et concr\u00e9tise la prise de position de la communaut\u00e9 scientifique dans ce qu&rsquo;elle a de plus prestigieux et de plus influent. Pour elle aussi, la crise est l\u00e0, urgente, extraordinairement grave,  la crise syst\u00e9mique par essence. Disons alors que <strong>les quatre coups sont frapp\u00e9s<\/strong>? Cela a moins d&rsquo;allure.)<\/p>\n<\/p>\n<p><p>\tLe rapport IPCC\/GIEC confirme l&rsquo;urgence de la crise, ach\u00e8ve de lancer la mobilisation plan\u00e9taire selon des normes connues. Chacun y prend sa place. Chirac, bien entendu, est en premi\u00e8re ligne. <em>Le Monde<\/em> <a href=\"http:\/\/www.lemonde.fr\/web\/imprimer_element\/0,40-0@2-3228,50-862857,0.html\" class=\"gen\">parle<\/a> d&rsquo;une croisade dont le \u00ab<em>chevalier vert s&rsquo;appelle Jacques Chirac<\/em>\u00bb. Le discours chiraquien fut \u00e0 mesure : \u00ab<em>Le temps est \u00e0 la r\u00e9volution. La r\u00e9volution des consciences. La r\u00e9volution de l&rsquo;\u00e9conomie. La r\u00e9volution de l&rsquo;action politique<\/em> [] <em>La plan\u00e8te souffre.<\/em> [&#8230;] <em>La nature souffre.<\/em> [&#8230;] <em>Nous sommes au seuil de l&rsquo;irr\u00e9versible.<\/em>\u00bb Qu&rsquo;importe, ces mots pompeux et grandiloquents ne le sont pas compl\u00e8tement puisqu&rsquo;ils ont un sens, puisqu&rsquo;ils s&rsquo;appliquent \u00e0 une mati\u00e8re pressante et r\u00e9elle. Lorsque Chirac parle d&rsquo;une \u00ab<em>r\u00e9volution des consciences <\/em>[qui doit] <em>rendre possible la r\u00e9volution de l&rsquo;\u00e9conomie<\/em>\u00bb et de la n\u00e9cessit\u00e9 d&rsquo;\u00e9voluer vers \u00ab<em>une transformation radicale de nos modes de production et de consommation<\/em>\u00bb, il rejoint l&rsquo;id\u00e9e que la crise climatique a \u00e9videmment une dimension politique imm\u00e9diate, et une dimension politique tr\u00e8s large avec des implications mettant en cause le syst\u00e8me qui nous conduit et l&rsquo;id\u00e9ologie qui l&rsquo;inspire. <\/p>\n<\/p>\n<p><p>\tIl y a l\u00e0, d\u00e9sormais, une dynamique en marche. Nous insistons depuis longtemps sur la n\u00e9cessit\u00e9 d&rsquo;int\u00e9grer la crise climatique dans les conditions politiques des crises qui touchent notre civilisation, qui se r\u00e9sument effectivement dans la crise g\u00e9n\u00e9rale du syst\u00e8me qui nous conduit et [de] l&rsquo;id\u00e9ologie qui l&rsquo;inspire. Il faut rechercher tous les indices et les signes qui vont dans ce sens, pour mieux comprendre les conditions de cette int\u00e9gration. L&rsquo;un des plus importants est sans contestation possible la position des USA, avec la diversit\u00e9 qui la caract\u00e9rise.<\/p>\n<\/p>\n<p><p>\t  Une administration f\u00e9d\u00e9rale arc-bout\u00e9e sur son refus de consid\u00e9rer la moindre mesure restrictive du fonctionnement de l&rsquo;\u00e9conomie. Sur ce point comme sur tant d&rsquo;autres, les mots chiraquiens (\u00ab<em>Le temps est \u00e0 la r\u00e9volution. La r\u00e9volution des consciences. La r\u00e9volution de l&rsquo;\u00e9conomie. La r\u00e9volution de l&rsquo;action politique<\/em>\u00bb) constituent un anath\u00e8me. L&rsquo;administration GW n&rsquo;est r\u00e9volutionnaire que dans le sens voulu par les n\u00e9o-conservateurs de la r\u00e9volution d\u00e9mocratique en Irak et autour, dans le Moyen-Orient,  et cette r\u00e9volution-l\u00e0 a un sens \u00e9conomique, en cherchant \u00e0 imposer le capitalisme radical, sans restriction, donc ennemi total de restrictions pour lutter contre la crise climatique.<\/p>\n<\/p>\n<p><p>\tLe lien entre le chaos irakien et les menaces de la crise iranienne d&rsquo;une part, et la crise climatique d&rsquo;autre part, est \u00e9tabli d&rsquo;une fa\u00e7on claire, dans le sens d&rsquo;une exclusion r\u00e9ciproque, d&rsquo;un antagonisme mortel. Pour GW et son groupe, la <em>Long War<\/em> contre la terreur, avec ses points de fusion irakien et iranien, est l&rsquo;ennemie mortelle de la crise climatique, par la concurrence de priorit\u00e9 et d&rsquo;\u00e9nergie, et peut-\u00eatre, et m\u00eame sans aucun doute, la concurrence id\u00e9ologique que cela suppose. La <em>Long War<\/em> est l&rsquo;expression apocalyptique de la d\u00e9fense inconditionnelle du syst\u00e8me ; la crise climatique est l&rsquo;expression apocalyptique,  potentielle hier, en train de s&rsquo;affirmer aujourd&rsquo;hui,  de la mise en cause du syst\u00e8me. A cet \u00e9gard, r\u00e9p\u00e9tons-le, les mots pompeux et grandiloquents de Chirac ont leur place parce qu&rsquo;ils ont un sens.<\/p>\n<\/p>\n<p><p>\t(GW \u00e9volue-t-il sur la crise climatique ? Il a bien \u00e9t\u00e9 oblig\u00e9 de reconna\u00eetre que la crise climatique existe, dans son discours sur l&rsquo;Etat de l&rsquo;Union. Pour le reste, il s&rsquo;en tient au refus de toute mesure r\u00e9gulatrice et restrictive. La technologie fera l&rsquo;affaire, et rien d&rsquo;autre. Le commentaire de George Monbiot du <a href=\"http:\/\/www.guardian.co.uk\/commentisfree\/story\/0,,2001694,00.html\" class=\"gen\">30 janvier<\/a>, dans le <em>Guardian<\/em>, de son c\u00f4t\u00e9, fait l&rsquo;affaire : \u00ab<em>Don&rsquo;t be fooled by Bush&rsquo;s defection: his cures are another form of denial. The president&rsquo;s avowed conversion on climate change is illusory. He is just drumming up new business for his chums.<\/em>\u00bb Ce point est essentiel : m\u00eame si la crise climatique existe, la priorit\u00e9 reste l&rsquo;\u00e9conomie, \u00e0 tout prix.)<\/p>\n<\/p>\n<p><p>\t  Le deuxi\u00e8me aspect de cette diversit\u00e9 am\u00e9ricaniste m\u00e9rite plus de d\u00e9veloppement. Il touche au cur d&rsquo;une crise latente des USA, \u00e0 l&rsquo;heure de la <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3659\" class=\"gen\">crise constitutionnelle<\/a> centrale qui se d\u00e9veloppe, sous la pression de la crise irako-iranienne. Cela fait beaucoup de pressions (et de crises) et il est bienvenu de s&rsquo;attarder \u00e0 l&rsquo;un de ces points de tension qui est en train de se d\u00e9velopper rapidement. Il s&rsquo;agit de la crise centrifuge de d\u00e9volution qui menace de s&rsquo;\u00e9tendre \u00e0 partir de la crise climatique, que les pouvoirs r\u00e9gionaux et le pouvoir l\u00e9gislatif envisagent d&rsquo;une fa\u00e7on diam\u00e9tralement oppos\u00e9e \u00e0 la voie choisie par le gouvernement f\u00e9d\u00e9ral. Cette menace, aliment\u00e9e par les pressions fusionnelles des crises washingtoniennes actuelles, qui isolent le pouvoir f\u00e9d\u00e9ral et le mettent en \u00e9tat d&rsquo;antagonisme avec le reste, est pleine de potentialit\u00e9s d\u00e9stabilisatrices. Elle annonce une crise sp\u00e9cifique.<\/p>\n<\/p>\n<p><p>\tSurprise, surprise,  oh non, pas tant que \u00e7a,  ce sont les Britanniques qui en sont les pyromanes Nous voyons cela <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3666\" class=\"gen\">par ailleurs<\/a>.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les trois coups sont frapp\u00e9s 3 f\u00e9vrier 2007 Au th\u00e9\u00e2tre, on frappe trois coups pour annoncer l&rsquo;ouverture de la pi\u00e8ce. Selon notre symbolique, le rapport IPCC\/GIEC (Intergovernmental Panel on Climate Change\/Groupe Intergouvernemental sur l&rsquo;Evolution du Climat) qui couronne la conf\u00e9rence sur la crise climatique de Paris pourrait r\u00e9sonner comme le troisi\u00e8me coup, apr\u00e8s le rapport&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3703,868,779,3392,3228,6392,4237,6350,2879,4238],"class_list":["post-68482","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-britanniques","tag-bush","tag-chirac","tag-climatique","tag-crise","tag-geic","tag-global","tag-ipcc","tag-revolution","tag-warming"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=68482"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68482\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=68482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=68482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=68482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}