{"id":68485,"date":"2007-02-03T00:00:00","date_gmt":"2007-02-03T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2007\/02\/03\/e-pluribus-unum-pour-combien-de-temps\/"},"modified":"2007-02-03T00:00:00","modified_gmt":"2007-02-03T00:00:00","slug":"e-pluribus-unum-pour-combien-de-temps","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2007\/02\/03\/e-pluribus-unum-pour-combien-de-temps\/","title":{"rendered":"\u201c<em>E Pluribus, Unum<\/em>\u201d, pour combien de temps?"},"content":{"rendered":"<p><h2 class=\"common-article\"><em>E Pluribus, Unum<\/em>, pour combien de temps?<\/h2>\n<\/p>\n<p><p>\t3 f\u00e9vrier 2007  Pour compl\u00e9ter notre premier <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3663\" class=\"gen\">F&#038;C<\/a> du jour, nous nous attachons \u00e0 l&rsquo;un des aspects de la situation am\u00e9ricaine par rapport \u00e0 la crise climatique. Nous mentionnions cet aspect dans cet article, en promettant d&rsquo;y revenir :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Il s&rsquo;agit de la crise centrifuge de d\u00e9volution qui menace de s&rsquo;\u00e9tendre \u00e0 partir de cette crise climatique, que les pouvoirs r\u00e9gionaux et le pouvoir l\u00e9gislatif envisagent d&rsquo;une fa\u00e7on diam\u00e9tralement oppos\u00e9e \u00e0 la voie choisie par le gouvernement f\u00e9d\u00e9ral. Cette menace, aliment\u00e9e par les pressions fusionnelles des crises washingtoniennes actuelles, qui isolent le pouvoir f\u00e9d\u00e9ral et le mettent en \u00e9tat d&rsquo;antagonisme avec le reste, est pleine de potentialit\u00e9s d\u00e9stabilisatrices. Elle annonce une crise sp\u00e9cifique.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Surprise, surprise,  oh non, pas tant que \u00e7a,  ce sont les Britanniques qui en sont les pyromanes Nous voyons cela par ailleurs.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tNous y voici,  et nous y voici, pr\u00e9cis\u00e9ment, parce que certaines nouvelles d&rsquo;origine britannique sont suffisamment peu ordinaires pour que nous nous attardions \u00e0 la chose.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est le <em>Times<\/em> de Londres qui d\u00e9veloppe ces nouvelles. Il pr\u00e9sente l&rsquo;initiative remarquable de deux ministres britanniques, en mission officielle aux Etats-Unis pour discuter avec des gouverneurs de plusieurs Etats de l&rsquo;Union d&rsquo;une mati\u00e8re internationale de premi\u00e8re importance, avec des ramifications concr\u00e8tes pr\u00e9cises. Il s&rsquo;agit de la lutte contre les \u00e9missions de CO2 et les dispositions dans les \u00e9changes commerciaux qui en d\u00e9couleraient, \u00e0 mettre en place avec l&rsquo;UE, ce qui repr\u00e9sente un effort complexe d&rsquo;arrangements internationaux o\u00f9 les Etats de l&rsquo;Union figureront quasiment comme des interlocuteurs souverains de l&rsquo;UE.<\/p>\n<\/p>\n<p><p>\tLe texte (d&rsquo;<a href=\"http:\/\/www.timesonline.co.uk\/article\/0,,2-2582032,00.html\" class=\"gen\">aujourd&rsquo;hui<\/a>) pr\u00e9cise le sens r\u00e9volutionnaire de cette action :  <em>bypassing President Bush<\/em>. Cerise sur le g\u00e2teau : les Britanniques esp\u00e8rent agir en ce sens comme repr\u00e9sentants l&rsquo;UE, entra\u00eenant l&rsquo;UE dans cette m\u00eame politique de doubler le pr\u00e9sident.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Britain is to spearhead a new drive against climate change by bypassing President Bush and urging US states to join directly with Europe&rsquo;s own carbon trading scheme.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>David Miliband, the Environment Secretary, and MPs will travel to America in a fortnight for talks with states and the Democratic-controlled Senate which back limits on US greenhouse gas emissions. The Government hopes that nine northeastern states and California can eventually join the European Union&rsquo;s carbon trading scheme in the first step towards a global scheme. The schemes are likely to prove far more effective by working together.<\/em><\/p>\n<\/p>\n<p><p>\t()<\/p>\n<\/p>\n<p><p>\t\u00bb<em>Mr Miliband told The Times last night: The science is moving faster than the politics now. In 2007 we need significant progress at the international level. The UK is showing leadership with its Climate Change Bill, the EU is showing leadership and we hope that other legislatures across the world will take similar action.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>California and the nine northeastern states, frustrated by President Bush&rsquo;s lack of action, have already set up their own carbon trading schemes. Arnold Schwarzenegger, the Governor of California, and George Pataki, Governor of New York, announced they would like to see ways to link up with the EU trading schemes. Despite good-will on both sides, the issue is fraught with difficulties, with the European Commission still having to resolve various legal issues.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Although there are signs that Mr Bush himself is finally beginning to shift ground, recognising climate change as a serious problem in his State of the Union speech last month, he still opposes capping carbon emissions. Mr Miliband will address the Washington Legislators Forum, which has been convened to take advantage of the opportunity created by the Democratic takeover of Congress last month.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Stephen Byers, the former Trade Secretary, will lead a discussion on how US states that have already set limits on greenhouse gases could be invited into the EU scheme. He said last night: Some of the proposals will bypass the White House, others will engage with sympathetic Republicans. We are seeking to put pressure on President Bush.<\/em>\u00bb<\/p>\n<h3>La destructuration de <em>Unum<\/em><\/h3>\n<\/p>\n<p><p>\tLors de sa rencontre avec Barroso et une d\u00e9l\u00e9gation de l&rsquo;UE, le 9 janvier, et alors qu&rsquo;on parlait des n\u00e9gociations commerciales USA-UE, Bush avait dit un peu sarcastiquement et abruptement,  ou peut-\u00eatre pour exorciser d&rsquo;une fa\u00e7on pr\u00e9monitoire une crainte \u00e0 venir ?  cette phrase dans le style habituel des pr\u00e9sidents US rencontrant les repr\u00e9sentants de l&rsquo;Europe institutionnelle : \u00ab<em>I have to be bold. But while you have to report to 27 MS <\/em>[Member States], <em>Sue Schwab reports only to me.<\/em>\u00bb (Schwab est la repr\u00e9sentante US aux n\u00e9gociations commerciales avec l&rsquo;UE.) Le paradoxe est que dans la situation qu&rsquo;on d\u00e9crit plus haut, o\u00f9 l&rsquo;on va parler de mati\u00e8res commerciales dans la logique des dispositions \u00e0 prendre contre la crise climatique, l&rsquo;UE parle pour tous les Etats-Membres sans gu\u00e8re de probl\u00e8mes de consultation alors que les USA se trouvent bien divis\u00e9s, et d&rsquo;une fa\u00e7on \u00e0 la fois logique, inhabituelle et inqui\u00e9tante.<\/p>\n<\/p>\n<p><p>\tLes Britanniques ont grand espoir de forcer la main de GW Bush. Ce n&rsquo;est pas la premi\u00e8re fois. (Blair nous a habitu\u00e9s \u00e0 cette sorte de phantasme.) Un autre <a href=\"http:\/\/www.timesonline.co.uk\/article\/0,,2-2581397,00.html\" class=\"gen\">article<\/a> du <em>Times<\/em> nous annonce en titre que GW va rejoindre la croisade (\u00ab<em>Bush takes his place on the bandwagon<\/em>\u00bb) mais la chose nous appara\u00eet bien sollicit\u00e9e. Le contenu de l&rsquo;article est largement en retrait du titre et les perspectives restent tr\u00e8s tr\u00e8s modestes apr\u00e8s l&rsquo;annonce, quatre heures apr\u00e8s la fin de la conf\u00e9rence de Paris sur la crise climatique, que GW confirme son refus de toute contrainte pour les \u00e9missions de CO2 (AP le <a href=\"http:\/\/news.yahoo.com\/s\/ap\/20070202\/ap_on_go_co\/climate_reax_us;_ylt=AvcDo4AXa_Owj0CQJApOT_qs0NUE;_ylu=X3oDMTA3OTB1amhuBHNlYwNtdHM-\" class=\"gen\">2 f\u00e9vrier<\/a> : \u00ab<em>Despite a strongly worded global warming report from the world&rsquo;s top climate scientists, the Bush administration expressed continued opposition Friday to mandatory reductions in heat-trapping greenhouse gases.<\/em>\u00bb)<\/p>\n<\/p>\n<p><p>\tLe <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=832\" class=\"gen\">sch\u00e9ma<\/a> d\u00e9j\u00e0 <a href=\"http:\/\/www.timesonline.co.uk\/article\/0,,2-2581397,00.html\" class=\"gen\">rencontr\u00e9<\/a> reste plus que jamais d&rsquo;actualit\u00e9 et le trait en est d\u00e9sormais forci. Il y a une rupture <em>de facto<\/em> aux USA entre le pouvoir f\u00e9d\u00e9ral et des pouvoirs \u00e0 tendance centrifuge (les Etats et le Congr\u00e8s dans ce r\u00f4le sp\u00e9cifique qu&rsquo;il jouerait de soutenir les Etats). Les projets britanniques impliquent l&rsquo;exploration d&rsquo;accords commerciaux entre ces interlocuteurs r\u00e9gionaux et l&rsquo;UE, sur une mati\u00e8re absolument fondamentale ; nous ne sommes pas loin du domaine de la s\u00e9curit\u00e9 nationale au sens \u00e9largi, qui est un domaine traditionnellement r\u00e9serv\u00e9 \u00e0 la pr\u00e9rogative du pouvoir f\u00e9d\u00e9ral. De tels accords seraient, pour notre \u00e9poque, une jurisprudence dans l&rsquo;esprit de la chose. Comme nous l&rsquo;avons d\u00e9j\u00e0 observ\u00e9, le r\u00f4le du Congr\u00e8s est, dans ce cas, centrifuge, puisqu&rsquo;il soutient les Etats contre le centre f\u00e9d\u00e9ral.<\/p>\n<\/p>\n<p><p>\tIl s&rsquo;agit de l&rsquo;\u00e9volution d&rsquo;une situation qui doit \u00eatre situ\u00e9e dans son contexte, qui en favorise les traits les plus d\u00e9structurants. Un pr\u00e9sident isol\u00e9, en butte \u00e0 une hostilit\u00e9 g\u00e9n\u00e9rale, dans une situation de quasi-ill\u00e9galit\u00e9 et de crise constitutionnelle sur le point d&rsquo;\u00e9clater, sur le point lui-m\u00eame de lancer (ou soup\u00e7onn\u00e9 d&rsquo;\u00eatre sur le point de ) une guerre folle contre l&rsquo;Iran. Le pr\u00e9sident est affaibli, le pr\u00e9sident est en situation de d\u00e9l\u00e9gitimation, et avec lui le pouvoir f\u00e9d\u00e9ral souffre d&rsquo;une d\u00e9saffection montante. Les Etats sont furieux de devoir combler, avec leur Garde Nationale, les trous en forces arm\u00e9es d&rsquo;un Pentagone qui re\u00e7oit des sommes pharamineuses et conduit des projets grandioses et inutiles avec un don rare pour le gaspillage et la corruption, et n&rsquo;est pas capable de trouver 150.000 hommes pour mener une guerre ha\u00efe par toute l&rsquo;Am\u00e9rique. Ce contexte va puissamment renforcer les initiatives sur la r\u00e9duction des \u00e9missions de CO2, comme autant d&rsquo;actes d&rsquo;autonomie par rapport au pouvoir f\u00e9d\u00e9ral.<\/p>\n<\/p>\n<p><p>\tLe temps travaille pour cette d\u00e9stabilisation parce que la crise climatique, comme nul ne l&rsquo;ignore, est l\u00e0 pour durer tr\u00e8s, tr\u00e8s longtemps. Sans solliciter l&rsquo;argument, on peut avancer l&rsquo;hypoth\u00e8se qu&rsquo;il y a l\u00e0 les germes d&rsquo;un mouvement de d\u00e9structuration fondamentale des Etats-Unis.<\/p>\n<\/p>\n<p><p>\tPeut-\u00eatre se justifierait-il de prendre date,  en savourant l&rsquo;ironie que cette dynamique a pour origine le z\u00e8le entreprenant des cousins britanniques, adorateurs des <em>special relationships<\/em>.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>E Pluribus, Unum, pour combien de temps? 3 f\u00e9vrier 2007 Pour compl\u00e9ter notre premier F&#038;C du jour, nous nous attachons \u00e0 l&rsquo;un des aspects de la situation am\u00e9ricaine par rapport \u00e0 la crise climatique. Nous mentionnions cet aspect dans cet article, en promettant d&rsquo;y revenir : \u00abIl s&rsquo;agit de la crise centrifuge de d\u00e9volution qui&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[4099,3392,3228,3907,6398,6395,4889,5694,6396,6397],"class_list":["post-68485","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-centrifuge","tag-climatique","tag-crise","tag-destructuration","tag-devolution","tag-e","tag-etats","tag-eu","tag-pluribus","tag-unum"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=68485"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68485\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=68485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=68485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=68485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}