{"id":68494,"date":"2007-02-06T00:00:00","date_gmt":"2007-02-06T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2007\/02\/06\/pour-des-experts-israeliens-on-peut-vivre-avec-un-iran-nucleaire\/"},"modified":"2007-02-06T00:00:00","modified_gmt":"2007-02-06T00:00:00","slug":"pour-des-experts-israeliens-on-peut-vivre-avec-un-iran-nucleaire","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2007\/02\/06\/pour-des-experts-israeliens-on-peut-vivre-avec-un-iran-nucleaire\/","title":{"rendered":"Pour des experts isra\u00e9liens, on peut vivre avec un Iran nucl\u00e9aire"},"content":{"rendered":"<p><p>La question nucl\u00e9aire iranienne tendrait d\u00e9sormais \u00e0 \u00eatre consid\u00e9r\u00e9e d&rsquo;une fa\u00e7on plus relative, y compris en Isra\u00ebl. Venant accidentellement en appui de la r\u00e9cente <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3661\" class=\"gen\">intervention<\/a> de Jacques <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3673\" class=\"gen\">Chirac<\/a>, un rapport de l&rsquo;Institut des Etudes de S\u00e9curit\u00e9 Nationale de l&rsquo;universit\u00e9 de Tel Aviv vient d&rsquo;\u00eatre publi\u00e9, qui examine les \u00e9ventuels projets de l&rsquo;Iran en mati\u00e8re de nucl\u00e9aire selon la logique de la dissuasion. C&rsquo;est le quotidien <em>Haaretz<\/em> du <a href=\"http:\/\/www.haaretz.com\/hasen\/objects\/pages\/PrintArticleEn.jhtml?itemNo=821796\" class=\"gen\">5 f\u00e9vrier<\/a> qui est cit\u00e9 ici. (Le rapport? \u00ab[A]<em>uthored by Ephraim Kam and a team of researchers at the Institute for National Security Studies at Tel Aviv University, <\/em>[It] <em>will be presented at a conference on Wednesday on Iran&rsquo;s nuclear program, its implications and options for dealing with it.<\/em>\u00bb)<\/p>\n<\/p>\n<p><p>\tLe rapport passe en revue les politiques iraniennes possibles. Il examine les th\u00e8ses op\u00e9rationnelles habituelles, notamment les possibilit\u00e9s d&rsquo;une attaque contre l&rsquo;Iran pour d\u00e9truire ses infrastructures de d\u00e9veloppement du nucl\u00e9aire. Il est peu encourageant. (\u00ab[T]<em>his is a very problematic and complex operation that involves many risks including an open-ended Iranian response. Moreover, a military operation is not guaranteed. At this stage the political conditions are also not ripe for an operation, so long as the diplomatic efforts continue<\/em>\u00bb).<\/p>\n<\/p>\n<p><p>\tLe rapport sacrifie aux appr\u00e9ciations maximalistes id\u00e9ologiques habituelles, courantes dans les milieux isra\u00e9liens de s\u00e9curit\u00e9 nationale : \u00ab<em>The report also notes that a nuclear-armed Iran has serious implications for Israel because for the first time an enemy state will have the technical capability of striking a mortal blow against Israel, particularly in view of the Iranian regime&rsquo;s specific call for the destruction of Israel. In essence, this combination holds an existential threat for Israel. <\/em>\u00bb <\/p>\n<\/p>\n<p><p>\tLa partie la plus int\u00e9ressante concerne l&rsquo;hypoth\u00e8se d&rsquo;un Iran devenant effectivement un pays avec une capacit\u00e9 nucl\u00e9aire.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>However, the report states that own must assume that a nuclear Iran will act logically, rationally evaluating the price and risks involved in its actions, and will not act out of religious-ideological motives. If one make this assumption, then one appreciates that Iran&rsquo;s motives for acquiring nuclear weapons are defensive, [and are to be used] against Iraq in the past and against the U.S. today.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Such an explanation can be added to its strategic goals of achieving regional hegemony and to bolster the domestic position of the Iranian regime.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em> It is reasonable to assume that also in the future Iran will opt to retain this type of weapons as a final card to use against extreme threats, and that the elimination of Israel is not considered to be an essential interest worthy of using such weapons.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>The report also assumes that the likelihood that Iran will transfer nuclear arms to terrorist organization is minimal.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>For Israel, the study&rsquo;s advice is to bolster its means of deterrence. Among other measures, this includes making a clear and convincing message that if Israel is attacked by nuclear weapons, it will still retain a counter-strike capability with severe consequences. In addition, emphasis should be placed on the likelihood that a nuclear strike against Israel may fail because of the performance of the Arrow anti-ballistic missile system, which is one of the elements that are meant to ensure that Israel can mount a counter-strike if necessary.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tIl ne semble pas que ce rapport tranche cat\u00e9goriquement la question du nucl\u00e9aire iranien (Isra\u00ebl doit-il envisager de s&rsquo;en accommoder ou doit-il tout faire pour tenter de le d\u00e9truire?). Son orientation et ses d\u00e9veloppements vont n\u00e9anmoins dans un sens significatif, indiquant qu&rsquo;il est possible pour Isra\u00ebl de vivre avec un Iran nucl\u00e9aire parce qu&rsquo;alors les rapports sont r\u00e9gis par la logique de la dissuasion. C&rsquo;est une mise en perspective tr\u00e8s relativiste, voire r\u00e9visionniste&rsquo; diront certains, de la crise iranienne. Si ce n&rsquo;est <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3654\" class=\"gen\">pas la premi\u00e8re indication<\/a> qu&rsquo;Isra\u00ebl peut envisager une logique de dissuasion mutuelle avec l&rsquo;Iran, le d\u00e9veloppement d&rsquo;une telle hypoth\u00e8se, dans la p\u00e9riode actuelle, est tr\u00e8s significatif. <\/p>\n<\/p>\n<p><p>\tLa question est de savoir si les pouvoirs politiques vont envisager s\u00e9rieusement cette situation. A partir du moment o\u00f9 l&rsquo;on admet la possibilit\u00e9 de l&rsquo;acceptation d&rsquo;un Iran nucl\u00e9aire, les options militaires radicales deviennent tr\u00e8s dangereuses, voire absurdes. Puisque la logique de la dissuasion est accept\u00e9e, pourquoi la compromettre par avance par une tension et des menaces dont on sait qu&rsquo;elles ont tr\u00e8s peu de chances, si elles en ont, de r\u00e9soudre le probl\u00e8me? Mais certes, sp\u00e9culer de cette fa\u00e7on implique qu&rsquo;on use de la raison pour le faire. Il n&rsquo;est pas assur\u00e9 que ce soit le cas dans les d\u00e9bats politiques tr\u00e8s fortement id\u00e9ologis\u00e9s en cours en Isra\u00ebl et aux USA.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 6 f\u00e9vrier 2007 \u00e0 23H04<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La question nucl\u00e9aire iranienne tendrait d\u00e9sormais \u00e0 \u00eatre consid\u00e9r\u00e9e d&rsquo;une fa\u00e7on plus relative, y compris en Isra\u00ebl. Venant accidentellement en appui de la r\u00e9cente intervention de Jacques Chirac, un rapport de l&rsquo;Institut des Etudes de S\u00e9curit\u00e9 Nationale de l&rsquo;universit\u00e9 de Tel Aviv vient d&rsquo;\u00eatre publi\u00e9, qui examine les \u00e9ventuels projets de l&rsquo;Iran en mati\u00e8re de&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[2929,2773,2774,3004],"class_list":["post-68494","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-dissuasion","tag-iran","tag-israel","tag-nucleaire"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=68494"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68494\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=68494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=68494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=68494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}