{"id":68566,"date":"2007-02-25T00:00:00","date_gmt":"2007-02-25T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2007\/02\/25\/mesure-de-la-revolte\/"},"modified":"2007-02-25T00:00:00","modified_gmt":"2007-02-25T00:00:00","slug":"mesure-de-la-revolte","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2007\/02\/25\/mesure-de-la-revolte\/","title":{"rendered":"Mesure de la r\u00e9volte"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955;font-size:2em;\">Mesure de la r\u00e9volte<\/h2>\n<\/p>\n<p><p>25 f\u00e9vrier 2007 &mdash; La question de la position, voire du \u00ab\u00a0moral\u00a0\u00bb des chefs militaires par rapport aux diverses entreprises bellicistes de l&rsquo;administration GW est un sujet aujourd&rsquo;hui classique. Il n&rsquo;a jamais \u00e9t\u00e9 aussi insistant et dramatique qu&rsquo;avec la possibilit\u00e9 d&rsquo;une attaque de l&rsquo;Iran. On a d\u00e9j\u00e0 lu qu&rsquo;un analyste et commentateur aussi r\u00e9put\u00e9 que William S. Lind recommande rien moins qu&rsquo;une sorte de <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3517\">\u00ab\u00a0putsch\u00a0\u00bb<\/a> des chefs d&rsquo;\u00e9tat-major pour tenter d&#8217;emp\u00eacher une telle attaque.<\/p>\n<\/p>\n<p><p>Le <em>Sunday Times<\/em> donne des \u00e9chos du climat actuel chez les g\u00e9n\u00e9raux et amiraux US. L&rsquo;image est dramatique. Dans l&rsquo;<a class=\"gen\" href=\"http:\/\/www.timesonline.co.uk\/tol\/news\/world\/iraq\/article1434540.ece\">article<\/a> qu&rsquo;il publie aujourd&rsquo;hui, le journal signale qu&rsquo;au moins cinq g\u00e9n\u00e9raux et amiraux sont pr\u00eats \u00e0 d\u00e9missionner en cas d&rsquo;attaque. Cette id\u00e9e m\u00eame est, sans aucun doute dans ces circonstances et avec cette publicit\u00e9, sans pr\u00e9c\u00e9dent dans l&rsquo;histoire militaire des Etats-Unis.<\/p>\n<\/p>\n<p><p>&laquo;<em>Tension in the Gulf region has raised fears that an attack on Iran is becoming increasingly likely before President George Bush leaves office. The Sunday Times has learnt that up to five generals and admirals are willing to resign rather than approve what they consider would be a reckless attack.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em> \u00ab\u00a0There are four or five generals and admirals we know of who would resign if Bush ordered an attack on Iran,\u00a0\u00bb a source with close ties to British intelligence said. \u00ab\u00a0There is simply no stomach for it in the Pentagon, and a lot of people question whether such an attack would be effective or even possible.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>A British defence source confirmed that there were deep misgivings inside the Pentagon about a military strike. \u00ab\u00a0All the generals are perfectly clear that they don&rsquo;t have the military capacity to take Iran on in any meaningful fashion. Nobody wants to do it and it would be a matter of conscience for them.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em> \u00ab\u00a0There are enough people who feel this would be an error of judgment too far for there to be resignations.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>A generals&rsquo; revolt on such a scale would be unprecedented. \u00ab\u00a0American generals usually stay and fight until they get fired,\u00a0\u00bb said a Pentagon source. Robert Gates, the defence secretary, has repeatedly warned against striking Iran and is believed to represent the view of his senior commanders.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Dans une autre partie de l&rsquo;article, le journal revient sur le cas du g\u00e9n\u00e9ral Pace, le pr\u00e9sident du comit\u00e9 des chefs d&rsquo;\u00e9tat-major, lorsque ce dernier a pris (le 14 f\u00e9vrier) le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3709\">contre-pied<\/a> de la position de son commandant en chef (le Pr\u00e9sident) sur la question des \u00ab\u00a0preuves\u00a0\u00bb de l&rsquo;engagement iranien en Irak. L&rsquo;article donne une interpr\u00e9tation qui fait de la position de Pace un acte clair de contradiction de la \u00ab\u00a0version officielle\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>&laquo;<em>But General Peter Pace, chairman of the joint chiefs of staff, said recently there was \u00ab\u00a0zero chance\u00a0\u00bb of a war with Iran. He played down claims by US intelligence that the Iranian government was responsible for supplying insurgents in Iraq, forcing Bush on the defensive.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Pace&rsquo;s view was backed up by British intelligence officials who said the extent of the Iranian government&rsquo;s involvement in activities inside Iraq by a small number of Revolutionary Guards was \u00ab\u00a0far from clear\u00a0\u00bb.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Hillary Mann, the National Security Council&rsquo;s main Iran expert until 2004, said Pace&rsquo;s repudiation of the administration&rsquo;s claims was a sign of grave discontent at the top.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>\u00ab\u00a0He is a very serious and a very loyal soldier,\u00a0\u00bb she said. \u00ab\u00a0It is extraordinary for him to have made these comments publicly, and it suggests there are serious problems between the White House, the National Security Council and the Pentagon.\u00a0\u00bb<\/em>&raquo;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Le ministre alli\u00e9 des g\u00e9n\u00e9raux\/amiraux<\/h3>\n<\/p>\n<p><p>L&rsquo;article du <em>Sunday Times<\/em> poursuit la saga de la position des militaires \u00e0 l&rsquo;\u00e9gard de l&rsquo;administration, avec un pouvoir civil notablement diminu\u00e9. C&rsquo;est un domaine important \u00e0 suivre dans cette p\u00e9riode de confrontation potentielle.<\/p>\n<\/p>\n<p><p>Nous avons tendance \u00e0 faire grand cr\u00e9dit \u00e0 cet article, pour deux raisons :<\/p>\n<\/p>\n<p><p>&bull; il est de deux correspondants du journal \u00e0 Washington (Michael Smith et Sarah Baxter) ;<\/p>\n<\/p>\n<p><p>&bull; il cite des \u00ab\u00a0<em>highly placed defence and intelligence sources<\/em>\u00a0\u00bb puis, plus loin, pr\u00e9cise diversement: \u00ab\u00a0<em>a source with close ties to British intelligence<\/em>\u00a0\u00bb et \u00ab\u00a0<em>British defence source <\/em>\u00ab\u00a0.<\/p>\n<\/p>\n<p><p>Ces pr\u00e9cisions ne sont \u00e9videmment pas gratuites et semblent indiquer une connexion avec des officiers du renseignement britannique ou des officiels britanniques de la d\u00e9fense, en poste ou en d\u00e9placement \u00e0 Washington, donc avec des contacts directs avec des officiels du renseignement US et du Pentagone. Cela nous conduit \u00e0 appr\u00e9cier ces informations comme \u00e9tant \u00ab\u00a0de premi\u00e8re main\u00a0\u00bb, r\u00e9sultant de contacts directs de ces sources britanniques avec les chefs am\u00e9ricains au Pentagone m\u00eame. Aujourd&rsquo;hui, les Britanniques travaillent par tous les moyens \u00e0 tenter de d\u00e9samorcer les vell\u00e9it\u00e9s d&rsquo;attaque de l&rsquo;Iran de l&rsquo;administration. Ils sont objectivement alli\u00e9s des chefs militaires US, qui suivent pour la plupart cette voie, et il est logique de penser que des courants d&rsquo;information existent pour alimenter le d\u00e9bat dans le sens voulu, par l&rsquo;interm\u00e9diaire de la presse.<\/p>\n<\/p>\n<p><p>Une autre pr\u00e9cision int\u00e9ressante du texte est l&rsquo;interpr\u00e9tation de la position de Gates, qui ne cesse de r\u00e9p\u00e9ter que les USA ne vont <strong>pas<\/strong> attaquer l&rsquo;Iran. La pr\u00e9cision ci-apr\u00e8s, rapport\u00e9e par l&rsquo;article, fait de Gates un \u00ab\u00a0complice\u00a0\u00bb objectif des chefs militaires, et plus que jamais un \u00ab\u00a0repr\u00e9sentant\u00a0\u00bb des mod\u00e9r\u00e9s du groupe Baker-ISG (dont Gates a fait lui-m\u00eame partie) \u00ab\u00a0plant\u00e9\u00a0\u00bb au sein de l&rsquo;administration : &laquo;<em>Robert Gates, the defence secretary, has repeatedly warned against striking Iran and is believed to represent the view of his senior commanders<\/em>.&raquo;<\/p>\n<\/p>\n<p><p>D&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, le sens de l&rsquo;article ne doit pas nous surprendre. Cela fait longtemps, et de sources diff\u00e9rentes et honorables (Hersh en <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2862\">avril 2006<\/a>), que l&rsquo;on r\u00e9p\u00e8te que les chefs militaires US ne sont gu\u00e8re favorables, c&rsquo;est le moins que l&rsquo;on puisse dire, \u00e0 l&rsquo;attaque contre l&rsquo;Iran. Les pr\u00e9cisions qu&rsquo;apporte le <em>Sunday Times<\/em> indiquent une aggravation du climat, \u00e0 mesure de la mont\u00e9e de la tension qu&rsquo;on observe chaque jour.<\/p>\n<\/p>\n<p><p>Plus encore, ces pr\u00e9cisions permettent d&rsquo;identifier une prise de conscience de l&rsquo;<em>establishment<\/em> de s\u00e9curit\u00e9 nationale \u00e0 Washington sur les limites tr\u00e8s r\u00e9elles des capacit\u00e9s militaires US face \u00e0 l&rsquo;Iran, ou n\u00e9cessaires \u00e0 une attaque efficace de l&rsquo;Iran : &laquo;<em>All the generals are perfectly clear that they don&rsquo;t have the military capacity to take Iran on in any meaningful fashion. Nobody wants to do it and it would be a matter of conscience for them.<\/em>&raquo; Il y a donc une crainte d\u00e9sormais tr\u00e8s concr\u00e8te qu&rsquo;une attaque mette en p\u00e9ril le potentiel strat\u00e9gique des forces arm\u00e9es US, d&rsquo;une fa\u00e7on ou l&rsquo;autre.<\/p>\n<\/p>\n<p><p>(Cette id\u00e9e rejoint, quoique <em>a contrario<\/em>, les pr\u00e9cisions r\u00e9cemment apport\u00e9es par <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3730\">Dan Plesch<\/a>. La description des forces n\u00e9cessaires \u00e0 l&rsquo;attaque que donnait Plesch indiquait effectivement l&rsquo;engagement de tout le potentiel strat\u00e9gique US. C&rsquo;est donc un tel rassemblement qui para&icirc;t \u00eatre jug\u00e9 insuffisant pour r\u00e9ussir l&rsquo;attaque contre l&rsquo;Iran.)<\/p>\n<\/p>\n<p><p>Nous sommes plac\u00e9s devant l&rsquo;impossibilit\u00e9 de d\u00e9terminer la r\u00e9alit\u00e9 de la politique US vis-\u00e0-vis de l&rsquo;Iran. Cette politique est aujourd&rsquo;hui si insaisissable qu&rsquo;on peut dire qu&rsquo;elle n&rsquo;existe pas en tant que telle, qu&rsquo;elle n&rsquo;existe qu&rsquo;en tant que r\u00e9sultante, \u00e9ventuellement brutale ou accidentelle, de toutes les fa\u00e7ons tr\u00e8s changeante, de toutes les forces qui s&rsquo;exercent sur elle. Il faut se reporter vers les positions et les capacit\u00e9s de pression des uns et des autres pour en deviner l&rsquo;orientation. Dans ce contexte, les pr\u00e9cisions apport\u00e9es par le <em>Sunday Times<\/em> sont importantes. Elles nous laissent \u00e0 penser sur l&rsquo;importance grandissante du poids des militaires dans le processus de d\u00e9cision, encore plus aujourd&rsquo;hui que Rumsfeld est parti. Au contraire d&rsquo;hier, o&ugrave; les g\u00e9n\u00e9raux se r\u00e9voltaient <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2600\">contre Rumsfeld<\/a>, aujourd&rsquo;hui les g\u00e9n\u00e9raux (et les amiraux) menacent de se r\u00e9volter, &mdash; mais, cette fois, comme on le comprend, plut\u00f4t avec le soutien \u00e0 peine discret du successeur de Rumsfeld.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mesure de la r\u00e9volte 25 f\u00e9vrier 2007 &mdash; La question de la position, voire du \u00ab\u00a0moral\u00a0\u00bb des chefs militaires par rapport aux diverses entreprises bellicistes de l&rsquo;administration GW est un sujet aujourd&rsquo;hui classique. Il n&rsquo;a jamais \u00e9t\u00e9 aussi insistant et dramatique qu&rsquo;avec la possibilit\u00e9 d&rsquo;une attaque de l&rsquo;Iran. On a d\u00e9j\u00e0 lu qu&rsquo;un analyste et&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[6476,5355,3984,5160,2773,3319,4519,3194],"class_list":["post-68566","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-amiraux","tag-demission","tag-gates","tag-generaux","tag-iran","tag-navy","tag-pace","tag-pentagone"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=68566"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68566\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=68566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=68566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=68566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}