{"id":68572,"date":"2007-02-27T00:00:00","date_gmt":"2007-02-27T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2007\/02\/27\/les-candidats-et-la-politique-exterieure\/"},"modified":"2007-02-27T00:00:00","modified_gmt":"2007-02-27T00:00:00","slug":"les-candidats-et-la-politique-exterieure","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2007\/02\/27\/les-candidats-et-la-politique-exterieure\/","title":{"rendered":"Les candidats et la politique ext\u00e9rieure"},"content":{"rendered":"<p><p>Interview\u00e9 par Jean-Jacques Bourdin sur BFM-TV-RMC hier 26 f\u00e9vrier, Nicolas Sarkozy a estim\u00e9 qu&rsquo;on ne parlait pas assez de politique ext\u00e9rieure dans cette campagne  pr\u00e9sidentielle. Puisqu&rsquo;on y \u00e9tait et pour r\u00e9pondre \u00e0 son attente, quelques questions du domaine lui ont \u00e9t\u00e9 pos\u00e9es, auxquelles il a <a href=\"http:\/\/www.dailymotion.com\/video\/x1b4b8_n-sarkozy-invite-de-jj-bourdin-22\" class=\"gen\">r\u00e9pondu<\/a>. La recension rapide qu&rsquo;en fait <a href=\"http:\/\/www.lemonde.fr\/web\/article\/0,1-0@2-823448,36-876472@51-823374,0.html\" class=\"gen\">Le Monde<\/a> montre un candidat sans grande originalit\u00e9,  surtout pas celle d&rsquo;\u00eatre pro-am\u00e9ricain,  et surtout attach\u00e9 \u00e0 ne pas trop s&rsquo;\u00e9loigner de la ligne classique de la position fran\u00e7aise.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Dans le reste de l&rsquo;entretien, Nicolas Sarkozy s&rsquo;est dit oppos\u00e9 \u00e0 une \u00e9ventuelle intervention militaire contre l&rsquo;Iran. Quand on voit ce qui se passe avec l&rsquo;Irak, qui peut croire que c&rsquo;est une perspective cr\u00e9dible ?, a-t-il r\u00e9pondu. Les Am\u00e9ricains sont dans l&rsquo;impasse en Irak et doivent envisager les conditions d&rsquo;un retrait, a-t-il ajout\u00e9. Il y a un trait\u00e9 international qui pr\u00e9voit la possibilit\u00e9 pour l&rsquo;Iran comme pour tous les autres pays d&rsquo;acc\u00e9der au nucl\u00e9aire civil, a poursuivi le pr\u00e9sident de l&rsquo;UMP, qualifiant le nucl\u00e9aire d&rsquo;\u00e9nergie de demain.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tSur <a href=\"http:\/\/tf1.lci.fr\/infos\/elections-2007\/0,,3401278,00-bayrou-voit-gaulle-mendes-france-.html\" class=\"gen\">TF1<\/a> hier soir, Fran\u00e7ois Bayrou a dit qu&rsquo;il \u00e9tait tr\u00e8s fier de l&rsquo;attitude de la France durant la crise irakienne de 2002-2003 et a rendu hommage \u00e0 Jacques Chirac. Interrog\u00e9 sur ses r\u00e9f\u00e9rences politiques (ses mod\u00e8les ou ce qu&rsquo;il voudrait \u00eatre en tant qu&rsquo;homme politique), il a cit\u00e9 Pierre Mend\u00e8s-France et Charles de Gaulle. R\u00e9f\u00e9rences de la grande ligne de la tradition fran\u00e7aise, et r\u00e9f\u00e9rences qui permettent d&rsquo;\u00e9carter le clivage gauche-droite (selon le vu de Bayrou) puisque leurs \u00e9tiquettes sont en principe oppos\u00e9es (Mend\u00e8s de gauche, de Gaulle de droite).<\/p>\n<\/p>\n<p><p>\tPar cons\u00e9quent, on notera que tout cela est extr\u00eamement classique, dans la continuit\u00e9 de la diplomatie fran\u00e7aise. On ne trouve gu\u00e8re d&rsquo;\u00e9cart par rapport \u00e0 une ligne fran\u00e7aise dont on sent qu&rsquo;elle est fortement ancr\u00e9e dans l&rsquo;opinion populaire. Il reste \u00e0 faire d\u00e9marrer un \u00e9ventuel d\u00e9bat sur la politique ext\u00e9rieure et, surtout, sur le comportement politique des USA (et la coh\u00e9rence et le fondement de la politique fran\u00e7aise \u00e0 cet \u00e9gard). Il reste \u00e0 s&rsquo;expliquer de la justesse et de la n\u00e9cessit\u00e9 de la grande ligne de la tradition fran\u00e7aise (que nous ne contestons pas une seconde mais qu&rsquo;il serait si int\u00e9ressant d&rsquo;\u00e9clairer). Nous n&rsquo;y sommes pas encore. Pour l&rsquo;instant, les candidats s&rsquo;abritent derri\u00e8re la r\u00e9f\u00e9rence unanime (la grande ligne de la tradition fran\u00e7aise), en y d\u00e9rogeant le moins possible. Pour certains d&rsquo;entre eux (Sarkozy), on pourrait juger que c&rsquo;est un changement (un progr\u00e8s) par rapport aux intentions qu&rsquo;on leur pr\u00eatait. Peut-\u00eatre. (Pour le m\u00eame Sarko, on en saura plus demain puisqu&rsquo;il donne une conf\u00e9rence de presse sur le sujet de la politique ext\u00e9rieure.)<\/p>\n<\/p>\n<p><p>\tPour tous, c&rsquo;est une position d&rsquo;attente, la t\u00eate rentr\u00e9e dans les \u00e9paules, en esp\u00e9rant qu&rsquo;on ne s&rsquo;aventure pas trop dans ce domaine de la vraie crise mondiale (la crise US). Sujet br\u00fblant.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 27 f\u00e9vrier 2007 \u00e0 08H20<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Interview\u00e9 par Jean-Jacques Bourdin sur BFM-TV-RMC hier 26 f\u00e9vrier, Nicolas Sarkozy a estim\u00e9 qu&rsquo;on ne parlait pas assez de politique ext\u00e9rieure dans cette campagne pr\u00e9sidentielle. Puisqu&rsquo;on y \u00e9tait et pour r\u00e9pondre \u00e0 son attente, quelques questions du domaine lui ont \u00e9t\u00e9 pos\u00e9es, auxquelles il a r\u00e9pondu. La recension rapide qu&rsquo;en fait Le Monde montre un&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[6443,6379,2687,4607,3340,5925],"class_list":["post-68572","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-bayrou","tag-exterieure","tag-france","tag-politique","tag-presidentielles","tag-sarko"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=68572"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68572\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=68572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=68572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=68572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}