{"id":68661,"date":"2007-03-27T00:00:00","date_gmt":"2007-03-27T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2007\/03\/27\/saint-gates\/"},"modified":"2007-03-27T00:00:00","modified_gmt":"2007-03-27T00:00:00","slug":"saint-gates","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2007\/03\/27\/saint-gates\/","title":{"rendered":"<strong><em>Saint-Gates<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Saint-Gates<\/h2>\n<\/p>\n<p><p>\t27 mars 2007  Le nouveau secr\u00e9taire am\u00e9ricain \u00e0 la d\u00e9fense Robert Gates est une \u00ab<em>surprise enthousiasmante<\/em>\u00bb tandis que Rice est \u00ab<em>le plus puissant secr\u00e9taire d&rsquo;Etat des \u00catats-Unis, peut-\u00eatre depuis Kissinger, et elle s&rsquo;est d\u00e9barrass\u00e9e de toutes les antennes extr\u00e9mistes du d\u00e9partement<\/em>\u00bb. Ainsi peut-on alterner des jugements assez justes avec des b\u00eatises surprenantes d&rsquo;ampleur et d&rsquo;inculture politique, m\u00eame si l&rsquo;on fait partie d&rsquo;une d\u00e9l\u00e9gation du plus haut niveau des institutions europ\u00e9ennes, Solana en t\u00eate, apr\u00e8s une visite \u00e0 Washington la semaine derni\u00e8re.<\/p>\n<\/p>\n<p><p>\tCes impressions nous viennent d&rsquo;une source que nous aurons l&rsquo;\u00e9l\u00e9gance de ne pas identifier et qui, \u00e0 Washington, a suivi indirectement mais tr\u00e8s pr\u00e9cis\u00e9ment le d\u00e9placement de la d\u00e9l\u00e9gation europ\u00e9enne,  avec principalement rencontres de Gates, de Rice et de Heyden (patron du NSC), parfois dans des conditions chaleureuses (d\u00eener intime Solana-Heyden, entre copains, dans un petit resto discret). L&rsquo;atmosph\u00e8re y fut \u00ab<em>chaleureuse, dans un \u00e9tat d&rsquo;esprit excellent, presque enthousiasmante. Les Am\u00e9ricains n&rsquo;ont cess\u00e9 de r\u00e9p\u00e9ter aux Europ\u00e9ens que l&rsquo;Europe \u00e9tait une alli\u00e9e indispensable, notamment au niveau de la s\u00e9curit\u00e9<\/em>\u00bb. Une sorte de super-Royaume-Uni, si l&rsquo;on veut, ce qui fait un compliment ambigu. Il n&#8217;emp\u00eache, ils (les Europ\u00e9ens) en ont \u00e9t\u00e9 ravis. Qui s&rsquo;en \u00e9tonnera ?<\/p>\n<\/p>\n<p><p>\tVoici les principaux th\u00e8mes de satisfaction, pour notre propre int\u00e9r\u00eat et selon notre s\u00e9lection.<\/p>\n<\/p>\n<p><p>\t  La p\u00e9riode de <em>hubris<\/em> de la politique \u00e9trang\u00e8re US, avec l&rsquo;unilat\u00e9ralisme qui va avec, est d\u00e9finitivement termin\u00e9e,  <em>over<\/em>, point final. Les USA sont \u00e0 nouveau \u00ab<em>un partenaire s\u00e9rieux, responsable<\/em>\u00bb, sur lequel on peut d\u00e9sormais compter. C&rsquo;est dans cette optique qu&rsquo;il faut placer l&rsquo;affirmation d\u00e9j\u00e0 mentionn\u00e9e du caract\u00e8re indispensable, pour les USA, de l&rsquo;alliance europ\u00e9enne.<\/p>\n<\/p>\n<p><p>\t La d\u00e9l\u00e9gation europ\u00e9enne est persuad\u00e9e que le vice-pr\u00e9sident Cheney et son \u00e9quipe sont marginalis\u00e9s. Le Diable a \u00e9t\u00e9 envoy\u00e9 en stage au purgatoire.<\/p>\n<\/p>\n<p><p>\t  On assiste \u00e0 une marche-arri\u00e8re toute sur la question iranienne. On a assur\u00e9 aux Europ\u00e9ens qu&rsquo;il n&rsquo;\u00e9tait plus question d&rsquo;attaque et que l&rsquo;approche diplomatique des Europ\u00e9ens \u00e9tait grandement appr\u00e9ci\u00e9e.<\/p>\n<\/p>\n<p><p>\t  C&rsquo;est le domaine des anti-missiles qui apporte aux Europ\u00e9ens le plus de satisfaction. Gates a \u00e9t\u00e9 \u00e0 cet \u00e9gard un interlocuteur particuli\u00e8rement appr\u00e9ci\u00e9. Il dit \u00ab<em>comprendre parfaitement les pr\u00e9occupations des Europ\u00e9ens, et m\u00eame  celles des Russes. Il a m\u00eame eu cette comparaison : que penseraient les Am\u00e9ricains si les Russes faisaient passer sous leur influence la Californie,  le Nouveau-Mexique et le Texas ?<\/em>\u00bb (ce dernier point, allusion \u00e0 l&rsquo;influence acquise par les USA dans des pays ex-sovi\u00e9tiques comme l&rsquo;Ukraine, la  G\u00e9orgie, etc.). Gates a affirm\u00e9 qu&rsquo;il ferait tout son possible pour \u00ab<em>forcer \u00e0 une nouvelle approche dans la question des anti-missiles, notamment avec des consultations approfondies avec les Russes, jusqu&rsquo;\u00e0 \u00e9voquer la possibilit\u00e9 d&rsquo;une coop\u00e9ration avec ces m\u00eames Russes dans le r\u00e9seau lui-m\u00eame<\/em>\u00bb<\/p>\n<h3>Rude labeur pour Saint-Gates<\/h3>\n<\/p>\n<p><p>\tD\u00e9barrassons-nous de l&rsquo;accessoire : faire de Rice un secr\u00e9taire d&rsquo;Etat puissant est risible et nous inqui\u00e8te un petit peu quant au reste des jugements. La chose (ainsi que la fin de l&rsquo;unilat\u00e9ralisme US) avait \u00e9t\u00e9 proclam\u00e9e une premi\u00e8re fois en f\u00e9vrier 2005 (voyage de Rice puis de GW-Rice en Europe, en vue d&rsquo;une r\u00e9conciliation solennelle, parfaitement r\u00e9ussie comme l&rsquo;on voit puisqu&rsquo;il s&rsquo;agit aujourd&rsquo;hui d&rsquo;une deuxi\u00e8me r\u00e9conciliation.) Rice est une personnalit\u00e9 falote, qui navigue entre les tendances majoritaires de l&rsquo;administration, qui a peur de Cheney, qui a une audience certaine chez Bush mais n&rsquo;a jamais pu la concr\u00e9tiser en influence et avantages politiques, qui ne cesse de construire sa pr\u00e9tendue puissance, affirm\u00e9e d\u00e8s sa nomination en 2004, en donnant des gages \u00e0 ceux qu&rsquo;elle \u00e9limine pr\u00e9tendument (le plus r\u00e9cent : d\u00e9part du mod\u00e9r\u00e9 Zelikow, <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3779\" class=\"gen\">remplac\u00e9<\/a> par le n\u00e9o-conservateur extr\u00e9miste Eliot Cohen). Bref, la d\u00e9l\u00e9gation europ\u00e9enne s&rsquo;en est tenue aux apparences, \u00e0 la politesse qu&rsquo;on doit \u00e0 une dame secr\u00e9taire d&rsquo;Etat, <em>African-American<\/em> de surcro\u00eet, et \u00e0 la fascination habituelle chez les Europ\u00e9ens pour les USA.<\/p>\n<\/p>\n<p><p>\t(En passant, et pour l&rsquo;accessoire toujours: la mise \u00e0 l&rsquo;\u00e9cart de Cheney nous para\u00eet un diagnostic bien rapide. C&rsquo;est croire \u00e0 la stabilit\u00e9 des choses \u00e0 Washington, c&rsquo;est ne rien entendre \u00e0 la situation de Washington. L&rsquo;influence de Cheney est \u00e0 \u00e9clipses, un peu comme celle de tous les autres. L&rsquo;\u00e9liminer du processus de d\u00e9cision est une conclusion bien audacieuse et tr\u00e8s idyllique.)<\/p>\n<\/p>\n<p><p>\tL&rsquo;\u00e9pisode Gates est, par contre, extr\u00eamement int\u00e9ressant. Il ne fait plus <strong>aucun doute<\/strong> que Gates est un <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3751\" class=\"gen\">mod\u00e9r\u00e9<\/a> \u00e0 l&rsquo;int\u00e9rieur de l&rsquo;administration GW, oppos\u00e9 aux projets bellicistes en cours. Le plus int\u00e9ressant pour nos pr\u00e9occupations actuelles est ce qu&rsquo;il a dit \u00e0 ses interlocuteurs europ\u00e9ens des anti-missiles. Il n&rsquo;y a aucune raison de ne pas prendre pour argent comptant ses affirmations, la r\u00e9alisation de l&rsquo;aspect contre-productif et d\u00e9stabilisant des anti-missiles en Europe \u00e9tant d&rsquo;une \u00e9vidence confondante. Le probl\u00e8me est la capacit\u00e9 de Gates d&rsquo;intervenir dans le sens qu&rsquo;il dit, d&rsquo;une part, et l&rsquo;aspect, paradoxalement, \u00e9ventuellement d\u00e9stabilisant de son intervention, d&rsquo;autre part.<\/p>\n<\/p>\n<p><p>\t  Bloquer sa bureaucratie dans son \u00e9lan de d\u00e9ploiement des anti-missiles ? Il l&rsquo;essaiera, sans doute, mais est-il s\u00fbr qu&rsquo;il y parviendra ? Il y a un pr\u00e9c\u00e9dent fameux : Reagan et la SDI. Contrairement \u00e0 la <em>narrative<\/em> qui nous est en g\u00e9n\u00e9ral servie, la SDI (la guerre des \u00e9toiles, premi\u00e8re id\u00e9e d&rsquo;un r\u00e9seau anti-missiles) est une id\u00e9e personnelle de Reagan. Un article du <em>Bulletin of Atomic Scientists<\/em> datant d&rsquo;octobre 1987 racontait les origines de la SDI, notamment avec le t\u00e9moignage du conseiller scientifique de Reagan, George Keyworth. Il montre un Reagan r\u00e9ellement obs\u00e9d\u00e9 par les perspectives d&rsquo;an\u00e9antissement r\u00e9ciproque et concevant la SDI comme l&rsquo;amorce d&rsquo;un syst\u00e8me destin\u00e9 \u00e0 \u00e9viter une guerre nucl\u00e9aire et pouvant devenir commun avec l&rsquo;URSS,  notamment avec l&rsquo;id\u00e9e extraordinaire du partage\/transfert des technologies avec l&rsquo;URSS. Le discours fut r\u00e9dig\u00e9 par Reagan lui-m\u00eame (Keyworth : \u00ab<em>This was a speech that came from the president&rsquo;s heart. The president wrote the speech in the end.<\/em>\u00bb), avec une toute petite \u00e9quipe du NSC autour de son directeur McFerlane, dans le plus grand secret. Le Pentagone ne fut mis au courant du discours que le 20 mars 1983 (le discours fut donn\u00e9 le 23) et ne put r\u00e9agir.  (Gil Rye, un des planificateurs du NSC impliqu\u00e9 dans le projet : \u00ab<em>Had we given the paper, there certainly would have been no speech.<\/em>\u00bb) Le discours eut lieu. En deux ans, sa substance fut pulv\u00e9ris\u00e9e. (Contrairement \u00e0 la m\u00eame <em>narrative<\/em>, les critiques les plus virulentes au d\u00e9part contre la SDI vinrent de Washington, pas d&rsquo;une Europe craignant une Am\u00e9rique strat\u00e9giquement isolationniste.) Il ne fut bien entendu plus jamais question de transferts de technologies vers l&rsquo;URSS, les remarques des journalistes dans ce sens dans les conf\u00e9rences de presse \u00e9tant prestement \u00e9touff\u00e9es avec un clin d&rsquo;il concernant l&rsquo;\u00e2ge du capitaine,  pardon, du pr\u00e9sident. La SDI fut enti\u00e8rement transform\u00e9e en un projet (puisqu&rsquo;elle ne fut jamais r\u00e9alis\u00e9e) d&rsquo;acquisition de la sup\u00e9riorit\u00e9 strat\u00e9gique des USA sur l&rsquo;URSS. Reagan n&rsquo;y put rien et ne tenta d&rsquo;ailleurs jamais rien de s\u00e9rieux.<\/p>\n<\/p>\n<p><p>\t  L&rsquo;intervention du mod\u00e9r\u00e9 (mais n\u00e9anmoins r\u00e9publicain) Gates peut avoir des cons\u00e9quences inattendues, vu la diversit\u00e9 et la concurrence des divers centres de pouvoir \u00e0 Washington. Par exemple, elle peut pousser le Congr\u00e8s d\u00e9mocrate, jusqu&rsquo;ici r\u00e9ticent notamment pour raisons <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3829\" class=\"gen\">financi\u00e8res<\/a> et partisanes (syst\u00e8me r\u00e9publicain) \u00e0 l&rsquo;\u00e9gard de la BMD, \u00e0 trouver des avantages nouveaux \u00e0 ce syst\u00e8me. Les d\u00e9mocrates ont d&rsquo;autres arguments pour cela : ils sont favorables \u00e0 l&rsquo;\u00e9largissement maximal de l&rsquo;OTAN vers l&rsquo;Ukraine et la G\u00e9orgie et professent une hostilit\u00e9 \u00e0 peine d\u00e9guis\u00e9e contre la Russie pour diverses raisons (activisme des centres d\u00e9mocrates de d\u00e9mocratisation dans les pays ex-sovi\u00e9tiques ; attention pour l&rsquo;\u00e9lectorat d&rsquo;origine polonaise et anti-russe de la r\u00e9gion de Chicago, tr\u00e8s pro-d\u00e9mocrate).<\/p>\n<\/p>\n<p><p>\t  Si le syst\u00e8me est communautaris\u00e9 et europ\u00e9anis\u00e9 pour faire plaisir aux Europ\u00e9ens, il ira directement \u00e0 l&rsquo;OTAN. Cela signifie plusieurs choses : que faire du projet OTAN en gestation intellectuelle approfondie (un rapport de <strong>10.000 pages<\/strong> [ouf] a \u00e9t\u00e9 r\u00e9dig\u00e9 sur le sujet l&rsquo;ann\u00e9e derni\u00e8re) ? Que vont dire les Europ\u00e9ens partisans d&rsquo;un programme europ\u00e9en, avec technologies europ\u00e9ennes,  les Fran\u00e7ais en t\u00eate ? Que vont dire les Europ\u00e9ens en g\u00e9n\u00e9ral si les USA, comme c&rsquo;est tr\u00e8s tr\u00e8s probable, leur demandent, en \u00e9change des amabilit\u00e9s de Gates, de participer au financement d&rsquo;un programme am\u00e9ricain devenu OTAN, constitu\u00e9 de technologies US ?<\/p>\n<\/p>\n<p><p>\t  Partager avec les Europ\u00e9ens, voire avec les Russes ? Qui aura le pouvoir de d\u00e9cision ? Se r\u00e9unira-t-on \u00e0 27 + les Russes apr\u00e8s trois jours de pol\u00e9mique pour choisir un lieu de r\u00e9union qui ne f\u00e2che personne, et surtout pas les Polonais avec les Russes, avant de d\u00e9cider d&rsquo;un tir d&rsquo;anti-missiles contre un ICBM fantasmatique et nord-cor\u00e9en tir\u00e9 trois jours plus t\u00f4t et \u00e9voluant \u00e0 25.000 km\/h? Laissera-t-on les Europ\u00e9ens et les Russes contr\u00f4ler des technologies US ? La bureaucratie pentagonesque et le Congr\u00e8s diront-ils Amen  ? Autant de r\u00eaveries romantiques et touchantes.<\/p>\n<\/p>\n<p><p>\t  Que dira-t-on aux braves Polonais qui se sont mouill\u00e9s jusqu&rsquo;au cou pour \u00eatre les interlocuteurs <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3844\" class=\"gen\">exclusifs<\/a> des USA et comptent sur ce syst\u00e8me,  auquel participeraient \u00e9ventuellement les Russes !  pour les prot\u00e9ger contre les Russes ?<\/p>\n<\/p>\n<p><p>\tConclusion-I : l&rsquo;affaire n&rsquo;est pas finie et elle risque de nous faire encore bien rire, fa\u00e7on efficacit\u00e9 tendance Pentagone.<\/p>\n<\/p>\n<p><p>\tConclusion-II : les Am\u00e9ricains vont vraiment tr\u00e8s mal pour faire cette sorte d&rsquo;efforts de s\u00e9duction vers les Europ\u00e9ens.<\/p>\n<\/p>\n<p><p>\tConclusion-III : Solana est vraiment tr\u00e8s fatigu\u00e9 (on le sait depuis longtemps) pour \u00e9prouver de tels enthousiasmes et son remplacement serait peut-\u00eatre une bonne chose. Par Mich\u00e8le Alliot-Marie, par exemple ? (On en parle.)<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saint-Gates 27 mars 2007 Le nouveau secr\u00e9taire am\u00e9ricain \u00e0 la d\u00e9fense Robert Gates est une \u00absurprise enthousiasmante\u00bb tandis que Rice est \u00able plus puissant secr\u00e9taire d&rsquo;Etat des \u00catats-Unis, peut-\u00eatre depuis Kissinger, et elle s&rsquo;est d\u00e9barrass\u00e9e de toutes les antennes extr\u00e9mistes du d\u00e9partement\u00bb. Ainsi peut-on alterner des jugements assez justes avec des b\u00eatises surprenantes d&rsquo;ampleur et&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[6543,3453,5433,3285,3984,3777],"class_list":["post-68661","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-aliot-marie","tag-anti-missiles","tag-bmd","tag-congres","tag-gates","tag-solana"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=68661"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68661\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=68661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=68661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=68661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}