{"id":68788,"date":"2007-05-12T00:00:00","date_gmt":"2007-05-12T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2007\/05\/12\/lesprit-du-temps\/"},"modified":"2007-05-12T00:00:00","modified_gmt":"2007-05-12T00:00:00","slug":"lesprit-du-temps","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2007\/05\/12\/lesprit-du-temps\/","title":{"rendered":"L&rsquo;esprit du temps"},"content":{"rendered":"<p><p>Nous extrayons des interventions de quelques historiens britanniques sur le souvenir historique de <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3968\" class=\"gen\">Tony Blair<\/a> un passage de celle de <a href=\"http:\/\/politics.guardian.co.uk\/tonyblair\/story\/0,,2075005,00.html\" class=\"gen\">Linda Colley<\/a>, professeur d&rsquo;histoire \u00e0 l&rsquo;universit\u00e9 de Princeton. Il n&rsquo;a pas \u00e0 voir directement avec Tony Blair, bien qu&rsquo;il pr\u00e9tende \u00e9videmment en faire indirectement l&rsquo;apologie,  c&rsquo;est l\u00e0 l&rsquo;une des missions d&rsquo;une historienne install\u00e9e, aujourd&rsquo;hui,  mais plus certainement avec ce que nous d\u00e9signerions comme l&rsquo;esprit du temps, mode anglo-saxon cela va de soi.<\/p>\n<\/p>\n<p><p>\tVoici le passage : \u00ab<em>Britain is now far more prosperous. No one is saying that there isn&rsquo;t poverty, but if one goes to visit Paris and walks around there, and then does the same in London, the amount of wealth and conspicuous consumption we have is striking, and that&rsquo;s true even beyond the capital. One can be moralising and say what is all this wealth really doing for us but on the whole being prosperous is far nicer than the alternative. People now take it for granted, so Blair doesn&rsquo;t get any credit.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tPlusieurs choses nous importent dans ce passage, marqu\u00e9 par l&rsquo;hypocrisie habituelle de cette sorte de propos en citant la France. Il va de soi que Linda Colley, citant la France comme t\u00eate de turc habituelle, n&rsquo;ira pas jusqu&rsquo;\u00e0 dire qu&rsquo;on y est plus pauvre qu&rsquo;au Royaume-Uni, parce qu&rsquo;elle sait que ce serait <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3917\" class=\"gen\">un mensonge<\/a> un peu trop grossier. Non, elle se fout des pauvres.<\/p>\n<\/p>\n<p><p>\t&bull; Effectivement, la France est l&rsquo;objet d&rsquo;une haine et d&rsquo;un d\u00e9nigrement sans fin des Anglo-Saxons et des partisans du syst\u00e8me. C&rsquo;est une sorte de r\u00e9flexe pavlovien, qui mesure la difficult\u00e9 de la t\u00e2che de ceux qui pr\u00e9tendraient changer ce pays (la France) dans le sens du vent. L&rsquo;impossibilit\u00e9 de l&rsquo;entente entre la France et les Anglo-Saxons lib\u00e9raux et libre-\u00e9changistes tient de la substance m\u00eame, de la pr\u00e9misse de toute r\u00e9flexion : elle tient non seulement \u00e0 la substance fran\u00e7aise mais, plus encore, \u00e0 la passion haineuse anglo-saxonne et lib\u00e9rale. M\u00eame les tra\u00eetres et les opportunistes fran\u00e7ais sont tenus en haute suspicion, ce qui rend la transformation vraiment impossible.<\/p>\n<\/p>\n<p><p>\t&bull; La r\u00e9duction de la pens\u00e9e \u00e0 une alternative est un autre signe des temps. Madame Colby semble ne voir qu&rsquo;une seule alternative dans la situation des peuples : \u00eatre prosp\u00e8re ou ne pas \u00eatre prosp\u00e8re, avec l&rsquo;\u00e9trange d\u00e9finition du mot prosp\u00e9rit\u00e9 qui est ici d\u00e9cisivement limit\u00e9e par le seul rapport aux riches. \u00catre prosp\u00e8re, c&rsquo;est avoir des super-riches tr\u00e8s tr\u00e8s riches, ne pas l&rsquo;\u00eatre c&rsquo;est les avoir un peu moins tr\u00e8s tr\u00e8s riches. La question de la condition des pauvres par rapport \u00e0 ces super-riches tr\u00e8s tr\u00e8s riches,  pauvres beaucoup plus nombreux dans ce cas, 17% au Royaume-Uni contre 7% en France,  est renvoy\u00e9e dans l&rsquo;enfer de la pens\u00e9e non conforme avec un m\u00e9prisant Evidemment, on peut moraliser et dire qu&rsquo;est-ce que toute cette richesse nous apporte?&rsquo;. Madame Colby ne semble pas imaginer qu&rsquo;\u00e0 c\u00f4t\u00e9 des riches (oh certes, il en faut), on puisse imaginer que la prosp\u00e9rit\u00e9 implique des pauvres moins pauvres et moins nombreux. Il y a l\u00e0, pour l&rsquo;esprit du temps, une sorte d&rsquo;incapacit\u00e9 de r\u00e9flexion ; comme si, finalement, la vertu se mesurait \u00e0 l&rsquo;Himalaya de fric, et que ce serait \u00e9videmment une occurrence sans int\u00e9r\u00eat et sans vertu si ces salauds de pauvres (selon Marcel Aym\u00e9, en pleine forme dans <em>la travers\u00e9e de Paris<\/em>) pr\u00e9tendaient en avoir un petit ch\u00e2teau de sable.<\/p>\n<\/p>\n<p><p>\t&bull; Il s&rsquo;agit d&rsquo;une manifestation extr\u00eame du nihilisme propre \u00e0 la doctrine lib\u00e9rale et \u00e0 l&rsquo;esprit anglo-saxon et pouss\u00e9 \u00e0 son extr\u00eame. Ce nihilisme conduit \u00e0 ne plus envisager comme \u00e9chelle de valeur que les degr\u00e9s de richesse d&rsquo;une seule cat\u00e9gorie sociologique,  celle des riches. La notion de pauvres, ou plut\u00f4t de non-riches en ceci que cette notion inclut la classe moyenne, est rejet\u00e9e dans le n\u00e9ant comme indigne de figurer dans cette \u00e9chelle de valeur. Le fait qu&rsquo;une historienne manifeste cette conception mesure l&rsquo;effondrement de l&rsquo;intelligence occidentale par la pathologie de la psychologie. En substance, l&rsquo;historien doit \u00e9tudier le pass\u00e9 \u00e0 la lumi\u00e8re de la diversit\u00e9 du monde ; l&rsquo;esprit de madame Colley s&rsquo;est referm\u00e9 sur la seule notion de riche, qui repr\u00e9sente pour elle la seule diversit\u00e9 du monde digne d&rsquo;\u00e9tude.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 12 mai 2007 \u00e0 06H14<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous extrayons des interventions de quelques historiens britanniques sur le souvenir historique de Tony Blair un passage de celle de Linda Colley, professeur d&rsquo;histoire \u00e0 l&rsquo;universit\u00e9 de Princeton. Il n&rsquo;a pas \u00e0 voir directement avec Tony Blair, bien qu&rsquo;il pr\u00e9tende \u00e9videmment en faire indirectement l&rsquo;apologie, c&rsquo;est l\u00e0 l&rsquo;une des missions d&rsquo;une historienne install\u00e9e, aujourd&rsquo;hui, mais&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3426,6670,5944,6671],"class_list":["post-68788","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-anglo-saxon","tag-colley","tag-nihilisme","tag-riches"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=68788"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68788\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=68788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=68788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=68788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}