{"id":68801,"date":"2007-05-17T00:00:00","date_gmt":"2007-05-17T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2007\/05\/17\/la-fonction-investit-lhomme\/"},"modified":"2007-05-17T00:00:00","modified_gmt":"2007-05-17T00:00:00","slug":"la-fonction-investit-lhomme","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2007\/05\/17\/la-fonction-investit-lhomme\/","title":{"rendered":"<strong><em>La fonction investit l&rsquo;homme<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">La fonction investit l&rsquo;homme<\/h2>\n<\/p>\n<p><p>\t17 mai 2007  Aux derni\u00e8res nouvelles, il n&rsquo;est pas tout \u00e0 fait confirm\u00e9 que la fonction cr\u00e9e l&rsquo;organe mais elle l&rsquo;aide certainement, en lui prenant la main et en la serrant tr\u00e8s fort. Telle fut donc l&rsquo;impression, hier, \u00e0 l&rsquo;inauguration du pr\u00e9sident Sarkozy,  et, par cons\u00e9quent, l&rsquo;impression du petit Nicolas devenu grand, ou en cours de le devenir.<\/p>\n<\/p>\n<p><p>\tLe discours a \u00e9t\u00e9 r\u00e9solument historique avec un partage \u00e9quitable mais r\u00e9v\u00e9lateur entre pass\u00e9 et avenir, r\u00e9solument pr\u00e9sidentiel dans la conception et l&rsquo;investissement de la charge, r\u00e9solument Cinqui\u00e8me R\u00e9publique avec deux sentiments dominant chez l&rsquo;homme qui le dit : \u00e9motion et gravit\u00e9. Ceci que le Pr\u00e9sident a dit express\u00e9ment (son discours \u00e0 lire, sur le site de <a href=\"http:\/\/www.elysee.fr\/elysee\/elysee.fr\/francais\/interventions\/discours_et_declarations\/2007\/mai\/allocution_de_m_nicolas_sarkozy_president_de_la_republique_a_l_occasion_de_la_ceremonie_d_installation.76633.html\" class=\"gen\">l&rsquo;Elys\u00e9e<\/a>), rend compte des deux choses:<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Je pense avec \u00e9motion \u00e0 cette attente, \u00e0 cette esp\u00e9rance, \u00e0 ce besoin de croire \u00e0 un avenir meilleur qui se sont exprim\u00e9s si fortement durant la campagne qui vient de s&rsquo;achever.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>Je pense avec gravit\u00e9 au mandat que le peuple fran\u00e7ais m&rsquo;a confi\u00e9 et \u00e0 cette exigence si forte qu&rsquo;il porte en lui et que je n&rsquo;ai pas le droit de d\u00e9cevoir.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tIl n&rsquo;y a rien de l\u00e9ger dans tout cela. Le discours a \u00e9t\u00e9 un hommage \u00e0 la fonction souveraine et \u00e0 la France, et d&rsquo;une tonalit\u00e9 assez sombre, correspondant \u00e0 la fois \u00e0 la majest\u00e9 tragique de la fonction et \u00e0 la conjoncture tragique des temps que nous vivons.<\/p>\n<\/p>\n<p><p>\tOn citera essentiellement <em>The Independent<\/em>, qui consacre plusieurs articles \u00e0 l&rsquo;investiture,  dont un \u00e0 <a href=\"http:\/\/comment.independent.co.uk\/commentators\/article2553903.ece\" class=\"gen\">la conception<\/a> qu&rsquo;a Sarkozy de la pr\u00e9sidence,  l&rsquo;autre, que nous citons, aux premiers <a href=\"http:\/\/news.independent.co.uk\/europe\/article2553948.ece\" class=\"gen\">actes<\/a> du pr\u00e9sident et \u00e0 l&rsquo;esprit qui les habite, ode \u00e0 la Grande Nation et \u00e0 sa fiert\u00e9 d&rsquo;\u00eatre (\u00ab<em>Patriotism and pride come first as Sarkozy takes power<\/em>\u00bb) :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>After the traditional, rather stiff ceremony of inauguration yesterday at the Elys\u00e9e Palace, and a ride up the Champs Elys\u00e9es in an open-top car, President Sarkozy added a gut-wrenching speech paying tribute to young resistance martyrs of the Second World War.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>He said his first act as president would be to order the final letter home of a condemned resistance hero to be read out to all French schoolchildren aged 15 to 18 each September. M. Sarkozy&rsquo;s message was plain. He plans to try to reform the French economy but he also plans to try to reform the French psyche, especially the psyche of the young. Self-doubt and self-flagellation is out. National pride is in.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>During the campaign, M. Sarkozy had implicitly criticised the outgoing president, Jacques Chirac, for adopting what he called a posture of repentance: apologising for dark periods in France&rsquo;s past, such as the role of the French state in the Holocaust.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>By going to a resistance shrine in the Bois de Boulogne as one of his first acts as president, M. Sarkozy signalled that he plans to resurrect the very different post-war approach of his political hero, Charles de Gaulle. Like De Gaulle&rsquo;s France, Sarkozy&rsquo;s France will glorify acts of patriotism and achievement. It will not dwell on past failures, wickedness or betrayals.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>It is essential that we explain to our children what it means to be young and French, M. Sarkozy said. Through the sacrifices of a handful of people in the past&#8230; (they must understand) what it means to give yourself up to a cause much greater than yourself.<\/em>\u00bb<\/p>\n<h3>L&rsquo;esprit de la nation<\/h3>\n<\/p>\n<p><p>\tEn un sens, on dirait que l&rsquo;\u00e9tat d&rsquo;immigr\u00e9 de Sarkozy l&rsquo;aide \u00e0 mieux magnifier la nation et la fonction. Il est mieux plac\u00e9 pour exalter l&rsquo;esprit de la Grande Nation qui rencontre sa chair et sa terre, lui qui n&rsquo;est ni de la chair ni de la terre de France,  par cons\u00e9quent, mieux plac\u00e9 pour en magnifier l&rsquo;esprit. Il retrouve la vraie d\u00e9finition de l&rsquo;ouverture de la France : la grandeur d&rsquo;un esprit qui permet \u00e0 ceux qui ne sont pas de sa chair et de sa terre de s&rsquo;y inscrire profond\u00e9ment, d&rsquo;en \u00eatre investi (voir plus loin). Son exaltation patriotique peut \u00eatre per\u00e7ue comme le r\u00e9sultat d&rsquo;un choix fondamental autant que l&rsquo;effet d&rsquo;une int\u00e9gration r\u00e9ussie. Cela rejoint les grandes d\u00e9finitions de cette nation, de Renan \u00e0 de Gaulle.<\/p>\n<\/p>\n<p><p>\tLe premier paragraphe de son discours d&rsquo;investiture,  avec le soulign\u00e9 qui est de nous,  est une immanquable r\u00e9f\u00e9rence \u00e0 la dualit\u00e9 de l&rsquo;histoire et du renouveau, \u00e0 la p\u00e9rennit\u00e9 de la nation fran\u00e7aise qui termine les <em>M\u00e9moires de guerre<\/em> (notamment \u00ab<em>Vieille France, accabl\u00e9e d&rsquo;Histoire, meurtrie de guerres et de r\u00e9volutions, allant et venant sans rel\u00e2che de la grandeur au d\u00e9clin, mais redress\u00e9e, de si\u00e8cle en si\u00e8cle, par le g\u00e9nie du renouveau!<\/em>\u00bb) :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>En ce jour o\u00f9 je prends officiellement mes fonctions de Pr\u00e9sident de la R\u00e9publique fran\u00e7aise, je pense \u00e0 la France,<\/em> <strong><em>ce vieux pays qui a travers\u00e9 tant d&rsquo;\u00e9preuves et qui s&rsquo;est toujours relev\u00e9,<\/em><\/strong> <em>qui a toujours parl\u00e9 pour tous les hommes et que j&rsquo;ai d\u00e9sormais la lourde t\u00e2che de repr\u00e9senter aux yeux du monde.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tDe m\u00eame, <em>The Independent<\/em> souligne justement la force et la signification des symboles choisis par Sarko : saluer la R\u00e9sistance, creuset d&rsquo;o\u00f9 est sortie la Cinqui\u00e8me R\u00e9publique (selon de Gaulle), dans son enti\u00e8ret\u00e9 nationale. (\u00ab<em>By going to a resistance shrine in the Bois de Boulogne as one of his first acts as president, M. Sarkozy signalled that he plans to resurrect the very different post-war approach of his political hero, Charles de Gaulle.<\/em>\u00bb) Sarkozy retrouve la conception qu&rsquo;avait expos\u00e9e Simone Veil, arr\u00eat\u00e9e comme r\u00e9sistante et d\u00e9port\u00e9e, lorsqu&rsquo;elle exposait ce qu&rsquo;elle avait per\u00e7u elle-m\u00eame de sa d\u00e9portation. Juive et r\u00e9sistante, elle aurait pu se percevoir comme une juive arr\u00eat\u00e9e et d\u00e9port\u00e9e ; c&rsquo;est, de fa\u00e7on diff\u00e9rente, comme une r\u00e9sistante arr\u00eat\u00e9e et d\u00e9port\u00e9e qu&rsquo;elle s&rsquo;est per\u00e7ue. Dans le premier cas (d\u00e9port\u00e9e comme juive), il s&rsquo;agit d&rsquo;une sp\u00e9cificit\u00e9 catastrophique de la guerre, par essence non rapport\u00e9e \u00e0 une nation ; dans le second cas, domine la r\u00e9f\u00e9rence \u00e0 la nation sans autre sp\u00e9cificit\u00e9 (r\u00e9sistance fran\u00e7aise).<\/p>\n<\/p>\n<p><p>\tMais encore s&rsquo;agit-il ici du fond du propos alors qu&rsquo;hier, c&rsquo;\u00e9tait la forme de la chose qui comptait,  la forme expliquant et justifiant le fond. Sarkozy n&rsquo;a pas rat\u00e9 son investiture ; c&rsquo;est-\u00e0-dire qu&rsquo;il a laiss\u00e9 subsister l&rsquo;ambigu\u00eft\u00e9 supr\u00eame qui fait qu&rsquo;en ce jour, \u00e0 cause de tout ce qu&rsquo;on sait du fondamental de cette fonction-l\u00e0, on ne sait plus qui investit qui,  et l&rsquo;on est conduit \u00e0 trancher dans le sens qui importe : hier, c&rsquo;est la fonction qui a investi l&rsquo;homme, non le contraire. Curieusement ou de fa\u00e7on r\u00e9v\u00e9latrice, on peut prendre le terme investir dans son double sens, car il y a effectivement comme <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3977\" class=\"gen\">une bataille pr\u00e9liminaire<\/a> entre la l\u00e9g\u00e8ret\u00e9 et la vanit\u00e9 de tout homme et le poids et la gravit\u00e9 de cette fonction transcendantale : \u00ab<em>Investir solennellement d&rsquo;un pouvoir<\/em>\u00bb et \u00ab<em>Entourer avec des troupes (un objectif militaire)<\/em>\u00bb.<\/p>\n<\/p>\n<p><p>\tIl est difficile d&rsquo;encore exprimer quelques doutes sur l&rsquo;orientation que Sarkozy veut donner \u00e0 sa pr\u00e9sidence (pour la r\u00e9ussite, c&rsquo;est une autre affaire). Nous ne sommes plus en campagne, nous sommes dans le vif du grand sujet. Sarko nous redit ce qu&rsquo;il nous a dit durant la campagne : la r\u00e9affirmation de la souverainet\u00e9 et de la puissance nationales (\u00ab<em>Je d\u00e9fendrai l&rsquo;ind\u00e9pendance et l&rsquo;identit\u00e9 de la France<\/em>\u00bb).<\/p>\n<\/p>\n<p><p>\tDu point de vue de la politique, qui sera le juge de ces intentions, il est assur\u00e9 que le terrain europ\u00e9en sera le favori pour les manuvres du nouveau pr\u00e9sident. La r\u00e9f\u00e9rence faite \u00e0 l&rsquo;Europe dans ce discours n&rsquo;est pas celle d&rsquo;une all\u00e9geance aux conceptions que la bureaucratie europ\u00e9enne veut imposer \u00e0 l&rsquo;Europe, mais, au contraire, une r\u00e9volte contre elles. C&rsquo;est presque une r\u00e9f\u00e9rence issue du non au r\u00e9f\u00e9rendum : \u00ab<em>Je me battrai pour une Europe qui prot\u00e8ge<\/em>\u00bb ; ce que <em>The Independent<\/em> traduit justement en termes concrets comme ceci : \u00ab<em>On the European Union, M. Sarkozy again gave a clear signal that his market-oriented policies stopped at Europe&rsquo;s external borders. He said he wanted an EU which protects its citizens.<\/em>\u00bb<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La fonction investit l&rsquo;homme 17 mai 2007 Aux derni\u00e8res nouvelles, il n&rsquo;est pas tout \u00e0 fait confirm\u00e9 que la fonction cr\u00e9e l&rsquo;organe mais elle l&rsquo;aide certainement, en lui prenant la main et en la serrant tr\u00e8s fort. Telle fut donc l&rsquo;impression, hier, \u00e0 l&rsquo;inauguration du pr\u00e9sident Sarkozy, et, par cons\u00e9quent, l&rsquo;impression du petit Nicolas devenu&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[2687,2891,4194,4617,4590,6639],"class_list":["post-68801","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-france","tag-grande","tag-nation","tag-presidence","tag-sarkozy","tag-transcendance"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=68801"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68801\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=68801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=68801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=68801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}