{"id":68819,"date":"2007-05-21T00:00:00","date_gmt":"2007-05-21T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2007\/05\/21\/notes-sur-maistre-sarko-lhistoire-et-le-reste\/"},"modified":"2007-05-21T00:00:00","modified_gmt":"2007-05-21T00:00:00","slug":"notes-sur-maistre-sarko-lhistoire-et-le-reste","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2007\/05\/21\/notes-sur-maistre-sarko-lhistoire-et-le-reste\/","title":{"rendered":"Notes sur Maistre, Sarko, l&rsquo;Histoire et le reste"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955; font-size:2em\">Notes sur Maistre, Sarko, l&rsquo;Histoire et le reste<\/h2>\n<\/p>\n<p><p>Le d\u00e9bat a bouillonn\u00e9 et brouillonn\u00e9 autour de <em>dedefensa.org<\/em>, \u00e0 propos de l&rsquo;interpr\u00e9tation que nous avons donn\u00e9e de l&rsquo;\u00e9lection de Sarko \u00e0 la pr\u00e9sidence de la R\u00e9publique, apr\u00e8s notre interpr\u00e9tation de la campagne \u00e9lectorale. Plusieurs th\u00e8mes de contestation sont apparus, figurant dans le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/forum.php?art_id=3977 \">\u00ab\u00a0Forum\u00a0\u00bb<\/a> de <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/forum.php?art_id=3948\">tel<\/a> ou <a class=\"gen\" href=\" http:\/\/www.dedefensa.org\/forum.php?art_id=3954\">tel<\/a> commentaire de <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/forum.php?art_id=3957\">tel<\/a> ou <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/forum.php?art_id=3988\">tel<\/a> texte. Dans ce texte g\u00e9n\u00e9ral, nous cherchons \u00e0 pr\u00e9senter nos propres r\u00e9actions aux diverses r\u00e9actions des lecteurs et en m\u00eame temps, et au-del\u00e0, nous d\u00e9finissons plus avant notre propre attitude.<\/p>\n<\/p>\n<p><p>Bien, nous commen\u00e7ons par un lecteur, notre lecteur Jean-Pierre Delorme, avec son courrier circonstanci\u00e9 en date du <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3957&lt;D\">8 mai<\/a>. Il nous lit en g\u00e9n\u00e9ral &laquo;<em>avec un immense int\u00e9r\u00eat<\/em>&raquo; parce que nous avons donn\u00e9 &laquo;<em>un cadre coh\u00e9rent et stimulant \u00e0 beaucoup de<\/em> [ses] <em>r\u00e9flexions<\/em>&raquo;. (Merci de cette appr\u00e9ciation. Que monsieur Delorme sache que nous lui en sommes reconnaissant parce que c&rsquo;est exactement notre but : non pas convaincre ni vaincre nos lecteurs, mais leur donner un outil qui \u00e9largisse le champ de leurs r\u00e9flexions.) Et puis, soudain, rien ne va plus&hellip; &laquo;<em> Et puis soudain, vous \u00e9crivez sur la France et&#8230; je ne comprends plus rien<\/em>&raquo;.<\/p>\n<\/p>\n<p><p>Evidemment, il y a de quoi \u00eatre perturb\u00e9 ; <em>dedefensa.org<\/em> deviendrait-il herm\u00e9tique, incompr\u00e9hensible, etc., d\u00e8s qu&rsquo;il s&rsquo;agit du \u00ab\u00a0cher pays de mon enfance\u00a0\u00bb?<\/p>\n<\/p>\n<p><p>D&rsquo;abord et avant de passer au principal, un terme nous arr\u00eate: \u00ab\u00a0comprendre\u00a0\u00bb. Il ne s&rsquo;agit pas de \u00ab\u00a0comprendre\u00a0\u00bb quelque chose.<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Quelques mots sur notre c\u00f4t\u00e9 \u00ab\u00a0maistrien\u00a0\u00bb<\/h2>\n<\/p>\n<p><p>Effectivement, l&rsquo;incompr\u00e9hension de monsieur Delorme concerne la r\u00e9f\u00e9rence \u00e0 Maistre dont nous avons fait grand usage ces derniers temps \u00e0 propos de la France. Notons tout de m\u00eame ces deux passages de son courrier :<\/p>\n<\/p>\n<p><p>&bull; Le d\u00e9but de sa r\u00e9flexion : &laquo;<em>Sans doute devrais-je me renseigner davantage sur Joseph de Maistre, et les notions li\u00e9es \u00e0 la transcendance nationale&#8230;<\/em>&raquo; (Y a-t-il de l&rsquo;ironie dans ce propos? Nous esp\u00e9rons que non et si oui, qu&rsquo;elle est purement amicale. Et puis, Maistre, &mdash; sa vie, son &oelig;uvre, &mdash; cela vaut le d\u00e9placement.)<\/p>\n<\/p>\n<p><p>&bull; La conclusion de sa r\u00e9flexion :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em> Ma conclusion serait que les instincts fran\u00e7ais nous ont fait r\u00e9sister &mdash; dans le plus grand d\u00e9sordre &mdash; vingt ans \u00e0 l&rsquo;avatar n\u00e9o-lib\u00e9ral de l&rsquo;am\u00e9ricanisme. Mais ce d\u00e9sordre \u00e9tant arriv\u00e9 \u00e0 son comble sans qu&rsquo;une r\u00e9action th\u00e9orique quelconque vienne contredire l&rsquo;adversaire, la capitulation risque d&rsquo;\u00eatre totale. Une fois encore c&rsquo;est dans l&rsquo;\u00e9preuve la pire que les ressources n\u00e9cessaires \u00e0 la r\u00e9sistance et \u00e0 la reconqu\u00eate vont devoir \u00e9clore et prosp\u00e9rer. Si du moins il reste \u00e0 la France un quelconque g\u00e9nie.<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Notre remarque pourrait \u00eatre, \u00e0 la lecture de la conclusion : &laquo;<em> Et puis soudain, vous \u00e9crivez sur la France et&#8230; je ne comprends plus rien<\/em>&raquo;&hellip; Non, tr\u00eave d&rsquo;ironie tr\u00e8s amicale, &mdash; notre r\u00e9action est plut\u00f4t ceci: monsieur Delorme, qui ne conna&icirc;t pas assez Maistre selon sa propre observation, termine son intervention en faisant du Maistre sans le savoir, comme monsieur Jourdain faisant de la prose. Il invoque des pr\u00e9c\u00e9dents qui ont plus \u00e0 voir avec des valeurs grandioses de la France qu&rsquo;on peut difficilement appr\u00e9hender avec la seule raison. Il invoque implicitement une puissance collective (le \u00ab\u00a0g\u00e9nie de la France\u00a0\u00bb) qui rel\u00e8ve de la transcendance, comme Maistre fait lui-m\u00eame en affirmant qu&rsquo;il existe dans l&rsquo;Histoire des forces qui d\u00e9passent le seul domaine de la raison. (Raisonnablement jugeant, il y a longtemps que la France devrait \u00eatre morte et monsieur Baverez citoyen de la communaut\u00e9 transatlantique.) Nous ne pouvons qu&rsquo;applaudir \u00e0 cette attitude, avec la plus grande ing\u00e9nuit\u00e9. Car c&rsquo;est exactement cela, voyez-vous.<\/p>\n<\/p>\n<p><p>Cher lecteur(s), la condition d&rsquo;un int\u00e9r\u00eat quelconque et enrichissant pour la m\u00e9thodologie maistrienne, c&rsquo;est de ne pas chercher \u00e0 la comprendre (\u00e0 l&rsquo;expliquer) mais de l&rsquo;utiliser apr\u00e8s l&rsquo;avoir <strong>ressentie<\/strong> comme juste par intuition et \u00e9ventuellement reconnue par exp\u00e9rience. Ce que, manifestement, vous faites et ce qui fut, \u00e0 notre sens, la d\u00e9marche initiale de Joseph de Maistre.<\/p>\n<\/p>\n<p><p>Qui est-il ce Maistre? Un \u00e9rudit aux opinions tranch\u00e9es et \u00e0 la plume superbe, mis au placard de la d\u00e9monisation par la sotte et indigne intelligence fran\u00e7aise qui tient les r\u00eanes du pouvoir, de ses ors et de ses privil\u00e8ges depuis des si\u00e8cles et des si\u00e8cles, et qui repr\u00e9sente n\u00e9cessairement le parti de l&rsquo;\u00e9tranger en France (des adversaires de Jeanne aux collabos de Hitler, aux staliniens du type \u00ab\u00a0Il ne faut pas d\u00e9sesp\u00e9rer Billancourt\u00a0\u00bb, aux lib\u00e9raux partisans des \u00ab\u00a0bombardements humanitaires\u00a0\u00bb du Pentagone d&rsquo;aujourd&rsquo;hui). Maistre est l&rsquo;arch\u00e9type de la hy\u00e8ne puante et r\u00e9actionnaire, du \u00ab\u00a0salopard\u00a0\u00bb sartrien avant l&rsquo;heure.<\/p>\n<\/p>\n<p><p>Cela dit, la v\u00e9rit\u00e9 est que Maistre fut, avant la R\u00e9volution, une lumi\u00e8re de la ma\u00e7onnerie (entr\u00e9e en 1773), qu&rsquo;il d\u00e9livra un M\u00e9moire superbe, rest\u00e9 c\u00e9l\u00e8bre, au Grand Ma&icirc;tre de son ordre, le duc de Brunswick. Puis il y eut la r\u00e9volution. Comme Chateaubriand, autre lib\u00e9ral bronz\u00e9 au feu de la m\u00e9diocre et sanglante folie humaine, Maistre devint anti-r\u00e9volutionnaire, papiste, r\u00e9actionnaire, protecteur des royaut\u00e9s l\u00e9gitimes. Cela dit (bis), il creva la faim comme tout homme de belle vertu non r\u00e9f\u00e9renc\u00e9e qui se respecte. Nomm\u00e9 ambassadeur du Roi de Pi\u00e9mont (dont il \u00e9tait le sujet) aupr\u00e8s du tsar Alexandre le lib\u00e9ral, c&rsquo;est lui-m\u00eame qui, \u00e0 Saint Petersbourg, entretenait chichement son ambassade, sur ses maigres deniers, crevant de froid parce qu&rsquo;il ne pouvait acheter du bois pour l&rsquo;\u00e2tre froide, recouvert d&rsquo;un manteau pour \u00e9crire ses d\u00e9p\u00eaches diplomatiques sublimes dont le roi du Pi\u00e9mont se foutait du tiers comme du quart. Le roi de Pi\u00e9mont oubliait de lui servir ses gages. Allez donc parler de cette anti-rente de la libert\u00e9 de l&rsquo;esprit \u00e0 nos intellectuels anti-sarkozystes et aux autres, les antiam\u00e9ricains de salon comme les pro-sarkozystes et pro-am\u00e9ricains des m\u00eames salons, &mdash; bref, \u00e0 tous nos intellectuels install\u00e9s, le cul au chaud&hellip;<\/p>\n<\/p>\n<p><p>Passons cette pol\u00e9mique pour vous dire que ce qui nous passionne chez Maistre, d&rsquo;ailleurs comme chez Chateaubriand (tiens, deux <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1754\">antimodernes<\/a> selon Compagnon), c&rsquo;est sa perception intuitive de la transcendance de l&rsquo;Histoire. Maistre n&rsquo;explique pas cela, il en est <strong>habit\u00e9<\/strong> et il observe le monde \u00e0 la lumi\u00e8re de ce feu int\u00e9rieur.<\/p>\n<\/p>\n<p><p>Notre d\u00e9marche est la m\u00eame, &mdash; inutile de chercher \u00e0 comprendre ce que nous sommes bien en peine de nous expliquer \u00e0 nous-m\u00eames. Vous prenez ou vous laissez. (Eventuellement, vous jugez au r\u00e9sultat : c&rsquo;est votre affaire.)<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">A propos de Nicolas S.<\/h3>\n<\/p>\n<p><p>Nos lecteurs sont ent\u00eat\u00e9s lorsqu&rsquo;ils s&rsquo;adressent \u00e0 nous, implicitement et parfois explicitement, comme \u00e0 des d\u00e9fenseurs de Sarko, voire des \u00ab\u00a0tra&icirc;tres\u00a0\u00bb ayant ralli\u00e9 sa cause. (Curieuse formulation : Sarko est un homme sans cause, o&ugrave; voit-on que l&rsquo;on puisse la rallier?)&hellip; O&ugrave; et quand avons-nous jamais, au grand jamais, tress\u00e9 quelque couronne de vertu que ce soit \u00e0 Sarko? Au contraire, nous pr&icirc;mes chaque fois le plus grand soin \u00e0 souligner et \u00e0 qualifier ses faiblesses sans dissimuler ses \u00e9ventuelles qualit\u00e9s. Ce n&rsquo;est pas montrer quelque penchant intellectuel ou int\u00e9ress\u00e9 que ce soit que <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3906\">d&rsquo;\u00e9crire<\/a>, \u00e0 propos de Nicolas S. : &laquo;<em>Jamais les hommes politiques n&rsquo;ont \u00e9t\u00e9 d&rsquo;une aussi faible carrure intellectuelle pour une \u00e9nergie aussi grande, tant politique que dialectique. Sarko est le \u00ab\u00a0mod\u00e8le-turbo\u00a0\u00bb de cette sorte.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Par ailleurs, que signifie ce proc\u00e8s autour de Sarko, de ce qu&rsquo;il est et de ce qu&rsquo;il vaut? Depuis quand faut-il des hommes vertueux pour faire des grandes politiques? L&rsquo;un des plus grands g\u00e9nies de la diplomatie fran\u00e7aise et l&rsquo;homme qui, sans doute, a le mieux compris ce que c&rsquo;est que \u00ab\u00a0servir la France\u00a0\u00bb (y compris son intrigue mondaine avec le tsar Alexandre, \u00e0 Erfurt), se nommait Talleyrand. Que pensez-vous de la r\u00e9putation de corruption de cette &laquo;<em>merde dans un bas de soie<\/em>&raquo;? (Aujourd&rsquo;hui, on ne dit plus &laquo;<em>de la merde dans un bas de soie<\/em>&raquo; mais \u00ab\u00a0un rapport d\u00e9complex\u00e9 \u00e0 l&rsquo;argent\u00a0\u00bb.) De Gaulle \u00e9tait un homme insupportable par certains aspects de son caract\u00e8re (voyez ce qu&rsquo;en dit l&rsquo;excellent <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=362\">Duff Cooper<\/a> jusqu&rsquo;\u00e0 la reconnaissance paradoxale de sa grandeur fondamentale) et ses man&oelig;uvres pour \u00e9liminer Giraud en 1943 ont tout \u00e0 voir avec le vice florentin de l&rsquo;intrigue. (Au fait, allez demander ce que les \u00ab\u00a0pieds-noirs\u00a0\u00bb pensent du &laquo;<em>Je vous ai compris<\/em>&raquo;, &mdash; ah oui, nous oublions, les \u00ab\u00a0pieds-noirs\u00a0\u00bb sont des m\u00e9chants, des vilains, des racistes d\u00e9voreurs des Arabes, &mdash; r\u00e9f\u00e9rence non valable, Votre Honneur.) Mitterrand avait collabor\u00e9 comme tout bon p\u00e9tainiste temporaire et occasionnel, Francisque d&rsquo;honneur comprise, avant que nombre d&rsquo;entre vous, chers lecteurs, soient n\u00e9s. La nullit\u00e9 politique et la corruption de Chirac, rempilant en 2002 pour ne pas aller devant le juge, ne faisaient de doute pour aucun d&rsquo;entre vous, en 1995 comme en 2002. Aujourd&rsquo;hui, nous pleurons sous ces ic\u00f4nes \u00e0 propos du m\u00e9chant Sarko que le destin nous fourre dans les pattes.<\/p>\n<\/p>\n<p><p>En plus, il va sur un yacht, le b\u00e9l&icirc;tre! Patatras dans notre nation de vierges aust\u00e8res, qui v\u00e9rifient les ceintures de chastet\u00e9 tous les deux mois, avec l&rsquo;aide d&rsquo;un serrurier. Dans ce cas-l\u00e0, pardonnez-nous, mais nous ne rel\u00e8verons contre le petit Nicolas, outre le manque de go&ucirc;t <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3965\">d\u00e9j\u00e0<\/a> mentionn\u00e9, qu&rsquo;une na\u00efvet\u00e9 d\u00e9concertante qui l&rsquo;oblit\u00e9rerait de toute pens\u00e9e vraiment vicieuse. Ca, un comploteur qui ne r\u00eave que de nous jeter sous le dentier \u00ab\u00a0yamamesque\u00a0\u00bb de la baronne Thatcher? Attendez, &mdash; pas tr\u00e8s habile, le Pirlouit, d&rsquo;en croquer avant m\u00eame d&rsquo;\u00eatre intronis\u00e9&hellip;En v\u00e9rit\u00e9, le grand courant historique dont nous parlons, celui que nous avons c\u00e9l\u00e9br\u00e9 durant la campagne, n&rsquo;en fera <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3977\">qu&rsquo;une bouch\u00e9e<\/a>, &mdash; si ce n&rsquo;est <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3988\">d\u00e9j\u00e0 fait<\/a>.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\"><em>Ecce Homo<\/em> dans le syst\u00e8me et en-dehors<\/h3>\n<\/p>\n<p><p>Nous allons vous confier un secret : l&rsquo;homme, &mdash; l&rsquo;homme public, l&rsquo;homme politique, &mdash; ne nous int\u00e9resse plus gu\u00e8re, &mdash; en v\u00e9rit\u00e9. Le syst\u00e8me l&rsquo;a d\u00e9vor\u00e9 et l&rsquo;homme qui peut encore nous attacher est en-dehors de ce syst\u00e8me, ou \u00e0 l&rsquo;int\u00e9rieur lorsqu&rsquo;il complote contre lui, de bon gr\u00e9 ou sans s&rsquo;en aviser. L&rsquo;homme du syst\u00e8me,&mdash; et ils en sont tous <strong>n\u00e9cessairement<\/strong>,&mdash; a choisi une voie qui n&rsquo;est pas la n\u00f4tre, dont l&rsquo;aboutissement sera la fin de tout ce qui nous attachait dans cette civilisation, &mdash; le peu qu&rsquo;il en restait, &mdash; et le triomphe de tout ce que nous m\u00e9prisons et qui nous donne envie de ne plus vivre. L&rsquo;homme du syst\u00e8me ne nous int\u00e9resse plus qu&rsquo;en tant qu&rsquo;outil. Sarko, le petit Nicolas, ne nous int\u00e9resse qu&rsquo;en tant qu&rsquo;outil. Alors, yacht ou pas yacht&hellip;<\/p>\n<\/p>\n<p><p>Cela ne signifie pas que nous lui d\u00e9nions de la qualit\u00e9 humaine. Mais si, il y a droit! Il a des qualit\u00e9s, une \u00e2me, une morale, et puis il court bien. Mais, plac\u00e9 dans la combinaison du syst\u00e8me, ce n&rsquo;est que le plus bas qu&rsquo;il a en lui qui s&rsquo;affirme. Alors, <em>basta<\/em> pour ce point.<\/p>\n<\/p>\n<p><p>Seulement il y a un cas essentiel de confluence qui fait que tout n&rsquo;est pas perdu, &mdash; puisque rien n&rsquo;est jamais perdu comme l&rsquo;on sait (l&rsquo;optimisme du d\u00e9sespoir ou le nihilisme anti-nihiliste de Nietzsche). Ce que nous guettons, c&rsquo;est le comportement de cet homme du syst\u00e8me lorsqu&rsquo;il se trouve \u00e0 la confluence du syst\u00e8me et des forces qui se sont lev\u00e9es contre le syst\u00e8me. L&rsquo;homme du syst\u00e8me en France se trouve \u00e0 cette confluence parce que la France est le <strong>seul<\/strong> pays de notre monde qui se trouve \u00e0 la fois compl\u00e8tement en-dedans et compl\u00e8tement en-dehors, compl\u00e8tement dans le syst\u00e8me et potentiellement compl\u00e8tement en r\u00e9volte contre le syst\u00e8me. La France est double, \u00e0 la fois compl\u00e8tement une partie du syst\u00e8me de la civilisation occidentale et am\u00e9ricanis\u00e9e sur la voie de la catastrophe et compl\u00e8tement en \u00e9tat d&rsquo;insurrection potentielle au nom de sa tradition historique et de sa sp\u00e9cificit\u00e9 politique.<\/p>\n<\/p>\n<p><p>Bien s&ucirc;r que Sarko peut trahir ses engagements de campagne. La chose est courante. Chirac, implicitement c\u00e9l\u00e9br\u00e9 par les anti-Sarko, implicitement regard\u00e9 comme l&rsquo;ultime gardien du gaullisme, &mdash; un comble quand on conna&icirc;t sa carri\u00e8re, &mdash; est celui qui, en septembre 1995, s&rsquo;est empress\u00e9 de trahir l&rsquo;argument essentiel de son \u00e9lection-miracle de mai 1995. Rappelez-vous : la \u00ab\u00a0fracture sociale\u00a0\u00bb aux oubliettes! Mais les temps \u00e9taient diff\u00e9rents et Chirac ne pourrait plus nous refaire le coup aujourd&rsquo;hui. En 1995, la globalisation triomphait et, avec elle, l&rsquo;Europe de Maastricht. Le truc de la \u00ab\u00a0fracture sociale\u00a0\u00bb \u00e9tait une trouvaille qui allait contre l&rsquo;air du temps. Aujourd&rsquo;hui, la globalisation est en d\u00e9route, et l&rsquo;Europe de Maastricht avec elle. L&rsquo;exaltation de la nation et de la sp\u00e9cificit\u00e9 fran\u00e7aise est quelque chose qui va de soi.<\/p>\n<\/p>\n<p><p>Sarko est un homme sans cause, qui n&rsquo;a comme id\u00e9ologie que le succ\u00e8s. Bien entendu, et nous n&rsquo;avons jamais rien dit d&rsquo;autre. Il se trouve que le \u00ab\u00a0succ\u00e8s\u00a0\u00bb aujourd&rsquo;hui, en France, comme l&rsquo;a montr\u00e9 l&rsquo;unanimisme de la campagne, c&rsquo;est l&rsquo;attaque de la globalisation et de l&rsquo;Europe de Maastricht. Concluez et dites-nous si l&rsquo;hypoth\u00e8se que nous consid\u00e9rons est absurde. Et admettez l\u00e0-dessus que l&rsquo;homme de la confluence, investi par la transcendance, peut \u00eatre transform\u00e9 et peut se transformer.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Une passion bien fran\u00e7aise<\/h3>\n<\/p>\n<p><p>Ce qui nous a \u00e9tonn\u00e9s et nous inqui\u00e8te, par contre, c&rsquo;est la passion anti-sarkozyste. Si la d\u00e9fense de Sarko ne nous int\u00e9resse pas, par contre la passion furieuse qu&rsquo;il soul\u00e8ve contre lui nous importe. Elle en dit plus long sur ceux qui sont touch\u00e9s par elle que sur lui, sur Sarko.<\/p>\n<\/p>\n<p><p>Sarko facho, apprenti-dictateur? Que n&rsquo;entend-on \u00e0 ce propos. Ah, ce n&rsquo;est pas de Gaulle, ajoute-t-on, l&rsquo;air vertueux et entendu, &mdash; de Gaulle, ce Panth\u00e9on de la vertu aust\u00e8re, r\u00e9publicaine et nationale. Allons donc.<\/p>\n<\/p>\n<p><p>Est-ce que vous vous rappelez que de Gaulle fut accus\u00e9 de pr\u00e9parer un coup d&rsquo;Etat de 1944 \u00e0 1969? Est-ce que vous vous rappelez son exclamation, agac\u00e9 d&rsquo;une question de plus sur ce th\u00e8me, lors de sa conf\u00e9rence de presse de mai 1958 : &laquo;<em>Dictateur, moi?! Mais pourquoi, Grand Dieu, voudriez-vous qu&rsquo;\u00e0 mon \u00e2ge, je commence une carri\u00e8re de dictateur?!<\/em>&raquo; De Gaulle fut poursuivie de diatribes et de soup\u00e7ons divers ; il fut accus\u00e9 en 1962 de \u00ab\u00a0forfaiture\u00a0\u00bb par Gaston Monnerville, pr\u00e9sident du S\u00e9nat et grand serviteur de l&rsquo;Etat, (d&rsquo;origine africaine, Monnerville, ce qui montre que la France pr\u00e9c\u00e9da sans tambours ni trompette les USA (Powell &#038; Condi) dans la promotion de ses enfants de couleur, comme on disait \u00e0 cette \u00e9poque raciste); il fut accus\u00e9 en 1964 de fomenter un <em>coup d&rsquo;Etat permanent<\/em>, par une plume \u00e9l\u00e9gante et politique qu&rsquo;on a revue depuis \u00e0 cette m\u00eame place du Commandeur-comploteur; il fut accus\u00e9 de ch\u00e9rir dans un secret alc\u00f4ve l&rsquo;Article 16 qui permettrait au fascisme immonde de prendre la vertueuse France. Cela venait de gauche, bien s&ucirc;r, mais \u00e9galement de droite (il faut lire <em>M\u00e9galonose &mdash; suppl\u00e9ment aux voyages de Gulliver<\/em>, de Michel D\u00e9on, publi\u00e9 en 1967 et r\u00e9cemment [1999] r\u00e9\u00e9dit\u00e9, portraiturant un M\u00e9galonose-de Gaulle en dictateur fasciste, nain et obs\u00e9d\u00e9 sexuel). Aujourd&rsquo;hui, qui ne fait ses d\u00e9votions \u00e0 la vertu du G\u00e9n\u00e9ral et, en son nom, ne d\u00e9nonce l&rsquo;apprenti-dictateur Sarko?<\/p>\n<\/p>\n<p><p>Le lendemain de l&rsquo;\u00e9lection de Sarko, un juriste belge observait que la fonction pr\u00e9sidentielle fran\u00e7aise donnait \u00e0 celui qui l&rsquo;endossait un pouvoir d&rsquo;une puissance unique parmi les d\u00e9mocraties occidentales.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>Malgr\u00e9 cela, en un demi-si\u00e8cle de fonctionnement jamais une tentation totalitaire s\u00e9rieuse n&rsquo;est apparue. Les successions se sont toutes d\u00e9roul\u00e9es dans l&rsquo;ordre le plus parfait, et avec un souci de continuit\u00e9 qui en dit long sur la solidit\u00e9 du syst\u00e8me.<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>La question est de savoir si, aujourd&rsquo;hui, ce n&rsquo;est pas la France qui d\u00e9tient une formule proche du meilleur usage possible du syst\u00e8me, &mdash; \u00e9ventuellement et naturellement pour mettre en cause le syst\u00e8me, &mdash; alors que ce r\u00f4le est traditionnellement et respectueusement d\u00e9volu au syst\u00e8me am\u00e9ricaniste dont on mesure d\u00e9sormais les limites et la perversit\u00e9 \u00e0 la lumi\u00e8re du chaos bushiste de Washington. La pr\u00e9sidence fran\u00e7aise marie \u00e0 la fois l&rsquo;autorit\u00e9, la l\u00e9gitimit\u00e9 et l&rsquo;exercice d&rsquo;une d\u00e9mocratie bien temp\u00e9r\u00e9e. Tout le monde, en France, la critique et veut la r\u00e9former, ce qui est bon signe.<\/p>\n<\/p>\n<p><p>A c\u00f4t\u00e9 de ce <strong>fait<\/strong> majeur, qui est bien assez puissant pour maintenir tout homme politique dans la perspective de l&rsquo;exercice judicieux du pouvoir, nous aurions tendance \u00e0 croire que la v\u00e9ritable faiblesse fran\u00e7aise est cette jactance th\u00e9orique, cette repr\u00e9sentation symbolique permanente des h\u00e9ritiers d&rsquo;une R\u00e9volution sans cesse re-mythifi\u00e9e, ce soup\u00e7on infini et spasmodique du fascisme mythique et du dictateur fantomatique, &mdash; bref, cette veille sans fin du cadavre pourrissant d&rsquo;un pass\u00e9 id\u00e9ologique archi-mort et qui n&rsquo;en finit pourtant pas de mourir, &mdash; alors que tant de dangers pressants nous accablent de tous c\u00f4t\u00e9s &hellip; C&rsquo;est comme une sorte de fuite devant la r\u00e9alit\u00e9, une sorte de valse-h\u00e9sitation renaissante \u00e0 chaque \u00e9lection, ce que nous pourrions nommer \u00ab\u00a0virtualisme \u00e0 la fran\u00e7aise\u00a0\u00bb, \u00e0 \u00e9clipses, \u00e0 mille facettes, beaucoup plus classique et raisonn\u00e9 que la version anglo-saxonne et hyst\u00e9rique.<\/p>\n<\/p>\n<p><p>L&rsquo;hyst\u00e9rie fran\u00e7aise aime \u00e0 se parer des atours de la raison et de la morale. Cette tendance est effectivement un pan de l&rsquo;entreprise g\u00e9n\u00e9rale d&rsquo;auto-d\u00e9nigrement de la France par ses \u00e9lites, pratique aussi vieille que la Grande Nation. Ceux qui y sacrifient sont le plus souvent, comme l&rsquo;on dit, de fort bonne foi. Tony Blair l&rsquo;\u00e9tait aussi, qui assura dans son discours d&rsquo;adieu : &laquo;<em>Hand on heart, I did what I thought was right. I may have been wrong. That&rsquo;s your call. But believe one thing if nothing else. I did what I thought was right for our country.<\/em>&raquo; Nul n&rsquo;a aucune raison d&rsquo;en douter tant il est vrai que la bonne conscience est, au bout du compte, et comptes faits des erreurs sanglantes dues aux erreurs de la bonne conscience, la plus effrayante menace que nous m\u00e9nage l&rsquo;esprit.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Revenons \u00e0 nos moutons, pour conclure<\/h3>\n<\/p>\n<p><p>S&rsquo;il s&rsquo;agit de <em>dedefensa.org<\/em> et <em>dedefensa.org<\/em> \u00e9tant ce qu&rsquo;il est, il est heureusement entendu que l&rsquo;on n&rsquo;en changera pas l&rsquo;esprit. Son ignorance de l&rsquo;\u00e9tiquette, celle de l&rsquo;id\u00e9ologie et l&rsquo;autre sans doute, est un caract\u00e8re fondateur de la chose. On ne revient pas sur cela ou bien l&rsquo;on se passe de <em>dedefensa.org<\/em>. Cette absence d&rsquo;\u00e9tiquetage induit l&rsquo;absence d&#8217;emballage autour des gens qui animent la politique, &mdash; et autour du reste qui nous int\u00e9resse. Cela n&rsquo;est pas une vertu originale dans des temps o&ugrave; tout le monde affiche sa libert\u00e9, mais c&rsquo;est en r\u00e9alit\u00e9 pour nous une <strong>m\u00e9thode<\/strong> de travail et pas du tout une vertu. Si un imb\u00e9cile, un suspect de d\u00e9viationnisme <em>ante<\/em>-d\u00e9mocratique ou une mauvaise r\u00e9putation dit une chose int\u00e9ressante, la chose nous int\u00e9resse. La Palisse ne dirait pas mieux.<\/p>\n<\/p>\n<p><p>Nous aimons bien la raison, mais pour nous en servir comme d&rsquo;un outil, pas pour en faire le Dieu-Raison. Pour nous, ce temps historique que nous vivons est <strong>exceptionnel<\/strong> parce que, avec les moyens du bord (communications et le reste) donn\u00e9s \u00e0 l&rsquo;individu, nous pouvons distinguer aussit\u00f4t, \u00e0 c\u00f4t\u00e9 et en-dessous de l&rsquo;\u00e9cume des jours de la vanit\u00e9 humaine d\u00e9guis\u00e9e en folie (ou est-ce sa folie d\u00e9guis\u00e9e en vanit\u00e9?), les profondeurs sublimes de l&rsquo;Histoire en train de se faire.<\/p>\n<\/p>\n<p><p>Pour nous, l&rsquo;Histoire est <strong>\u00e0 la fois<\/strong> ce qu&rsquo;en disait le Grand Will lorsque Hamlet parle de la vie (<em>Hamlet<\/em>, Acte 5, sc\u00e8ne 5) :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>La vie n&rsquo;est qu&rsquo;une ombre qui marche ; un pauvre com\u00e9dien \/ qui s&rsquo;agite et se pavane une heure sur sc\u00e8ne \/ et puis qu&rsquo;on n&rsquo;entend plus ; c&rsquo;est une histoire, \/<\/em> <strong><em>racont\u00e9e par un idiot, pleine de bruit et de fureur, \/ et qui ne signifie rien.<\/em><\/strong>&raquo;<\/p>\n<\/p>\n<p><p>(&raquo;<em>Life&rsquo;s but a walking shadow; a poor player, \/ That struts and frets his hour upon the stage, \/ And then is heard no more: it is a tale \/ Told by an idiot, full of sound and fury, \/ Signifying nothing.<\/em>&raquo;)<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&hellip; Et, d&rsquo;autre part, une organisation myst\u00e9rieuse que constate la raison lorsqu&rsquo;elle se d\u00e9barrasse de ses pr\u00e9jug\u00e9s, c&rsquo;est-\u00e0-dire une organisation en train de se faire et inexplicable enti\u00e8rement par la seule raison. Notre mission est, \u00e0 ce point, de tenter d&rsquo;en rendre compte apr\u00e8s avoir mesur\u00e9 la vanit\u00e9 d&rsquo;en donner une explication uniquement humaine. C&rsquo;est pourquoi nous privil\u00e9gions le plus souvent l&rsquo;appr\u00e9ciation du d\u00e9sordre lorsque nous observons le spectacle imm\u00e9diat du monde et nous nous gardons si compl\u00e8tement des explications humaines, trop humaines (complots, plans machiav\u00e9liques, habilet\u00e9 hors du commun, contr\u00f4le des m\u00e9canismes, arri\u00e8re-pens\u00e9es, implications id\u00e9ologiques, poign\u00e9es de main chaleureuses, etc.) ; c&rsquo;est pourquoi, notre pessimisme profond lorsque nous jugeons de la vanit\u00e9-folie humaine d\u00e9bouche sur ce qui semble \u00e0 certains un optimisme bien peu justifi\u00e9 par l&rsquo;apparence des faits. Il est d\u00e8s lors bien entendu que les notions humaines, trop humaines d'\u00a0\u00bboptimisme\u00a0\u00bb et de \u00ab\u00a0pessimisme\u00a0\u00bb n&rsquo;ont pas vraiment leur place, &mdash; sauf pour quelque plaisanterie qui ont leur signification (pour juger des capacit\u00e9s humaines d&rsquo;organisation de l&rsquo;Histoire, \u00ab\u00a0un pessimiste est un optimiste bien inform\u00e9\u00a0\u00bb).<\/p>\n<\/p>\n<p><p>Nous avons, comme on l&rsquo;a compris, notre m\u00e9thode, &mdash; ou bien devrions-nous dire notre M\u00e9thode, sans fausse humilit\u00e9? (Nous parlons beaucoup plus de \u00ab\u00a0m\u00e9thode\u00a0\u00bb que de \u00ab\u00a0croyance\u00a0\u00bb m\u00eame si l&rsquo;on peut avancer que l&rsquo;une et l&rsquo;autre pourraient bien se confondre en ce que nous nommerions \u00ab\u00a0conviction\u00a0\u00bb, apr\u00e8s tout. Ce dernier point est un d\u00e9bat pour d&rsquo;autres lieux, &mdash; pour l&rsquo;instant. Pour l&rsquo;essentiel, si notre m\u00e9thode est une croyance, elle ne se laisse pas enivrer par les effluves habituelles des esprits qui en perdent la raison.) Nous appliquons cette m\u00e9thode, y compris en nous r\u00e9f\u00e9rant \u00e0 quelques ma&icirc;tres. (On a compris que Maistre en est un.) Le r\u00e9sultat n&rsquo;est pas si d\u00e9testable et la raison du lecteur reconna&icirc;tra les siens. Ainsi soit-il.<\/p>\n<\/p>\n<p><p>Pour le reste, continuez \u00e0 nous \u00e9crire. Cela anime nos propos et excite notre r\u00e9flexion. Notre aventure est une belle bataille. Acceptez-en, pour notre compte, les principes qui nous guident comme nous acceptons les v\u00f4tres, sans en juger n\u00e9cessairement, &mdash; surtout ceci : sans en juger. L&rsquo;Histoire reconna&icirc;tra les siens.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notes sur Maistre, Sarko, l&rsquo;Histoire et le reste Le d\u00e9bat a bouillonn\u00e9 et brouillonn\u00e9 autour de dedefensa.org, \u00e0 propos de l&rsquo;interpr\u00e9tation que nous avons donn\u00e9e de l&rsquo;\u00e9lection de Sarko \u00e0 la pr\u00e9sidence de la R\u00e9publique, apr\u00e8s notre interpr\u00e9tation de la campagne \u00e9lectorale. Plusieurs th\u00e8mes de contestation sont apparus, figurant dans le \u00ab\u00a0Forum\u00a0\u00bb de tel ou&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[2631,2981,2685,3518,4596,4590,6639],"class_list":["post-68819","post","type-post","status-publish","format-standard","hentry","category-analyse","tag-de","tag-dedefensa-org","tag-gaulle","tag-histoire","tag-maistre","tag-sarkozy","tag-transcendance"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=68819"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68819\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=68819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=68819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=68819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}