{"id":68836,"date":"2007-05-27T00:00:00","date_gmt":"2007-05-27T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2007\/05\/27\/le-devoir-de-vacance-du-giuliani-par-le-professeur-ron-paul\/"},"modified":"2007-05-27T00:00:00","modified_gmt":"2007-05-27T00:00:00","slug":"le-devoir-de-vacance-du-giuliani-par-le-professeur-ron-paul","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2007\/05\/27\/le-devoir-de-vacance-du-giuliani-par-le-professeur-ron-paul\/","title":{"rendered":"Le devoir de vacance du Giuliani, par le professeur Ron Paul"},"content":{"rendered":"<p><p>Ron Paul, l&rsquo;\u00e9tonnant candidat \u00e0 la d\u00e9signation r\u00e9publicaine pour les pr\u00e9sidentielles de 2008, continue \u00e0 faire parler de lui. Il riposte d&rsquo;une fa\u00e7on spirituelle aux commentaires effar\u00e9s de l&rsquo;ancien maire de New York Giuliani apr\u00e8s <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4000\" class=\"gen\">ses d\u00e9clarations<\/a> sur l&rsquo;attaque du 11 septembre 2007. Il lui donne un devoir de lecture pour cet \u00e9t\u00e9, pour l&rsquo;aider \u00e0 comprendre la politique ext\u00e9rieure des USA.<\/p>\n<\/p>\n<p><p>\tLes quatre livres que devra lire le brave Giuliani : le rapport de la Commission officielle sur l&rsquo;attaque du 11 septembre, <em>Dying to Win<\/em> de Robert Pace, <em>Blowback<\/em> de Chalmers Johnson et <em>Imperial Hubris<\/em> de Michael Scheuer. (Evidemment, trois excellentes analyses peu suspectes de sympathie pour la politique expansionniste US,  avec, en plus, l&rsquo;ironie de la recommandation de lire le rapport de la Commission.)<\/p>\n<\/p>\n<p><p>\tCBS a consacr\u00e9 <a href=\"http:\/\/wcbstv.com\/topstories\/local_story_144165257.html\" class=\"gen\">un sujet<\/a> \u00e0 cette intervention de Paul, le 24 mai au cours d&rsquo;une conf\u00e9rence au National Press Club de Washington.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Rudy Giuliani led New York City through the tragic events of Sept. 11, but one of his rivals for the Republican presidential nomination suggested Thursday the former mayor needs a foreign policy education, even going so far as to come up with a book list.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Among the books Texas Rep. Ron Paul said Giuliani should read, believe it or not, the 9-11 Commission Report.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>I&rsquo;m giving Mr. Giuliani a reading assignment, he said Thursday at the National Press Club. This is what I expect him to read before the next debate.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>He&rsquo;s calling for Giuliani to read a total of four books, including Dying To Win, Blowback and Imperial Hubris. In addition, Paul said his campaign chairman said he would be happy to send Giuliani Cliff&rsquo;s Notes, in case he is too busy giving hundred-thousand-dollar speeches on national security.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tBien entendu, le bureau de Giuliani a r\u00e9pondu, \u00e9ructant d&rsquo;indignation, plein de mots tels que absurde, choquant, etc., et par cons\u00e9quent ajoutant l&rsquo;exc\u00e8s au ridicule : \u00ab<em>The response from Team Giuliani was swift. Mayor Giuliani said it best, said a spokesman. It is extraordinary and reckless to claim that the United States invited the attacks on Sept. 11. And to further declare Rudy Giuliani needs to be educated on Sept. 11 when millions of people around the world saw him dealing with the terrorist attacks firsthand is just absurd.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tRon Paul est habile, en plus de pr\u00e9senter une cause politique avec un grand courage dans ce monde politique am\u00e9ricaniste gangren\u00e9 par une paralysie conformiste de l&rsquo;esprit \u00e0 un degr\u00e9 jamais vu. Il joue sur l&rsquo;humour, sur la d\u00e9rision, prenant avec ironie les r\u00e9actions pleines d&rsquo;enflure et d&rsquo;une solennit\u00e9 grossi\u00e8re de Giuliani. Ce faisant, il attire l&rsquo;attention des grands m\u00e9dias qui, au d\u00e9part, l&rsquo;avaient <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4002\" class=\"gen\">ignor\u00e9<\/a> (<a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4005\" class=\"gen\">sauf CNN<\/a>) dans leur grande majorit\u00e9 par alignement conformiste courant. Le sujet d\u00e9velopp\u00e9 par CBS, mais aussi le succ\u00e8s de la conf\u00e9rence de presse de Paul t\u00e9moignent de l&rsquo;efficacit\u00e9 de la tactique. Les r\u00e9actions du camp giulianesque ne font qu&rsquo;ajouter au processus.<\/p>\n<\/p>\n<p><p>\tIl est vrai qu&rsquo;en tenant le syst\u00e8me par la barbichette comme le fait Ron Paul, en d\u00e9fendant avec conviction une cause \u00e9vidente, en moquant les grossi\u00e8res boursouflures de fonctionnement du susdit syst\u00e8me et de ses serviteurs, on finit par mettre les rieurs de son c\u00f4t\u00e9 et par devenir une attraction pour les m\u00e9dias <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2827\" class=\"gen\">MSM<\/a> alli\u00e9s au syst\u00e8me. On devient un objet spectaculaire, attrait auquel les m\u00e9dias ne r\u00e9sistent pas. Finalement, les m\u00e9dias parlent de vous. Le tranquille et habile Ron Paul semble avoir compris cette tactique classique et \u00e9vidente de l&rsquo;entrisme.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 27 mai 2007 \u00e0 12H56<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ron Paul, l&rsquo;\u00e9tonnant candidat \u00e0 la d\u00e9signation r\u00e9publicaine pour les pr\u00e9sidentielles de 2008, continue \u00e0 faire parler de lui. Il riposte d&rsquo;une fa\u00e7on spirituelle aux commentaires effar\u00e9s de l&rsquo;ancien maire de New York Giuliani apr\u00e8s ses d\u00e9clarations sur l&rsquo;attaque du 11 septembre 2007. Il lui donne un devoir de lecture pour cet \u00e9t\u00e9, pour l&rsquo;aider&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[6711,6712,5523,3140,3310],"class_list":["post-68836","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-giuliani","tag-lecture","tag-msm","tag-paul","tag-ron"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=68836"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68836\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=68836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=68836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=68836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}