{"id":68955,"date":"2007-06-30T00:00:00","date_gmt":"2007-06-30T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2007\/06\/30\/padd-si-non-e-vero\/"},"modified":"2007-06-30T00:00:00","modified_gmt":"2007-06-30T00:00:00","slug":"padd-si-non-e-vero","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2007\/06\/30\/padd-si-non-e-vero\/","title":{"rendered":"<strong><em>PADD : \u201cSi non \u00e8 vero \u2026\u201d<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">PADD : <strong><em>Si non \u00e8 vero <\/em><\/strong><\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t30 juin 2007  Ce texte nous a arr\u00eat\u00e9s, intrigu\u00e9s, enthousiasm\u00e9s, confondus, d\u00e9gris\u00e9s,  mais pas pour longtemps D&rsquo;abord, nous n&rsquo;en croyions pas notre lecture puis nous y avons cru puis nous avons dout\u00e9. Dans tous les cas, chapeau bas \u00e0 l&rsquo;auteur,  soit pour le montage, soit pour le canular, soit pour nous avoir sorti de son chapeau cette affaire de PADD (\u00ab<em>Political Attention Deficit Disorder<\/em>\u00bb).<\/p>\n<\/p>\n<p><p>\tNous croyons qu&rsquo;il pourrait \u00eatre compl\u00e8tement conforme \u00e0 la r\u00e9alit\u00e9, et peut-\u00eatre <strong>l&rsquo;est-il<\/strong> apr\u00e8s tout comme une sorte de pr\u00e9monition, peut-\u00eatre est-il le r\u00e9sultat d&rsquo;une \u00e9tude secr\u00e8te ou peut-\u00eatre anticipe-t-il une \u00e9tude qui ne tardera pas,   ou bien, est-ce trop beau pour \u00eatre vrai? Notre enthousiasme vient sans doute de notre pratique assidue du virtualisme,  car PADD a des aspects qui diagnostiquent sans aucun doute une affection du virtualisme.<\/p>\n<\/p>\n<p><p>\tBref, si l&rsquo;on cherche sur <em>Google<\/em> \u00e0 diff\u00e9rents mots sp\u00e9cifiques au texte, on trouve ce texte repris sur divers sites avec des commentaires variant entre l&rsquo;enthousiasme sur le contenu et le scepticisme sur sa v\u00e9racit\u00e9 (et l&rsquo;un n&rsquo;\u00e9tant pas exclusif de l&rsquo;autre). Sur le site du <a href=\" http:\/\/www.ama-assn.org\/ama\/pub\/category\/1800.html\" class=\"gen\">Council on Science and Public Health<\/a>, pas de trace de PADD ni des divers noms cit\u00e9s.<\/p>\n<\/p>\n<p><p>\tDans tous les cas, l&rsquo;auteur, Joel S. Hirschhorn, est un observateur suffisamment fin des d\u00e9sordres de la d\u00e9mocratie am\u00e9ricaniste pour qu&rsquo;on le lise avec le plus grand int\u00e9r\u00eat. Peu importe la r\u00e9alit\u00e9 dans ce cas. PADD, canular ou pas, doit retenir toute notre attention. Reprenons quelques sympt\u00f4mes de PADD (texte <a href=\"http:\/\/www.dedefensa.org\/choix.php?link_id=7146&#038;comm=1\" class=\"gen\">par ailleurs<\/a> repris sur ce site), pour le plaisir et pour la justesse du contenu<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Nearly 80 percent of adult American citizens are unable to pay sustained attention to issues and problems associated with their government. They are unable to accept their responsibility as citizens, including their obligation to vote, read in-depth articles and books on political issues, become active members of politically oriented groups, and initiate discussions on current events with friends and family.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The decades-old decline in voter turnout is a direct result of a national epidemic of PADD, said the report.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The chief cause of PADD is the desire to avoid the very real pain of cognitive dissonance, the difference between what Americans want to believe about the greatness of their country and the disturbing reality that their government and country are in terrible shape, which is a constant reminder when there is normal, healthy political attention. Such pain suppression, however, is counterproductive and was found through careful studies at several universities, including the Harvard Medical College, to correlate with depression and anxiety disorders, as well as a heightened level of cynicism and despair. According to the report, many suicides and possibly many criminal acts result from PADD.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Another consequence of PADD is that people devote more of their time, energy and money to pleasure-seeking distractions. PADD is correlated with profound statistical significance to clinical symptoms such as obesity, alcoholism, drug addiction, video game addiction, Internet addiction, sexual promiscuity, excessive shopping, gambling addiction, and other harmful behaviors.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The report profiles a person severely afflicted by PADD. The psychiatrists unanimously concluded that George W. Bush is a PADD victim. Symptoms include no desire to pursue major and contentious policy issues through in-depth reading, discussion and analysis; a clear dependence on others for policy decisions, particularly Vice President Cheney; an inability to maintain sustained focus on diverse policy issues simultaneously; and an inability to articulate policy. The widespread public perception that Bush is unintelligent, uninformed and dogmatic stems from his PADD, concluded the council.<\/em>\u00bb<\/p>\n<h3>L&rsquo;influence du syst\u00e8me sur la psychologie<\/h3>\n<\/p>\n<p><p>\tL&rsquo;int\u00e9r\u00eat de ce vrai-faux canular est qu&rsquo;il fait un lien direct entre la situation politique aux USA et la politique des USA (situations collectives \u00e9v\u00e9nementielles) et les psychologies individuelles des Am\u00e9ricains. Les canulars (vrai-faux) sont toujours une indication de l&rsquo;air du temps et, dans ce cas, la chose est parfaitement conforme.<\/p>\n<\/p>\n<p><p>\tDepuis au moins la r\u00e9\u00e9lection de GW Bush (novembre 2004) dans le cadre de plus en plus identifi\u00e9 de la catastrophe irakienne et de toute sa politique en g\u00e9n\u00e9ral, et sans aucun doute depuis les \u00e9lections <em>mid-term<\/em> de novembre 2006, se pose d&rsquo;une fa\u00e7on tr\u00e8s publique et pressante la question du comportement des citoyens US. D&rsquo;une part, leur opposition \u00e0 la politique de l&rsquo;administration, elle-m\u00eame soutenue peu ou prou par un syst\u00e8me scl\u00e9ros\u00e9 et obsc\u00e8ne de parti unique compos\u00e9 des deux partis, ne parvient pas \u00e0 se concr\u00e9tiser malgr\u00e9 une mesure constante de son importance et de son accroissement. Les raisons sont diverses. Elles tiennent au m\u00e9canisme du syst\u00e8me certes, mais aussi \u00e0 certaines attitudes erratiques des citoyens (leur opinion sur les responsabilit\u00e9s dans l&rsquo;attaque 9\/11 est toujours \u00e9tonnante) et, surtout, \u00e0 une extraordinaire incapacit\u00e9 \u00e0 concr\u00e9tiser cette opposition dans des actes concrets d&rsquo;opposition. Le conformisme, et le l\u00e9galisme presque pointilliste qui va avec, cons\u00e9cutivement \u00e0 une sorte de certitude entr\u00e9e dans les psychologies de la quasi-perfection du syst\u00e8me am\u00e9ricaniste, semblent les freins les plus puissants.<\/p>\n<\/p>\n<p><p>\tD\u00e8s lors, le canular-PADD nous invite \u00e0 prendre le probl\u00e8me \u00e0 l&rsquo;envers. Il pose implicitement la question de savoir si la psychologie am\u00e9ricaniste est capable d&rsquo;accepter une action cons\u00e9quente contre un syst\u00e8me qu&rsquo;elle juge exceptionnel, malgr\u00e9 la critique tr\u00e8s puissante qu&rsquo;elle formule de sa politique. D&rsquo;o\u00f9 PADD, cette intense frustration, avec sa principale cause qui est finalement un rejet de la confrontation entre la nature suppos\u00e9e du syst\u00e8me et l&rsquo;action constat\u00e9e du syst\u00e8me, avec le versement dans le virtualisme \u00e0 l&rsquo;occasion :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The chief cause of PADD is the desire to avoid the very real pain of cognitive dissonance, the difference between what Americans want to believe about the greatness of their country and the disturbing reality that their government and country are in terrible shape, which is a constant reminder when there is normal, healthy political attention.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tMais le canular-PADD, qui m\u00e9riterait de ne pas l&rsquo;\u00eatre au point qu&rsquo;il pourrait \u00eatre vrai, ouvre un autre champ d&rsquo;exploration, qui nous passionne, ici \u00e0 <em>de defensa<\/em> : les rapports entre les m\u00e9canismes des psychologies individuelles et les actes politiques ainsi que la situation politique produits par un syst\u00e8me dont on est peu ou prou partie prenante ; qui plus est, un syst\u00e8me qui se veut absolument d\u00e9mocratique et qui l&rsquo;est <strong>absolument<\/strong> \u00e0 notre sens, donc qui fait porter une part \u00e9crasante de la responsabilit\u00e9 de ses actes \u00e0 ses constituants, et particuli\u00e8rement les citoyens avec leurs psychologies. PADD devient alors le complexe (au sens psychologique et militaire) de d\u00e9fense de la psychologie individuelle devant l&rsquo;horreur enfant\u00e9e par le syst\u00e8me dont elle est partie prenante. Litt\u00e9ralement, le canular-PADD est vrai : les Am\u00e9ricains deviennent individuellement malades \u00e0 cause du syst\u00e8me auquel ils souscrivent de tout leur \u00eatre, d&rsquo;une fa\u00e7on dite d\u00e9mocratique, et qui produit cette chose insens\u00e9e qu&rsquo;est la politique \u00e9trang\u00e8re am\u00e9ricaniste.<\/p>\n<\/p>\n<p><p>\tOn dirait que PADD-canular ou pas-canular n&rsquo;est pas vraiment nouveau. Nous citons toujours l&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1141\" class=\"gen\">identification de la n\u00e9vrose<\/a>, dite mal am\u00e9ricain, par le docteur Beard en 1879 comme premi\u00e8re intervention du constat du psychologue  apr\u00e8s les remarques finement intuitives de l&rsquo;humaniste-sociologue Tocqueville  sur les rapports de la psychologie individuelle avec un syst\u00e8me librement consenti, qui attaque fondamentalement l&rsquo;\u00e9quilibre de cette psychologie individuelle (la n\u00e9vrose \u00e9tant le r\u00e9sultat de cette confrontation). Mais nous sommes au-del\u00e0 de Tocqueville et de Beard, quoique toujours dans leur piste logique de visionnaires. Aujourd&rsquo;hui, dans la situation folle o\u00f9 nous nous trouvons, les moyens de communication qui bombardent massivement (<em>carpet bombing<\/em>, si am\u00e9ricaniste) les psychologies de faits, d\u00e9guis\u00e9s ou pas, d\u00e9form\u00e9s ou r\u00e9els, poussent au paroxysme cette confrontation n\u00e9vrotique. <\/p>\n<\/p>\n<p><p>\tConclusion : si PADD n&rsquo;existe pas, il est temps de l&rsquo;inventer comme simple constat de la r\u00e9alit\u00e9, par exemple \u00e0 partir du canular. Les voies de la v\u00e9rit\u00e9, dans notre \u00e9trange temps historique, sont imp\u00e9n\u00e9trables ; mais elles sont bien l\u00e0.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PADD : Si non \u00e8 vero 30 juin 2007 Ce texte nous a arr\u00eat\u00e9s, intrigu\u00e9s, enthousiasm\u00e9s, confondus, d\u00e9gris\u00e9s, mais pas pour longtemps D&rsquo;abord, nous n&rsquo;en croyions pas notre lecture puis nous y avons cru puis nous avons dout\u00e9. Dans tous les cas, chapeau bas \u00e0 l&rsquo;auteur, soit pour le montage, soit pour le canular, soit&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[6804,6803,3099,610],"class_list":["post-68955","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-hirschhorn","tag-padd","tag-psychologie","tag-virtualisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=68955"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68955\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=68955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=68955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=68955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}