{"id":68968,"date":"2007-07-04T00:00:00","date_gmt":"2007-07-04T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2007\/07\/04\/dead-on-a-fourth-of-july\/"},"modified":"2007-07-04T00:00:00","modified_gmt":"2007-07-04T00:00:00","slug":"dead-on-a-fourth-of-july","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2007\/07\/04\/dead-on-a-fourth-of-july\/","title":{"rendered":"<strong><em> \u201cDead on a Fourth of July\u201d\u2026 ?<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\"><em>Dead on a Fourth of July<\/em> ?<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t4 juillet 2007  Un communiqu\u00e9 du candidat r\u00e9publicain \u00e0 la pr\u00e9sidence Ron Paul, diffus\u00e9 pour le 4 juillet (la f\u00eate nationale<\/p>\n<\/p>\n<p><p>\t des USA), restitue justement l&rsquo;enjeu de la crise qui d\u00e9chire les USA aujourd&rsquo;hui. (Nous soulignons en gras la phrase qui nous para\u00eet la plus importante.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>&#8230; I believe there is no way to square our nation&rsquo;s traditions and reverence for independence, with the globalist policies [the] elites are currently pursuing. The American concept of independent nationhood inscribed in our Declaration cannot be maintained, if we are going to pursue a policy that undermines the independence of other nations. National independence is an idea, and the erosion of the independence of other nations only serves to erode that idea.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>At the same time, if we allow the erosion of that idea, by ignoring it in certain instances, we will be contributing to its erosion in all times and nations, even our own. In this way our nation&rsquo;s independence is linked with the independence of all nations&#8230; Only the safe-guards and limitations that are enshrined in a constitutionally-limited republic can prohibit a nation from lurching toward empire&#8230; Only by recapturing the spirit of independence can we ensure<\/em> <strong><em>our government never resembles the one from which the American States declared their separation.<\/em><\/strong>\u00bb<\/p>\n<\/p>\n<p><p>\tA c\u00f4t\u00e9 de ce jugement abrupt sur la situation des USA, on trouve les signes de cette situation notamment dans la crise de la pr\u00e9sidence GW Bush, de son actuelle impopularit\u00e9, dans ce que <em> The Independent<\/em>  <a href=\"http:\/\/news.independent.co.uk\/world\/americas\/article2733246.ece\" class=\"gen\">d&rsquo;aujourd&rsquo;hui<\/a> appelle une \u00ab<em>Imploding presidency<\/em>\u00bb, enfin dans ce chiffre sans pr\u00e9c\u00e9dent de l&rsquo;indice statistique fondamental de l&rsquo;\u00e9tat d&rsquo;esprit des Am\u00e9ricains : \u00ab<em>an unprecedented 74 per cent of Americans convinced the country is heading in the wrong direction.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Mr Bush&rsquo;s unpopularity is now challenging long established records. Some presidents briefly have been more disliked: Jimmy Carter slipped to a 21 per cent approval rating in July 1980, four months before he was trounced by Ronald Reagan in that year&rsquo;s election. But even at the height of opposition to the Vietnam War, Lyndon Johnson&rsquo;s approval ratings averaged above 40 per cent in 1967-68.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Not since Harry Truman in the early 1950s has a president been as unloved for as long as Mr Bush. He slipped below the 50 per cent mark in spring 2005, and for the past year and a half, he has been stuck in the mid-30s. In one poll he fell to 28 per cent, worse even than his father at his lowest before he lost to Bill Clinton in November 1992.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>With public dissatisfaction over Iraq continuing to grow, and the right track, wrong track barometer showing an unprecedented 74 per cent of Americans convinced the country is heading in the wrong direction, Mr Bush will probably remain deeply unpopular for the 18 months remaining until he leaves office in January 2009.<\/em>\u00bb<\/p>\n<h3>Une crise de l\u00e9gitimit\u00e9<\/h3>\n<\/p>\n<p><p>\tSelon la conception classique que nous avons d&rsquo;une crise, la crise am\u00e9ricaniste actuelle est bien entendu extr\u00eamement sp\u00e9cifique et \u00e9tonnante. Elle a d\u00e9marr\u00e9 \u00e0 partir d&rsquo;une position de puissance per\u00e7ue comme sans pr\u00e9c\u00e9dent (2002-2003), dont les param\u00e8tres essentiels n&rsquo;ont pas vraiment \u00e9t\u00e9 modifi\u00e9s depuis. M\u00eame l&rsquo;Irak reste, si l&rsquo;on consid\u00e8re ce conflit en termes de puissance et qu&rsquo;on le compare au poids de la puissance US, un probl\u00e8me mineur. Il s&rsquo;agit, pour comprendre la crise, de parler  essentiellement de la question de la perception.<\/p>\n<\/p>\n<p><p>\tD&rsquo;un point de vue diplomatique et militaire, la position qu&rsquo;occupaient les USA d&rsquo;une h\u00e9g\u00e9monie absolue dans les ann\u00e9es 2002-2003 pouvait \u00eatre ais\u00e9ment maintenue, dans les faits autant que dans la perception. C&rsquo;est l&rsquo;encha\u00eenement ininterrompu d&rsquo;erreurs de la part de l&rsquo;administration, soutenue d&rsquo;une fa\u00e7on massive par l&rsquo;<em>establishment<\/em> jusqu&rsquo;en 2006 (constitution de l&rsquo;Iraq Study Group et \u00e9lections <em>mid term<\/em>), qui a entra\u00een\u00e9 la perception de l&rsquo;effondrement de l&rsquo;h\u00e9g\u00e9monie US (qui n&rsquo;est pas automatiquement l&rsquo;effondrement de la puissance US). Aujourd&rsquo;hui encore, des analystes peuvent plaider justement que les facteurs essentiels de la puissance US subsistent. Pourtant, la psychologie US se trouve prise dans la perception d&rsquo;une crise profonde et radicale,  cette perception lui \u00e9tant confirm\u00e9e par le d\u00e9clin acc\u00e9l\u00e9r\u00e9 de la popularit\u00e9 et de l&rsquo;influence US dans le reste du monde.<\/p>\n<\/p>\n<p><p>\tLes deux facteurs soulign\u00e9s ci-dessous le montrent \u00e0 suffisance, comme deux exemples parmi tant d&rsquo;autres.<\/p>\n<\/p>\n<p><p>\t La phrase de Ron Paul (\u00ab<em>Only by recapturing the spirit of independence can we ensure our government never resembles the one from which the American States declared their separation<\/em>\u00bb) mesure effectivement la perte de confiance historique en cours dans la capacit\u00e9 et la l\u00e9gitimit\u00e9 du syst\u00e8me \u00e0 occuper la place centrale qu&rsquo;il occupe actuellement. La r\u00e9f\u00e9rence \u00e0 1776, le syst\u00e8me washingtonien prenant la place analogique de l&rsquo;Angleterre de George III tant d\u00e9test\u00e9e, est impressionnante et va au cur de l&rsquo;id\u00e9e \u00e9voqu\u00e9e ici.<\/p>\n<\/p>\n<p><p>\t Le pessimisme de 74% des Am\u00e9ricains sur l&rsquo;avenir de leur pays est un chiffre effrayant, qui touche l&rsquo;une des valeurs essentielles de la stabilit\u00e9 du r\u00e9gime : l&rsquo;optimisme de la population am\u00e9ricaine, r\u00e9duit aujourd&rsquo;hui \u00e0 une poign\u00e9e d&rsquo;irr\u00e9ductibles.  Bien entendu, il confirme, justifie et renforce le jugement de Ron Paul.<\/p>\n<\/p>\n<p><p>\tLa crise qui s&rsquo;est d\u00e9velopp\u00e9e essentiellement par la perception, donc au niveau psychologique, se transforme essentiellement en une crise de l\u00e9gitimit\u00e9 massive. L&rsquo;\u00e9volution est naturelle : la l\u00e9gitimit\u00e9 est d&rsquo;abord affaire de perception, c&rsquo;est un lien existant entre le citoyen et le pouvoir, qui donne \u00e0 ce pouvoir la l\u00e9gitimit\u00e9 de s&rsquo;exercer. Le pessimisme des Am\u00e9ricains renforce \u00e9videmment cette crise de la l\u00e9gitimit\u00e9 dans un pays qui n&rsquo;a pas de fondation historique r\u00e9galienne.<\/p>\n<\/p>\n<p><p>\tDes \u00e9volutions semblables d&rsquo;une crise d\u00e9marrant \u00e0 partir d&rsquo;une position de puissance semblant inexpugnable se sont produites dans l&rsquo;histoire US, dans un pays o\u00f9 perception et psychologie jouent un r\u00f4le essentiel. C&rsquo;est m\u00eame le seul type de crise s\u00e9rieuse qui semble pouvoir survenir. La crise de la Grande D\u00e9pression est \u00e9videmment l&rsquo;exemple qui vient \u00e0 l&rsquo;esprit, puisqu&rsquo;elle a d\u00e9marr\u00e9 alors que les USA se trouvaient au z\u00e9nith de leur puissance \u00e9conomique. Mais alors, un \u00e9v\u00e9nement r\u00e9el (l&rsquo;effondrement de Wall Street) a aussit\u00f4t identifi\u00e9 la crise en la d\u00e9clenchant. La crise elle-m\u00eame fut donc aussit\u00f4t un \u00e9v\u00e9nement identifiable qui a certes conduit l&rsquo;Am\u00e9rique au bord du gouffre mais qui a finalement donn\u00e9 un socle solide pour organiser une mobilisation et le redressement. On savait pourquoi l&rsquo;on se battait et comment il fallait se battre.<\/p>\n<\/p>\n<p><p>\tDans le cas actuel, les diff\u00e9rents aspects de la puissance \u00e9norme des USA, les divers r\u00e9seaux et s\u00e9curit\u00e9s qui les maintiennent ont contenu jusqu&rsquo;ici les possibilit\u00e9s d&rsquo;effondrement concret d&rsquo;un aspect de cette puissance. Bien entendu, la fiction de la guerre contre la terreur est impuissante \u00e0 fournir un socle de mobilisation ; la guerre en Irak \u00e9volue de mal en pis, \u00e9galement, sans provoquer de mobilisation sinon contre elle ; tous ces \u00e9v\u00e9nements sont trop d\u00e9risoires en termes de puissance r\u00e9elle par rapport \u00e0 la puissance US pour r\u00e9ellement provoquer l&rsquo;effondrement d&rsquo;un pan de cette puissance US. Mais ils sont suffisamment pressants et, surtout, ils entretiennent une perception d&rsquo;une puissance colossale de d\u00e9clin et de d\u00e9b\u00e2cle. Ils entretiennent ainsi dramatiquement la crise psychologique.<\/p>\n<\/p>\n<p><p>\tLa crise psychologique prosp\u00e8re sans trouver d&rsquo;exutoire. Ainsi en arrive-t-on naturellement, face \u00e0 cette crise apparemment sans cause identifiable, \u00e0 mettre en cause le centre du pouvoir. On en arrive \u00e0 une crise de l\u00e9gitimit\u00e9 qui est, historiquement, la crise qui met en cause un r\u00e9gime de mani\u00e8re fondamentale. C&rsquo;est ce qu&rsquo;exprime l&rsquo;atmosph\u00e8re plut\u00f4t sombre de ce 4 juillet.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dead on a Fourth of July ? 4 juillet 2007 Un communiqu\u00e9 du candidat r\u00e9publicain \u00e0 la pr\u00e9sidence Ron Paul, diffus\u00e9 pour le 4 juillet (la f\u00eate nationale des USA), restitue justement l&rsquo;enjeu de la crise qui d\u00e9chire les USA aujourd&rsquo;hui. (Nous soulignons en gras la phrase qui nous para\u00eet la plus importante.) \u00ab&#8230; I&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3493,3253,3228,3494,3140,6375,3310],"class_list":["post-68968","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-3493","tag-americanisme","tag-crise","tag-juillet","tag-paul","tag-pessimisme","tag-ron"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=68968"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68968\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=68968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=68968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=68968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}