{"id":68982,"date":"2007-07-07T00:00:00","date_gmt":"2007-07-07T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2007\/07\/07\/le-tres-haut-prix-de-la-tres-longue-guerre\/"},"modified":"2007-07-07T00:00:00","modified_gmt":"2007-07-07T00:00:00","slug":"le-tres-haut-prix-de-la-tres-longue-guerre","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2007\/07\/07\/le-tres-haut-prix-de-la-tres-longue-guerre\/","title":{"rendered":"Le tr\u00e8s haut prix de la tr\u00e8s Longue Guerre"},"content":{"rendered":"<p><p>De nouvelles \u00e9valuations et estimations ont \u00e9t\u00e9 faites sur le co\u00fbt <strong>direct<\/strong> des op\u00e9rations faites depuis le 11 septembre 2001 dans le cadre de ce que Washington nomme la Longue Guerre (<em>the Long War<\/em>), ou la Grande Guerre contre la Terreur (GWOT). Il s&rsquo;agit d&rsquo;\u00e9valuations faites par un organisme officiel, le Congressional Research Service, dans un rapport dat\u00e9 du <a href=\"http:\/\/blog.wired.com\/defense\/files\/RL33110.pdf\" class=\"gen\">28 juin<\/a> et dont l&rsquo;existence et le contenu sont r\u00e9v\u00e9l\u00e9s sur le site <em>Danger Room<\/em> le <a href=\"http:\/\/blog.wired.com\/defense\/2007\/07\/war-costs-soar-.html\" class=\"gen\">6 juillet<\/a>.<\/p>\n<\/p>\n<p><p>\tComme on peut s&rsquo;y attendre, les co\u00fbts ont notablement augment\u00e9, passant pour la seule guerre en Irak de $8,7 milliards \u00e0 $12 milliards par mois entre 2006 et 2007. Le rapport du CRS estime que la GWOT, ou Longue Guerre, atteindra en 2017 un co\u00fbt de $1.400 milliards depuis le 11 septembre 2001. Le site <em>Danger Room<\/em> r\u00e9sume les donn\u00e9es essentielles du rapport :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>It&rsquo;s not just the troops that are surging.  War costs are up for American operations in Iraq and Afghanistan  way up, more than a third higher than last year.  In the first half of this fiscal year, the Defense Department&rsquo;s average monthly obligations for contracts and pay is running about $12 billion per month, well above the $8.7 billion in FY2006, says a new report, obtained by Danger Room, from the non-partisan Congressional Research Service.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Additional war costs for the next  10 years could total about $472 billion if troop levels fall to 30,000 by 2010, or $919 billion if troop levels fall to 70,000 by about 2013.  If these estimates are added to already appropriated amounts, total funding about $980 billion to $1.4 trillion by 2017.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tCes estimations doivent \u00eatre appr\u00e9ci\u00e9es comme tr\u00e8s restrictives et tr\u00e8s mod\u00e9r\u00e9es. D&rsquo;une part, comme on l&rsquo;a not\u00e9, elle prennent en compte seulement les co\u00fbts directs de la guerre,  qui peuvent \u00eatre quasiment multipli\u00e9s par deux si l&rsquo;on prend en compte les cons\u00e9quences indirectes sur la programmation, sur l&rsquo;\u00e9volution budg\u00e9taire inflatoire du Pentagone et sur l&rsquo;endettement f\u00e9d\u00e9ral, etc. Elles prennent en compte la situation pass\u00e9e et nullement la dynamique inflatoire constamment en augmentation. A cet \u00e9gard, l&rsquo;indication la plus int\u00e9ressante est certainement l&rsquo;augmentation r\u00e9elle constat\u00e9e dans les d\u00e9penses mensuelles en Irak entre 2006 et 2007. <\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 7 juillet 2007 \u00e0 10H41<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De nouvelles \u00e9valuations et estimations ont \u00e9t\u00e9 faites sur le co\u00fbt direct des op\u00e9rations faites depuis le 11 septembre 2001 dans le cadre de ce que Washington nomme la Longue Guerre (the Long War), ou la Grande Guerre contre la Terreur (GWOT). Il s&rsquo;agit d&rsquo;\u00e9valuations faites par un organisme officiel, le Congressional Research Service, dans&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3767,6827,2645,4661,6588,5010,3477],"class_list":["post-68982","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-cout","tag-crs","tag-guerre","tag-gwot","tag-inflation","tag-longue","tag-prix"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=68982"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/68982\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=68982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=68982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=68982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}