{"id":69097,"date":"2007-08-07T00:00:00","date_gmt":"2007-08-07T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2007\/08\/07\/le-jugement-surprenant-est-ce-bien-sur-de-john-bolton\/"},"modified":"2007-08-07T00:00:00","modified_gmt":"2007-08-07T00:00:00","slug":"le-jugement-surprenant-est-ce-bien-sur-de-john-bolton","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2007\/08\/07\/le-jugement-surprenant-est-ce-bien-sur-de-john-bolton\/","title":{"rendered":"Le jugement surprenant (est-ce bien s\u00fbr?) de John Bolton"},"content":{"rendered":"<p><p>Le <em>Financial Times<\/em> a l&rsquo;habitude d&rsquo;organiser, apr\u00e8s la publication de certains articles de contributeurs ext\u00e9rieurs, des d\u00e9bats entre les auteurs et les lecteurs. Ce fut le cas pour John Bolton, \u00e0 propos de son article du <a href=\"http:\/\/www.ft.com\/cms\/s\/3259025a-3f73-11dc-b034-0000779fd2ac.html\" class=\"gen\">31 juillet<\/a> sur les relations entre les USA et le Royaume-Uni avec l&rsquo;arriv\u00e9e de Gordon Brown \u00e0 la t\u00eate du gouvernement UK. Nous avons effectivement <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4285\" class=\"gen\">parl\u00e9<\/a> de cet article en m\u00eame temps que d&rsquo; <a href=\"http:\/\/www.telegraph.co.uk\/opinion\/main.jhtml;jsessionid=GR0Q23XYQNHU3QFIQMFSFFOAVCBQ0IV0?xml=\/opinion\/2007\/08\/01\/do0102.xml\" class=\"gen\">un autre<\/a>, allant dans le m\u00eame sens, d&rsquo;Irwin Stelzer.<\/p>\n<\/p>\n<p><p>\tLe d\u00e9bat Bolton-public sous les auspices du FT a donc eu lieu le <a href=\"http:\/\/www.ft.com\/cms\/s\/bfc11676-3f89-11dc-b034-0000779fd2ac.html\" class=\"gen\">6 ao\u00fbt<\/a>. Nous confirmons \u00e0 cette occasion ce que nous ressentons de l&rsquo;intervention de Bolton (inhabituellement mesur\u00e9e m\u00eame s&rsquo;il dit droitement quelques v\u00e9rit\u00e9s qui peuvent appara\u00eetre mena\u00e7antes ou d\u00e9plac\u00e9es), contrairement \u00e0 <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4291\" class=\"gen\">l&rsquo;interpr\u00e9tation<\/a> qu&rsquo;en donn\u00e8rent certains commentateurs am\u00e9ricains.<\/p>\n<\/p>\n<p><p>\tUne r\u00e9ponse de Bolton nous a particuli\u00e8rement int\u00e9ress\u00e9s par l&rsquo;int\u00e9ressante ambigu\u00eft\u00e9 qu&rsquo;elle soul\u00e8ve. Il s&rsquo;agit d&rsquo;une r\u00e9ponse \u00e0 une question d&rsquo;un Am\u00e9ricain, Carl Fitz, du Texas, sur la France de Sarkozy, sur les liens USA-France par rapport aux liens USA-UK et ainsi de suite.<\/p>\n<\/p>\n<p><p>\t\u00ab<strong><em>Carl Fitz:<\/em><\/strong> <em>Considering Sarkozy&rsquo;s election in France is expected to usher in a new age of French-American relations, and there is a fear of Gordon Brown distancing the UK from the US, what type of implications does this have for the US in terms of its relations with other EU members? Is it a possibility that the US could form stronger ties with France than the UK in the near future?<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<strong><em>John Bolton:<\/em><\/strong> <em>My experience in diplomatic dealings with France over many years is that France unfailingly pursues what Paris sees as its core national interests. While such an approach has often put France at odds with the United States, it is at least straightforward and intellectually honest. I respect it.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>By contrast, too often in recent years, and frequently in the United Nations, the UK position, as defined by the FCO, has been ideological rather than national, pursuing what the international High Minded set calls global governance.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Given the choice, vive la France!<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tRemarquez combien Bolton <strong>ne r\u00e9pond pas<\/strong> directement \u00e0 la question pos\u00e9e, mais comment il y r\u00e9pond finalement d&rsquo;une fa\u00e7on indirecte qui est bien plus r\u00e9v\u00e9latrice qu&rsquo;une r\u00e9ponse directe. Remarquez comment il exp\u00e9die sans m\u00eame s&rsquo;y attarder une seconde la tarte \u00e0 la cr\u00e8me de Sarko l&rsquo;Am\u00e9ricain et de l&rsquo;alignement de la France sur les USA, pour aller au plus fondamental. C&rsquo;est instructif.<\/p>\n<\/p>\n<p><p>\tD\u00e9taillons sa r\u00e9ponse.<\/p>\n<\/p>\n<p><p>\t Bolton a eu le loisir d&rsquo;\u00e9tudier le comportement des Fran\u00e7ais \u00e0 l&rsquo;ONU. Il appr\u00e9cie dans leur d\u00e9marche une politique qui est la recherche constante de l&rsquo;int\u00e9r\u00eat national fran\u00e7ais. Il respecte et m\u00eame appr\u00e9cie cette politique m\u00eame si elle conduit la France, dans telle ou telle circonstance, \u00e0 s&rsquo;opposer aux USA.<\/p>\n<\/p>\n<p><p>\t Au contraire, il estime que la politique britannique r\u00e9pond non aux int\u00e9r\u00eats nationaux britanniques mais \u00e0 une id\u00e9ologie qui est celle de la globalisation, de la <em>global governance<\/em> (dans ce cas, \u00e9ventuellement l&rsquo;ONU). Surprise, pour ceux qui ont du Royaume-Uni l&rsquo;image d&rsquo;un pays au nationalisme sourcilleux, type <em>right ot wrong, my country<\/em>? Peut-\u00eatre, mais surprise seulement en apparence. Il est vrai qu&rsquo;avec Blair, le Royaume-Uni s&rsquo;est fortement id\u00e9ologis\u00e9e, et il affiche aujourd&rsquo;hui une compl\u00e8te faveur pour un lib\u00e9ralisme sans frein (avec l&rsquo;effondrement de l&rsquo;orientation nationale de certaines de ses valeurs industrielles) ainsi que pour les th\u00e8ses n\u00e9o-imp\u00e9rialistes \u00e0-la-<a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=171\" class=\"gen\">Cooper<\/a>, dont s&rsquo;inspire l&rsquo;UE, et qui sont appuy\u00e9es sur la n\u00e9gation de la souverainet\u00e9 nationale. Bolton, en, bon unilat\u00e9raliste, ne go\u00fbte pas cette \u00e9volution. (Notre appr\u00e9ciation est que cette \u00e9volution britannique est en fait un faux-nez au d\u00e9part: dissimuler l&rsquo;humiliation de devoir sacrifier des int\u00e9r\u00eats nationaux \u00e0 l&rsquo;alignement constant sur les USA en trouvant particuli\u00e8rement intelligent cet exercice par un habillage id\u00e9ologique qui permet de tels \u00e9carts; lequel faux-nez, \u00e0 force, est devenue une v\u00e9ritable id\u00e9ologie \u00e0 laquelle le Royaume-Uni est d\u00e9sormais encha\u00een\u00e9, en compl\u00e8te contradiction avec sa tradition).<\/p>\n<\/p>\n<p><p>\t La conclusion de Bolton est incroyablement ambigu\u00eb. Dans la logique de la question pos\u00e9e, la phrase-pirouette \u00ab<em>Given the choice, vive la France!<\/em>\u00bb signifie bien : Si je pouvais choisir mon alli\u00e9 privil\u00e9gi\u00e9, ce serait la France (et non le Royaume-Uni). Mais il sait bien, Bolton, qu&rsquo;il n&rsquo;a pas le choix puisqu&rsquo;il vient de d\u00e9finir la France, avec une certaine admiration, comme une nation ind\u00e9pendante dont la d\u00e9fense de ses int\u00e9r\u00eats la place \u00e9pisodiquement et m\u00eame r\u00e9guli\u00e8rement en opposition aux USA,  et alors, ce ne peut \u00eatre l&rsquo;alli\u00e9 privil\u00e9gi\u00e9 que Washington a avec le Royaume-Uni. Cela nous confirme bien plus qu&rsquo;un tr\u00e8s long discours ce qu&rsquo;est, pour le Royaume-Uni, l&rsquo;alliance avec les USA: la suj\u00e9tion et rien d&rsquo;autre. Bolton ne le dit pas mais il nous le fait comprendre, comme il nous fait comprendre que les gens s\u00e9rieux,  pour cette fois, lui-m\u00eame appara\u00eet s\u00e9rieux dans son jugement,  n&rsquo;ont rien \u00e0 attendre de la France de Sarkozy (de la France tout court, puisqu&rsquo;elle est ind\u00e9pendante) qui ait quelque chose de commun avec le comportement des Britanniques. D&rsquo;autre part, et plac\u00e9e dans le contexte o\u00f9 elle se trouve des jugements sur les politiques des deux pays, la phrase-pirouette \u00ab<em>Given the choice, vive la France!<\/em>\u00bb n&rsquo;est plus du tout une r\u00e9ponse, m\u00eame indirecte, \u00e0 la question pos\u00e9e et signifie \u00e9galement: entre les deux comportements politiques, celui de la France et celui du Royaume-Uni, c&rsquo;est celui de la France que je pr\u00e9f\u00e8re. Les deux interpr\u00e9tations sont acceptables et, d&rsquo;ailleurs, elles se compl\u00e8tent et se confirment. Elles nous disent qu&rsquo;aux yeux de Bolton, le Royaume-Uni n&rsquo;est qu&rsquo;un pays soumis dissimulant sa soumission sous une id\u00e9ologie pompeuse tandis que la France a le comportement d&rsquo;une vraie puissance, \u00e0 l&rsquo;image du comportement US selon le nationaliste qu&rsquo;est Bolton. Rien \u00e0 redire.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 7 ao\u00fbt 2007 \u00e0 16H59<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Financial Times a l&rsquo;habitude d&rsquo;organiser, apr\u00e8s la publication de certains articles de contributeurs ext\u00e9rieurs, des d\u00e9bats entre les auteurs et les lecteurs. Ce fut le cas pour John Bolton, \u00e0 propos de son article du 31 juillet sur les relations entre les USA et le Royaume-Uni avec l&rsquo;arriv\u00e9e de Gordon Brown \u00e0 la t\u00eate&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[1092,2851,2687,3345,3344,2852,2758],"class_list":["post-69097","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-bolton","tag-financial","tag-france","tag-relationships","tag-special","tag-times","tag-uk"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69097"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69097\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}