{"id":69105,"date":"2007-08-11T00:00:00","date_gmt":"2007-08-11T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2007\/08\/11\/cest-nous-us-et-le-chaos\/"},"modified":"2007-08-11T00:00:00","modified_gmt":"2007-08-11T00:00:00","slug":"cest-nous-us-et-le-chaos","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2007\/08\/11\/cest-nous-us-et-le-chaos\/","title":{"rendered":"C&rsquo;est nous (\u201cUS\u201d) et le chaos"},"content":{"rendered":"<p><h2 class=\"common-article\">C&rsquo;est nous (<em>US<\/em>) <strong><em>et<\/em><\/strong> le chaos<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t11 ao\u00fbt 2007  Un de nos lecteurs, Miquet, que nous remercions, nous signale sur le <em>Forum<\/em> du <a href=\"http:\/\/www.dedefensa.org\/forum.php\" class=\"gen\">9 ao\u00fbt<\/a> la deuxi\u00e8me partie d&rsquo;une longue analyse d&rsquo;Axel Brot (en fait : nom de plume pour un ancien analyste et officier du renseignement allemand,  et certaines pr\u00e9cisions circonstanci\u00e9es confirment cette identification).<\/p>\n<\/p>\n<p><p>\tCet \u00e9norme travail d&rsquo;Axel Brot est en fait un v\u00e9ritable essai mis en ligne sur le site <em>Atimes.com<\/em> (trois parties les <a href=\"http:\/\/www.atimes.com\/atimes\/Front_Page\/IH08Aa01.html\" class=\"gen\"><\/p>\n<\/p>\n<p><p>\t8 ao\u00fbt<\/a>, 9 ao\u00fbt et <a href=\"http:\/\/atimes.com\/atimes\/Front_Page\/IH10Aa01.html\" class=\"gen\">10 ao\u00fbt<\/a>,  nous parlons ici essentiellement de la  deuxi\u00e8me partie, du <a href=\"http:\/\/atimes.com\/atimes\/Front_Page\/IH09Aa01.html\" class=\"gen\">9 ao\u00fbt<\/a>  et l&rsquo;ensemble comptant autour de 115.000 signes). Ce travail m\u00e9rite notre attention essentiellement pour un des passages de cette deuxi\u00e8me partie du 9 ao\u00fbt.<\/p>\n<\/p>\n<p><p>\tSi l&rsquo;on s&rsquo;en r\u00e9f\u00e8re \u00e0 l&rsquo;identification des fonctions de l&rsquo;auteur, la partie qui nous int\u00e9resse dans cette longue analyse appara\u00eet comme un effort d&rsquo;analyse majeur venu d&rsquo;un auteur li\u00e9 \u00e0 la bureaucratie de s\u00e9curit\u00e9 nationale d&rsquo;un pays de l&rsquo;Ouest europ\u00e9en traditionnel concernant le <strong>seul<\/strong> sujet de fond qui importe aujourd&rsquo;hui. La personnalit\u00e9 de l&rsquo;auteur \u00e9carte la tonalit\u00e9 pol\u00e9mique habituelle, et les soup\u00e7ons de manque de s\u00e9rieux qui s&rsquo;y rattachent. Dans notre temps historique en  r\u00e9alit\u00e9 si simpliste et si compl\u00e8tement marqu\u00e9 par l&rsquo;extr\u00eame radicalisation des perspectives, ce <strong>seul<\/strong> sujet de fond qui importe aujourd&rsquo;hui est ce que nous d\u00e9signerions comme la folie de l&rsquo;Ouest  c&rsquo;est-\u00e0-dire la folie de la civilisation occidentale suscit\u00e9e dans une mesure importante, voire essentielle, voire exclusive, par la folie centrale du syst\u00e8me de l&rsquo;am\u00e9ricanisme.<\/p>\n<\/p>\n<p><p>\tPour cette raison, nous reprenons le passage qui nous semble essentiel de cette analyse (doublant sa pr\u00e9sence sur le <em>Forum<\/em> mais il est bon de faire figurer ce passage dans plusieurs rubriques de <em>dedefensa.org<\/em>). Il concerne effectivement l&rsquo;\u00e9tat d&rsquo;esprit, ou plut\u00f4t l&rsquo;\u00e9tat de la psychologie de l&rsquo;<em>establishment<\/em> am\u00e9ricaniste. Il concerne en tous points ce que nous percevons de cette situation, caract\u00e9ris\u00e9e par l&rsquo;image historique classique de l&rsquo;exp\u00e9dition Cortez en Am\u00e9rique au XVI\u00e8me si\u00e8cle: ils ont br\u00fbl\u00e9 leurs vaisseaux derri\u00e8re eux Ils en sont en train de d\u00e9truire les ponts qui les relient encore \u00e0 ce qu&rsquo;il leur reste de raison (\u00ab<em>They are already competing in burning the bridges to a somewhat more patient approach<\/em>\u00bb). Axel Brot se concentre sur le cas allemand, en cours d&rsquo;infection juge-t-il par la folie am\u00e9ricaniste, mais nous pensons que le centre de tout est bien cette folie am\u00e9ricaniste. L&rsquo;auteur s&rsquo;y attache ici, en ouverture du deuxi\u00e8me volet de son essai.<\/p>\n<h3>\u00ab<strong><em>Broken machinery<\/em><\/strong><\/h3>\n<\/p>\n<p><p>\t\u00bb<em>The American political class seems to have drawn all the wrong conclusions from the end of the Cold War and the breakup of the Soviet Union. Its leisurely stroll towards permanent global hegemony just did not happen. Thus, frustration and the craving for revenge have become main drivers of US policies. The events of September 11 focused their common dysfunctionality, but they are not its root cause.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>It is from this vantage point that arises the resigned and poignant expectation that the US will permit neither a stable Russia nor a non-cataclysmic accommodation of China&rsquo;s rise. American politics now have just enough flexibility to negotiate the short-term priorities of whom to put under the pressure of regime-changing demands; but the system is rigged not to reward persuasion or accommodation but toward increasing confrontation, deadline diplomacy, and grandstanding on principles that carry the load of broken credibility.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Notwithstanding the worthy efforts of the Iraq Study Group or the Princeton Project on National Security to get some means-to-ends rationality back into US policies, politics are impaired by the lack of discipline and prudence that come with the reinforcement of the imperial mind-set of official Washington by the media and think tanks.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Unfortunately, this mind-set is not only the defining attribute of the present administration but of both parties  and abundantly so, of the serious contenders for the next US presidency. They are already competing in burning the bridges to a somewhat more patient approach to imperial policies while berating the present administration for its weakness. Different combinations of bombing Iran, breaking Hezbollah, confronting the Russians, sanctioning the Chinese, squeezing the Saudis and Pakistanis, pressuring the Indians into a subordinate relationship, installing an accountable dictatorship in Iraq (and\/or taking it apart), are on the menu of the main candidates  plus unfettering US soft power and hitching the allies more effectively to whatever load is to be pulled.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>It is therefore all too easy to see in the current travails of global diplomacy efforts to adapt to the implicit American choice of either the US or chaos. But the lessons are not only Iraq and Afghanistan, but the failed attempts of Serbia (1999), Iran (2003) and Syria (ongoing), to bow to US\/Western demands while keeping a measure of independence and dignity. In fact, looking at the last 16 years or so, at the fate of the former Soviet Union in the 1990s, of the former Yugoslavia, and of Iraq or Afghanistan, they may come to the conclusion that they have nothing to lose even in a military confrontation.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>And since the march of empire is tuned to the racial  alias civilizational  superiority (of the Anglosphere), non-Western elites may interpret this choice as the US and chaos. If it is their ambition just to loot their countries and then to set-up shop in one of the Western tax-sheltered playgrounds or to turn into sharecroppers of their countries\u00b4 resources, the choice is a good one. If they are at all attentive, reasonably patriotic, and have a measure of pride, they cannot but resist it.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>It is, in the last analysis, also a question of self-esteem and a sense of historical accountability. Can elites in their right mind bear to be the butt of a sardonic witticism like the one going around among Anglo-Saxon officials, targeting the Saudi combination of immense corruption and paying immense protection money: the Saudis prefer to suffocate on their knees instead of dying on their feet.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>But contempt and the lust for chaos (creative destruction) have become the coin of the realm. They are heated by fantasies of a global caste society where The Shield of Achilles, Imperial Grunts, Left Behind, and The Diamond Age are busy cross-pollinating the imperial imagination. One might add that a Pentagon (Office for Net Assessment) study of the consequences of climate change provides a window into the darkest, survivalist corner of this mind-set and implies, in addition, an answer to the questions who is the West? and who is superfluous?<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The return with a vengeance of the covert operations approach to US international policies, therefore, has much more to do with this sinister self-fictionalization than with the nature of threats or the simple availability of the instruments. While for most periods of the Cold War, concerns about exposure, blowback, and provoking war with the Soviets kept it somewhat under control, it has slipped the leash. Everyone who can has gone into business. It is not only the White House that is exceedingly liberal in its use of privateers, frequently retreaded intelligence and military officials who should have been disposed of out of harm&rsquo;s way<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tR\u00e9sumons par quelques points :<\/p>\n<\/p>\n<p><p>\t Le syst\u00e8me US est bloqu\u00e9 dans une position, involontaire et irr\u00e9sistible parce que d\u00e9pendante d&rsquo;une psychologie frustr\u00e9e et malade (\u00ab<em>Thus, frustration and the craving for revenge have become main drivers of US policies<\/em>\u00bb), qui se ram\u00e8ne \u00e0 la situation du aucun retour en arri\u00e8re n&rsquo;est possible. C&rsquo;est effectivement la strat\u00e9gie \u00e0 la Cortez qui br\u00fblait ses vaisseaux pour \u00e9carter toute tentation de retour en arri\u00e8re, mais transcrite en une psychologie. Ils br\u00fblent leurs vaisseaux parce qu&rsquo;ils ne savent plus comment les manier, comment retourner en arri\u00e8re vers la raison. Le cas est psychiatrique plus que strat\u00e9gique. En principe, Cortez savait ce qu&rsquo;il faisait,  eux, pas.<\/p>\n<\/p>\n<p><p>\t Le programme qui en d\u00e9coule est simple : non pas <MI>The US or the chaos<M> comme on aimerait faire croire mais bien <M>The US AND the chaos<D>,  ou mieux dit encore : <em>The chaos BECAUSE the US<\/em>. (Traduisons pour cette fois : le chaos A CAUSE des USA.)<\/p>\n<\/p>\n<p><p>\t Cette psychologie infect\u00e9e touche absolument tout l&rsquo;<em>establishment<\/em> washingtonien, donc tous les candidats pour novembre 2008 (sauf peut-\u00eatre un <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4298\" class=\"gen\">Ron Paul<\/a>?). Nous n&rsquo;avons rien \u00e0 esp\u00e9rer avec le d\u00e9part de Bush. Par sa puissance et sa perception totalitaire, cette infection de la psychologie, cet encha\u00eenement psychologique au totalitarisme du syst\u00e8me emp\u00eache toute vision \u00e0 long terme (\u00ab<em>American politics now have just enough flexibility to negotiate the short-term priorities<\/em>\u00bb), par cons\u00e9quent toute mesure contre les cons\u00e9quences et les fondements de cette folie. Aucun nouveau pr\u00e9sident issu du syst\u00e8me et psychologiquement infect\u00e9 par lui ne pourra rien y changer; d&rsquo;ailleurs, puisque le mal est psychologique, il ne songera pas \u00e0 le faire.<\/p>\n<\/p>\n<p><p>\t Tous les aspects structurels et comportementaux sont touch\u00e9s : les politiques, les mouvements de personnels, les int\u00e9r\u00eats bureaucratiques, les connexions entre les pouvoirs politiques, le monde \u00e9conomique, le monde ill\u00e9gal, la corruption, les familles d&rsquo;int\u00e9r\u00eat ou de proximit\u00e9, etc.,  tout cela est absolument affect\u00e9 par ce mouvement belliciste et d\u00e9structurant. C&rsquo;est toute une soci\u00e9t\u00e9 politique de puissance qui est encha\u00een\u00e9e \u00e0 un effort dont m\u00eame les ralliements obtenus provoquent des violences supp\u00e9mentaires (\u00ab<em> but the system is rigged not to reward persuasion or accommodation but toward increasing confrontation, deadline diplomacy, and grandstanding on principles that carry the load of broken credibility<\/em>\u00bb).<\/p>\n<\/p>\n<p><p>\t Les perspectives sont implicitement d\u00e9crites comme apocalyptiques, notamment si l&rsquo;on consid\u00e8re ce que l&rsquo;appareil de pr\u00e9vision du syst\u00e8me pr\u00e9dit des cons\u00e9quences de la crise climatique au niveau de la s\u00e9curit\u00e9. La porte est ouverte \u00e0 des politiques d&rsquo;extermination et\/ou des politiques suicidaires. Il n&rsquo;y a rien d&rsquo;\u00e9tonnant : les perspectives <strong>ne peuvent \u00eatre<\/strong> qu&rsquo;apocalyptiques car la vision est r\u00e9duite \u00e0 la survivance du syst\u00e8me,  avec un m\u00e9lange extraordinaire et extraordinairement explosif de sophistication (soci\u00e9t\u00e9 \u00e0 pr\u00e9tention d&rsquo;\u00eatre tr\u00e8s avanc\u00e9e et capable d&rsquo;un contr\u00f4le tr\u00e8s \u00e9tendue) et de primarit\u00e9 (vision parano\u00efaque de survivance). La question essentielle revient toujours \u00e0 la psychologie : s&rsquo;agit-il d&rsquo;une vision bas\u00e9e sur des faits objectifs ou bien d&rsquo;une vision d&rsquo;une psychologie malade bas\u00e9e sur des faits provoqu\u00e9s par cette m\u00eame psychologie malade? La diff\u00e9rence entre les deux questions ne nous \u00e9vitera pas n\u00e9cessairement l&rsquo;apocalypse (terme pris dans un sens symbolique plus que factuel) mais influera sans aucun doute sur la forme et la chronologie de cette apocalypse. En d&rsquo;autres termes : l&rsquo;apocalypse aura-t-elle lieu d&rsquo;abord dans le reste du monde ou d&rsquo;abord \u00e0 Washington D.C.? <\/p>\n<\/p>\n<p><p>\tPour compl\u00e9ter un des aspects essentiels de cette analyse, qui est la constante de la politique destructrice des USA au-del\u00e0 de GW Bush, qui est selon nous l&rsquo;apport principal de ces textes, nous ajouterons un passage d&rsquo;une chronique du <a href=\"http:\/\/www.timesonline.co.uk\/tol\/comment\/columnists\/gerard_baker\/article2231334.ece\" class=\"gen\">10 ao\u00fbt<\/a> d&rsquo;un journaliste connu comme \u00e9tant un relais direct de l&rsquo;am\u00e9ricanisme dans les pages du <em>Times<\/em>. Il s&rsquo;agit de Gerard Bake et l&rsquo;extrait concerne le futur pr\u00e9sident des USA (et d\u00e9j\u00e0 cit\u00e9 par nous <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4307\" class=\"gen\">par ailleurs<\/a>). Dit en des termes plus diplomatique que ceux de Brot, il dit pourtant la m\u00eame chose :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The Democratic contenders for the presidency  whether it is Barack Obama promising to invade Pakistan if he deems it necessary to win the War on Terror, or Hillary Clinton trying to sound like General Patton over Iran and other potential threats  have figured out that Americans may want a different president but they still don&rsquo;t want to outsource foreign policy to the United Nations or the European Union.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Winning plaudits from the Labour Left and the Brussels bureaucracy by sniffing noisily at Bush foreign policy is easy politics but not a substitute for serious decision-making. We have already seen with the unfolding disaster in Basra, where Britain has for largely domestic political reasons opted out of a difficult military mission, that such decisions lead to disastrous foreign policy in practice.<\/em>\u00bb<\/p>\n<h3>L&rsquo;impasse de l&rsquo;analyse rationnelle des actes et des effets des actes d&rsquo;une psychologie malade <\/h3>\n<\/p>\n<p><p>\tD&rsquo;abord, il est important de constater qu&rsquo;un ancien fonctionnaire ou fonctionnaire en poste mais anonyme puisse songer \u00e0 publier une telle analyse, et qu&rsquo;il en soit venu, dans la position o\u00f9 il se trouverait (au sein de la bureaucratie du renseignement) \u00e0 une telle analyse de l&rsquo;\u00e9tat des lieux et surtout des psychologies \u00e0 Washington D.C. L&rsquo;analyse n&rsquo;est pas pour nous surprendre puisqu&rsquo;elle est n\u00f4tre depuis un temps assez long.<\/p>\n<\/p>\n<p><p>\tMais cette analyse est justement le travail d&rsquo;un analyste. M\u00eame si l&rsquo;objet de la description est une affection extr\u00eame de ce qui se rapproche \u00e0 grands pas d&rsquo;une folie suicidaire, le jugement a tendance \u00e0 d\u00e9duire de l&rsquo;acte de cette quasi-folie suicidaire et compl\u00e8tement irrationnelle des comportements et des effets rationnels qui donnent une image \u00e0 notre sens compl\u00e8tement th\u00e9orique et artificielle de la situation prospective. C&rsquo;est un travers classique de l&rsquo;analyse du renseignement et de l&rsquo;incapacit\u00e9 de l&rsquo;esprit des experts occidentaux de comprendre la nouvelles forme de conflit \u00e0 laquelle ils sont confront\u00e9s. Ils continuent \u00e0 raisonner en termes g\u00e9opolitiques d&rsquo;espaces conquis, contr\u00f4l\u00e9s ou occup\u00e9s, et nullement en termes psychopolitiques.<\/p>\n<\/p>\n<p><p>\tPar exemple, les pr\u00e9sences US (et occidentales) en Irak et en Afghanistan sont per\u00e7ues comme des positions strat\u00e9giques importantes, sinon des succ\u00e8s par cons\u00e9quent. De m\u00eame, les affirmations sur la mission des arm\u00e9es occidentales de se lancer dans des guerres approchant les guerres d&rsquo;extermination qui vont naturellement r\u00e9duire l&rsquo;adversaire (?) n&rsquo;ont aucun sens. Les guerres en cours sont moins des guerres de tueries que des guerres de d\u00e9sordre ; moins des actes de destruction de l&rsquo;ennemi que des actes de d\u00e9structuration de tout le th\u00e9\u00e2tre, affectant \u00e9galement et \u00f4 combien les arm\u00e9es occidentales, la psychologie occidentale et les int\u00e9r\u00eats occidentaux. Elles d\u00e9montrent plus des incapacit\u00e9s que des capacit\u00e9s. L&rsquo;arm\u00e9e US est totalement incapable d&rsquo;imposer en Irak le contr\u00f4le que les Allemands exerc\u00e8rent sur la Pologne entre septembre 1939 et juin 1944, et qu&rsquo;ils perdirent \u00e0 cause de l&rsquo;Arm\u00e9e Rouge. Les Am\u00e9ricains n&rsquo;ont jamais assur\u00e9 le moindre contr\u00f4le de l&rsquo;Irak, sans qu&rsquo;il soit n\u00e9cessaire de leur opposer une Arm\u00e9e Rouge. L&rsquo;Irak est pour eux un abc\u00e8s de fixation dont l&rsquo;infection les ronge alors que la Pologne \u00e9tait pour l&rsquo;Allemagne une base d&rsquo;attaque contre l&rsquo;URSS.<\/p>\n<\/p>\n<p><p>\tIl y a dans ces analyses l&rsquo;habituel cloisonnement affectant le jugement des analystes, comme il affecte les structures des services de renseignement,  et sans doute en est-il le double intellectuel :<\/p>\n<\/p>\n<p><p>\t Cloisonnement entre les actes de politique ext\u00e9rieure et la situation de politique int\u00e9rieure de ceux qui dirigent cette politique ext\u00e9rieure. Croit-on qu&rsquo;on pourra supporter longtemps la contradiction entre les deux dans un syst\u00e8me si compl\u00e8tement caract\u00e9ris\u00e9 par les communications, la circulation de l&rsquo;information et le discr\u00e9dit de l&rsquo;information officielle? Si Brot pr\u00e9sente sans pour l&rsquo;instant en tirer de conclusion sp\u00e9cifique le cas allemand (<em>establishment<\/em> \u00e9voluant vers la mentalit\u00e9 US de guerre sans fin contre opinion publique de plus en plus anti-am\u00e9ricaniste et anti-belliciste bien plus que pacifiste), on peut d&rsquo;ores et d\u00e9j\u00e0 observer le cas britannique o\u00f9 la situation int\u00e9rieure a d\u00e9j\u00e0 conduit le nouveau Premier ministre \u00e0 incurver sa politique d&rsquo;une fa\u00e7on qui est per\u00e7ue par les USA comme de plus en plus <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4307\" class=\"gen\">antagoniste<\/a> de la politique US. <\/p>\n<\/p>\n<p><p>\t Cloisonnement entre les actes de cette politique ext\u00e9rieure et les effets de ces actes sur la situation de la politique ext\u00e9rieure dans son ensemble. Dans le premier cas \u00e9merge une image d&rsquo;une puissance omnipr\u00e9sente et installant partout le d\u00e9sordre \u00e0 son avantage (?), dans le deuxi\u00e8me une image d&rsquo;une puissance ayant effectivement entrepris des aventures militaristes partout et se d\u00e9sint\u00e9grant, se d\u00e9structurant elle-m\u00eame en un \u00e9tat de d\u00e9sordre \u00e0 cause des effets de ces aventures. Cette d\u00e9structuration touche m\u00eame la cha\u00eene de commandement qui nous semble pourtant si rigide. Le cas de l&rsquo;U.S. Navy <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4286\" class=\"gen\">manoeuvrant<\/a>, au propre et au figur\u00e9, pour emp\u00eacher une attaque contre l&rsquo;Iran est sans aucun doute un cas \u00e9clairant <em>a contrario<\/em>.<\/p>\n<\/p>\n<p><p>\t Cloisonnement entre les actes de cette politique ext\u00e9rieure et la psychologie des dirigeants de cette politique. C&rsquo;est peut-\u00eatre l&rsquo;aspect le plus erron\u00e9 de ce type d&rsquo;analyse. Apr\u00e8s nous avoir expos\u00e9 (fort justement) une psychologie am\u00e9ricaniste totalement bloqu\u00e9e dans une perspective schizophr\u00e9nique n\u00e9e d&rsquo;\u00e9v\u00e9nements psychiatriques \u00e9vidents (\u00ab<em>Thus, frustration and the craving for revenge have become main drivers of US policies<\/em>\u00bb), on en tire les effets d&rsquo;une grande politique de d\u00e9stabilisation mondiale parfaitement coordonn\u00e9e et entra\u00eenant les autres <em>establishment<\/em>. Comment ne pas prendre en compte les effets destructeurs de l&rsquo;\u00e9volution de la psychologie am\u00e9ricaniste dont on diagnostique la maladie sur la politique dont elle est devenue la prisonni\u00e8re? N&rsquo;a-t-on toujours pas compris que la d\u00e9faite allemande dans la Deuxi\u00e8me Guerre mondiale, au travers de diverses erreurs strat\u00e9giques majeures, est d&rsquo;abord la d\u00e9faite d&rsquo;une psychologie malade avant d&rsquo;\u00eatre une d\u00e9faite militaire, la premi\u00e8re entra\u00eenant inexorablement la seconde?<\/p>\n<\/p>\n<p><p>\tNotre analyse est qu&rsquo;il est temps de se concentrer sur la source de tous les maux : la psychologie malade du syst\u00e8me de l&rsquo;am\u00e9ricanisme. Le reste, les cons\u00e9quences de cette psychologie malade, rel\u00e8ve de la boule de cristal opaque de la voyante elle-m\u00eame schizophr\u00e8ne. Comment peut-on pr\u00e9voir rationnellement les actes et les effets des actes d&rsquo;un fou? On ne parvient qu&rsquo;\u00e0 une seule certitude: on a choisi, avec la pr\u00e9vision rationnelle, la seule voie pr\u00e9visionniste qui ne se r\u00e9alisera pas. Constater, apr\u00e8s avoir \u00e9nonc\u00e9 les nombreuses simili-victoires se transformant en crises larv\u00e9es insolubles des USA depuis 16 ans que les dirigeants US \u00ab<em>peuvent en venir \u00e0 la conclusion qu&rsquo;ils n&rsquo;ont plus rien \u00e0 perdre m\u00eame dans la confrontation militaire<\/em>\u00bb, ne laisse gu\u00e8re pr\u00e9voir des succ\u00e8s qu&rsquo;on peut rationnellement d\u00e9tailler selon une prospective d&rsquo;expert. Il s&rsquo;agit d&rsquo;un cas psychiatrique de spasme d\u00e9sesp\u00e9r\u00e9 d&rsquo;affirmation d&rsquo;une puissance partout tenue en \u00e9chec par rapport aux ambitions qu&rsquo;on y a mises.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>C&rsquo;est nous (US) et le chaos 11 ao\u00fbt 2007 Un de nos lecteurs, Miquet, que nous remercions, nous signale sur le Forum du 9 ao\u00fbt la deuxi\u00e8me partie d&rsquo;une longue analyse d&rsquo;Axel Brot (en fait : nom de plume pour un ancien analyste et officier du renseignement allemand, et certaines pr\u00e9cisions circonstanci\u00e9es confirment cette identification).&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[6926,3907,6927,3099,6928,3248],"class_list":["post-69105","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-brot","tag-destructuration","tag-psychiatrie","tag-psychologie","tag-suicidaire","tag-washington"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69105"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69105\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}