{"id":69127,"date":"2007-08-18T00:00:00","date_gmt":"2007-08-18T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2007\/08\/18\/laideur-de-la-corruption\/"},"modified":"2007-08-18T00:00:00","modified_gmt":"2007-08-18T00:00:00","slug":"laideur-de-la-corruption","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2007\/08\/18\/laideur-de-la-corruption\/","title":{"rendered":"Laideur de la corruption"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Laideur de la corruption<\/h2>\n<\/p>\n<blockquote>\n<p><p>L&rsquo;affaire BAE\/ArabieSaoudite, devenue un scandale depuis neuf mois, nous donne un exemple de la \u00ab\u00a0subversion de la laideur\u00a0\u00bb, ou le cas d&rsquo;un autre angle d&rsquo;attaque de la psychologie par le nihilisme moderniste<\/p>\n<\/p>\n<\/blockquote>\n<p><p>En un sens, nous tentons ici de poursuivre, sous un angle diff\u00e9rent, la r\u00e9flexion entam\u00e9e dans notre num\u00e9ro du 10 mai 2007 sur l&rsquo;attaque de la psychologie humaine par <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4072\">le triomphe de la laideur<\/a>. Cette fois, il s&rsquo;agit du domaine particulier de la corruption auquel nous attachons effectivement une dimension esth\u00e9tique (d&rsquo;o&ugrave; le jugement de \u00ab\u00a0laideur\u00a0\u00bb). Nous devrons d\u00e9finir ces termes et \u00e0 mesure de l&rsquo;avancement de cet exercice, la r\u00e9flexion se d\u00e9gagera d&rsquo;elle-m\u00eame.<\/p>\n<\/p>\n<p><p>C&rsquo;est l&rsquo;affaire BAE-<em>Yamamah<\/em> qui nous conduit \u00e0 cet exercice. Depuis octobre 2006, cette affaire dont le contenu corrupteur \u00e9tait largement connu des milieux concern\u00e9s depuis des ann\u00e9es voire des d\u00e9cennies (depuis les suites de l&rsquo;\u00e9laboration du premier contrat <em>Yamamah<\/em> en 1985), &mdash; cette affaire est devenue scandale. Sa caract\u00e9ristique principale est la difficult\u00e9 o&ugrave; les autorit\u00e9s et puissances concern\u00e9es se trouvent de la boucler, de l&rsquo;\u00e9touffer. Cette r\u00e9sistance est en soi le signe de son caract\u00e8re exemplaire.<\/p>\n<\/p>\n<p><p>On conna&icirc;t les p\u00e9rip\u00e9ties et les personnages de la pi\u00e8ce. Nous en avons fait largement \u00e9cho, justement parce que nous jugeons depuis longtemps qu&rsquo;elle a un caract\u00e8re exemplaire. Nous allons tenter ici de d\u00e9finir la corruption aujourd&rsquo;hui (la corruption moderniste) \u00e0 partir de cette affaire scandaleuse, mais sans nous y attacher du point de vue politique, industriel, juridique ou anecdotique. Cela nous donnera plus de libert\u00e9 pour aborder le probl\u00e8me qui nous importe, notamment en affectant un champ historique \u00e0 la r\u00e9flexion. Il nous semble int\u00e9ressant (original?) de pouvoir comparer <em>de facto<\/em> deux personnages tels que Talleyrand, prince de B\u00e9n\u00e9vent, et Prince Bandar ben Sultan ben Abdulaziz.<\/p>\n<\/p>\n<p><p>D&rsquo;ores et d\u00e9j\u00e0, nous pouvons attendre de rencontrer les m\u00eames conclusions d\u00e9j\u00e0 propos\u00e9es \u00e0 d&rsquo;autres occasions. Si telle activit\u00e9 est esth\u00e9tiquement laide, elle a un effet amollissant sur la psychologie; et pour que cette activit\u00e9 ne soit pas \u00ab\u00a0laide\u00a0\u00bb, il faut moins de la vertu qu&rsquo;une identit\u00e9 de caract\u00e8re et d&rsquo;action.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">Subversion psychologique structurelle <\/h3>\n<\/p>\n<p><p>Il faut avoir vu, \u00e0 l&rsquo;\u00e9mission <em>Panorama<\/em> de la BBC le 11 juin, Prince Bandar r\u00e9pondre aux questions insistantes de la r\u00e9alisatrice; patelin, ironique, peut-\u00eatre cynique et encore, philosophe en un sens, pas vraiment m\u00e9content de lui (pourquoi le serait-il?). Bandar nous expliquait que, voyez-vous, la corruption a exist\u00e9 de tous temps, c&rsquo;est l&rsquo;humanit\u00e9 et m\u00eame l&rsquo;esp\u00e8ce qui veulent cela, et la marche des affaires; alors pourquoi s&rsquo;arr\u00eater \u00e0 cette corruption-l\u00e0, &mdash; par ailleurs corruption non prouv\u00e9e n&rsquo;est-ce pas, all\u00e9gations de journalistes, sans fondement, et ainsi de suite.<\/p>\n<\/p>\n<p><p>Prince Bandar repr\u00e9sente un personnage typique de notre temps. C&rsquo;est un citoyen international des milieux financiers et strat\u00e9giques de la connexion entre le monde anglo-saxon et le Moyen-Orient. Une sorte de <em>Jet Set<\/em> de la gestion strat\u00e9gique du monde fond\u00e9e sur le dollar, l&rsquo;armement et le p\u00e9trole. Bandar a \u00e9t\u00e9 ambassadeur d&rsquo;Arabie \u00e0 Washington (il semblait inamovible jusqu&rsquo;\u00e0 son d\u00e9part, \u00e0 la fin de l&rsquo;ann\u00e9e derni\u00e8re); ami du groupe Carlyle, de la famille Bush, de James Baker, de Frank Carlucci, tant d&rsquo;autres. C&rsquo;est la connexion am\u00e9ricano-moyenne-orientale, n\u00e9e en 1945 avec la rencontre de Franklin D. Roosevelt et du roi Saoud d&rsquo;Arabie \u00e0 Alexandrie. Ce n&rsquo;est que dans le courant des ann\u00e9es 1970, avec la crise p\u00e9troli\u00e8re, que ces relations prirent un tour si particulier de complicit\u00e9 presque fraternelle. Cette \u00e9volution au Moyen-Orient s&rsquo;accompagnait aux USA d&rsquo;une \u00e9volution \u00e9galement d\u00e9cisive, \u00e0 partir du <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=353\">\u00ab\u00a0Manifeste Powell\u00a0\u00bb<\/a> de septembre 1971 qui mobilisait les puissances priv\u00e9es pour r\u00e9agir apr\u00e8s les troubles des ann\u00e9es 1960 et restaurer la toute-puissance du secteur priv\u00e9. Cette pouss\u00e9e des moyens d&rsquo;influence les plus puissants ouvrit l&rsquo;\u00e8re hyper-lib\u00e9rale, la d\u00e9r\u00e9gulation, le reaganisme et le thatch\u00e9risme.<\/p>\n<\/p>\n<p><p>La rencontre entre Bandar et cette \u00e9volution du monde (anglo-saxon) dominant allait de soi. Elle se fit dans les ann\u00e9es 1980, d&rsquo;une fa\u00e7on assez paradoxale mais r\u00e9v\u00e9latrice, avec le vieux Royaume-Uni, l&rsquo;ancien Empire qui croyait pour l&rsquo;occasion rena&icirc;tre de ses cendres. On a vu les m\u00e9canismes des contrats <em>Yamamah<\/em>. On a vu comment ces contrats ont litt\u00e9ralement infect\u00e9 l&rsquo;<em>establishment<\/em> britannique, jusqu&rsquo;\u00e0 le conduire \u00e0 l&rsquo;\u00e9tat de d\u00e9composition morale et civique o&ugrave; il se trouve aujourd&rsquo;hui, o&ugrave; les h\u00e9ritiers des tribus b\u00e9douines se permettent de faire chanter l&rsquo;Empire (menace indirecte d&rsquo;actes de terrorisme) contre la suspension d&rsquo;une enqu\u00eate de corruption. Les Britanniques, BAE en t\u00eate mais avec l&rsquo;implication enthousiaste de la famille Thatcher, s&rsquo;\u00e9taient pr\u00e9cipit\u00e9s dans <em>Yamamah<\/em> en retrouvant la vieille m\u00e9thode de l&rsquo;Empire qui a toujours travaill\u00e9 au travers de r\u00e9seaux d&rsquo;influence, d&rsquo;hommes liges dans les pseudo-colonies, de pouvoirs corrompus et corrupteurs sur place. L&rsquo;Empire corrompait ses conqu\u00eates avant de les investir ou de les transformer en protectorats. L&rsquo;ironie de ce retour de l&rsquo;Histoire est que, cette fois, c&rsquo;est la conqu\u00eate coloniale corrompue qui s&rsquo;est retourn\u00e9e et a corrompu le corrupteur. D&rsquo;o&ugrave; le scandale BAE-<em>Yamamah<\/em> qui secoue l&rsquo;<em>establishment<\/em> londonien mais laisse Prince Bandar placide, souriant et plaisantant.<\/p>\n<\/p>\n<p><p>&#8230; En d&rsquo;autres mots, le plus corrompu des deux n&rsquo;est pas celui qu&rsquo;on pense.<\/p>\n<\/p>\n<p><p>Or, il faut savoir d&rsquo;o&ugrave; l&rsquo;on vient et comment l&rsquo;on est arriv\u00e9 o&ugrave; l&rsquo;on se trouve. La route qui a conduit \u00e0 cette situation est celle de la <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4235\">\u00ab\u00a0politique de la morale\u00a0\u00bb<\/a>. Cette politique a remplac\u00e9 le mensonge utile ou n\u00e9cessaire de la vieille politique, &mdash; mensonge mis au service de la politique qui peut parfois \u00eatre haute, &mdash; par le mensonge vertueux et imp\u00e9ratif, dont la politique et les hommes qui la servent (les \u00ab\u00a0sc\u00e9l\u00e9rats\u00a0\u00bb de Maistre ou \u00ab\u00a0le dernier homme\u00a0\u00bb de Nietzsche) sont les prisonniers \u00e0 perp\u00e9tuit\u00e9. C&rsquo;est par l\u00e0, d\u00e9sormais, que la corruption s&rsquo;engouffre, dans un domaine o&ugrave; n&rsquo;existent plus gu\u00e8re les r\u00e9f\u00e9rences r\u00e9galiennes habituelles (nation essentiellement, ses int\u00e9r\u00eats, les positions qu&rsquo;on a vis-\u00e0-vis de ses politiques, etc.). Les r\u00e9f\u00e9rences sont les vagues principes moraux qu&rsquo;on peut ais\u00e9ment tourner \u00e0 son avantage, tandis que la r\u00e9f\u00e9rence d&rsquo;action principale est \u00e9conomique (les ph\u00e9nom\u00e8nes de corruption se placent essentiellement aujourd&rsquo;hui dans des contextes \u00e9conomiques directs et indirects).<\/p>\n<\/p>\n<p><p>Le r\u00e9sultat est, lui, compl\u00e8tement politique et compl\u00e8tement d\u00e9fini par le mot de \u00ab\u00a0perversit\u00e9\u00a0\u00bb. Le m\u00eame march\u00e9 BAE-<em>Yamamah<\/em> nous en a donn\u00e9 un exemple \u00e9clatant fin juin, lorsque s&rsquo;effectuait la transition de la direction du gouvernement entre Tony Blair et Gordon Brown. Le sentiment g\u00e9n\u00e9ral, notamment au Salon du Bourget, \u00e9tait que Britanniques et Saoudiens allaient signer le troisi\u00e8me contrat <em>Yamamah<\/em>, celui des 72 Eurofighter <em>Typhoon<\/em> dont l&rsquo;Arabie a annonc\u00e9 au d\u00e9but de 2006 son intention de les acqu\u00e9rir. Mais le 25 juin, un article du <em>Times<\/em> annon\u00e7ait que la signature du contrat \u00e9tait report\u00e9e au mieux \u00e0 octobre. Alors que les Saoudiens avaient jusqu&rsquo;alors pouss\u00e9 les choses pour une signature rapide, voil\u00e0 qu&rsquo;ils temporisaient. Mais le texte se r\u00e9v\u00e8le rapidement sans ambigu\u00eft\u00e9s: les Saoudiens veulent \u00e9valuer Gordon Brown et appr\u00e9cier si l&rsquo;on peut faire \u00ab\u00a0affaire\u00a0\u00bb avec lui.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo;<em>The deal has now been put off until October because defence sources say that the Saudis want a better relationship with Gordon Brown, who becomes prime minister this week, before committing to such a large contract. They see the Typhoon deal as key to cementing diplomatic and military relations with the UK.<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Plus loin, cette phrase extraordinaire:<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo;<em>The negotiations over the Typhoons have become even more important in recent months as the Saudis want a demonstration of loyalty after allegations emerged [about] Prince Bandar, nephew to the king.<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>L&rsquo;expression \u00ab\u00a0<em>demonstration of loyalty<\/em>\u00ab\u00a0, dans les circonstances actuelles, n&rsquo;implique ni plus ni moins qu&rsquo;un acte d&rsquo;all\u00e9geance de la part du nouveau Premier ministre.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">La corruption devenue substance de la politique elle-m\u00eame<\/h3>\n<\/p>\n<p><p>On voit par ailleurs les dimensions prises par l&rsquo;affaire BAE-<em>Yamamah<\/em>, et ses dimensions potentielles sans aucun doute, notamment depuis que les USA ont d\u00e9cid\u00e9 l&rsquo;ouverture d&rsquo;une enqu\u00eate. Les ramifications diverses, les sous-entendus \u00e9chang\u00e9s entre les deux puis les trois pays (UK, USA, Arabie), nous font comprendre que nous avons affaire dans cette circonstance \u00e0 des adversaires f\u00e9roces, qui ne sont pourtant pas des ennemis, qui sont aussi des partenaires, voire dans certains cas des associ\u00e9s. Il est \u00e9galement \u00e9vident que ce qui a suscit\u00e9 cette position est l&rsquo;argent, l&rsquo;int\u00e9r\u00eat, \u00ab\u00a0les affaires\u00a0\u00bb. Quelles que soient les psychologies des uns et des autres, la base de leurs rapports est effectivement l&rsquo;argent et tout ce qui se rapporte \u00e0 lui.<\/p>\n<\/p>\n<p><p>Du point de vue de la politique, qui reste tout de m\u00eame un champ d&rsquo;activit\u00e9 pour un Tony Blair, un Prince Bandar ou un pr\u00e9sident Bush, on ne sent aucune pens\u00e9e particuli\u00e8re sinon des mots d&rsquo;ordre qui peuvent se nommer p\u00e9trole, terrorisme, conflit isra\u00e9lo-palestinien, etc., dont les termes restent \u00e9trangement fig\u00e9s et les positions des uns et des autres fix\u00e9es \u00e0 mesure. M\u00eame l&rsquo;incroyable enfer de d\u00e9sordre et de mort qu&rsquo;est devenu l&rsquo;Irak ne semble gu\u00e8re avoir modifi\u00e9 les pens\u00e9es. Les discours emport\u00e9s et fi\u00e9vreux sur la \u00ab\u00a0d\u00e9mocratisation\u00a0\u00bb du Moyen-Orient sont bien entendu rest\u00e9s des discours, comme on pouvait ais\u00e9ment le pr\u00e9voir. La situation du Moyen-Orient elle-m\u00eame, appr\u00e9ci\u00e9e comme la matrice des bouleversements qu&rsquo;on jugeait in\u00e9luctables depuis le 11 septembre n&rsquo;a pas sensiblement \u00e9volu\u00e9. Les m\u00eames syst\u00e8mes restent en place, les m\u00eames fili\u00e8res, les m\u00eames r\u00e9seaux, et le terrorisme qui est surtout devenu un immense d\u00e9sordre semble lui aussi \u00e9voluer comme un paradoxal \u00e9l\u00e9ment de paralysie de plus. Il n&rsquo;y a aucune pens\u00e9e strat\u00e9gique digne de ce nom parce que tout semble r\u00e9duit \u00e0 une appr\u00e9ciation et \u00e0 une action tactiques dont le coeur est une situation d\u00e9termin\u00e9e au d\u00e9part par l&rsquo;existence des int\u00e9r\u00eats, des \u00ab\u00a0affaires\u00a0\u00bb, &mdash; de l&rsquo;argent, en un mot.<\/p>\n<\/p>\n<p><p>Il n&rsquo;y a pas de r\u00e9el jugement moral dans ce propos. On ne signifie pas par l\u00e0 que ces personnages soient plus cupides, plus \u00ab\u00a0corrompus\u00a0\u00bb que d&rsquo;autres au sens classique du terme. Nous sugg\u00e9rons plut\u00f4t l&rsquo;existence d&rsquo;une paralysie de la psychologie comme outil d&rsquo;\u00e9laboration de la pens\u00e9e, et donc une situation o&ugrave; la corruption est bien plus psychologique que vulgairement v\u00e9nale. Le r\u00e9sultat est effectivement une paralysie de la pens\u00e9e mais <strong>par l&rsquo;int\u00e9rieur<\/strong> si l&rsquo;on veut, par l&rsquo;incapacit\u00e9 o&ugrave; se trouve la psychologie de faire son travail. La psychologie est encha&icirc;n\u00e9e, prisonni\u00e8re d&rsquo;une situation g\u00e9n\u00e9rale o&ugrave; l&rsquo;argent semble \u00e0 la fois le moteur et la r\u00e9f\u00e9rence.<\/p>\n<\/p>\n<p><p>Le contraste avec le pass\u00e9 est stup\u00e9fiant. Nous prenons l&rsquo;exemple d&rsquo;un \u00ab\u00a0corrompu\u00a0\u00bb historique notoire, qui est Talleyrand, Prince de B\u00e9n\u00e9vent. Le fait de la corruption de Talleyrand, c&rsquo;est-\u00e0-dire d&rsquo;une fa\u00e7on plus g\u00e9n\u00e9rale de son rapport int\u00e9ress\u00e9 \u00e0 l&rsquo;argent, est notoire. Il est inutile d&rsquo;\u00e9piloguer \u00e0 ce propos, et moins encore d&rsquo;ironiser lourdement. Les jugements \u00e0 cet \u00e9gard sont toujours tr\u00e8s tranch\u00e9s. Talleyrand est toujours l&rsquo;objet d&rsquo;une pol\u00e9mique constante, particuli\u00e8rement chez les historiens fran\u00e7ais. Il suscite des haines tr\u00e8s fortes, deux si\u00e8cles apr\u00e8s qu&rsquo;il se soit trouv\u00e9 au coeur de l&rsquo;action diplomatique de son temps, comme s&rsquo;il ne pouvait vraiment b\u00e9n\u00e9ficier de l&rsquo;amnistie de la passion que devraient donner la perspective historique.<\/p>\n<\/p>\n<p><p>Pour autant, Talleyrand reste un homme myst\u00e9rieux dans nombre de ses actes, car nombre de ses actes ne peuvent \u00eatre expliqu\u00e9s, sans le moindre doute, par ses rapports \u00e0 l&rsquo;argent. Sur l&rsquo;un des \u00e9pisodes qui lui est le plus souvent reproch\u00e9, la \u00ab\u00a0trahison\u00a0\u00bb d&rsquo;Erfurt (lorsqu&rsquo;il choisit d&rsquo;informer le tsar Alexandre contre Napol\u00e9on, dans les n\u00e9gociations qui avaient lieu entre les deux hommes), deux jugements non-fran\u00e7ais nous donnent l&rsquo;\u00e9clairage qui compte pour notre propos:<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo;<em>S&rsquo;il n&rsquo;avait song\u00e9 qu&rsquo;\u00e0 son propre bien, il aurait agi diff\u00e9remment car il risquait tout: sa position, sa fortune, peut-\u00eatre sa vie en s&rsquo;opposant \u00e0 la volont\u00e9 d&rsquo;un homme qui avait d\u00e9truit jusque-l\u00e0 tous ceux qui s&rsquo;\u00e9taient dress\u00e9s contre lui.<\/em>&raquo; (Duff Cooper, <em>Talleyrand, 1754-1838<\/em>)<\/p>\n<\/p>\n<p><p>&laquo;<em>Non, la \u00ab\u00a0trahison\u00a0\u00bb d&rsquo;Erfurt est inexplicable. Le Talleyrand de la tradition aurait pu \u00ab\u00a0trahir\u00a0\u00bb Napol\u00e9on, le jour o&ugrave; il aurait jou\u00e9 un petit risque contre la chance d&rsquo;un gros profit: il ne l&rsquo;aurait jamais \u00ab\u00a0trahi\u00a0\u00bb comme le vrai Talleyrand l&rsquo;a fait, avec un risque \u00e9norme et sans aucun profit.<\/em>&raquo; (Guglielmo Ferrero, <em>Reconstruction, Talleyrand \u00e0 Vienne, 1814-1815<\/em>.)<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Notre propos n&rsquo;est pas ici d&rsquo;interpr\u00e9ter la \u00ab\u00a0trahison\u00a0\u00bb d&rsquo;Erfurt, d&rsquo;analyser la pens\u00e9e de Talleyrand, le r\u00f4le qu&rsquo;il voulait faire jouer \u00e0 l&rsquo;Autriche contre le voeu de Napol\u00e9on qui cherchait plut\u00f4t \u00e0 la priver du moindre r\u00f4le. Il suffit d&rsquo;observer qu&rsquo;en cette occasion, comme dans bien d&rsquo;autres, lorsqu&rsquo;il recommande \u00e0 ses \u00ab\u00a0ma&icirc;tres\u00a0\u00bb successifs (la Convention, le Directoire, Napol\u00e9on) des politiques contraires \u00e0 leurs habitudes et, souvent, \u00e0 leur brutalit\u00e9, Talleyrand-le-corrompu suit des engagements qui ne sont pas conformes \u00e0 ses int\u00e9r\u00eats. Qu&rsquo;il parvienne dans nombre de cas \u00e0 sauvegarder ses int\u00e9r\u00eats n&rsquo;est qu&rsquo;un hommage rendu \u00e0 son habilet\u00e9 et \u00e0 son sens de l&rsquo;opportunit\u00e9. Pour le reste, ce qui nous importe est d&rsquo;observer combien l&rsquo;homme est libre dans ses jugements, par rapport aux forces dominantes, par rapport aux sources de l&rsquo;argent dont il a besoin ou dont il a le go&ucirc;t. Dans la hi\u00e9rarchie des attitudes, il existe effectivement &mdash; \u00f4 combien, &mdash; un esprit et un jugement chez Talleyrand, et force est de constater que l&rsquo;un et l&rsquo;autre sont caract\u00e9ris\u00e9s par la libert\u00e9. La psychologie de Talleyrand-le-corrompu sort indemne du fait de corruption. La fr\u00e9quentation de l&rsquo;argent ne le trouble pas et n&rsquo;interf\u00e8re en rien sur son jugement. Qu&rsquo;il soit ou non un corrompu v\u00e9nal, il n&rsquo;est en aucun cas un corrompu psychologique. Pour certains (Ferrero), c&rsquo;est m\u00eame un r\u00e9volt\u00e9, &laquo;<em>contre tous les pouvoirs du monde, y compris ceux qu&rsquo;il devra servir<\/em>&raquo;&#8230;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">La modernit\u00e9, ou la corruption devenu crise esth\u00e9tique<\/h3>\n<\/p>\n<p><p>Il nous semble que ces parall\u00e8les esquiss\u00e9s et grossi\u00e8rement trac\u00e9s suffisent \u00e0 observer une \u00e9volution radicale de la corruption, entre l&rsquo;ancien temps et les temps modernes. Nous nous gardons de jugement historique sur telle ou telle \u00e9poque, voire m\u00eame de jugement politique sur tel ou tel. Nous ne nous pronon\u00e7ons pas sur la corruption, sa permanence, sa nuisance, etc. Ce qui nous int\u00e9resse, c&rsquo;est la situation de la corruption par rapport \u00e0 la psychologie et son effet sur la psychologie.<\/p>\n<\/p>\n<p><p>La diff\u00e9rence se mesure effectivement au niveau psychologique. L&rsquo;exemple de Talleyrand montre que la corruption n&rsquo;appara&icirc;t pas comme un facteur fondamental de sa pens\u00e9e, ni m\u00eame de son comportement. Cela para&icirc;t conforme aux conceptions de l&rsquo;\u00e9poque. L&rsquo;acceptation, &mdash; empress\u00e9e ou fataliste c&rsquo;est selon, &mdash; de ce qu&rsquo;on nomme \u00ab\u00a0corruption\u00a0\u00bb aujourd&rsquo;hui, ne semble pas impliquer une dimension morale p\u00e9remptoire mais \u00eatre envisag\u00e9e du seul point de vue du r\u00e9alisme. Cette attitude permet d&rsquo;\u00e9viter d&rsquo;accorder une place trop grande \u00e0 la corruption. La question de la corruption reste une question v\u00e9nale, avec laquelle chacun s&rsquo;arrange, ou refuse de s&rsquo;arranger, comme il le peut dans des conditions r\u00e9alistes. Il n&rsquo;y a pas d&rsquo;interf\u00e9rence psychologique sp\u00e9cifique. Si, au contraire de ceux de Talleyrand, la pens\u00e9e et le comportement de certains peuvent en \u00eatre affect\u00e9s, c&rsquo;est qu&rsquo;il s&rsquo;agit de caract\u00e8res faibles qui \u00e9taient destin\u00e9s de toutes les fa\u00e7ons \u00e0 succomber \u00e0 leurs faiblesses, corruption ou pas. Au contraire, on sent chez Talleyrand une fermet\u00e9 des conceptions, &mdash; quoi qu&rsquo;on pense de celles-ci, &mdash; qui gouverne le reste, y compris le fait de la corruption en s&rsquo;en arrangeant.<\/p>\n<\/p>\n<p><p>L&rsquo;attitude dans l&rsquo;\u00e9poque moderniste est compl\u00e8tement diff\u00e9rente. Le triomphe de ce qu&rsquo;on nomme \u00e9galement \u00ab\u00a0la morale bourgeoise\u00a0\u00bb, avec ses n\u00e9cessit\u00e9s hypocrites, conduit \u00e0 faire de la corruption une question fondamentale en soi. Pour \u00e9viter la condamnation morale implicite que suppose le fait d&rsquo;y succomber, il importe alors de ne pas para&icirc;tre, \u00e0 ses propres yeux, y succomber. La r\u00e9action est alors d&rsquo;influencer et d&rsquo;orienter sa pens\u00e9e et son comportement d&rsquo;une fa\u00e7on qui \u00e9pouse par avance les effets que recherche le corrupteur. On va alors au-devant des buts suscit\u00e9s par la corruption pour ne pas sembler \u00e0 soi-m\u00eame y succomber. La corruption touche ainsi la psychologie et devient caract\u00e9ristique de notre \u00e9poque moderniste, o&ugrave; les imp\u00e9ratifs d&rsquo;une morale qu&rsquo;on a install\u00e9e au sommet des affaires impliquent qu&rsquo;on modifie la perception des faits bien plus que les actes pouvant influer sur les faits.<\/p>\n<\/p>\n<p><p>Il y a une correspondance certaine dans cette \u00e9volution de la corruption et l&rsquo;\u00e9volution signal\u00e9e <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4072\">pr\u00e9c\u00e9demment<\/a>, de la beaut\u00e9 en laideur, &mdash; et la laideur omnipr\u00e9sente aujourd&rsquo;hui nous \u00e9tant pr\u00e9sent\u00e9e comme la beaut\u00e9 m\u00eame. (Pour rappel, cette immortelle observation du philosophe Alain Rey, commentateur du \u00ab\u00a0Robert Culturel\u00a0\u00bb:<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo;<em>Echappant aux couchers de soleil, aux cath\u00e9drales et aux mus\u00e9es, r\u00e9pandu dans les supermarch\u00e9s et dans les d\u00e9bris du quotidien, le beau se veut aujourd&rsquo;hui le signe transcendant du r\u00e9el, de tout le r\u00e9el.<\/em>&raquo;)<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Il s&rsquo;agit au fond de sauver l&rsquo;homme (dirait-on m\u00eame: l&rsquo;Homme?) et l&rsquo;image qu&rsquo;on en a trac\u00e9e pour pouvoir justifier la place pr\u00e9pond\u00e9rante qu&rsquo;on lui assigne, &mdash; au centre de tout, et notamment de la morale et de la vertu.<\/p>\n<\/p>\n<p><p>Ainsi l&rsquo;homme (l&rsquo;Homme) est-il mis tr\u00e8s haut, plus haut que tout apr\u00e8s tout. Pour ne pas abaisser l&rsquo;homme perverti par la corruption, il s&rsquo;agit donc de hausser le fait de la corruption. Pour cela, il suffit d&rsquo;adapter la pens\u00e9e \u00e0 la corruption par le processus psychologique vu plus haut, en arguant qu&rsquo;en r\u00e9alit\u00e9 c&rsquo;est la corruption (qui est alors \u00e9ventuellement habill\u00e9e d&rsquo;un autre nom, beaucoup plus somptueux) qui est adapt\u00e9e \u00e0 la pens\u00e9e, &mdash; qui vient, si l&rsquo;on veut, \u00ab\u00a0r\u00e9compenser\u00a0\u00bb la pens\u00e9e, la r\u00e9tribuer en un sens, selon les r\u00e8gles en vigueur dans le capitalisme courant. Cette sorte de raisonnement permet d&rsquo;avancer, d&rsquo;ailleurs assez justement, que certains emplois, certaines r\u00e9tributions, certains salaires ressortent de la m\u00eame d\u00e9marche que la corruption en g\u00e9n\u00e9ral.<\/p>\n<\/p>\n<p><p>Par cons\u00e9quent, il nous semble que Bandar-le-philosophe se trompe, sans doute par d\u00e9sint\u00e9r\u00eat pour l&rsquo;historique des pratiques occidentales et pour l&rsquo;\u00e9volution historique de l&rsquo;Occident en g\u00e9n\u00e9ral. Si la corruption a toujours exist\u00e9, il est de fait qu&rsquo;elle a chang\u00e9 de nature, &mdash; telle qu&rsquo;elle nous appara&icirc;t aujourd&rsquo;hui, dans notre \u00e9trange temps historique. Il nous semble \u00e9vident que la corruption telle que nous la d\u00e9crivons, avec la fa\u00e7on dont elle force \u00e0 des orientations politiques pour \u00e9viter une condamnation morale factice, constitue un facteur central de la paralysie et de l&rsquo;ossification de la politique am\u00e9ricaniste, anglo-saxonne (et, d&rsquo;une certaine fa\u00e7on, occidentale en g\u00e9n\u00e9ral), de la strat\u00e9gie, de la vision du monde. Cette id\u00e9e vaut notamment pour la r\u00e9gion du Moyen-Orient, qui est le berceau de Prince Bandar. Elle vaut \u00e9galement dans des domaines comme ceux qui sont embrass\u00e9s par le complexe militaro-industriel, dans la conduite des processus bureaucratiques, etc.<\/p>\n<\/p>\n<p><p>Le ph\u00e9nom\u00e8ne est si important qu&rsquo;il agit m\u00eame lorsqu&rsquo;il n&rsquo;y a pas corruption, ou lorsque la corruption esp\u00e9r\u00e9e ou crainte n&rsquo;a pas lieu. D&rsquo;une certaine fa\u00e7on, \u00e0 cause du processus d\u00e9crit plus haut qui m\u00eale paradoxalement le rapport \u00e0 l&rsquo;argent \u00e0 la moralisation n\u00e9cessaire, et qui agit par cons\u00e9quent sur la psychologie d&rsquo;une mani\u00e8re pr\u00e9ventive au fait m\u00eame de la corruption, la corruption est devenue un probl\u00e8me int\u00e9rieur \u00e0 nous-m\u00eames. De ce point de vue, il devient \u00e9vident que nous parlons d&rsquo;un probl\u00e8me de civilisation, que le mot \u00ab\u00a0corruption\u00a0\u00bb finit par embrasser d&rsquo;autres ph\u00e9nom\u00e8nes que ceux li\u00e9s \u00e0 l&rsquo;argent puisqu&rsquo;elle concerne la pens\u00e9e elle-m\u00eame. Elle renvoie \u00e0 la perte de r\u00e9f\u00e9rences stables, des r\u00e9f\u00e9rences identitaires et identifi\u00e9es comme telles, qui caract\u00e9rise le monde post-moderne.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepblue\" style=\"color:#0f3955; font-size:1.25em\">La corruption moderniste subvertit directement la psychologie<\/h3>\n<\/p>\n<p><p>Ce n&rsquo;est pas l&rsquo;argent qui importe mais le rapport \u00e0 l&rsquo;argent, la position de la psychologie dans ce rapport \u00e0 l&rsquo;argent et ainsi de suite. Ce constat nous invite \u00e9videmment \u00e0 d\u00e9passer notre sujet sp\u00e9cifique pour le mettre dans ce mouvement plus g\u00e9n\u00e9ral d&rsquo;enlaidissement que nous constations dans notre <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4072\">analyse<\/a> sur la &laquo;<em>subversion de la laideur<\/em>&raquo;.<\/p>\n<\/p>\n<p><p>La corruption postmoderniste est devenue un facteur d&rsquo;enlaidissement de la psychologie, au m\u00eame titre que la subversion de la beaut\u00e9 en laideur est devenue un facteur d&rsquo;enlaidissement du monde agissant sur la psychologie. Le r\u00e9sultat est, comme dans le cas de la beaut\u00e9 devenant laideur, une \u00e9volution d&rsquo;affaiblissement essentiel de la psychologie.<\/p>\n<\/p>\n<p><p>Il s&rsquo;agit d&rsquo;une logique g\u00e9n\u00e9rale d&rsquo;enlaidissement du monde et des conditions d&rsquo;\u00e9volution de la soci\u00e9t\u00e9, qui constitue un probl\u00e8me v\u00e9ritablement esth\u00e9tique d&rsquo;effondrement d&rsquo;une civilisation. Le point central que nous voulons mettre en \u00e9vidence, dans cette analyse comme dans les pr\u00e9c\u00e9dentes que nous avons cit\u00e9es, est que cette crise esth\u00e9tique attaque directement la psychologie humaine. En l&rsquo;affaiblissant comme nous tentons de d\u00e9crire le ph\u00e9nom\u00e8ne, cette crise esth\u00e9tique fait de la psychologie humaine une complice active de ce processus d&rsquo;effondrement de la civilisation.<\/p>\n<\/p>\n<p><p>Il y a l\u00e0 une confirmation selon laquelle notre civilisation, d&rsquo;une puissance m\u00e9caniste (technologie, communications, etc.) telle qu&rsquo;aucune autre puissance ne peut lui r\u00e9sister, est en r\u00e9alit\u00e9 mise en danger de destruction par l&rsquo;int\u00e9rieur d&rsquo;elle-m\u00eame, par la psychologie. C&rsquo;est \u00e9galement \u00e0 l&rsquo;int\u00e9rieur qu&rsquo;une r\u00e9sistance, ou une pr\u00e9paration \u00e0 une alternative, peut \u00eatre poursuivie, en retournant contre cette civilisation d\u00e9cadente ses propres outils de d\u00e9cadence.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Laideur de la corruption L&rsquo;affaire BAE\/ArabieSaoudite, devenue un scandale depuis neuf mois, nous donne un exemple de la \u00ab\u00a0subversion de la laideur\u00a0\u00bb, ou le cas d&rsquo;un autre angle d&rsquo;attaque de la psychologie par le nihilisme moderniste En un sens, nous tentons ici de poursuivre, sous un angle diff\u00e9rent, la r\u00e9flexion entam\u00e9e dans notre num\u00e9ro du&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[5],"tags":[3792,5667,3423,3858,6637,3099,2699,4364],"class_list":["post-69127","post","type-post","status-publish","format-standard","hentry","category-de-defensa","tag-bae","tag-bandar","tag-civilisation","tag-corruption","tag-laideur","tag-psychologie","tag-talleyrand","tag-yamamah"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69127"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69127\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}