{"id":69133,"date":"2007-08-19T00:00:00","date_gmt":"2007-08-19T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2007\/08\/19\/le-jsf-premiere-victime-de-la-g4g\/"},"modified":"2007-08-19T00:00:00","modified_gmt":"2007-08-19T00:00:00","slug":"le-jsf-premiere-victime-de-la-g4g","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2007\/08\/19\/le-jsf-premiere-victime-de-la-g4g\/","title":{"rendered":"Le JSF, premi\u00e8re victime de la G4G ?"},"content":{"rendered":"<p><p>Une nouvelle importante concernant l&rsquo;\u00e9volution du programme JSF dans le contexte de l&rsquo;\u00e9volution g\u00e9n\u00e9rale de la d\u00e9finition et des besoins des conflits \u00e0 la lumi\u00e8re de Guerre de la 4\u00e8me G\u00e9n\u00e9ration (G4G),  dans ce cas, bien s\u00fbr, l&rsquo;affrontement Isra\u00ebl-Hezbollah de l&rsquo;\u00e9t\u00e9 dernier, typique de la <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3033\" class=\"gen\">G4G<\/a>. Il s&rsquo;agit d&rsquo;une nouvelle venue d&rsquo;Isra\u00ebl, que nous signale notre lecteur <em>Foxbat<\/em> (nous l&rsquo;en remercions) dans le <a href=\"http:\/\/www.dedefensa.org\/forum.php\" class=\"gen\">Forum<\/a> du jour. La nouvelle est donn\u00e9e par un <a href=\"http:\/\/www.haaretz.com\/hasen\/spages\/894799.html\" class=\"gen\">article<\/a> d&rsquo;<em>Haaretz<\/em> de ce m\u00eame jour, annon\u00e7ant le d\u00e9lai possible\/probable de la commande du JSF\/F-35 par l&rsquo;IDF (Israel Defense Force),  sans doute de un \u00e0 deux ans par rapport \u00e0 la planification actuelle (entr\u00e9e en service en 2015-2016 au lieu de 2014).<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The Israel Defense Forces will conduct a force structure review this week under the guidance of deputy Chief of Staff Moshe Kaplinsky, and will consider postponing the procurement of the F-35 stealth strike fighter. <\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The review, essentially a workshop of the General Staff&rsquo;s top brass, is expected to analyze the shape the IDF will take in the coming years, particularly in terms of large procurement projects.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The review, originally scheduled to take place on the eve of the Second Lebanon War last summer, is part of a broad series of changes then-chief of staff Dan Halutz sought to initiate in the army. One of the main changes Halutz sought to implement, which met with vociferous opposition from ground force generals, revolved around further cuts in the numbers of reserve armored brigades.<\/em><\/p>\n<\/p>\n<p><p>\t()<\/p>\n<\/p>\n<p><p>\t\u00bb<em>The Israel Air Force lobby at the General Staff suffered a setback when Halutz resigned, and some generals, including Kaplinsky, are unlikely to be sad to see the massive procurement project for the stealth strike fighter postponed for a year or two.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Mieux, c&rsquo;est une nouvelle <strong>tr\u00e8s<\/strong> importante et nous nous proposons d&rsquo;y revenir plus en d\u00e9tail, sans doute demain. Il s&rsquo;agit de la premi\u00e8re victoire majeure de la G4G au sein de l&rsquo;<em>establishment<\/em> militaire occidental, du point de vue de la programmation et de l&rsquo;orientation des programmes, en plus des conceptions tactiques et strat\u00e9giques. (Quoi qu&rsquo;il en soit de la d\u00e9cision effective: l&rsquo;essentiel est le raisonnement bureaucratique qui appara\u00eet \u00e0 cette occasion.) Il est possible que des r\u00e9percussions importantes se fassent sentir dans les mois et les ann\u00e9es qui viennent, notamment pour le JSF.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 19 ao\u00fbt 2007 \u00e0 15H15<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une nouvelle importante concernant l&rsquo;\u00e9volution du programme JSF dans le contexte de l&rsquo;\u00e9volution g\u00e9n\u00e9rale de la d\u00e9finition et des besoins des conflits \u00e0 la lumi\u00e8re de Guerre de la 4\u00e8me G\u00e9n\u00e9ration (G4G), dans ce cas, bien s\u00fbr, l&rsquo;affrontement Isra\u00ebl-Hezbollah de l&rsquo;\u00e9t\u00e9 dernier, typique de la G4G. Il s&rsquo;agit d&rsquo;une nouvelle venue d&rsquo;Isra\u00ebl, que nous signale&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[5701,4472,2774],"class_list":["post-69133","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-g4g","tag-hezbollah","tag-israel"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69133"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69133\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}