{"id":69163,"date":"2007-08-28T00:00:00","date_gmt":"2007-08-28T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2007\/08\/28\/presse-uk-sarko-larc-en-ciel-des-emotions-diverses\/"},"modified":"2007-08-28T00:00:00","modified_gmt":"2007-08-28T00:00:00","slug":"presse-uk-sarko-larc-en-ciel-des-emotions-diverses","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2007\/08\/28\/presse-uk-sarko-larc-en-ciel-des-emotions-diverses\/","title":{"rendered":"Presse UK &amp; Sarko : l&rsquo;arc en ciel des \u00e9motions diverses"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Presse UK &#038; Sarko : l&rsquo;arc en ciel des \u00e9motions diverses<\/h2>\n<\/p>\n<p><p>On sait que les Britanniques suivent Sarkozy de pr\u00e8s ; parce qu&rsquo;ils n&rsquo;aimaient pas Chirac et que Sarkozy leur a fait esp\u00e9rer une direction fran\u00e7aise plus mall\u00e9able ; parce qu&rsquo;ils ont \u00ab\u00a0interpr\u00e9t\u00e9\u00a0\u00bb Sarkozy \u00e0 la lumi\u00e8re de cette esp\u00e9rance ; parce que, depuis l&rsquo;\u00e9lection, ils auraient tendance \u00e0 flairer le coup fourr\u00e9 \u00e0-la-fran\u00e7aise, surtout depuis <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4136\">Bruxelles<\/a> \u00e0 la fin juin. Les commentaires britanniques sur le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4364\">discours<\/a> de Sarkozy \u00e9taient int\u00e9ressants \u00e0 lire.<\/p>\n<\/p>\n<p><p>Ils sont \u00e9tonnants dans leur diversit\u00e9 parfois exotique, parfois tr\u00e8s fine, parfois aveugl\u00e9e. Cete diversit\u00e9 refl\u00e8te bien l&rsquo;extraordinaire passion et la d\u00e9bauche d&rsquo;interpr\u00e9tations contradictoire que suscite Sarkozy, &mdash; pour l&rsquo;instant, personnage bien plus int\u00e9ressant par les perceptions qu&rsquo;on en a et par les r\u00e9actions qu&rsquo;il suscite que par ce qu&rsquo;il est.<\/p>\n<\/p>\n<p><p>Dans les r\u00e9actions de cette presse, nous nous sommes cantonn\u00e9s \u00e0 deux quotidiens, qui repr\u00e9sentent chacun dans leur genre des tendance bien marqu\u00e9es, o&ugrave; ils sont \u00e0 la fois les plus repr\u00e9sentatifs et les plus significatifs. Malgr\u00e9 leur proximit\u00e9 id\u00e9ologique, leur divergence d&rsquo;interpr\u00e9tation est remarquable, au point que l&rsquo;on se demande s&rsquo;il s&rsquo;agit du m\u00eame discours.<\/p>\n<\/p>\n<p><p>&bull; Le <em>Financial Times<\/em> a pris de la distance et lu le discours \u00e0 sa fa\u00e7on. Dans le texte qu&rsquo;il a mis en ligne, le <a class=\"gen\" href=\"http:\/\/www.ft.com\/cms\/s\/0\/7ee9e8dc-54d1-11dc-890c-0000779fd2ac.html\">27 ao&ucirc;t<\/a> et r\u00e9actualis\u00e9 le 28 ao&ucirc;t au matin, pas une seule fois le mot \u00ab\u00a0Iran\u00a0\u00bb n&rsquo;appara&icirc;t. Pas un mot sur le passage qui a mobilis\u00e9 l&rsquo;attention g\u00e9n\u00e9rale. Le FT se concentre sur les projets europ\u00e9ens de Sarko, qu&rsquo;il juge manifestement comme le passage plus important dans le discours. Peut-\u00eatre n&rsquo;a-t-il pas tort. Il aurait pu alors relever le passage sur <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4366\">la d\u00e9fense europ\u00e9enne<\/a>, qui pr\u00e9cise exactement les moyens que Sarko voudrait mettre en &oelig;uvre pour pousser sa politique europ\u00e9enne et qui confrontera les Britanniques \u00e0 un probl\u00e8me \u00e9pineux (comment se situer par rapport aux propositions fran\u00e7aises \u00e0 venir?). La description que fait le FT du projet implique que le quotidien a la perception d&rsquo;un projet d'\u00a0\u00bbEurope puissance\u00a0\u00bb. Encore une fois, peut-\u00eatre n&rsquo;a-t-il pas tort.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>France will press for a bolder European Union security strategy when it assumes the rotating presidency next year, aiming to turn the continent into a global power with a decisive role in promoting a more just and effective world order.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>In his first major foreign policy speech as France&rsquo;s president, Nicolas Sarkozy described the EU as a model of effective multilateralism that boasted a full range of instruments to address international crises, including military force, humanitarian assistance and financial aid. \u00ab\u00a0Europe must progressively affirm itself as a first-rank player for peace and security, in co-operation with the United Nations, the Atlantic alliance and the African Union,\u00a0\u00bb he said.<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>&bull; Le <em>Times<\/em> a une analyse rageuse, absolument n\u00e9o-conservatrice, d&rsquo;une France basculant (enfin) dans le camp am\u00e9ricaniste. L&rsquo;entame de l&rsquo;article du <a class=\"gen\" href=\"http:\/\/www.timesonline.co.uk\/tol\/news\/world\/europe\/article2337190.ece\">28 ao&ucirc;t<\/a>, qui confirme le titre (&laquo;<em>Sarkozy talks of bombing if Iran gets nuclear arms<\/em>&raquo;), est significative dans son raccourci, car quelle autre impression d&rsquo;une attaque prochaine de l&rsquo;Iran \u00e0 laquelle participerait la France peut-on tirer de ces 30 mots? O&ugrave; voit-on l&rsquo;impression essentielle de l&rsquo;expression \u00ab\u00a0alternative catastrophique\u00a0\u00bb que Sarkozy propose pour qualifer cette situation?<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>President Sarkozy called Iran&rsquo;s nuclear ambition the world&rsquo;s most dangerous problem yesterday and raised the possibility that the country could be bombed if it persisted in building an atomic weapon.<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Lorsqu&rsquo;on va dans le d\u00e9tail, on trouve la m\u00eame sollicitation des fats, comme dans ce passage o&ugrave; le \u00ab\u00a0pr\u00e9sident fran\u00e7ais le plus pro-am\u00e9ricain depuis des d\u00e9cennies\u00a0\u00bb, semble le prouver aussit\u00f4t en r\u00e9it\u00e9rant sa condamnation de l&rsquo;attaque US en Irak (?), mais surtout en r\u00e9pudiant le mot \u00ab\u00a0multipolarit\u00e9\u00a0\u00bb qui donne des boutons \u00e0 Washington. Pour comparaison, le texte fran\u00e7ais o&ugrave; Sarko parle de la \u00ab\u00a0multipolarit\u00e9\u00a0\u00bb, observant qu&rsquo;elle est un fait accompli mais malheureusement bien mal utilis\u00e9. L&rsquo;encha&icirc;nement sur une critique de Washington a de la peine \u00e0 nous r\u00e9concilier avec l&rsquo;interpr\u00e9tation du <em>Times<\/em> :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>President Sarkozy, the most pro-American French leader for decades, condemned the US invasion of Iraq, but also distanced himself from Mr Chirac&rsquo;s doctrine of a \u00ab\u00a0multipolar world\u00a0\u00bb, a formula that Washington saw as code for a refusal of European partnership.<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Extrait du discours de Sarkozy :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>Ces \u00e9volutions s&rsquo;accompagnent d&rsquo;une seconde r\u00e9alit\u00e9, qui n&rsquo;est pas moins pr\u00e9occupante : le monde est devenu multipolaire mais cette multipolarit\u00e9, qui pourrait annoncer un nouveau concert des grandes puissances, d\u00e9rive plut\u00f4t vers le choc de politiques de puissance.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Les Etats-Unis n&rsquo;ont pas su r\u00e9sister \u00e0 la tentation du recours unilat\u00e9ral \u00e0 la force et ne d\u00e9montrent malheureusement pas, dans la protection de l&rsquo;environnement, cette capacit\u00e9 de \u00ab\u00a0leadership\u00a0\u00bb qu&rsquo;ils revendiquent ailleurs.<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<\/p>\n<p><p>Mis en ligne le 28 ao&ucirc;t 2007 \u00e0 18H42<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Presse UK &#038; Sarko : l&rsquo;arc en ciel des \u00e9motions diverses On sait que les Britanniques suivent Sarkozy de pr\u00e8s ; parce qu&rsquo;ils n&rsquo;aimaient pas Chirac et que Sarkozy leur a fait esp\u00e9rer une direction fran\u00e7aise plus mall\u00e9able ; parce qu&rsquo;ils ont \u00ab\u00a0interpr\u00e9t\u00e9\u00a0\u00bb Sarkozy \u00e0 la lumi\u00e8re de cette esp\u00e9rance ; parce que, depuis l&rsquo;\u00e9lection,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[2870,4875,2851,6980,2773,4590,2852],"class_list":["post-69163","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-attaque","tag-britannique","tag-financial","tag-interpretation","tag-iran","tag-sarkozy","tag-times"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69163"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69163\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}