{"id":69173,"date":"2007-08-31T00:00:00","date_gmt":"2007-08-31T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2007\/08\/31\/la-guerre-divise-les-chefs-militaires-us-autant-que-les-adversaires-ethniques-et-religieux-en-irak\/"},"modified":"2007-08-31T00:00:00","modified_gmt":"2007-08-31T00:00:00","slug":"la-guerre-divise-les-chefs-militaires-us-autant-que-les-adversaires-ethniques-et-religieux-en-irak","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2007\/08\/31\/la-guerre-divise-les-chefs-militaires-us-autant-que-les-adversaires-ethniques-et-religieux-en-irak\/","title":{"rendered":"La guerre divise les chefs militaires US autant que les adversaires ethniques et religieux en Irak"},"content":{"rendered":"<p><p>Il s&rsquo;agit sans aucun doute d&rsquo;un \u00e9v\u00e9nement compl\u00e8tement in\u00e9dit dans un cas aussi grave de la politique de s\u00e9curit\u00e9 nationale des USA. Les chefs militaires US n&rsquo;adresseront pas une seule recommandation au pr\u00e9sident Bush le mois prochain, lors du <em>strategy assesment<\/em> sur la poursuite de l&rsquo;offensive dite <em>surge<\/em> en Irak. Chacun donnera son avis<\/p>\n<\/p>\n<p><p>\tC&rsquo;est le site McClatchy Newspapers, qui s&rsquo;av\u00e8re \u00eatre une tr\u00e8s bonne source sur la situation \u00e0 Washington, qui publie une analyse sur cette question le <a href=\"http:\/\/www.mcclatchydc.com\/homepage\/story\/19356.html\" class=\"gen\">30 ao\u00fbt<\/a>.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>In a sign that top commanders are divided over what course to pursue in Iraq, the Pentagon said Wednesday that it won&rsquo;t make a single, unified recommendation to President Bush during next month&rsquo;s strategy assessment, but instead will allow top commanders to make individual presentations.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Consensus is not the goal of the process, Geoff Morrell, a Pentagon spokesman, told reporters. If there are differences, the president will hear them.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Military analysts called the move unusual for an institution that ordinarily does not air its differences in public, especially while its troops are deployed in combat.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The professional military guys are going to the non-professional military guys and saying Resolve this,&rsquo; said Jeffrey White, a military analyst for the Washington Institute for Near East Policy. That&rsquo;s what it sounds like.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>White said it suggests that the military commanders want to be able to distance themselves from Iraq strategy by making it clear that whatever course is followed is the president&rsquo;s decision, not what commanders agreed on.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tQuelle que soit la pr\u00e9sentation officielle <em>soft<\/em> qui en est faite, cet \u00e9v\u00e9nement est compl\u00e8tement exceptionnel. La p\u00e9n\u00e9tration du climat que tout le monde conna\u00eet dans le processus officiel de la sacro-sainte <em>chain of command<\/em> en est une bonne mesure.<\/p>\n<\/p>\n<p><p>\tL&rsquo;\u00e9v\u00e9nement marque l&rsquo;\u00e9volution d&rsquo;un climat sans pr\u00e9c\u00e9dent dans la hi\u00e9rarchie militaire, o\u00f9 les solidarit\u00e9s sont d\u00e9sormais fracass\u00e9es par les interventions du pouvoir civil, les ambitions personnelles, la conduite de guerres folles sans r\u00e9elles justifications, les arrangements et provocations diverses mont\u00e9s en pleine lumi\u00e8re. Ces ruptures interviennent m\u00eame au sein d&rsquo;une m\u00eame arme, comme entre le g\u00e9n\u00e9ral Petraeus, U.S. Army, commandant en Irak, et son pr\u00e9d\u00e9cesseur, le g\u00e9n\u00e9ral Casey, devenu chef d&rsquo;\u00e9tat-major de la m\u00eame U.S. Army. Il semble que le pouvoir civil en g\u00e9n\u00e9ral, lui-m\u00eame fragment\u00e9 en factions rivales au sein de l&rsquo;administration, n&rsquo;a \u00e9videmment plus aucune autorit\u00e9, ne s&rsquo;accordant pas lui-m\u00eame sur des consignes \u00e0 donner \u00e0 ses chefs militaires. Ceux-ci n&rsquo;ont cure de donner des recommandations utiles puisqu&rsquo;ils vont parler \u00e0 un commandant-en-chef dont ils savent que la d\u00e9termination de poursuivre la guerre existe avant m\u00eame qu&rsquo;il entende leurs appr\u00e9ciations. Chacun songe donc \u00e0 sauvegarder ses int\u00e9r\u00eats, prot\u00e9ger sa r\u00e9putation et nourrir ses ambitions. C&rsquo;est une situation de d\u00e9sordre vraiment sans pr\u00e9c\u00e9dent.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 31 ao\u00fbt 2007 \u00e0 14H35<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il s&rsquo;agit sans aucun doute d&rsquo;un \u00e9v\u00e9nement compl\u00e8tement in\u00e9dit dans un cas aussi grave de la politique de s\u00e9curit\u00e9 nationale des USA. Les chefs militaires US n&rsquo;adresseront pas une seule recommandation au pr\u00e9sident Bush le mois prochain, lors du strategy assesment sur la poursuite de l&rsquo;offensive dite surge en Irak. Chacun donnera son avis C&rsquo;est&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4188,6993,5581,857,3194,6264],"class_list":["post-69173","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-casey","tag-chefs","tag-division","tag-irak","tag-pentagone","tag-petraeus"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69173"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69173\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}