{"id":69228,"date":"2007-09-16T00:00:00","date_gmt":"2007-09-16T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2007\/09\/16\/lirak-2005-pire-que-le-rouanda-1994-5\/"},"modified":"2007-09-16T00:00:00","modified_gmt":"2007-09-16T00:00:00","slug":"lirak-2005-pire-que-le-rouanda-1994-5","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2007\/09\/16\/lirak-2005-pire-que-le-rouanda-1994-5\/","title":{"rendered":"L&rsquo;Irak-2005 pire que le Rouanda-1994"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">L&rsquo;Irak-2005 pire que le Rouanda-1994<\/h2>\n<\/p>\n<p><p>Une enqu\u00eate bien document\u00e9e, techniquement sans faille et qui pr\u00e9sente toutes les apparences de la respectabilit\u00e9 conclut que plus d&rsquo;un million d&rsquo;Irakiens (1,2 million) sont morts en Irak depuis 2003, de \u00ab\u00a0morts violentes\u00a0\u00bb pouvant \u00eatre consid\u00e9r\u00e9es comme des cons\u00e9quences de l&rsquo;invasion US du pays. Le site <em>WSWS.org<\/em> rapporte cette nouvelle <a class=\"gen\" href=\"http:\/\/www.wsws.org\/articles\/2007\/sep2007\/orb-s15.shtml\">hier<\/a>, pr\u00e9cisant que les r\u00e9sultats de cette enqu\u00eate atteignent le rythme d&rsquo;un g\u00e9nocide selon la d\u00e9finition la plus r\u00e9cente puisque le rythme des assassinats d\u00e9passe d\u00e9sormais celui du g\u00e9nocide du Rouanda (800.000 assassinats en 1994). Les pr\u00e9cisions qui sont donn\u00e9es sur l&rsquo;enqu\u00eate et sur l&rsquo;organisation qui l&rsquo;a r\u00e9alis\u00e9e sont pleinement rassurantes quant \u00e0 la valeur de ce travail.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo; <em>ORB (Opinion Research Business), qui m\u00e8ne des sondages en Irak depuis 2005, a publi\u00e9 les r\u00e9sultats d&rsquo;une enqu\u00eate men\u00e9e aupr\u00e8s de 1 461 adultes \u00e0 travers le pays. Entre autres questions, il demandait : &laquo; Combien de membres de votre foyer, le cas \u00e9ch\u00e9ant, sont morts \u00e0 cause du conflit en Irak depuis 2003 (c&rsquo;est-\u00e0-dire \u00e0 cause de la violence plut\u00f4t que d&rsquo;une mort naturelle comme la vieillesse) ? Veuillez noter que je parle de ceux qui vivaient r\u00e9ellement sous votre toit.<\/em><\/p>\n<\/p>\n<p><p><em>&raquo;Parmi ceux qui ont r\u00e9pondu, 78 pour cent ont d\u00e9clar\u00e9 que leur foyer n&rsquo;avait connu aucune mort violente, 16 pour cent avait connu un d\u00e9c\u00e8s, 5 pour cent deux d\u00e9c\u00e8s, 1 pour cent trois d\u00e9c\u00e8s ou plus. Compte tenu du nombre de m\u00e9nages que compte le pays, 4 050 597 selon les chiffres du recensement de 2005, cela repr\u00e9sente pr\u00e8s de 1,2 million de d\u00e9c\u00e8s. [&hellip;]<\/em><\/p>\n<\/p>\n<p><p><em>&raquo;Opinion Research Business n&rsquo;est pas un groupe de gauche ou anti-guerre, mais un organisme de sondage bien \u00e9tabli, fond\u00e9 en 1994 par Gordon Heald, qui a dirig\u00e9 Gallup Britain de 1980 \u00e0 1994. Parmi ses clients figurent l&rsquo;\u00e9norme groupe minier Anglo American, la Bank of Scotland. , et le Parti conservateur. Son directeur non ex\u00e9cutif est Geoffrey Martin OBE, actuellement conseiller sp\u00e9cial du secr\u00e9taire g\u00e9n\u00e9ral pour les relations strat\u00e9giques du Commonwealth britannique.<\/em><\/p>\n<\/p>\n<p><p><em>&raquo; L&rsquo;enqu\u00eate ORB \u00e9tait bas\u00e9e sur des entretiens en face-\u00e0-face men\u00e9s entre le 12 et le 19 ao&ucirc;t aupr\u00e8s d&rsquo;un \u00e9chantillon repr\u00e9sentatif \u00e0 l&rsquo;\u00e9chelle nationale de 1 720 adultes (dont 1 461 ont r\u00e9pondu), avec une marge d&rsquo;erreur standard de 2,4 pour cent. Un \u00e9chantillonnage al\u00e9atoire a \u00e9t\u00e9 utilis\u00e9 pour s\u00e9lectionner les personnes interrog\u00e9es dans 15 des 18 provinces irakiennes<\/em>.&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Ces nouvelles sont effrayantes mais sont-elles \u00e9tonnantes ? Le syst\u00e8me d\u00e9cha&icirc;n\u00e9s, comme il l&rsquo;est aujourd&rsquo;hui, devient, dans des situations \u00e0 peine extr\u00eames, un syst\u00e8me de mort. Les deux composants \u00e0 l&rsquo;&oelig;uvre sont le capitalisme et la bureaucratie, deux composants aveugles qui ne manifestent aucun int\u00e9r\u00eat pour des probl\u00e8mes \u00ab\u00a0collat\u00e9raux\u00a0\u00bb tels les morts et souffrances humaines, les destructions, l&rsquo;a-culturation, la pauvret\u00e9, l&rsquo;oppression, etc. Le syst\u00e8me est naturellement conduit \u00e0 une politique entropique, conduite par une thermodynamique de la mort et de la destruction, mais dans des conditions telles, notamment gr\u00e2ce \u00e0 l&rsquo;action de la communication mais pas seulement, que la morale a beaucoup de difficult\u00e9s \u00e0 poser le diagnostic fondamental. La branche militaire du syst\u00e8me n&rsquo;a rien de sp\u00e9cifique, selon la tradition militaire; elle est totalement bureaucratis\u00e9e et en voie de fonctionner comme le capitalisme, avec les diverses proc\u00e9dures de privatisation des forces militaires. De ce point de vue-l\u00e0 non plus, la logique qu&rsquo;on d\u00e9crit ici n&rsquo;est nullement entrav\u00e9e.<\/p>\n<\/p>\n<p><p>Ces remarques nous sont inspir\u00e9es par le livre <em>La perfidie de l&rsquo;Histoire<\/em>, du professeur Richard L. Rubenstein. (Publi\u00e9 aux USA en 1975, il a \u00e9t\u00e9 publi\u00e9 en fran\u00e7ais aux \u00e9ditions du Cerf, en 2005. Les \u00e9diteurs ont malheureusement demand\u00e9 une postface \u00e0 Rubenstein, datant de 2004, ou bien est-ce Rubenstein qui a d\u00e9sir\u00e9 la faire figurer. 9\/11 est pass\u00e9 par l\u00e0 et nous, nous nous serions bien pass\u00e9s de la postface&hellip;) Rubenstein montre avec une grande pr\u00e9cision les similitudes du m\u00e9canisme qui aboutit aux camps d&rsquo;extermination nazis et du m\u00e9canisme capitalisto-bureaucratique du syst\u00e8me de l&rsquo;am\u00e9ricanisme et de son extension globalis\u00e9e :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em\">\n<p><p>&laquo;<em>Avec le temps, il devient \u00e9vident que les atrocit\u00e9s perp\u00e9tr\u00e9es par les nazis dans leur soci\u00e9t\u00e9 de domination totale, comme les mutilations et exp\u00e9riences m\u00e9dicales meurtri\u00e8res sur des \u00eatres humains, ainsi que l&rsquo;utilisation des esclaves dans les camps de la mort, ne sont que la logique extr\u00eame des proc\u00e9dures et conduites pr\u00e9dominantes dans les entreprises modernes et le travail bureaucratique.<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<\/p>\n<p><p>Mis en ligne le 16 septembre 2007 \u00e0 11H01<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;Irak-2005 pire que le Rouanda-1994 Une enqu\u00eate bien document\u00e9e, techniquement sans faille et qui pr\u00e9sente toutes les apparences de la respectabilit\u00e9 conclut que plus d&rsquo;un million d&rsquo;Irakiens (1,2 million) sont morts en Irak depuis 2003, de \u00ab\u00a0morts violentes\u00a0\u00bb pouvant \u00eatre consid\u00e9r\u00e9es comme des cons\u00e9quences de l&rsquo;invasion US du pays. Le site WSWS.org rapporte cette nouvelle&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[7046,7047,4757,4880,857,7048,7045,7044,4881],"class_list":["post-69228","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-7046","tag-7047","tag-genocide","tag-holocauste","tag-irak","tag-millions","tag-orb","tag-rouanda","tag-rubenstein"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69228"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69228\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}