{"id":69246,"date":"2007-09-21T00:00:00","date_gmt":"2007-09-21T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2007\/09\/21\/embrasement-des-esprits-provinciaux-de-paris\/"},"modified":"2007-09-21T00:00:00","modified_gmt":"2007-09-21T00:00:00","slug":"embrasement-des-esprits-provinciaux-de-paris","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2007\/09\/21\/embrasement-des-esprits-provinciaux-de-paris\/","title":{"rendered":"Embrasement des esprits provinciaux de Paris"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Embrasement des esprits provinciaux de Paris<\/h2>\n<\/p>\n<p><p>Nos dirigeants (<em>dito<\/em>, les dirigeants fran\u00e7ais) sont-ils des provinciaux? Plus pr\u00e9cis\u00e9ment: sont-ils \u00ab\u00a0des provinciaux du monde\u00a0\u00bb? Ou, dit d&rsquo;une autre fa\u00e7on: \u00eatre pro-am\u00e9ricaniste, avec des petites \u00e9toiles dans les yeux qui clignotent au son de la fameuse musique de <em>American Dream<\/em>, n&rsquo;est-ce pas entretenir un princialisme de l&rsquo;esprit qui peut vous jouer des tours?<\/p>\n<\/p>\n<p><p>Tout cela a l&rsquo;air \u00e9nigmatique et plaisantin, mais non, cela concerne une mati\u00e8re essentielle. Posons la question autrement: pourquoi la direction fran\u00e7aise s&rsquo;est-elle embras\u00e9e dans le cas de l&rsquo;Iran, &mdash; ou a-t-elle sembl\u00e9 le faire?<\/p>\n<\/p>\n<p><p>Apr\u00e8s avoir d\u00e9velopp\u00e9 les plus r\u00e9centes pr\u00e9visins d&rsquo;attaque US contre l&rsquo;Iran (renouvellement hebdomadaire garanti), la Lettre d&rsquo;Information <em>TTU<\/em> pr\u00e9cise, dans son num\u00e9ro du 19 septembre 2007:<\/p>\n<\/p>\n<p><p>&laquo;<em>&#8230;Voil\u00e0 pourquoi l&rsquo;Iran a sans doute \u00e9t\u00e9 au c&oelig;ur de la conversation des Pr\u00e9sidents fran\u00e7ais et am\u00e9ricain, lors du d\u00e9jeuner estival de Kennebunkport, dans la r\u00e9sidence familiale des Bush. Voil\u00e0 pourquoi, quinze jours plus tard, devant un parterre d&rsquo;ambassadeurs fran\u00e7ais, Nicolas Sarkozy, encore tout plein des propos entendus, a pr\u00e9sent\u00e9 sur un ton fortement anxiog\u00e8ne le premier \u00ab\u00a0des trois d\u00e9fis du XXI\u00e8me si\u00e8cle\u00a0\u00bb qu&rsquo;\u00e9tait \u00ab\u00a0la menace de confrontation entre l&rsquo;Islam et l&rsquo;Occident\u00a0\u00bb, et a conclu sur l&rsquo;\u00e9vocation de cette \u00ab\u00a0alternative catastrophique : la bombe iranienne ou le bombardement de l&rsquo;Iran\u00a0\u00bb.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<strong><em>Voil\u00e0 pourquoi, pris \u00e0 son tour dans une telle ambiance, Bernard Kouchner a laiss\u00e9 \u00e9chapper l&rsquo;id\u00e9e qu&rsquo;il fallait \u00ab\u00a0se pr\u00e9parer au pire\u00a0\u00bb&hellip;<\/em><\/strong> <em>c&rsquo;est-\u00e0-dire \u00e0 \u00ab\u00a0la guerre\u00a0\u00bb. Bien s&ucirc;r, il s&rsquo;est ensuite laborieusement d\u00e9fendu de tout entra&icirc;nement sur une telle pente, se ln\u00e7ant m\u00eame dans une construction quelque peu p\u00e9rilleuse selon laquelleil n&rsquo;\u00e9tait il fallait encore plus de sanctions<\/em> [contre] <em>l&rsquo;Iran pour lui \u00e9pargner un conflit. Mais les mots, \u00e0 ce niveau, s&rsquo;envolent et prennent leur viepropre. Et ces mots-l\u00e0, \u00e0 travers le monde, ont pris toute la dimension d&rsquo;une \u00ab\u00a0self-fulfilling prophecy\u00a0\u00bb : d&rsquo;une proph\u00e9tie auto-r\u00e9alistruice, comme disent nos almis am\u00e9ricains.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Le ton l\u00e9g\u00e9rement moqueur, sceptique et critique, montre bien, vu la proximit\u00e9 de <em>TTU<\/em> des milieux de la d\u00e9fense, que la d\u00e9fense a pris une position critique dans cette affaire, marqu\u00e9e <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4450\">d\u00e9j\u00e0<\/a> par l&rsquo;interview du ministre Morin. Ce ton caract\u00e9rise l&rsquo;explication du durcissement Sarkozy-Kouchner de fin-ao&ucirc;t d\u00e9but-septembre. Cette explication recoupe d&rsquo;autres confidences dans ce sens. Il semble bien que la rencontre de Bush ait \u00e9t\u00e9 un \u00e9l\u00e9ment d\u00e9cisif.<\/p>\n<\/p>\n<p><p>&hellip; Parce que le pr\u00e9sident a annonc\u00e9 la probabalit\u00e9 de l&rsquo;in\u00e9luctabilit\u00e9 d&rsquo;une frappe US? Sans doute, comme l&rsquo;explique par ailleurs <em>TTU<\/em>. C&rsquo;est l\u00e0 que le cas devient it\u00e9ressant.<\/p>\n<\/p>\n<p><p>Il existe, du c\u00f4t\u00e9 fran\u00e7ais une pr\u00e9vention extraordinaire pour prendre en compte la r\u00e9elle situation \u00e0 Washington. On s&rsquo;en tient \u00e0 la hi\u00e9rarchie et aux pouvoirs officiels. Le pr\u00e9sident est compl\u00e8tement isol\u00e9, les forces militaires US sont soit diminu\u00e9es, soit tr\u00e8s r\u00e9ticentes \u00e0 une attaque jusqu&rsquo;\u00e0 un point proche d&rsquo;une insubordination larv\u00e9e, certains ministres (Gates) sont r\u00e9ticents eux aussi dans une mesure qui a peu de pr\u00e9c\u00e9dent. Le Congr\u00e8s pourrait, &mdash; enfin, &mdash; monter une <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4437\">opposition s\u00e9rieuse<\/a> au Pr\u00e9sident sur ce projet. Dans tous les cas, les projets d&rsquo;attaque sont <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4436\">hebdomadaires<\/a> depuis deux ans, avec des cas o&ugrave; l&rsquo;administration (y compris GW) a du reculer devant l&rsquo;opposition des militaires.<\/p>\n<\/p>\n<p><p>Les Fran\u00e7ais ne semblent gu\u00e8re tenir compte de ces r\u00e9alit\u00e9s. Ils raisonnent en Fran\u00e7ais, habitu\u00e9s au pouvoir r\u00e9galien et \u00e0 sa logique inflexible. A Washington, le pouvoir est celui des groupes d&rsquo;int\u00e9r\u00eat et les am\u00e9ricains ont du mal \u00e0 traduire le mot \u00ab\u00a0r\u00e9galien\u00a0\u00bb (\u00ab\u00a0<em>kingly<\/em>\u00a0\u00bb ne suffit certainement pas). En cas de crise de d\u00e9s\u00e9quilibre de ce syst\u00e8me comme celle qui est en cours, la situation devient insaisissable et s&rsquo;en tenir \u00e0 la seule parole d&rsquo;un pr\u00e9sident qui est \u00e0 25%-28% de jugements favorables, qui est reconnu comme lunatique, est risqu\u00e9.<\/p>\n<\/p>\n<p><p>Dans ces conditions, la na\u00efvet\u00e9 et l&rsquo;inexp\u00e9rience des dirigeants politiques fran\u00e7ais dans ces rapports ont jou\u00e9 \u00e0 plein et elle rel\u00e8ve de l&rsquo;inexp\u00e9rience de provinciaux entrant dans les affaires. Ils se sont enflamm\u00e9s \u00e0 partir de confidences de GW Bush, qui pour soutenir les projets US, qui pour indirectement les contenir, selon l&rsquo;explication qu&rsquo;on priviligiera. Mais ces projets sont loin d&rsquo;\u00eatre concrets et les Fran\u00e7ais se sont d\u00e9couverts bien trop t\u00f4t et dans des conditions tr\u00e8s d\u00e9favorables, d\u00e9clenchant contre eux des r\u00e9actions violentes. De ce point de vue, l&rsquo;op\u00e9ration n&rsquo;est pas une r\u00e9ussite.<\/p>\n<\/p>\n<p><p>Mis en ligne le 21 septembre \u00e0 16H45<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Embrasement des esprits provinciaux de Paris Nos dirigeants (dito, les dirigeants fran\u00e7ais) sont-ils des provinciaux? Plus pr\u00e9cis\u00e9ment: sont-ils \u00ab\u00a0des provinciaux du monde\u00a0\u00bb? Ou, dit d&rsquo;une autre fa\u00e7on: \u00eatre pro-am\u00e9ricaniste, avec des petites \u00e9toiles dans les yeux qui clignotent au son de la fameuse musique de American Dream, n&rsquo;est-ce pas entretenir un princialisme de l&rsquo;esprit qui&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[868,3228,2773,7061,7062,4590],"class_list":["post-69246","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-bush","tag-crise","tag-iran","tag-paroxysme","tag-provinciaux","tag-sarkozy"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69246"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69246\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69246"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}