{"id":69256,"date":"2007-09-24T00:00:00","date_gmt":"2007-09-24T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2007\/09\/24\/y-a-t-il-une-opa-de-lusaf-sur-lattaque-contre-liran\/"},"modified":"2007-09-24T00:00:00","modified_gmt":"2007-09-24T00:00:00","slug":"y-a-t-il-une-opa-de-lusaf-sur-lattaque-contre-liran","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2007\/09\/24\/y-a-t-il-une-opa-de-lusaf-sur-lattaque-contre-liran\/","title":{"rendered":"Y a-t-il une OPA de l&rsquo;USAF sur l&rsquo;attaque contre l&rsquo;Iran?"},"content":{"rendered":"<p><h2 class=\"common-article\">Y a-t-il une OPA de l&rsquo;USAF sur l&rsquo;attaque contre l&rsquo;Iran?<\/h2>\n<\/p>\n<p><p>\t24 septembre 2007  Nous revenons sur un int\u00e9ressant article du <em>Sunday Times<\/em> de Londres du <a href=\"http:\/\/www.timesonline.co.uk\/tol\/news\/world\/asia\/article2512097.ece\" class=\"gen\">23 septembre<\/a>, dont nous parlions d\u00e9j\u00e0 <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4460\" class=\"gen\">hier<\/a>. Il s&rsquo;agit de quelques d\u00e9tails sur la mise en place d&rsquo;un groupe autonome de l&rsquo;USAF, dit <em>Project Checkmate<\/em>, charg\u00e9,  ou qui s&rsquo;est auto-charg\u00e9?  de pr\u00e9parer un plan de campagne a\u00e9rienne contre l&rsquo;Iran. <\/p>\n<\/p>\n<p><p>\t\u00ab<em>The United States Air Force has set up a highly confidential strategic planning group tasked with fighting the next war as tensions rise with Iran. Project Checkmate, a successor to the group that planned the 1991 Gulf War&rsquo;s air campaign, was quietly reestablished at the Pentagon in June. It reports directly to General Michael Moseley, the US Air Force chief, and consists of 20-30 top air force officers and defence and cyberspace experts with ready access to the White House, the CIA and other intelligence agencies.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Detailed contingency planning for a possible attack on Iran has been carried out for more than two years by Centcom (US central command), according to defence sources. Checkmate&rsquo;s job is to add a dash of brilliance to Air Force thinking by countering the military&rsquo;s tendency to fight the last war and by providing innovative strategies for warfighting and assessing future needs for air, space and cyberwarfare. It is led by Brigadier-General Lawrence Stutz Stutzriem, who is considered one of the brightest air force generals. He is assisted by Dr Lani Kass, a former Israeli military officer and expert on cyberwarfare.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tD&rsquo;autre part, le <em>Sunday Times<\/em> nous donne quelques pr\u00e9cisions sur un aspect plus politique de <em>Project Checkmate<\/em>, avec surtout la suggestion des rapports de cette \u00e9quipe avec CentCom (le commandement qui chapeaute la zone comprenant notamment l&rsquo;Irak et l&rsquo;Iran et qui serait en charge d&rsquo;une attaque \u00e9ventuelle):<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Checkmate&rsquo;s freethinking mission is to provide planning inputs to warfighters that are strategically, operationally and tactically sound, logistically supportable and politically feasible. Its remit is not specific to one country, according to defence sources, but its forward planning is thought relevant to any future air war against Iranian nuclear and military sites. It is also looking at possible threats from China and North Korea.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Checkmate was formed in the 1970s to counter Soviet threats but fell into disuse in the 1980s. It was revived under Colonel John Warden and was responsible for drawing up plans for the crushing air blitz against Saddam Hussein at the opening of the first Gulf war. Warden told The Sunday Times: When Saddam invaded Kuwait, we had access to unlimited numbers of people with expertise, including all the intelligence agencies, and were able to be significantly more agile than Centcom.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>He believes that Checkmate&rsquo;s role is to develop the necessary expertise so that if somebody says Iran, it says: here is what you need to think about&rsquo;. Here are the objectives, here are the risks, here is what it will cost, here are the numbers of planes we will lose, here is how the war is going to end and here is what the peace will look like.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Warden added: The Centcoms of this world are executional  they don&rsquo;t have the staff, the expertise or the responsibility to do the thinking that is needed before a country makes the decision to go to war. War planning is not just about bombs, airplanes and sailing boats.<\/em>\u00bb<\/p>\n<h3>Quelques faits pour le d\u00e9cor<\/h3>\n<\/p>\n<p><p>\tNous rapportons ici quelques faits qu&rsquo;il est int\u00e9ressant de garder \u00e0 l&rsquo;esprit.<\/p>\n<\/p>\n<p><p>\t On a <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2602\" class=\"gen\">d\u00e9j\u00e0<\/a> vu que l&rsquo;USAF \u00e9tait particuli\u00e8rement int\u00e9ress\u00e9e par une \u00e9ventuelle campagne contre l&rsquo;Iran.<\/p>\n<\/p>\n<p><p>\t On a <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1513\" class=\"gen\">d\u00e9j\u00e0<\/a> vu que l&rsquo;USAF est un service marqu\u00e9 r\u00e9cemment par des engagements fondamentalistes appuy\u00e9s. On ne dirait pas que l&rsquo;USAF est une force caract\u00e9ris\u00e9e par un engagement religieux d&rsquo;extr\u00eame-droite, mais certains de ses \u00e9l\u00e9ments en sont fortement marqu\u00e9s.<\/p>\n<\/p>\n<p><p>\t On a <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3128\" class=\"gen\">d\u00e9j\u00e0<\/a> vu que l&rsquo;USAF est tr\u00e8s proche d&rsquo;Isra\u00ebl, qu&rsquo;elle a inspir\u00e9, sinon impos\u00e9 ses doctrines \u00e0 la force a\u00e9rienne isra\u00e9lienne. Isra\u00ebl est hyst\u00e9riquement favorable \u00e0 une attaque de l&rsquo;Iran, ce qui rencontre la tendance de l&rsquo;USAF mise en \u00e9vidence ici. La pr\u00e9sence d&rsquo;experts d&rsquo;origine isra\u00e9lienne dans <em>Project Checkmate<\/em> confirme cet aspect de cette affaire.<\/p>\n<\/p>\n<p><p>\t On a \u00e9galement <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3989\" class=\"gen\">rencontr\u00e9<\/a> \u00e0 plusieurs <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4297\" class=\"gen\">reprises<\/a> la position tr\u00e8s particuli\u00e8re de l&rsquo;U.S. Navy et de l&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4407\" class=\"gen\">amiral Fallon<\/a>, commandant de CentCom depuis f\u00e9vrier dernier.<\/p>\n<\/p>\n<p><p>\t Enfin, on conna\u00eet les liens de Murdoch, soutien des n\u00e9o-conservateurs US, avec le <em>Times<\/em>: lien de la chose poss\u00e9d\u00e9e avec son propri\u00e9taire,  et Murdoch est un propri\u00e9taire exigeant, qui aime faire partager autoritairement ses engagements politiques. Le rapport entre le <em>Times<\/em> et l&rsquo;USAF est par cons\u00e9quent \u00e9vident.<\/p>\n<h3>USAF <strong><em>versus<\/em><\/strong> CentCom<\/h3>\n<\/p>\n<p><p>\tLe fait que <em>Project Checkmate<\/em> et ses caract\u00e9ristiques <strong>politiques<\/strong> aient \u00e9t\u00e9 rendus publics par une courroie de transmission de la politique Murdoch est une puissante indication. C&rsquo;est une affirmation du <em>War Party<\/em> qu&rsquo;il est pr\u00eat \u00e0 jouer son propre jeu, qu&rsquo;il le fait d&rsquo;ores et d\u00e9j\u00e0, qu&rsquo;il affiche cette intention et qu&rsquo;il est pr\u00eat \u00e0 marginaliser ses adversaires en les tournant m\u00eame si ceux-ci repr\u00e9sentent le commandement l\u00e9gal (CentCom) en temps de guerre.<\/p>\n<\/p>\n<p><p>\tIl est extr\u00eamement difficile de ne pas voir dans ces circonstances une confirmation de la situation bien inhabituelle r\u00e9gnant au sein des forces arm\u00e9es US, et au coeur du pouvoir am\u00e9ricaniste en g\u00e9n\u00e9ral. <em>Project Chekmate<\/em> semble avoir \u00e9t\u00e9 \u00e9tabli hors de la cha\u00eene de commandement normale (CentCom) pour une op\u00e9ration contre l&rsquo;Iran, puisqu&rsquo;il semble d\u00e9pendre directement du chef d&rsquo;\u00e9tat-major de l&rsquo;USAF et de la Maison-Blanche. Si la chose est confirm\u00e9e, ce serait  une diff\u00e9rence majeure du groupe <em>Project Chekmate<\/em>, ou \u00e9quivalent, de la premi\u00e8re Guerre du Golfe, dirig\u00e9 par le g\u00e9n\u00e9ral Horner, qui avait \u00e9t\u00e9 organis\u00e9 en coordination avec CentCom (g\u00e9n\u00e9ral Schwartzkopf) et rendait compte effectivement \u00e0 CentCom. (Horner \u00e9tait commandant Air \u00e0 CentCom, donc sous l&rsquo;autorit\u00e9 de Schwarzkopf. Pour ce qu&rsquo;on en sait, rien de semblable pour le groupe actuel.) Quoi qu&rsquo;il en soit, dans le contexte pr\u00e9sent, cette situation extraordinaire r\u00e9pond \u00e0 la logique du d\u00e9sordre washingtonien.<\/p>\n<\/p>\n<p><p>\tAujourd&rsquo;hui, CentCom est aux mains d&rsquo;un homme notoirement et, depuis peu, <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4461\" class=\"gen\">publiquement<\/a> hostile \u00e0 une guerre contre l&rsquo;Iran. La structure <em>Project Chekmate<\/em> \u00e9chappe \u00e9galement, semble-t-il, \u00e0 la pr\u00e9sidence du Joint Chief of Staff (JCS) qui est aux mains de l&rsquo;U.S. Navy et d&rsquo;un chef (amiral Muellen) \u00e9galement peu inclin\u00e9 \u00e0 soutenir une attaque contre l&rsquo;Iran. Tout converge pour alimenter l&rsquo;hypoth\u00e8se de forces suivant des comportements op\u00e9rationnels ou de communication autonomes, qui traduisent une opposition politique fondamentale. L&rsquo;USAF contre la Navy, ce n&rsquo;est pas nouveau, mais <strong>jamais<\/strong> le d\u00e9saccord n&rsquo;a port\u00e9 sur une mati\u00e8re politique aussi explosive, et d&rsquo;une fa\u00e7on aussi claire.<\/p>\n<\/p>\n<p><p>\tOn observera que cette opposition implicite est exprim\u00e9e d&rsquo;une fa\u00e7on assez m\u00e9prisante, traduisant l&rsquo;\u00e2pret\u00e9 de la concurrence des forces au niveau des qualifications, par les jugements peu am\u00e8nes, voire provocants, exprim\u00e9s par le colonel Warden sur les qualifications de CentCom \u00e0 planifier une attaque (\u00ab<em>The Centcoms of this world are executional  they don&rsquo;t have the staff, the expertise or the responsibility to do the thinking that is needed before a country makes the decision to go to war. War planning is not just about bombs, airplanes and sailing boats.<\/em>\u00bb : qualifier CentCom d&rsquo;ex\u00e9cutant, incapable d&rsquo;une pens\u00e9e strat\u00e9gique,  et ne pensant qu&rsquo;en termes de bombes, d&rsquo;avions  et, cerise sur le g\u00e2teau dans l&rsquo;expression du m\u00e9pris, en termes de bateaux \u00e0 voiles [<em>sailing boats<\/em>]; si ce n&rsquo;est une allusion m\u00e9prisante au fait que CentCom est sous le commandement d&rsquo;un amiral) Cette critique provocatrice est assez injustifi\u00e9e si l&rsquo;on se r\u00e9f\u00e8re aux deux guerres contre l&rsquo;Irak, o\u00f9 CentCom assura effectivement l&rsquo;essentiel de la planification des attaques.<\/p>\n<\/p>\n<p><p>\t(L&rsquo;opposition Navy-USAF est une constante de l&rsquo;<em>establishment<\/em> militaire US, selon la perspective historique des rapports des deux armes et de leurs philosophies respectives. La Navy est une arme de dimensions globales, qui a une vision tr\u00e8s structur\u00e9e des relations internationales et de la n\u00e9cessit\u00e9 de leur stabilit\u00e9. Sa mission, le contr\u00f4le des mers, suppose effectivement une telle stabilit\u00e9, la protection de l&rsquo;ordre existant, etc. L&rsquo;USAF est, au contraire, une arme r\u00e9volutionnaire, appuy\u00e9e sur les hautes technologies et les interventions d\u00e9stabilisantes, plut\u00f4t cr\u00e9atrices d&rsquo;un chaos chez l&rsquo;ennemi qu&rsquo;on esp\u00e8re cr\u00e9ateur. Elle n&rsquo;est pas \u00e9trang\u00e8re \u00e0 des op\u00e9rations bureaucratiques du type <em>Project Checkmate<\/em>, \u00e0 la limite de la l\u00e9galit\u00e9 interne des forces arm\u00e9es et de la l\u00e9galit\u00e9 tout court : en ao\u00fbt 1941, l&rsquo;U.S. Army Air Corps\/Air Force [alors d\u00e9pendant de l&rsquo;Army] d\u00e9tacha quatre officiers pour \u00e9laborer clandestinement les grandes lignes du plan d&rsquo;offensive strat\u00e9gique US contre l&rsquo;Allemagne, dit AWPD-1,  clandestinement, parce que de tels plans \u00e9taient interdits par le Congr\u00e8s, alors isolationniste ; le groupe visita notamment les banques US pour identifier les avoirs industriels US en Allemagne, que les bombardiers de l&rsquo;USAAF devraient \u00e9viter de bombarder&#8230; D&rsquo;une fa\u00e7on tr\u00e8s significative, on pourrait,  faisant r\u00e9f\u00e9rence aux classifications que nous offrons pour les mouvements en cours, temp\u00e9r\u00e9e du fait que nous sommes \u00e0 l&rsquo;int\u00e9rieur du syst\u00e8me am\u00e9ricaniste,  qualifier la Navy de force structurante et l&rsquo;USAF de force d\u00e9structurante.  On comprend combien il est normal que la Navy traditionaliste d\u00e9teste les n\u00e9o-conservateurs et leur folie guerri\u00e8re et que l&rsquo;USAF r\u00e9volutionnaire en soit proche.)<\/p>\n<\/p>\n<p><p>\tOn comprend que ces conditions compliquent extraordinairement la perspective d&rsquo;une attaque contre l&rsquo;Iran. Irait-on jusqu&rsquo;\u00e0 concevoir des plans concurrents, des structures autonomes les unes des autres, des chefs aux buts de guerre diff\u00e9rents et ainsi de suite? D&rsquo;autre part, dans le climat actuel, pourrait-on concevoir sans des remous politiques d\u00e9stabilisateurs, des mesures violentes pr\u00e9paratoires \u00e0 la guerre, comme par exemple le remplacement de l&rsquo;amiral Fallon? Cela a d\u00e9j\u00e0 \u00e9t\u00e9 tent\u00e9 par Cheney et l&rsquo;op\u00e9ration s&rsquo;est heurt\u00e9e \u00e0 un refus cat\u00e9gorique de Gates, qui pourrait mettre sa d\u00e9mission dans la balance si de telles pressions se poursuivaient. Au contraire, on sait qu&rsquo;un projet fracassant de Fallon serait un refus implicite d&rsquo;ob\u00e9ir \u00e0 un ordre d&rsquo;attaque en lui opposant sa d\u00e9mission si cet ordre \u00e9tait donn\u00e9, ce qui aurait une tout autre signification que son remplacement, mais un effet d\u00e9stabilisateur bien aussi fort.<\/p>\n<\/p>\n<p><p>\t Tout cela se comprend logiquement, \u00e0 part que nous sommes dans une tr\u00e8s grande d\u00e9mocratie et qu&rsquo;un tel d\u00e9sordre, une telle fragmentation et une telle concurrence des pouvoirs, une telle absence de pouvoir l\u00e9gitime, constituent un cas peu ordinaire. La fragmentation et la concurrence des pouvoirs \u00e0 Washington, qui r\u00e9duisent \u00e0 n\u00e9ant le concept de l\u00e9gitimit\u00e9 n\u00e9cessitant par essence un seul pouvoir, sont vraiment des facteurs politiques centraux de la crise. Les experts (europ\u00e9ens notamment) qui conseillent leurs gouvernements devraient commencer \u00e0 songer \u00e0 ne plus tenir compte des seuls communiqu\u00e9s officiels pour leurs \u00e9valuations, et entreprendre de s&rsquo;int\u00e9resser \u00e0 cette sorte de situation.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Y a-t-il une OPA de l&rsquo;USAF sur l&rsquo;attaque contre l&rsquo;Iran? 24 septembre 2007 Nous revenons sur un int\u00e9ressant article du Sunday Times de Londres du 23 septembre, dont nous parlions d\u00e9j\u00e0 hier. Il s&rsquo;agit de quelques d\u00e9tails sur la mise en place d&rsquo;un groupe autonome de l&rsquo;USAF, dit Project Checkmate, charg\u00e9, ou qui s&rsquo;est auto-charg\u00e9?&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[2870,7071,3228,6296,3984,2773,5751,3319,7070,41],"class_list":["post-69256","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-attaque","tag-checkmate","tag-crise","tag-fallon","tag-gates","tag-iran","tag-muellen","tag-navy","tag-opa","tag-usaf"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69256"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69256\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}