{"id":69271,"date":"2007-09-29T00:00:00","date_gmt":"2007-09-29T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2007\/09\/29\/gw-completement-isole-a-washington-les-amis-de-plus-en-plus-irrites\/"},"modified":"2007-09-29T00:00:00","modified_gmt":"2007-09-29T00:00:00","slug":"gw-completement-isole-a-washington-les-amis-de-plus-en-plus-irrites","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2007\/09\/29\/gw-completement-isole-a-washington-les-amis-de-plus-en-plus-irrites\/","title":{"rendered":"GW compl\u00e8tement isol\u00e9 \u00e0 Washington, les amis de plus en plus irrit\u00e9s"},"content":{"rendered":"<p><p>Le reste du monde,  ou disons l&rsquo;essentiel du reste du monde puisque seuls les pays les plus importants \u00e9taient pr\u00e9sents,  est furieux \u00e0 l&rsquo;issue de la conf\u00e9rence sur la crise climatique que GW Bush avait annonc\u00e9e \u00e0 grand coup de tambour et trompette lors du r\u00e9cent G8 de juin, en Allemagne. Comme pr\u00e9vu, cette conf\u00e9rence se r\u00e9duisit une p\u00e9nible manuvre de diversion ou de retardement, pour on ne sait quoi, pour on ne sait quel but. M\u00eame des pays comme le Br\u00e9sil, l&rsquo;Inde et la Chine qui, sur cette question de la lutte contre le r\u00e9chauffement climatique, se retrouvaient parfois aux c\u00f4t\u00e9s des USA, ont particip\u00e9 \u00e0 la mauvaise humeur g\u00e9n\u00e9rale \u00e0 l&rsquo;encontre du pr\u00e9sident des USA. M\u00eame l&rsquo;ami fid\u00e8le par tous les temps, le Britannique, n&rsquo;a pa m\u00e2ch\u00e9 ses mots et a fait savoir hautement son jugement catastrophique sur cette conf\u00e9rence. Il est notable de relever, dans cet article du <em>Guardian<\/em> d&rsquo;<a href=\"http:\/\/www.guardian.co.uk\/environment\/2007\/sep\/29\/usnews.climatechange\" class=\"gen\">aujourd&rsquo;hui<\/a>, l&rsquo;\u00e9cho sans pudeur de l&rsquo;humeur massacrante des divers amis convoqu\u00e9s \u00e0 Washington.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>George Bush was castigated by European diplomats and found himself isolated yesterday after a special conference on climate change ended without any progress.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>European ministers, diplomats and officials attending the Washington conference were scathing, particularly in private, over Mr Bush&rsquo;s failure once again to commit to binding action on climate change.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Although the US and Britain have been at odds over the environment since the early days of the Bush administration, the gap has never been as wide as yesterday.<\/em><\/p>\n<\/p>\n<p><p>\t()<\/p>\n<\/p>\n<p><p>\t\u00bb<em>A senior European diplomat attending the conference, speaking on condition of anonymity, said the meeting confirmed European suspicions that it had been intended by Mr Bush as a spoiler for a major UN conference on climate change in Bali in December.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>It was a total charade and has been exposed as a charade, the diplomat said. I have never heard a more humiliating speech by a major leader. He [Mr Bush] was trying to present himself as a leader while showing no sign of leadership. It was a total failure.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>John Ashton, Britain&rsquo;s special envoy on climate change, who attended the conference, said: It is striking here how isolated the US has become on this issue. There is no support among the industrialised countries for the proposition that we should proceed on the basis of voluntary commitments.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tIl semble qu&rsquo;on commence \u00e0 se fatiguer s\u00e9rieusement de GW Bush et de la politique US en g\u00e9n\u00e9ral. C&rsquo;est une sorte de Bush fatigue, comme si la fr\u00e9quentation du pr\u00e9sident US, malgr\u00e9 le respect du aux us et coutumes du conformisme international et la r\u00e9v\u00e9rence habituelle pour la puissance US, finissait par devenir insupportable. On ressent ce sentiment \u00e0 la fois de lassitude et d&rsquo;agacement tr\u00e8s affirm\u00e9 dans ces remarques: \u00ab<em>Although many of those attending had predicted the conference would break up without significant agreement, there had been hopes that Mr Bush, in search of a legacy, might produce a surprise. Instead, he stuck to his previous position, shunning mandatory caps in favour of clean coal, nuclear power and developing clean energy technology.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tIl est difficile de penser que cette pantalonnade de Washington et l&rsquo;irritation qui en a \u00e9t\u00e9 \u00e9prouv\u00e9e provoqueront un effet politique important. Pour l&rsquo;imm\u00e9diat et pour la conclusion officielle, l&rsquo;Am\u00e9rique reste l&rsquo;Am\u00e9rique. Disons que la chose participe du courant g\u00e9n\u00e9ral de d\u00e9gradation catastrophique de l&rsquo;image des USA dans le monde, courant plus profond, plus marquant, plus fondamental que les r\u00e9actions quotidiennes.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 29 septembre 2007 \u00e0 09H44<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le reste du monde, ou disons l&rsquo;essentiel du reste du monde puisque seuls les pays les plus importants \u00e9taient pr\u00e9sents, est furieux \u00e0 l&rsquo;issue de la conf\u00e9rence sur la crise climatique que GW Bush avait annonc\u00e9e \u00e0 grand coup de tambour et trompette lors du r\u00e9cent G8 de juin, en Allemagne. Comme pr\u00e9vu, cette conf\u00e9rence&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3392,3228,3198,7081,3248],"class_list":["post-69271","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-climatique","tag-crise","tag-gw","tag-isole","tag-washington"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69271"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69271\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}