{"id":69301,"date":"2007-10-08T00:00:00","date_gmt":"2007-10-08T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2007\/10\/08\/entree-du-jsf-dans-linconnu\/"},"modified":"2007-10-08T00:00:00","modified_gmt":"2007-10-08T00:00:00","slug":"entree-du-jsf-dans-linconnu","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2007\/10\/08\/entree-du-jsf-dans-linconnu\/","title":{"rendered":"Entr\u00e9e du JSF dans l&rsquo;inconnu"},"content":{"rendered":"<p><h2 class=\"common-article\">Entr\u00e9e du JSF dans l&rsquo;inconnu<\/h2>\n<\/p>\n<p><p>\t8 octobre 2007  Certes, nous n&rsquo;avons jamais cach\u00e9 notre peu d&rsquo;app\u00e9tence pour le programme JSF. Nous ne l&rsquo;avons pas \u00e9pargn\u00e9. Nous nous sommes int\u00e9ress\u00e9s \u00e0 lui jusqu&rsquo;\u00e0 ce qui pourrait para\u00eetre de l&rsquo;acharnement (parce que c&rsquo;est un \u00e9v\u00e9nement fondamental de l&rsquo;a\u00e9ronautique, des affaires politiques et militaires, qui m\u00e9rite absolument cette attention). Cette fois, nous commen\u00e7ons \u00e0 plaindre ce pauvre programme et \u00e0 craindre r\u00e9ellement pour son destin.<\/p>\n<\/p>\n<p><p>\tQue se passe-t-il? Voici un article de <em>Aviation Week &#038; Space Technology<\/em> (disons <em>AW&#038;ST<\/em>), num\u00e9ro du 1er octobre 2007. Il est int\u00e9ressant de le lire. Il nous apprend ceci: les coop\u00e9rants internationaux du JSF, ceux qui sont mont\u00e9s dans la gal\u00e8re, ceux qui sont du voyage, ceux-l\u00e0 commencent \u00e0 se comporter avec des exigences, des soup\u00e7ons et des radineries, comme s&rsquo;ils ne risquaient rien eux-m\u00eames; ceux-l\u00e0 qu&rsquo;on <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3872\" class=\"gen\">invitait<\/a> encore r\u00e9cemment \u00e0 payer et qui semblent ne pas vouloir du tout le faire.<\/p>\n<\/p>\n<p><p>\tIl pourrait sembler que la question la plus importante est de savoir si ces gens, les coop\u00e9rants, ne commencent pas \u00e0 se douter de quelque chose Non, pourtant; la question la plus importante concerne la conscience qu&rsquo;ont ces coop\u00e9rants de leurs responsabilit\u00e9s dans ce programme. S&rsquo;ils n&rsquo;ont pas cette conscience, en effet, les difficult\u00e9s \u00e0 attendre du programme seront encore pires que celles qu&rsquo;on attendait. Ce n&rsquo;est pas peu dire.<\/p>\n<\/p>\n<p><p>\tVoici le d\u00e9but de ce texte, qui donne une id\u00e9e de l&rsquo;atmosph\u00e8re qui r\u00e8gne au sein du programme:<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Initial efforts by Lockheed Martin to entice international participants into early commitments to the Joint Strike Fighter (JSF) appear faltering, as key partners hold off on final decisions.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Lockheed Martin&rsquo;s first Lightning Strike meeting last month on the F-35 hasn&rsquo;t yet fomented unified support among the program&rsquo;s foreign partners. The company has been trying to obtain early firm commitments from program participants.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>However, the only level one partner in the program, the U.K., will not pronounce aircraft numbers until several years into the next decade, according to a statement from the Defense Ministry. London&rsquo;s formal input during the discussions is not known. The U.K. appears to be trying to leverage its commitment to production numbers against assurances in access, particularly regarding low-observable technology, and support of the aircraft.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The investment approach for the Joint Combat Aircraft will be incremental in order to balance commitments with JSF program maturity, says a Defense Ministry official. The Joint Combat Aircraft is the U.K. name for the F-35.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The next investment decision is planned for early in 2009, when we will consider buying up to three aircraft to support Operational Test and Evaluation in the U.S., which will independently confirm that the aircraft meets the require ments set for it, says the ministry official.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Le texte continue en mettant en \u00e9vidence cette d\u00e9gradation du climat, en en renvoyant la responsabilit\u00e9 au Pentagone lui-m\u00eame: \u00ab<em>Though the U.S. will be the largest buyer, its hesitance seems to be driving the lack of interest for early purchases among international buyers<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Chemin faisant, on d\u00e9couvre d&rsquo;autres contestations et exigences Notamment ceci, alors qu&rsquo;on croyait tout de m\u00eame la question du transfert des technologies et de souverainet\u00e9 op\u00e9rationnelle r\u00e9gl\u00e9e entre Washington et Londres, alors qu&rsquo;on a sign\u00e9 des <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2746\" class=\"gen\">accords<\/a> et des <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4143\" class=\"gen\">trait\u00e9s<\/a> bien ambitieux \u00e0 cet \u00e9gard: \u00ab<em>A positive U.K. main investment decision will depend on the satisfactory outcome of operational test and evaluation activity, and continued progress in achieving operational sovereignty, the ministry official adds. The U.K.&rsquo;s ability to maintain the aircraft and independently verify the radar cross section of the JCA are significant elements of that operational sovereignty. Central to the U.K.&rsquo;s aspirations are a maintenance, repair and upgrade facility and a low- observability verification facility. The latter is also thought to be part of the U.K.&rsquo;s JSF Stealth Technology Acquisition Plan.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Technology access issues continue to be a source of tension between the U.K. and the U.S.and to color U.K. views as to when it would be appropriate to fully commit to the JSF<\/em>\u00bb<\/p>\n<h3>Le domaine terrible des <strong><em>unknown unknowns<\/em><\/strong><\/h3>\n<\/p>\n<p><p>\tIl se passe une chose \u00e9tonnante et importante dans le programme JSF. On observera que, jusqu&rsquo;ici, rien qui soit d\u00e9favorable au programme n&rsquo;a eu lieu officiellement ni n&rsquo;a \u00e9t\u00e9 annonc\u00e9 officiellement. Lockheed Martin n&rsquo;est pas <em>dedefensa.org<\/em>, bien plus s\u00e9rieux sans aucun doute. Officiellement,  insistons sur ce mot qui nous est si \u00e9tranger puisque jamais notre propos sur le JSF n&rsquo;a \u00e9t\u00e9 celui dont nous parlons ici,  tout a march\u00e9 comme sur des roulettes. Le premier revers est intervenu il y a un mois, avec le retournement de position des <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4426\" class=\"gen\">Isra\u00e9liens<\/a>. (Notez qu&rsquo;on ne s&rsquo;\u00e9tend pas sur la question, le silence de la presse officielle est assourdissant. C&rsquo;est un signe imparable que la nouvelle est importante.)<\/p>\n<\/p>\n<p><p>\tSoudain, cet article nous montre une situation caract\u00e9ris\u00e9e par la m\u00e9fiance, la r\u00e9ticence, l&rsquo;appr\u00e9ciation critique implicite du programme. La position des pays refusant d&rsquo;acheter l&rsquo;un ou l&rsquo;autre mod\u00e8le initial pour l&rsquo;exp\u00e9rimentation en vol est compr\u00e9hensible du point de vue de leurs int\u00e9r\u00eats (pourquoi viendraient-ils au secours de Lockheed-Martin qui s&rsquo;est montr\u00e9 imprudent, mauvais gestionnaire ou d\u00e9pensier en entamant fortement sa r\u00e9serve destin\u00e9e \u00e0 l&rsquo;achat de ces m\u00eames avions d&rsquo;essai en vol?). Le probl\u00e8me est que ces m\u00eames pays sont partie prenante du programme, et acheteurs potentiels mais presque oblig\u00e9s; en refusant cette aide, ils affaiblissent le programme et le rendent extraordinairement plus risqu\u00e9, ce qui se r\u00e9percutera au niveau de leurs int\u00e9r\u00eats dans cet autre domaine de leur engagement dans le programme, autant dans le retard du programme que dans l&rsquo;augmentation des co\u00fbts (notamment des avions \u00e0 l&rsquo;achat). Les pays coop\u00e9rants entrent dans le coeur de leur contradiction: \u00e0 la fois coop\u00e9rants d&rsquo;un programme qu&rsquo;ils ne ma\u00eetrisent pas et qui conna\u00eet d\u00e9sormais des difficult\u00e9s av\u00e9r\u00e9es, \u00e0 la fois clients de ce programme; d\u00e9sormais, ces deux positions ont des int\u00e9r\u00eats contradictoires et ces coop\u00e9rants sont plac\u00e9s devant une alternative antagoniste.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est dans ce contexte qu&rsquo;il appara\u00eet de plus en plus que le programme JSF est engag\u00e9 dans une voie extr\u00eamement p\u00e9rilleuse. En plus des probl\u00e8mes d\u00e9j\u00e0 rencontr\u00e9s (jusqu&rsquo;ici dissimul\u00e9s, ou r\u00e9duits au minimum de publicit\u00e9 possible) s&rsquo;ouvre une p\u00e9riode d&rsquo;incertitudes extraordinaires, \u00e0 cause des restrictions des essais en vol et des appr\u00e9ciations des performances r\u00e9elles et des probl\u00e8mes r\u00e9els de l&rsquo;avion. C&rsquo;est l&rsquo;entr\u00e9e dans une p\u00e9riode que <em>Aviation Week &#038; Space Technology<\/em> d\u00e9signe comme le risque des <em>unknow unknows<\/em>,   c&rsquo;est-\u00e0-dire les inconnus de l&rsquo;inconnu (\u00ab<em>The unknown unknown is not something you thought you had gotten right but didn&rsquo;t. Rather, it is something you didn&rsquo;t even know you had to get right<\/em>\u00bb). Aux difficult\u00e9s et aux risques d\u00e9j\u00e0 rencontr\u00e9s et connus, r\u00e9solus ou non encore r\u00e9solus, s&rsquo;ajoute d\u00e9sormais la perspective de difficult\u00e9s et de risques compl\u00e8tement ignor\u00e9s, contre lesquels on est \u00e9videmment tr\u00e8s mal arm\u00e9. (Un \u00e9ditorial dans le m\u00eame num\u00e9ro de la revue renforce encore le sentiment d&rsquo;inqui\u00e9tude qu&rsquo;on signale ici. Nous en rendons compte dans un <em>Bloc-Notes<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4510\" class=\"gen\">jour<\/a>.)<\/p>\n<\/p>\n<p><p>\tOn appr\u00e9ciera dans tous les cas que se dessine \u00e9galement un \u00e9chec fondamental, celui de l&rsquo;offensive virtualiste qui a accompagn\u00e9 le JSF pendant dix ans. Cette offensive semblait avoir impos\u00e9 l&rsquo;image d&rsquo;un programme irr\u00e9sistible, auquel il \u00e9tait imp\u00e9ratif de participer, notamment dans le chef des alli\u00e9s europ\u00e9ens. Le revers de cette m\u00e9daille virtualiste, c&rsquo;est que la mari\u00e9e est trop belle. En un sens, lorsqu&rsquo;on en arrive aux choses s\u00e9rieuses (et la demande de Lockheed Martin aux coop\u00e9rants d&rsquo;acheter l&rsquo;un ou l&rsquo;autre mod\u00e8le d&rsquo;essai en vol est une chose s\u00e9rieuse puisqu&rsquo;il est question d&rsquo;argent), il devient imp\u00e9ratif que le programme r\u00e9ponde dans la r\u00e9alit\u00e9 \u00e0 la perfection de l&rsquo;image virtualiste qu&rsquo;on en a donn\u00e9. Le virtualisme impose des exigences d&rsquo;autant plus fortes \u00e0 la r\u00e9alit\u00e9. Si ce n&rsquo;est pas le cas, la critique et la m\u00e9fiance naissent avec d&rsquo;autant plus de force qu&rsquo;on attendait la perfection,  et ce n&rsquo;est pas le cas puisque la demande de Lockheed Martin porte sur une participation financi\u00e8re inattendue \u00e0 cause de difficult\u00e9s financi\u00e8res. La critique et la m\u00e9fiance vont donc conduire \u00e0 d\u00e9couvrir les retards qu&rsquo;on avait ignor\u00e9s jusqu&rsquo;alors, l&rsquo;importance des probl\u00e8mes qu&rsquo;on avait minimis\u00e9e. C&rsquo;est ce qui est en train de se passer, m\u00eame si leurs int\u00e9r\u00eats entrecrois\u00e9s font que ceux qui montrent cette m\u00e9fiance font \u00e9galement le geste contradictoire de participer \u00e0 l&rsquo;affaiblissement du programme dans lequel ils sont engag\u00e9s. Tant pis, la dynamique psychologique de la m\u00e9fiance est lanc\u00e9e, elle est d\u00e9j\u00e0 en marche.<\/p>\n<\/p>\n<p><p>\tIl est possible qu&rsquo;on fixe \u00e0 l&rsquo;engagement dans la deuxi\u00e8me phase du probl\u00e8me de fin 2006 des pays coop\u00e9rants le dernier acte r\u00e9ussi du JSF virtualiste; et \u00e0 2007, l&rsquo;entr\u00e9e dans la r\u00e9alit\u00e9 du m\u00eame programme JSF.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entr\u00e9e du JSF dans l&rsquo;inconnu 8 octobre 2007 Certes, nous n&rsquo;avons jamais cach\u00e9 notre peu d&rsquo;app\u00e9tence pour le programme JSF. Nous ne l&rsquo;avons pas \u00e9pargn\u00e9. Nous nous sommes int\u00e9ress\u00e9s \u00e0 lui jusqu&rsquo;\u00e0 ce qui pourrait para\u00eetre de l&rsquo;acharnement (parce que c&rsquo;est un \u00e9v\u00e9nement fondamental de l&rsquo;a\u00e9ronautique, des affaires politiques et militaires, qui m\u00e9rite absolument cette&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[4195,7110,250,3501,3502,610,4247],"class_list":["post-69301","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-aviation","tag-inconnu","tag-jsf","tag-lockheed","tag-martin","tag-virtualisme","tag-week"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69301"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69301\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}