{"id":69315,"date":"2007-10-12T00:00:00","date_gmt":"2007-10-12T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2007\/10\/12\/la-liberte-est-devenue-notre-prison\/"},"modified":"2007-10-12T00:00:00","modified_gmt":"2007-10-12T00:00:00","slug":"la-liberte-est-devenue-notre-prison","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2007\/10\/12\/la-liberte-est-devenue-notre-prison\/","title":{"rendered":"<strong><em>\u201cLa \u2018Libert\u00e9&rsquo; est devenue notre prison\u201d<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">La Libert\u00e9&rsquo; est devenue notre prison<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t12 octobre 2007  James Carroll, qui est <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=2923\" class=\"gen\">connu<\/a> de nos lecteurs, a \u00e9crit un texte qui appara\u00eetra ambigu (Boston <em>Globe<\/em> du 10 octobre, repris le <a href=\"http:\/\/www.iht.com\/articles\/2007\/10\/10\/news\/edcarroll.php\" class=\"gen\">12 octobre 2007<\/a> dans l&rsquo;International <em>Herald Tribune<\/em>); le terme extr\u00eame de cette ambigu\u00eft\u00e9 concerne <em>in fine<\/em> le probl\u00e8me \u00e9videmment fondamental du sort\/de la fin de l&rsquo;Am\u00e9rique. Nous disons <em>in fine<\/em> car la chose est plut\u00f4t \u00e9voqu\u00e9e d&rsquo;une mani\u00e8re presque secondaire mais assez claire, secondaire parce que sans \u00eatre explicit\u00e9e apr\u00e8s avoir \u00e9t\u00e9 mentionn\u00e9e.<\/p>\n<\/p>\n<p><p>\tLe titre n&rsquo;est pas sensationnel mais dramatique. Sa signification profonde est bouleversante: \u00ab<em>A troubling turn in American history.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tCarroll commence par \u00e9num\u00e9rer certains cas d&rsquo;erreurs et de fausses orientations de l&rsquo;histoire US, constatant qu&rsquo;\u00e0 chaque fois il y eut reconnaissance de l&rsquo;erreur, tentative de correction, plus ou moins r\u00e9ussie, etc. En un sens, il y avait conscience de l&rsquo;histoire en train de se faire, et appr\u00e9ciation relative des \u00e9v\u00e9nements, avec intervention pour tenter de les corriger. Il constate que ce n&rsquo;est plus le cas. L&rsquo;Irak, en un sens, c&rsquo;est bien cela, et pour cette raison ce n&rsquo;est pas le Vietnam. Dans le cas du Vietnam, \u00e0 partir d&rsquo;un moment-clef (disons l&rsquo;offensive du T\u00eat de f\u00e9vrier 1968), il fut reconnu qu&rsquo;une victoire \u00e9tait impossible, que le Vietnam \u00e9tait une erreur et qu&rsquo;il fallait d\u00e9sormais songer \u00e0 s&rsquo;en d\u00e9sengager; que le d\u00e9sengagement ait \u00e9t\u00e9 cruel, rat\u00e9, hypocrite, etc.,  certes, mais il y avait eu reconnaissance de la faute ou de l&rsquo;erreur, et la r\u00e9action. Avec l&rsquo;Irak, rien de semblable.<\/p>\n<\/p>\n<p><p>\tVoici le passage o\u00f9 Carroll, \u00e0 l&rsquo;aide d&rsquo;exemples pr\u00e9cis, expose le probl\u00e8me qu&rsquo;il identifie : <\/p>\n<\/p>\n<p><p>\t\u00ab<em>That brings us to today. If this nation followed the pattern of its own historic reckoning with the ever unfinished work of public morality, political discourse would be defined by the dual-project of eliminating nuclear weapons and building international structures of peace. Instead, we are paralyzed by a war that no one wants, unable to change what matters most.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Last week, this story reached a climax of sorts, with developments like these:<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>War Cost. With new budget requests, the Iraq war price tag jumped over the $600 billion mark  enough, extrapolating from figures of the National Priorities Project, to add 9 million teachers to public schools for a year. Where would American education be if that happened instead? And where Iraq?<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Mercenaries. We learned that the United States government has surrendered to private contractor hit squads the primal function of protecting its own diplomats in Iraq. Such unaccountable and profit-driven forces betray the foundational American military ethic. Hessians at last.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Abolition. Barack Obama made a major speech calling for a return to the long-abandoned goal of nuclear elimination. We need to change our nuclear policy and our posture, which is still focused on deterring the Soviet Union  a country that doesn&rsquo;t exist. The major news media ignored this important declaration, obsessing instead with horse-race polls and fund-raising totals. Nuclear reform (antidote to proliferation and terrorism both) is not a campaign issue.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Torture. The Bush administration was revealed to have again secretly approved enhanced interrogation methods at restored CIA black sites, where prisoners are once more held without treaty protections  measures that Congress and the Supreme Court have already rejected. Despite scandals, U.S. torture continues.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>These developments would be disturbing enough, but what they point to is an interruption in this nation&rsquo;s most important public tradition  the movement from recognition of a problem to its attempted resolution. From ill treatment of native peoples, to enslavement of Africans, to temptations to empire, to a religious embrace of violence, to Red Scare paranoia, to an insane arms race  we Americans have had our failings. But we have faced them. The capacity for self-criticism and change has defined our history. But that is not happening today. We are in an arms race with ourselves, and will not stop. Our unjust war is just unending. Our politics and media, meanwhile, form a feedback loop of banality.<\/em> <strong><em>Freedom has become our prison.<\/em><\/strong>\u00bb<\/p>\n<\/p>\n<p><p>\tNous avons volontairement soulign\u00e9 la derni\u00e8re phrase,  La Libert\u00e9&rsquo; est devenue notre prison, que nous jugeons ambigu\u00eb, qui est l&rsquo;illustration de cette ambigu\u00eft\u00e9 g\u00e9n\u00e9rale signal\u00e9e plus haut. Cette ambigu\u00eft\u00e9 n&rsquo;est pas le fait d&rsquo;un esprit confus, qui distingue mal les choses et lance l&rsquo;une ou l&rsquo;autre phrase, pour prendre date mais sans y rien comprendre. Cette ambigu\u00eft\u00e9 serait plut\u00f4t de la prudence et de la r\u00e9ticence \u00e0 aller jusqu&rsquo;au bout d&rsquo;un raisonnement  n\u00e9 des constats que nous offre Carroll. La cause en est qu&rsquo;on devine bien quelle bouleversante conclusion nous attendrait,  qui ne serait rien de moins que la mort de l&rsquo;id\u00e9e am\u00e9ricaine et de l&rsquo;Am\u00e9rique aussi bien en tant que nation (fausse nation \u00e0 notre sens, et tout est l\u00e0) qu&rsquo;en tant qu&rsquo;id\u00e9e historique r\u00e9volutionnaire.<\/p>\n<\/p>\n<p><p>\tLe dernier paragraphe forme la conclusion. Elle suit imm\u00e9diatement la phrase ambigu\u00eb \u00e0 laquelle nous nous sommes attach\u00e9e (La Libert\u00e9&rsquo; est devenue notre prison). Elle est elle-m\u00eame marqu\u00e9e par ce trait de l&rsquo;ambigu\u00eft\u00e9  sugg\u00e9rer mais ne pas affirmer la <strong>vraie<\/strong> conclusion \u00e0 laquelle aboutit Carroll. \u00ab<em>Does all of this reveal a deeper flaw in our moral narrative itself? After all, we say today that our story began with Columbus. But what about the ones who welcomed him?<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLa conclusion r\u00e9sume l&rsquo;histoire m\u00eame de l&rsquo;Am\u00e9rique, et sugg\u00e8re son \u00e9chec d\u00e9sormais irr\u00e9m\u00e9diable et in\u00e9luctable. Il ne reste plus qu&rsquo;\u00e0 attendre que les \u00e9v\u00e9nements sanctionnent cette irr\u00e9m\u00e9diabilit\u00e9 et cette in\u00e9luctabilit\u00e9. Ce n&rsquo;est pas rien pour Carroll, auteur extr\u00eamement critique du syst\u00e8me mais qui a (jusqu&rsquo;ici?) gard\u00e9 l&rsquo;espoir d&rsquo;une r\u00e9forme radicale qui renverserait le cours des choses et tuerait le monstre qui d\u00e9vore l&rsquo;Am\u00e9rique.<\/p>\n<h3>La Libert\u00e9 est-elle liberticide?<\/h3>\n<\/p>\n<p><p>\tA quoi se r\u00e9sume le constat de Carroll, si l&rsquo;on \u00e9carte l&rsquo;ambigu\u00eft\u00e9 n\u00e9e de la r\u00e9ticence qu&rsquo;on a d\u00e9crite? La phrase signal\u00e9e est ambigu\u00eb dans son contexte mais elle se d\u00e9couvre clairement en elle-m\u00eame. La Libert\u00e9&rsquo; est devenue notre prison affirme une chose bien pr\u00e9cise, indiscutable selon la forme propos\u00e9e. L&rsquo;Am\u00e9rique a succomb\u00e9 \u00e0 l&rsquo;exercice de ce qui \u00e9tait appr\u00e9ci\u00e9 comme sa vertu absolument fondamentale: la libert\u00e9. Ce constat nous autorise \u00e0 pousser le raisonnement \u00e0 son terme,  malgr\u00e9 les guillemets et la majuscule pour le mot <em>Freedom<\/em>,  ou plut\u00f4t \u00e0 cause d&rsquo;eux, car alors c&rsquo;est bien le principe supr\u00eame qui est d\u00e9sign\u00e9, les guillemets sugg\u00e9rant combien ce principe a donn\u00e9 son contraire.<\/p>\n<\/p>\n<p><p>\tSi la libert\u00e9 est devenue notre prison, quel espoir reste-t-il? En bonne logique, cet espoir devrait passer par la liquidation de cette libert\u00e9 devenue monstre qui nous emprisonne. Il ne s&rsquo;agit pas du constat que la libert\u00e9 a \u00e9t\u00e9 bafou\u00e9e, d\u00e9form\u00e9e, trahie ; non, c&rsquo;est la libert\u00e9 elle-m\u00eame qui nous a trahis. La libert\u00e9 n&rsquo;est donc pas la lib\u00e9ration de l&rsquo;homme mais, au contraire, son emprisonnement. On comprend que Carroll h\u00e9site \u00e0 affirmer cela, m\u00eame si l&rsquo;on peut juger critiquable  qu&rsquo;il ne le fasse pas. Vis-\u00e0-vis de lui-m\u00eame, ce jugement serait terrible et bouleversant.<\/p>\n<\/p>\n<p><p>\tLes exemples qu&rsquo;il offre dans l&rsquo;extrait choisi l\u00e0-dessus ne sont pas des accidents mais l&rsquo;illustration d&rsquo;une tendance d\u00e9sormais assez syst\u00e9matique pour qu&rsquo;on la juge structurelle et par cons\u00e9quent irr\u00e9m\u00e9diable. Son affirmation n&rsquo;est pas un jeu de l&rsquo;esprit, une proposition th\u00e9orique, une hypoth\u00e8se, c&rsquo;est bien le <strong>constat<\/strong> d&rsquo;une situation de fait. La sp\u00e9culation n&rsquo;est plus de mise. Nous en venons au simple r\u00e9alisme de nous incliner devant la r\u00e9alit\u00e9.<\/p>\n<\/p>\n<p><p>\tLes situations qu&rsquo;il d\u00e9crit sont les r\u00e9sultats d&rsquo;une \u00e9volution g\u00e9n\u00e9rale paradoxalement caract\u00e9ris\u00e9e par la libert\u00e9. Les divers processus ayant conduit \u00e0 ces situations se sont d\u00e9roul\u00e9s sans entraves, en toute libert\u00e9 justement. La libert\u00e9 a conduit \u00e0 des situations diverses toutes caract\u00e9ris\u00e9es par l&#8217;emprisonnement,  par le contraire de la libert\u00e9. Le rappel des origines est le motif final d&rsquo;absence d&rsquo;espoir d&rsquo;un renversement. A l&rsquo;origine de l&rsquo;\u00e9tablissement des colons au nom de la libert\u00e9, il y a une trahison de la libert\u00e9: \u00ab<em>But what about the ones who welcomed him?<\/em>\u00bb (Ceux-l\u00e0, les Indiens, ou <em>Native Americans<\/em>, que nous avons priv\u00e9s de leur libert\u00e9 jusqu&rsquo;\u00e0 leur extermination?)  Mais non, justement, si ce n&rsquo;\u00e9tait pas la trahison de la libert\u00e9 mais l&rsquo;acte de la libert\u00e9 tout court, d\u00e9couvert comme paradoxal et vicieux irr\u00e9m\u00e9diablement, une trahison de la libert\u00e9 par la libert\u00e9? La libert\u00e9 acquise par les colons se forme et s&rsquo;affirme en emprisonnant les autres, les Indiens, en les privant de leur libert\u00e9, en les d\u00e9truisant. La libert\u00e9 d\u00e9truit la libert\u00e9. La <em>narrative<\/em>, mot qui va mieux pour l&rsquo;Am\u00e9rique qu&rsquo;Histoire, a d\u00e9tourn\u00e9 tout cela par la dissimulation, le mensonge, la falsification.<\/p>\n<\/p>\n<p><p>\t(Si l&rsquo;on fait l&rsquo;objection de l&rsquo;injustice, ou l&rsquo;in\u00e9galit\u00e9 des forces en pr\u00e9sence, notamment \u00e9conomiques, qui conduisent l&rsquo;\u00e9volution en toute libert\u00e9 \u00e0 des triomphes qui m\u00e9nagent le contraire de la libert\u00e9, on n&rsquo;a rien r\u00e9solu. Lutter contre cette injustice ou cette in\u00e9galit\u00e9 suppose une action arbitraire, en g\u00e9n\u00e9ral d&rsquo;un pouvoir public, qui est, selon la conception am\u00e9ricaniste et sans contredire la logique, l&rsquo;antith\u00e8se de la libert\u00e9, et par cons\u00e9quent une attaque mortelle contre la libert\u00e9.)<\/p>\n<\/p>\n<p><p>\tVoil\u00e0 l&rsquo;arr\u00eat de mort de l&rsquo;Am\u00e9rique. Cette nation qui n&rsquo;en est pas une, qui n&rsquo;a aucune transcendance pour la soutenir au-del\u00e0 de ses avatars terrestres, s&rsquo;est construite totalement sur la libert\u00e9. (Contrairement \u00e0 nombre d&rsquo;analyses, notre appr\u00e9ciation est effectivement que le r\u00e9gime am\u00e9ricaniste n&rsquo;est pas oppressif,  m\u00eame s&rsquo;il est policier. Il est \u00e0 la fois conformiste, r\u00e9gul\u00e9, niveleur et, plus r\u00e9cemment, virtualiste. Mais, dans ce cadre qui n&rsquo;impose rien de politiquement contraint, la libert\u00e9 occupe la place centrale. Elle est essentielle notamment parce qu&rsquo;elle est la condition de l&rsquo;\u00e9conomie capitaliste,  libert\u00e9 vis-\u00e0-vis de toute entrave r\u00e9gulatrice de la puissance publique.) La libert\u00e9 se r\u00e9v\u00e9lant tromperie et contraire d&rsquo;elle-m\u00eame, et liberticide par cons\u00e9quent, d\u00e9truisant d&rsquo;abord celle des autres puis, en phase finale, se d\u00e9truisant elle-m\u00eame. Ainsi en est-il pour l&rsquo;Am\u00e9rique.<\/p>\n<\/p>\n<p><p>\tIl ne fait aucun doute que, s&rsquo;il est confirm\u00e9 et accept\u00e9, ce constat dramatique pour l&rsquo;Am\u00e9rique vaudrait \u00e9galement pour nous, Europ\u00e9ens, qui pla\u00e7ons cette valeur au-dessus de toutes selon les conceptions de la modernit\u00e9. Mais notre situation est diff\u00e9rente parce que nous avons une tradition et une l\u00e9gitimit\u00e9 historiques qui ne d\u00e9pendent pas de la seule libert\u00e9; dans certaines conditions, on peut concevoir que cette situation pourrait en th\u00e9orie pr\u00e9server la libert\u00e9 sans en devenir prisonniers, en contenant son paradoxal caract\u00e8re liberticide; le vice fondamental de l&rsquo;Am\u00e9rique serait alors d&rsquo;avoir choisi la seule libert\u00e9 pour se construire, et d&rsquo;avoir rejet\u00e9 les structures historiques qui pourraient conduire \u00e0 une autre issue que l&rsquo;auto-destruction. Quoi qu&rsquo;il en soit, le d\u00e9bat abord\u00e9 par ces quelques remarques de Carroll est bouleversant.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Libert\u00e9&rsquo; est devenue notre prison 12 octobre 2007 James Carroll, qui est connu de nos lecteurs, a \u00e9crit un texte qui appara\u00eetra ambigu (Boston Globe du 10 octobre, repris le 12 octobre 2007 dans l&rsquo;International Herald Tribune); le terme extr\u00eame de cette ambigu\u00eft\u00e9 concerne in fine le probl\u00e8me \u00e9videmment fondamental du sort\/de la fin&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[2947,3369,5276,3287,7124],"class_list":["post-69315","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-amerique","tag-carroll","tag-indiens","tag-liberte","tag-liberticide"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69315"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69315\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}