{"id":69323,"date":"2007-10-15T00:00:00","date_gmt":"2007-10-15T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2007\/10\/15\/comment-avec-laide-de-son-ame-poutine-ancien-brillant-officier-du-kgb-avait-reussi-a-retourner-gw\/"},"modified":"2007-10-15T00:00:00","modified_gmt":"2007-10-15T00:00:00","slug":"comment-avec-laide-de-son-ame-poutine-ancien-brillant-officier-du-kgb-avait-reussi-a-retourner-gw","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2007\/10\/15\/comment-avec-laide-de-son-ame-poutine-ancien-brillant-officier-du-kgb-avait-reussi-a-retourner-gw\/","title":{"rendered":"Comment, avec l&rsquo;aide de son \u00e2me, Poutine, ancien \u201cbrillant officier du KGB\u201d, avait r\u00e9ussi \u00e0 \u201cretourner\u201d GW\u2026"},"content":{"rendered":"<p><p>L&rsquo;activit\u00e9 est grande, aujourd&rsquo;hui, dans les centres d&rsquo;analyse occidentaux, pour d\u00e9terminer ce qui n&rsquo;a pas march\u00e9 avec Poutine. (Puisqu&rsquo;il s&rsquo;av\u00e8re, \u00e0 vrai dire, que la politique occidentale vis-\u00e0-vis de Poutine n&rsquo;est pas une r\u00e9ussite.) En marge de leur <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4527\" class=\"gen\">visite moscovite<\/a>, les Am\u00e9ricains se sont activ\u00e9s \u00e0 faire le compte. Triste d\u00e9compte.<\/p>\n<\/p>\n<p><p>\tOn a une bonne analyse de ce d\u00e9bat dans une d\u00e9p\u00eache de McClatchy Newspapers, en date du <a href=\"http:\/\/www.mcclatchydc.com\/227\/story\/20508.html\" class=\"gen\">12 octobre<\/a> ; une analyse qui, nous dit-on, refl\u00e8te bien le courant auto-critique qui parcourt actuellement les milieux de s\u00e9curit\u00e9 nationale de Washington.<\/p>\n<\/p>\n<p><p>\tLe rapport McClatchy Newspapers est int\u00e9ressant parce qu&rsquo;il nous expose les modalit\u00e9s des erreurs US vis-\u00e0-vis de Poutine,  puisqu&rsquo;il s&rsquo;av\u00e8re (titre de l&rsquo;article) que \u00ab<em>Bush, aides grossly misjudged Putin<\/em>\u00bb. Quelques extraits exposant le cas: <\/p>\n<\/p>\n<p><p>\t\u00ab<em>Bush&rsquo;s strategy on Russia assumed that Russian President Vladimir Putin embraced democracy, wanted integration with the West and sought a strategic partnership in which Moscow would acquiesce to U.S. policies such as NATO expansion. Feuds could be resolved through the close personal relationship that Bush believed he had with his Russian counterpart.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Instead, fueled by record oil and natural gas prices and resentment of what he lambasted in February as Bush&rsquo;s almost uncontained hyper use of force, Putin has led global opposition to the U.S. war in Iraq, hosted Palestinians on the U.S. list of terrorist groups, sold anti-aircraft missiles and other arms to Iran and stymied Bush&rsquo;s drive to tighten U.N. sanctions on the Islamic republic for refusing to suspend uranium enrichment.<\/em><\/p>\n<\/p>\n<p><p>\t()<\/p>\n<\/p>\n<p><p>\t\u00bb<em>The U.S.-Russian tensions are a far cry from June 2001, when Bush declared after his first meeting with Putin in Slovenia that he&rsquo;d looked in the Russian leader&rsquo;s eyes, found him trustworthy and was able to get a sense of his soul.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Bush and his aides grossly misjudged Putin, considering him a good guy and one of us, said Michael McFaul of Stanford University&rsquo;s Hoover Institution.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The former KGB officer created that illusion partly by appearing to share Bush&rsquo;s political and religious convictions, standard tradecraft employed by intelligence officers to recruit spies, he said.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Putin . . . is a brilliant case officer, said Carlos Pasqual, a former senior State Department official now at The Brookings Institution, a center-left policy organization in Washington.<\/em><\/p>\n<\/p>\n<p><p>\t()<\/p>\n<\/p>\n<p><p>\t\u00bb<em>U.S. officials refused to accept that the Russians do have an interest in what they call their near abroad,&rsquo; said a former top State Department official who requested anonymity to speak more freely. The Russians would have differences of opinion with us, and we would not acknowledge that we had differences of opinions.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tAinsi apprend-on successivement :<\/p>\n<\/p>\n<p><p>\t Ce que les Am\u00e9ricains (et l&rsquo;Ouest avec, bien s\u00fbr) attendaient de leurs nouvelles relations avec la Russie, comme une chose naturelle et \u00e9vidente, comme une alliance enfin \u00e9quilibr\u00e9e entre les anciens adversaires de la guerre froide,  c&rsquo;est que la Russie dev\u00eent une d\u00e9mocratie \u00e0 l&rsquo;occidentale, c&rsquo;est-\u00e0-dire align\u00e9e sur les USA, int\u00e9gr\u00e9e dans les circuits \u00e9conomiques et financiers occidentaux, agr\u00e9ant aux diverses initiatives occidentales (dont l&rsquo;expansion de l&rsquo;OTAN).<\/p>\n<\/p>\n<p><p>\t Il n&rsquo;\u00e9tait pas concevable ni envisag\u00e9 une seconde que les Russes aient leurs int\u00e9r\u00eats propres, notamment dans les pays proches de l&rsquo;ex-bloc communiste. Comme le dit l&rsquo;officiel du d\u00e9partement d&rsquo;Etat cit\u00e9, on refusait d&rsquo;admettre que les Russes aient des opinion diff\u00e9rentes de celles du d\u00e9partement d&rsquo;Etat.<\/p>\n<\/p>\n<p><p>\t La chose se r\u00e9sume dans la phrase fameuse de Bush, annon\u00e7ant qu&rsquo;il avait d\u00e9couvert que Poutine avait une \u00e2me, bref qu&rsquo;il \u00e9tait un \u00eatre humain comme vous et moi. Cela signifiait, bien \u00e9videmment, qu&rsquo;il \u00e9tait un Am\u00e9ricains, comme vous et moi ; qu&rsquo;il \u00e9tait \u00ab<em>a good guy and one of us<\/em>\u00bb, comme r\u00e9sume brillamment Michael McFaul, de la Hoover Institution de Stanford.<\/p>\n<\/p>\n<p><p>\t Nous avons enfin la r\u00e9v\u00e9lation de la substance du g\u00e9nie de Poutine. Il r\u00e9side en ceci qu&rsquo;il a r\u00e9ussi, en bon officier du KGB, \u00e0 retourner et, quasiment, \u00e0 recruter GW Bush : \u00ab<em>The former KGB officer created that illusion partly by appearing to share Bush&rsquo;s political and religious convictions, standard tradecraft employed by intelligence officers to recruit spies, he said.<\/em>\u00bb M\u00eame si nous sommes un peu \u00e9tourdi par le brio de l&rsquo;analyse, une objection venue \u00e0 notre esprit est de nous demander dans quelle mesure le brillant officier du KGB avait besoin de simuler pour para\u00eetre avoir les m\u00eames convictions que Bush pour le retourner puisque le d\u00e9partement d&rsquo;Etat avait d&rsquo;ores et d\u00e9j\u00e0 d\u00e9cid\u00e9 que c&rsquo;\u00e9tait bien le cas (on refusait d&rsquo;admettre que les Russes aient des opinion diff\u00e9rentes de celles du d\u00e9partement d&rsquo;Etat).<\/p>\n<\/p>\n<p><p>\tOn se demande ce qui est le plus remarquable: les erreurs qui furent commises, qui ne sont rien d&rsquo;autre que l&rsquo;expression de la nature la plus primaire de la psychologie am\u00e9ricaniste et du <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1250\" class=\"gen\">virtualisme<\/a> d\u00e9sormais courant \u00e0 Washington, ou la critique apparemment l\u00e9g\u00e8re et sereine, voire souriante, qui en est faite. Tout le monde, critiques et critiqu\u00e9s, continue \u00e0 \u00eatre content de soi et du syst\u00e8me de l&rsquo;am\u00e9ricanisme. Comme dit <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4517\" class=\"gen\">l&rsquo;autre<\/a>, \u00ab[i]<em>n Washington, nothing succeeds more than failure<\/em>\u00bb.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 15 octobre 2007 \u00e0 14H21<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;activit\u00e9 est grande, aujourd&rsquo;hui, dans les centres d&rsquo;analyse occidentaux, pour d\u00e9terminer ce qui n&rsquo;a pas march\u00e9 avec Poutine. (Puisqu&rsquo;il s&rsquo;av\u00e8re, \u00e0 vrai dire, que la politique occidentale vis-\u00e0-vis de Poutine n&rsquo;est pas une r\u00e9ussite.) En marge de leur visite moscovite, les Am\u00e9ricains se sont activ\u00e9s \u00e0 faire le compte. Triste d\u00e9compte. On a une bonne&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[7127,4058,3551,916,610],"class_list":["post-69323","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-budh","tag-echec","tag-kgb","tag-poutine","tag-virtualisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69323"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69323\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}