{"id":69339,"date":"2007-10-19T00:00:00","date_gmt":"2007-10-19T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2007\/10\/19\/american-fluidite\/"},"modified":"2007-10-19T00:00:00","modified_gmt":"2007-10-19T00:00:00","slug":"american-fluidite","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2007\/10\/19\/american-fluidite\/","title":{"rendered":"<strong><em>\u201cAmerican\u201d fluidit\u00e9<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\"><em>American<\/em> fluidit\u00e9<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t19 octobre 2007  Nous nous sommes attach\u00e9s \u00e0 un texte de Bernard Weiner, \u00e9diteur du site <em>Crisis Papers<\/em>. Bernard Weiner, po\u00e8te et auteur de th\u00e9\u00e2tre, a \u00e9t\u00e9 le critique th\u00e9\u00e2tral du San Francisco <em>Chronicle<\/em> pendant 16 ans. Il est aussi, autre facette remarquable, professeur de relations internationales, enseignant dans plusieurs universit\u00e9s. Le texte date du <a href=\"http:\/\/www.crisispapers.org\/essays7w\/suicide.htm\" class=\"gen\">16 octobre<\/a>, bas\u00e9 sur une conf\u00e9rence de Weiner \u00e0 Munich (le 10 octobre) devant un rassemblement de citoyens US \u00e0 l&rsquo;\u00e9tranger, membres militants du parti d\u00e9mocrate. D\u00e9mocrate lui-m\u00eame, Weiner donne un bon aper\u00e7u du d\u00e9sarroi peu ordinaire qui parcourt l&rsquo;\u00e9lectorat US (en g\u00e9n\u00e9ral, r\u00e9publicain compris) et, plus particuli\u00e8rement dans ce cas, l&rsquo;\u00e9lectorat d\u00e9mocrate,  d&rsquo;un parti qui sort d&rsquo;une victoire exceptionnelle (novembre 2006) et se dirige, dit-on, vers une victoire non moins exceptionnelle (novembre 2008).<\/p>\n<\/p>\n<p><p>\tNous avons beaucoup abord\u00e9 des questions ponctuelles concernant telle ou telle candidature ou non-candidature, des plus <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4504\" class=\"gen\">assur\u00e9es<\/a> aux plus <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4513\" class=\"gen\">inattendues<\/a>, aux plus <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4525\" class=\"gen\">\u00e9tonnantes<\/a>. Cette fois, nous voulons aborder d&rsquo;une fa\u00e7on plus g\u00e9n\u00e9rale l&rsquo;\u00e9tat d&rsquo;esprit des \u00e9lecteurs. D\u00e9couvrir un tel d\u00e9sarroi chez des repr\u00e9sentants du parti de la victoire quasi-assur\u00e9e, voil\u00e0 qui ne laisse pas d&rsquo;\u00eatre un constat int\u00e9ressant.<\/p>\n<\/p>\n<p><p>\tCi-dessous, un extrait (la fin) du texte de Wesner, analysant ce qu&rsquo;il per\u00e7oit de la situation de l&rsquo;\u00e9lectorat d\u00e9mocrate, \u00e0 partir de son exp\u00e9rience US autant que de sa conf\u00e9rence en Allemagne. Effectivement, le terme nous para\u00eet ad\u00e9quat: la situation est fluide<\/p>\n<\/p>\n<p><p>\t\u00ab<em>THE FLUIDITY OF POLITICS<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Things are fairly fluid politically right now. As I&rsquo;ve written previously, there is a potential opening for a third-party run, drawing from the disenchanted wings of both the Republican and Democratic parties. Is there a charismatic crossover candidate willing to take advantage of that momentary opening to help mount a viable run for the White House in 2008? If a strong third party candidacy emerged, which major party would be most helped, the Republicans or the Democrats? Could the Republican candidate slide by into the White House if too many Democrats deserted their party to vote for this third-party candidate? Might the chances for popular approval soar if that third-party were to create a bi-partisan Unity ticket, made up of a leading Democrat and a leading, anti-war Republican. (Gore\/Hagel?)<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Finally, a longer-range thought. Even if a viable third party doesn&rsquo;t get born this time out, the Democrats are ripe, as are the Republicans, for a good, long, soul-searching debate about the future of the party. Redefining the mission. Coming up with some philosophies of governance, and foreign policies, we all can agree on. Developing policy statements in various areas that are not just reactions to what the Republicans are doing. Etc. Etc.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>In short, the 2008 election may well turn out to be a watershed in modern American politics, re-aligning the electorate in ways they feel more comfortable with. We shall see.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>THE Q&#038;A SESSION<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>What followed those prepared remarks was a wide-ranging discussion of U.S. domestic and foreign politics, everything from: whether Gore (now Nobel Laureate Gore) will jump into the presidential ring  there was much enthusiasm among the DA crowd for the idea; the intricacies of vote-tabulation and the likelihood of electoral fraud again; the insanity of attacking Iran and why CheneyBush would take that route; the possible genesis of Democratic wimpiness these days; the punishment the Party leadership is preparing for several state Dem organizations such as in Florida and Michigan for pushing their primaries way forward, etc. But a good share of the conversation involved the frustration and puzzlement they feel toward their wimpy Party leadership. And about the Democratic contenders, especially whether anyone can stop Hillary.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>And, of course, these DA members wanted to know my preferred candidate(s). I told them that, for a wide variety of pragmatic and policy reasons, I would prefer the Dem nominee not be Hillary Clinton; of the potentially electable candidates, I am more favorably inclined to John Edwards, with much to admire also about Bill Richardson and Barack Obama. Despite their elitist ties and tendencies, any of these three would be somewhat more progressive, anti-war, civil libertarian and more sympatico than is Hillary.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>But, if Hillary Clinton turns out to be the Dem standard-bearer in 2008, then all we progressive, anti-imperialist Democrats will face the usual moral dilemma next November. Clearly, there are significant differences between the two parties. The question is: Will there be enough of a difference between our candidates and those put forward by the Republicans to justify yet again holding our noses and voting for the lesser of two evils? I suspect the answer is yes, but we shall see how the political drama plays out in the next six months.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tWeiner cite dans son texte une lettre re\u00e7ue par le San Francisco <em>Chronicle<\/em>, d&rsquo;un lecteur qui lui semble repr\u00e9senter l&rsquo;\u00e9lecteur typique US, d\u00e9go\u00fbt\u00e9 du parti auquel il adh\u00e9rait et qui se tournerait vers un candidat ind\u00e9pendant ou un troisi\u00e8me parti. D&rsquo;autre part, les calculs \u00e9lectoraux que pr\u00e9sente cet \u00e9lecteur t\u00e9moignent de la complexit\u00e9 des blocages des courats de la politique US.<\/p>\n<\/p>\n<p><p>\t\u00ab<em> Editor &#8211; &#8230; As of today, I will vote for Sen. Barack Obama or Bill Richardson [in the primary], because in my opinion, Sen. Hillary Clinton is the best chance the Democrats have to lose the 2008 presidential general election.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>If she is their nominee, hatred of her will motivate Republican conservatives to vote and work to elect the Republican candidate, whoever he is.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>At the same time, Clinton is the most likely to drive a third party candidate from her left to enter the race. The growing number of independent voters includes disaffected Republicans and they, too, would be more inclined to vote Republican if Clinton is the Democratic candidate.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Even though I strongly feel that the U.S. will be best served if a Democrat, not a Republican, is elected President in 2008, I will vote for a third-party candidate, even if it means the Republican candidate is elected. I won&rsquo;t be alone in doing so.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Jim DiCarlo, San Francisco (23 September, 2007).<\/em>\u00bb<\/p>\n<h3>GW est-il l&rsquo;arbre qui cache la for\u00eat?<\/h3>\n<\/p>\n<p><p>\tIl nous semble que l&rsquo;\u00e9lection pr\u00e9sidentielle de 2008 aux USA sera tr\u00e8s paradoxale et, peut-\u00eatre, extraordinaire dans son d\u00e9roulement, dans la perspective d&rsquo;une p\u00e9riode pr\u00e9-\u00e9lectorale qui a d&rsquo;ores et d\u00e9j\u00e0 commenc\u00e9. Nous voudrions l&rsquo;envisager ici sans vraiment nous int\u00e9resser aux r\u00e9sultats possibles, \u00e0 la personnalit\u00e9 des candidats, etc. De ce point de vue, savoir si Hillary  fera \u00e9quipe avec Bill ou si Ron Paul sera candidat ind\u00e9pendant ne nous importe pas. (Par contre, savoir que Hillary fera \u00e9quipe avec Bill pour les raisons qu&rsquo;on sait, que Ron Paul a une position de force extraordinaire, qu&rsquo;il ne faut pas \u00e9carter l&rsquo;hypoth\u00e8se Gore en cas d&rsquo;\u00e9v\u00e9nement dramatique, tout cela nous importe dans le cadre de ce texte pour ce que ces faits et sp\u00e9culations nous disent de l&rsquo;\u00e9tat d&rsquo;esprit US.)<\/p>\n<\/p>\n<p><p>\tAu reste,  et c&rsquo;est pourquoi nous consid\u00e9rons le texte de Weiner comme un indicateur d&rsquo;ambiance plut\u00f4t qu&rsquo;un texte de politique \u00e0 proprement dit,  il nous semble peu ordinaire que dans un tel texte o\u00f9 il appara\u00eet que les diff\u00e9rents protagonistes (l&rsquo;intervenant et auteur du texte et son auditoire) sont extr\u00eamement libres de leurs esprits et de leur parole, le nom de Ron Paul n&rsquo;apparaisse pas une seule fois alors qu&rsquo;on \u00e9voque l&rsquo;hypoth\u00e8se d&rsquo;une candidature ind\u00e9pendante avec un ticket unitaire du type d\u00e9mocrate-r\u00e9publicain dissident Gore-<a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4437\" class=\"gen\">Hagel<\/a>,  rien que \u00e7a ! (\u00ab<em>Might the chances for popular approval soar if that third-party were to create a bi-partian Unity ticket, made up of a leading Democrat and a leading, anti-war Republican. (Gore\/Hagel?).<\/em>\u00bb) Cela indique pour le moins un certain \u00e9clatement de la situation pr\u00e9-\u00e9lectorale; le refus, volontaire ou pas, ou l&rsquo;incapacit\u00e9 de prendre en compte tous les faits de cette situation (cela vaut pour les commentateurs comme pour les \u00e9tat-majors politiques); la possibilit\u00e9 d&rsquo;autant plus ouverte, \u00e0 partir de cette situation d&rsquo;autisme s\u00e9lectif dans l&rsquo;un ou l&rsquo;autre sens, d&rsquo;une surprise dans le cours de la campagne, etc.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est de ce point de vue de l&rsquo;ambiance psychologique que nous nous r\u00e9f\u00e9rons \u00e0 ce texte. Dans ce cas, la libert\u00e9 des esprits et de la parole compte beaucoup (notamment le fait que l&rsquo;audience est faite de citoyens US expatri\u00e9s, donc lib\u00e9r\u00e9s de la pesanteur psychologique consid\u00e9rable du conformisme <em>at home<\/em>). Il s&rsquo;agit de psychologies plus libres, m\u00eame si les opinions sont semblables, que celles de participants \u00e0 un d\u00e9bat aux USA. A cette lumi\u00e8re, le fait essentiel de notre constat est que l&rsquo;\u00e9lection de 2008 s&rsquo;annonce tr\u00e8s diff\u00e9rente de celle de 2004. Elle est v\u00e9ritablement d\u00e9senchant\u00e9e (nous avons h\u00e9sit\u00e9 devant le terme d\u00e9sesp\u00e9r\u00e9e) ou d\u00e9boussol\u00e9e par rapport \u00e0 celle de 2004. Le d\u00e9sarroi vaut pour tous les acteurs en pr\u00e9sence, y compris pour le syst\u00e8me lui-m\u00eame qui appara\u00eet tr\u00e8s impuissant devant certaines potentialit\u00e9s (l&rsquo;\u00e9quip\u00e9e Ron Paul, par exemple).<\/p>\n<\/p>\n<p><p>\tObservons qu&rsquo;il n&rsquo;est nullement incongru de discuter de la chose (l&rsquo;\u00e9lection de 2008) un an avant cette \u00e9lection. Pour l&rsquo;\u00e9lection de 2004, le m\u00eame ph\u00e9nom\u00e8ne d&rsquo;int\u00e9r\u00eat actif plus d&rsquo;un an avant avait eu lieu. Sur notre site, le premier texte r\u00e9f\u00e9renc\u00e9 envisageant la question de l&rsquo;\u00e9lection de novembre 2004 est dat\u00e9 du <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=830\" class=\"gen\">2 ao\u00fbt 2003<\/a>. Il ne s&rsquo;agit pas d&rsquo;une sp\u00e9culation qui nous \u00e9tait propre puisque nous pr\u00e9sentions un texte ext\u00e9rieur sur le sujet. Justement, ce texte exposait le sujet qui caract\u00e9risa les sp\u00e9culations avant 2004: \u00ab<em>Would an Incoming Democratic Administration Be Forced to Maintain the Bush Doctrine?<\/em>\u00bb, de la soci\u00e9t\u00e9 d&rsquo;analyse <a href=\"http:\/\/www.pinr.com\" class=\"gen\">PINR<\/a>. <\/p>\n<\/p>\n<p><p>\t(Nous-m\u00eames, nous \u00e9voquions la question de savoir si la politique US depuis 9\/11 serait diff\u00e9rente sans GW, si elle ne tenait qu&rsquo;\u00e0 GW, dans un texte du <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=501\" class=\"gen\">8 d\u00e9cembre 2002<\/a> pr\u00e9sentant une <em>Analyse<\/em> de notre Lettre d&rsquo;Analyse <em>de defensa<\/em> du 25 octobre 2002. Bien entendu, notre r\u00e9ponse \u00e9tait n\u00e9gative, comme elle l&rsquo;a toujours \u00e9t\u00e9.)<\/p>\n<\/p>\n<p><p>\tEn 2004, la sp\u00e9culation \u00e9tait nette. La proposition dominante \u00e9tait caract\u00e9ris\u00e9e par ce slogan tr\u00e8s en vogue : <em>Everybody But Bush<\/em> (N&rsquo;importe qui mais pas Bush,  nous ne sommes pas s\u00fbrs de la formulation mais c&rsquo;est l&rsquo;esprit). En d&rsquo;autres termes, la politique catastrophique \u00e9tait identifi\u00e9e \u00e0 un homme, m\u00eame pas \u00e0 un parti (r\u00e9publicain) ; c&rsquo;est un peu comme 9\/11, comme ceux qui font de cet \u00e9v\u00e9nement un cataclysme, et un cataclysme comploteur \u00e9ventuellement, selon la logique transparente qu&rsquo;il y a un avant-9\/11 et un apr\u00e8s-9\/11, impliquant par cons\u00e9quent que le syst\u00e8me dans toute sa dur\u00e9e est moins en cause que le syst\u00e8me-d\u00e9cha\u00een\u00e9-depuis-et-par-9\/11.<\/p>\n<\/p>\n<p><p>\t(Pour nous, effectivement, 9\/11,  complot ou pas, cela importe peu,  n&rsquo;a rien chang\u00e9 de fondamental de la nature des choses am\u00e9ricanistes, m\u00eame s&rsquo;il a boulevers\u00e9 les psychologies; il a <strong>r\u00e9v\u00e9l\u00e9<\/strong> sans doute <strong>d\u00e9finitivement<\/strong> la vraie nature du syst\u00e8me; le syst\u00e8me existait en substance avant 9\/11. Le fait du syst\u00e8me de l&rsquo;am\u00e9ricanisme, qui remonte \u00e0 1787 et qui est l&rsquo;image exacte et achev\u00e9e par les circonstances am\u00e9ricaines de la modernit\u00e9 n\u00e9e en Europe, est <strong>infiniment<\/strong> plus important que 9\/11,  complot ou pas. Nous comprenons bien ceci, dans cette th\u00e8se: les USA ne sont pas une aberration qui ne nous concerne pas, ils sont une aberration enfant\u00e9e par l&rsquo;Europe et sa philosophie du Progr\u00e8s,  donc <strong>nous<\/strong> sommes en cause.)<\/p>\n<\/p>\n<p><p>\tEn 2008 (sp\u00e9culations de 2007 pour 2008), l&rsquo;atmosph\u00e8re est compl\u00e8tement diff\u00e9rente, sans rapport avec l&rsquo;atmosph\u00e8re de 2003 pour 2004. Ce texte nous montre que, chez des \u00e9lecteurs (les d\u00e9mocrates expatri\u00e9s) qu&rsquo;on ne peut juger marginaux ou dissidents, qui sont des d\u00e9mocrates actifs, travaillant \u00e0 l&rsquo;int\u00e9rieur du parti, de tendance plut\u00f4t progressiste, l&rsquo;atmosph\u00e8re psychologique est d\u00e9senchant\u00e9e, d\u00e9sorient\u00e9e et radicale. C&rsquo;est un ph\u00e9nom\u00e8ne remarquable car ces gens sont au cur d&rsquo;un parti qui a gagn\u00e9 en 2006 et qui va sans doute gagner en 2008.<\/p>\n<\/p>\n<p><p>\tLe ph\u00e9nom\u00e8ne est donc bien celui-ci, et c&rsquo;est une forte \u00e9volution depuis 2003-2004. On n&rsquo;attend plus le d\u00e9part de GW Bush, qui est \u00e9videmment acquis, on irait jusqu&rsquo;\u00e0 <strong>craindre<\/strong> de d\u00e9part de GW Bush. Lui qui semblait \u00eatre la cause de tout, la calamit\u00e9 en 2003-2004, il est aujourd&rsquo;hui, en 2007-2008, le bouc-\u00e9missaire, l&rsquo;arbre qui cache la for\u00eat. Le sentiment sous-jacent serait presque: qu&rsquo;allons-nous faire lorsqu&rsquo;il ne sera plus l\u00e0 pour expliquer, par sa seule m\u00e9diocre et binaire personne, la catastrophe qui frappe les USA?<\/p>\n<\/p>\n<p><p>\tMais m\u00eame cette perspective terrifiante (une situation catastrophique sans l&rsquo;explication de la pr\u00e9sence de GW) ne mobilise plus personne pour tenter de trouver parmi les candidats une issue acceptable. Il y a \u00e9galement, par la force des choses, un rejet massif du syst\u00e8me. La m\u00e9fiance o\u00f9 est explicitement tenue Hillary, le soup\u00e7on qui l&rsquo;accompagne syst\u00e9matiquement sont tr\u00e8s significatifs. Il y a une telle hostilit\u00e9 non pour ce qu&rsquo;elle est (Hillary n&rsquo;est ni m\u00e9diocre ni intellectuellemet frustre) mais parce qu&rsquo;elle est per\u00e7ue comme totalement repr\u00e9sentative du syst\u00e8me dans ce qu&rsquo;il a de plus accaparant. Mais tout cela se termine par l&rsquo;habituelle question (rejeter le syst\u00e8me pour mettre quoi \u00e0 la place?), l&rsquo;impasse compl\u00e8te pour des esprits qui n&rsquo;ont pas encore os\u00e9 penser jusqu&rsquo;\u00e0 son terme l&rsquo;id\u00e9e r\u00e9volutionnaire que le syst\u00e8me c&rsquo;est le d\u00e9sordre contrairement \u00e0 sa pr\u00e9tention d&rsquo;affirmer un ordre. Le d\u00e9sarroi des \u00e9lecteurs tient \u00e9videmment au fait qu&rsquo;en tant que citoyens am\u00e9ricains, ils continuent \u00e0 croire aux fondements du syst\u00e8me tout en constatant sa perversion et sa d\u00e9cadence dramatique. A la question subsidiaire: qui pourrait restaurer le syst\u00e8me de l&rsquo;am\u00e9ricanisme selon ses valeurs originelles?, il n&rsquo;y pas de r\u00e9ponse acceptable.<\/p>\n<\/p>\n<p><p>\t(Pourrait-il y avoir Ron Paul dont personne ne parle pour ce cas? Sans lui d\u00e9nier des qualit\u00e9s bien r\u00e9elles, nous pensons que sa popularit\u00e9 est d&rsquo;abord le fait de d\u00e9ceptions sans nombre du syst\u00e8me. C&rsquo;est tr\u00e8s significatif mais ce n&rsquo;est pas suffisant. Pour l&rsquo;instant, Ron Paul est un point s\u00e9rieux de r\u00e9sistance. On ne peut rien dire de plus.) <\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>American fluidit\u00e9 19 octobre 2007 Nous nous sommes attach\u00e9s \u00e0 un texte de Bernard Weiner, \u00e9diteur du site Crisis Papers. Bernard Weiner, po\u00e8te et auteur de th\u00e9\u00e2tre, a \u00e9t\u00e9 le critique th\u00e9\u00e2tral du San Francisco Chronicle pendant 16 ans. Il est aussi, autre facette remarquable, professeur de relations internationales, enseignant dans plusieurs universit\u00e9s. Le texte&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[4906,3009,7145,4141,7146,3278,3140,6895],"class_list":["post-69339","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-4906","tag-democrates","tag-desenchantement","tag-elections","tag-fluidite","tag-hillary","tag-paul","tag-weiner"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69339"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69339\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}