{"id":69372,"date":"2007-11-01T00:00:00","date_gmt":"2007-11-01T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2007\/11\/01\/laxe-hagel-fallon\/"},"modified":"2007-11-01T00:00:00","modified_gmt":"2007-11-01T00:00:00","slug":"laxe-hagel-fallon","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2007\/11\/01\/laxe-hagel-fallon\/","title":{"rendered":"L&rsquo;axe Hagel-Fallon\u2026"},"content":{"rendered":"<p><p>Sur son site <em>The Washington Note<\/em> et dans le cadre de l&rsquo;initiative Hagel qu&rsquo;il nous rapporte, et dont nous parlons <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4584\" class=\"gen\">pr\u00e9c\u00e9demment<\/a>, Steve Clemons donne une pr\u00e9cision du plus haut int\u00e9r\u00eat. Une copie de la lettre que Hagel a envoy\u00e9e \u00e0 Bush a \u00e9t\u00e9 communiqu\u00e9e \u00e0 l&rsquo;amiral Fallon, commandant de Central Command, dont on <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4461\" class=\"gen\">conna\u00eet<\/a> le tr\u00e8s ti\u00e8de enthousiasme pour une attaque de l&rsquo;Iran. Fallon a r\u00e9pondu en donnant ce qui pourrait \u00eatre d\u00e9fini par sa compl\u00e8te approbation. Clemons semble ignorer si la lettre a \u00e9t\u00e9 transmise directement \u00e0 Fallon ou si elle a transit\u00e9 par Gates.<\/p>\n<\/p>\n<p><p>\t(Clemons pr\u00e9cise \u00e9galement qu&rsquo;il n&rsquo;a pas eu ces informations, ainsi que la lettre de Hagel, par Hagel mais par une autre source. On peut admirer le beau geste de Clemons et la manoeuvre normale de couvrir celui qu&rsquo;on devine aussit\u00f4t comme \u00e9tant sa source, si l&rsquo;on a \u00e0 l&rsquo;esprit les liens unissant Clemens et Hagel. Actons donc que ce n&rsquo;est pas Hagel qui a donn\u00e9 tout cela \u00e0 Clemons,  et actons \u00e9galement que rien n&rsquo;interdit de n&rsquo;en penser pas moins.) <\/p>\n<\/p>\n<p><p>\tClemons \u00e9crit donc  <a href=\"http:\/\/www.thewashingtonnote.com\/archives\/002471.php\" class=\"gen\">aujourd&rsquo;hui<\/a>:<\/p>\n<\/p>\n<p><p>\t\u00ab<em>I have since learned that the letter somehow made its way to US Central Command Commander William Fallon, perhaps through Defense Secretary Gates or other avenues, and Fallon allegedly communicated with the Senator that serious articulations of American interests and consideration of the options Hagel recommends are much needed in this current political and policy environment.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tDans le cadre qu&rsquo;on a trac\u00e9, l&rsquo;intervention aupr\u00e8s de Fallon, et le soutien de l&rsquo;amiral exprim\u00e9 \u00e0 l&rsquo;initiative de Hagel, mesurent une situation qu&rsquo;on ne peut cesser d&rsquo;appr\u00e9cier comme exceptionnelle \u00e0 Washington. Peu de choses sont dites \u00e0 cet \u00e9gard du point de vue institutionnel et constitutionnel, puisqu&rsquo;on se contente en g\u00e9n\u00e9ral d&rsquo;acter l&rsquo;attitude de certains chefs militaires comme si cette attitude allait de soi dans les circonstances qu&rsquo;on conna\u00eet. Ce n&rsquo;est absolument pas le cas. Il s&rsquo;agit de toutes les fa\u00e7ons d&rsquo;une situation o\u00f9 le pouvoir central n&rsquo;exerce plus son autorit\u00e9, o\u00f9 la l\u00e9gitimit\u00e9 de la pr\u00e9sidence est en miettes sans que rien ne soit dit \u00e0 haute voix \u00e0 cet \u00e9gard. Nous ne cessons de <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3751\" class=\"gen\">r\u00e9p\u00e9ter<\/a> ce constat de la situation <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4361\" class=\"gen\">extraordinaire<\/a> \u00e0 Washington et des perspectives \u00e9ventuellement explosives (notamment <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4488\" class=\"gen\">en cas<\/a> d&rsquo;attaque contre l&rsquo;Iran).<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 1er novembre 2007 \u00e0 14H48<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sur son site The Washington Note et dans le cadre de l&rsquo;initiative Hagel qu&rsquo;il nous rapporte, et dont nous parlons pr\u00e9c\u00e9demment, Steve Clemons donne une pr\u00e9cision du plus haut int\u00e9r\u00eat. Une copie de la lettre que Hagel a envoy\u00e9e \u00e0 Bush a \u00e9t\u00e9 communiqu\u00e9e \u00e0 l&rsquo;amiral Fallon, commandant de Central Command, dont on conna\u00eet le&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[6296,4841,3538,3248],"class_list":["post-69372","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-fallon","tag-hagel","tag-militaires","tag-washington"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69372"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69372\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}