{"id":69381,"date":"2007-11-04T00:00:00","date_gmt":"2007-11-04T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2007\/11\/04\/elargissement-constant-du-domaine-de-lanti-americanisme-etre-realiste-cest-etre-anti-americaniste\/"},"modified":"2007-11-04T00:00:00","modified_gmt":"2007-11-04T00:00:00","slug":"elargissement-constant-du-domaine-de-lanti-americanisme-etre-realiste-cest-etre-anti-americaniste","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2007\/11\/04\/elargissement-constant-du-domaine-de-lanti-americanisme-etre-realiste-cest-etre-anti-americaniste\/","title":{"rendered":"Elargissement constant du domaine de l&rsquo;anti-am\u00e9ricanisme: \u00eatre \u201cr\u00e9aliste\u201d, c&rsquo;est \u00eatre anti-am\u00e9ricaniste\u2026"},"content":{"rendered":"<p><p>Nous revenons sur un article paru en d\u00e9but de semaine (lors de notre court entr&rsquo;acte <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4581\" class=\"gen\">technique<\/a>), dans le <em>Daily Telegraph<\/em> du <a href=\"http:\/\/www.telegraph.co.uk\/opinion\/main.jhtml?xml=\/opinion\/2007\/10\/29\/do2901.xml\" class=\"gen\">29 octobre<\/a>. On nous a en effet signal\u00e9 l&rsquo;importance de cet article, marqu\u00e9 par ailleurs par l&rsquo;extraordinaire abondance des commentaires et r\u00e9flexions de lecteurs. Pour le seul premier jour de mise en ligne, on calcule,  cette mesure, sans \u00eatre parfaite, en vaut une autre,  un volume pour le texte de 6.892 signes et un volume pour les r\u00e9actions et commentaires (largement plus de la centaine) de 91.481 signes. <\/p>\n<\/p>\n<p><p>\tL&rsquo;article est de Janet Daley, universitaire et philosophe britannique, faisant partie de cette <em>intelligentsia<\/em> lib\u00e9rale et lib\u00e9rale-interventionniste, dans tous les cas convertie dans ce sens et sous cette \u00e9tiquette, qui traverse le monde politique occidental, de Christopher Hitchens \u00e0 Michael Ignatieff, \u00e0 Timothy Garton-Ash, \u00e0 Bernard Kouchner, \u00e0 Bernard-Henri Levy, etc. L&rsquo;article est d&rsquo;abord une affirmation vibrante de l&rsquo;interventionnisme de type lib\u00e9ral (<em>liberal interventionnism<\/em> et <em>liberal hawks<\/em> pour ceux qui le pratiquent), qui conduit \u00e0 mesure, avec les contorsions d&rsquo;usage (quelle dommage que Bush ait fait des erreurs, quelle dommage que certains individus dans l&rsquo;administration Bush ait \u00e9t\u00e9 arrogants, etc.), \u00e0 identifier cet interventionnisme avec l&rsquo;am\u00e9ricanisme, puis avec la vertu am\u00e9ricaniste et l&rsquo;interventionnisme am\u00e9ricaniste en action \u00e0 pleine vapeur depuis 9\/11. Par cons\u00e9quent, toute personne qui s&rsquo;oppose \u00e0 l&rsquo;interventionnisme lib\u00e9ral ou interventionnisme humanitaire est anti-am\u00e9ricaniste; d&rsquo;autre part, toute personne ou homme politique qui d\u00e9nonce l&rsquo;interventionnisme lib\u00e9ral au nom du r\u00e9alisme par opposition \u00e0 l&rsquo;id\u00e9alisme (mais nous pr\u00e9f\u00e9rerions utopisme) est anti-am\u00e9ricaniste. Par cons\u00e9quent, le r\u00e9alisme est anti-am\u00e9ricaniste.<\/p>\n<\/p>\n<p><p>\tCe qui se dit comme ceci, avec le soulign\u00e9 en gras de nous-m\u00eames:<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The doctrine of liberal interventionism which impels free nations to do what they can to liberate the populations of countries ruled by corrupt totalitarian regimes has been well and truly (if not necessarily permanently) discredited by the Bush administration. But I would suggest, unfashionably, that Mr Cameron is making a critical mistake.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Along with the countless old diplomatic hands who have been muttering (or proclaiming to any journalist they can find) the same message, he assumes that it was that doctrine  or even idealism in foreign policy itself  that failed in Iraq, when in fact the peace was lost because of stupid strategic errors and the arrogance of certain individuals.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>There was nothing inherently unrealistic about the project of removing Saddam: that objective was indeed, carried out with startling efficiency. Nor was it wildly idealistic  in the pejorative sense of naively over-optimistic  to believe that a country that has always had a highly educated political class might be able to organise itself into a constitutional recovery.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Well, it didn&rsquo;t happen. Or at least, it hasn&rsquo;t happened yet, as much because of other global players whose machinations were disastrously underestimated by Washington as anything else.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>But where does this leave the fundamental breakdown in understanding between America and much of Europe (whose view Britain is moving to adopt) about the moral responsibilities of free nations?<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>For that is what this is about in the end. And, absurdly, it is just those people  Mr Cameron himself, for example  who talk about our moral mission to cure global problems such as starvation and child poverty in the developing world, who now seem to want to give up on the one remedy for those problems that has proved to be effective.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The cure for mass poverty and the political criminality that it breeds is a combination of liberal democratic government and free market economics. To be aware of that truth and yet refuse to disseminate it must be as wicked as withholding Western drugs that can cure Third World diseases.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>And it will not do to dismiss some peoples, with post-colonial contempt, as unready. The only way that people learn how to deal with freedom is to exercise it. To say that they must win it for themselves without outside interference is to ignore the terrifying effectiveness of modern tyranny, with its armoury of weapons and electronically comprehensive surveillance.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>I do believe  however much Mr Cameron and other protagonists deny it  that there is<\/em> <strong><em>something specifically anti-American in this demand for a new realism<\/em><\/strong> <em>about interfering with the whims of despots. Why else do so many of those who condemn the US attitude toward Iran, whose nuclear ambitions are the greatest threat to international security in our time, simultaneously demand action against President Mugabe, whose regime is repulsive but far less destabilising to the world at large?<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLe premier int\u00e9r\u00eat de ce texte est donc d&rsquo;\u00e9largir notablement le champ de l&rsquo;anti-am\u00e9ricanisme, avec le pan important du r\u00e9alisme qui est ajout\u00e9 comme attitude intellectuelle anti-am\u00e9ricaniste. On notera, \u00e0 cette occasion, qu&rsquo;on pourrait \u00e9ventuellement lier le r\u00e9alisme \u00e0 l&rsquo;anti-s\u00e9mitisme puisqu&rsquo;il nous est affirm\u00e9 par ailleurs et de plus en plus souvent que l&rsquo;anti-am\u00e9ricanisme \u00e9quivaut \u00e0 l&rsquo;anti-s\u00e9mitisme comme chose absolument condamnable. Par contraste, l&rsquo;expression th\u00e9orique de la vertu absolue, c&rsquo;est-\u00e0-dire de l&rsquo;am\u00e9ricanisme, c&rsquo;est bien l&rsquo;interventionnisme lib\u00e9ral, ou interventionnisme humanitaire.<\/p>\n<\/p>\n<p><p>\tCet \u00e9largissement du champ de l&rsquo;anti-am\u00e9ricanisme r\u00e9duit \u00e0 mesure le territoire autoris\u00e9 pour l&rsquo;exercice de la libert\u00e9 de pens\u00e9e. A mesure que la vertu et la n\u00e9cessit\u00e9 de la libert\u00e9 ne cessent de grandir et d&rsquo;\u00eatre affirm\u00e9es, avec pompes et circonstances, son exercice est de plus en plus limit\u00e9, de plus en plus contraint et encadr\u00e9, pour le bien de notre morale et de nos \u00e2mes. Cette limitation de l&rsquo;exercice de la libert\u00e9 est inversement conforme \u00e0 l&rsquo;\u00e9largissement de ce qui est identifi\u00e9 comme le territoire de l&rsquo;anti-am\u00e9ricanisme, auquel de plus en plus d&rsquo;activit\u00e9s intellectuelles sont assimil\u00e9es, o\u00f9 vous n&rsquo;avez aucun droit de vous aventurer sous peine d&rsquo;excommunication majeure, sans aucun retour ni accus\u00e9 de r\u00e9ception. C&rsquo;est un peu comme les prisons am\u00e9ricanistes: de plus en plus propres (gants blancs, cellules en b\u00e9ton uniforme, lumi\u00e8re au n\u00e9on tr\u00e8s vive, musique tr\u00e8s forte, etc.), avec un contr\u00f4le [de plus en plus] rapproch\u00e9 et [de plus en plus] continu sur les prisonniers, selon les termes d\u00e9finissant l&rsquo;ambiance g\u00e9n\u00e9rale \u00e0 Guantanamo.<\/p>\n<\/p>\n<p><p>\tDonc, la civilisation progresse sur un territoire de plus en plus r\u00e9duit et de plus en plus surveill\u00e9. Le concept de libert\u00e9 de pens\u00e9e est de plus en plus c\u00e9l\u00e9br\u00e9 et de plus rarement autoris\u00e9 \u00e0 \u00eatre exerc\u00e9, pour ne pas g\u00e2cher ni alt\u00e9rer sa puret\u00e9. On n&rsquo;est jamais trop prudent dira-t-on d&rsquo;une part, pour d\u00e9fendre la cause des gardiens arm\u00e9s jusqu&rsquo;aux dents de la libert\u00e9. On rel\u00e9vera d&rsquo;autre part que nous avons aussi l\u00e0 tous les sympt\u00f4mes d&rsquo;une fi\u00e8vre de l&rsquo;esprit grandissante chez les <em>liberal hawks<\/em> pour qui la guerre s&rsquo;affirme de plus en plus comme la perspective ultime de l&rsquo;exercice de la libert\u00e9,  c&rsquo;est-\u00e0-dire la seule perspective apr\u00e8s tout. Bient\u00f4t, pour penser libre, nous ne saurons plus autoris\u00e9s que penser la guerre, ou penser en \u00e9tat de guerre.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 4 novembre 2007 \u00e0 15H43<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous revenons sur un article paru en d\u00e9but de semaine (lors de notre court entr&rsquo;acte technique), dans le Daily Telegraph du 29 octobre. On nous a en effet signal\u00e9 l&rsquo;importance de cet article, marqu\u00e9 par ailleurs par l&rsquo;extraordinaire abondance des commentaires et r\u00e9flexions de lecteurs. Pour le seul premier jour de mise en ligne, on&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3561,7190,3206,3490,4679,1361],"class_list":["post-69381","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-anti-americanisme","tag-daley","tag-hawks","tag-interventionnisme","tag-liberal","tag-realisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69381"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69381\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}