{"id":69392,"date":"2007-11-08T00:00:00","date_gmt":"2007-11-08T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2007\/11\/08\/le-vide-et-la-vertu\/"},"modified":"2007-11-08T00:00:00","modified_gmt":"2007-11-08T00:00:00","slug":"le-vide-et-la-vertu","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2007\/11\/08\/le-vide-et-la-vertu\/","title":{"rendered":"<strong><em>Le vide et la vertu<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Le vide et la vertu<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t8 novembre 2007 &#8212; Sarko \u00e0 Washington, on en parle? Et comment&#8230; Avant d&#8217;\u00e9ventuellement aborder le voyage, ses pompes et ses circonstances, et ses r\u00e9sultats \u00e9ventuellement, l&#8217;occasion est bonne de parler du personnage. Le pr\u00e9sident fran\u00e7ais se trouvait, \u00e0 Washington, plac\u00e9 dans une situation o\u00f9 se manifestait le c\u00f4t\u00e9 le plus \u00e9tonnant, le plus pol\u00e9mique et le plus incertain de son personnage. &#8220;Sarko l&#8217;Am\u00e9ricain, le voici&#8221;, &#8211; un peu comme John <em>Black Jack<\/em> Pershing ne pronon\u00e7a jamais la phrase fameuse, le \u00ab<em>La Fayette, we are there<\/em>\u00bb, &#8211; dit par le colonel Stanton, un jour de juillet 1917, devant la tombe du marquis, en pr\u00e9sence de Pershing qui jugea cette phrase &#8220;splendide&#8221;.<\/p>\n<\/p>\n<p><p>\tSarko-Pershing fut donc au centre de nos pr\u00e9occupations pendant ces deux rapides journ\u00e9es washingtoniennes. C&#8217;est l&#8217;occasion de nous pencher sur le cas psychologique de Notre-Pr\u00e9sident. Un livre nous en donne l&#8217;occasion.<\/p>\n<h3><em>Sarko l&#8217;Am\u00e9ricain<\/em>, de Jean-Philippe Immarigeon<\/h3>\n<\/p>\n<p><p>\tL&#8217;opportunit\u00e9 est \u00e9vidente et le moment ne pouvait \u00eatre mieux choisi. Au moment o\u00f9`Sarko fait sa repr\u00e9sentation \u00e0 Washington au milieu des pompes et des circonstances du syst\u00e8me, avec La Fayette en sautoir, Jean-Philippe Immarigeon publie <em>Sarko l&#8217;Am\u00e9rican<\/em> (en vente \u00e0 partir d&#8217;aujourd&#8217;hui) (*). Apr\u00e8s son <em>American Parano<\/em>, qui passait puissamment en revue les complexit\u00e9s destructrices du syst\u00e8me de l&#8217;am\u00e9ricanisme, Immarigeon passe en revue ce penchant finalement remarquable et \u00e9trange du pr\u00e9sident fran\u00e7ais pour les USA: le pro-am\u00e9ricanisme du pr\u00e9sident Nicolas Sarkozy.<\/p>\n<\/p>\n<p><p>\tSon pro-am\u00e9ricanisme, &#8211; effectivement &#8220;remarquable et \u00e9trange&#8221;, &#8211; est \u00e0 la fois le c\u00f4t\u00e9 le plus int\u00e9ressant comme une passion enfi\u00e9vr\u00e9e qui emporte le sentiment et le jugement, et le c\u00f4t\u00e9 le plus d\u00e9routant comme une montagne accouchant d&#8217;une souris de Nicolas Sarkozy. Ce pro-am\u00e9ricanisme est remarquablement primaire, inculte, compl\u00e8tement attach\u00e9 aux seules apparences (les apparences de l&#8217;apparence puisque l&#8217;am\u00e9ricanisme est lui-m\u00eame fait d&#8217;une construction d&#8217;apparences). La pens\u00e9e sarkozyste est \u00e0 cet \u00e9gard confondante par sa vacuit\u00e9 et son primarisme, &#8211; pour ne pas dire sa primarit\u00e9 pour user de termes savants et tenter de faire contraste. (De &#8220;primarisme&#8221; : \u00ab<em>Caract\u00e8re (d&#8217;une personne, d&#8217;une pens\u00e9e) primaire<\/em>\u00bb \u00e0 &#8220;primarit\u00e9&#8221; ; \u00ab<em>Modalit\u00e9 du retentissement dans laquelle pr\u00e9dominent les r\u00e9actions imm\u00e9diates mais superficielles et \u00e9ph\u00e9m\u00e8res<\/em>\u00bb). Un &#8220;ado&#8221; du temps courant, format standard entre Coca <em>light<\/em> et <em>Ecstasy<\/em>, hors-banlieue pour ne pas choquer, ne ferait pas pire&#8230;<\/p>\n<\/p>\n<p><p>\tS&#8217;il faut tenter de d\u00e9finir ce pro-am\u00e9ricanisme de Sarkozy, on penchera donc plut\u00f4t vers le camp des &#8220;atlantistes b\u00e9ats&#8221; (type Philippe Labro, Kouchner &#038; compagnie), comme les qualifie Immarigeon. Il s&#8217;agit de ceux qui ne font, en regardant l&#8217;Am\u00e9rique, que regarder l&#8217;image qu&#8217;ils se font de l&#8217;Am\u00e9rique, sinon l&#8217;image qu&#8217;ils se font d&#8217;eux-m\u00eames en train de regarder l&#8217;image qu&#8217;ils se font de l&#8217;Am\u00e9rique. Il s&#8217;agit par cons\u00e9quent d&#8217;une image de l&#8217;Am\u00e9rique qu&#8217;ils se fabriquent compl\u00e8tement, qu&#8217;ils dessinent dans les contours incertains et d\u00e9licieux du r\u00eave, comme l&rsquo;on fait dans &#8220;la fabrique du r\u00eave&#8221; (Hollywood). Il n&#8217;est pas question de les interrompre ni de les pinailler. \u00ab<em>Ils nous somment, au risque de nous faire taxer d&#8217;antiam\u00e9ricanisme primaire, de consid\u00e9rer l&#8217;objet de leur flamme non pas tel qu&#8217;il est mais tel qu&#8217;ils nous la racontent. Ils sont comme cette femme surprise par son amant en tierce compagnie : &#8220;Ah Monsieur! Je vois bien que vous ne m&#8217;aimez plus : vous croyez plus ce que vous voyez que ce que je vous dis&#8221;.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tImmarigeon semble se pincer tout au long de son bouquin : qu&#8217;est-ce que Sarko va faire de cette bouillie pour chat? Trahir? Transformer la France en bastion de l&#8217;atlantisme? Tout de m\u00eame, cette sorte d&#8217;entreprise demande des \u00e9paules plus carr\u00e9es, car n&#8217;est pas tra\u00eetre \u00e0 de Gaulle qui veut. C&#8217;est une chose d&#8217;\u00e9crire des articles \u00e0 la Glucksmann apr\u00e8s avoir \u00e9crit, au printemps 1995 <em>De Gaulle, o\u00f9 es-tu?<\/em> (apologie de De Gaulle et sacr\u00e9 coup de main \u00e0 Chirac, par Andr\u00e9 Glucksmann). C&#8217;en est une autre de trahir d&#8217;une fa\u00e7on effective et efficace le grand homme, &#8211; lequel doit bien rire, en sa demeure \u00e9ternelle &#8230; Et Immarigeon de constater d&#8217;entr\u00e9e de livre (d\u00e8s sa pr\u00e9face):<\/p>\n<\/p>\n<p><p>\t\u00ab<em>A l&#8217;origine, il n&#8217;est pas all\u00e9 chercher ce qualificatif d&#8217;Am\u00e9ricain qui se voulait p\u00e9joratif : il l&#8217;a repris et l&#8217;a retourn\u00e9 pour s&#8217;en faire un titre de noblesse aupr\u00e8s de l&#8217;opinion et de la presse am\u00e9ricaine. Il le leur r\u00e9p\u00e8te : il l&#8217;assume, \u00e0 preuve le fait qu&#8217;il revendique cette amiti\u00e9 devant ses propres compatriotes. En fait, pas tant que cela. Il ne nous a que tr\u00e8s rarement chant\u00e9 la messe, \u00e0 nous Fran\u00e7ais, sur les grands principes fondateurs d&#8217;une civilisation transatlantique ou le suppos\u00e9 partage de valeurs communes. C&#8217;est un discours qu&#8217;il r\u00e9serve aux Am\u00e9ricains, devant qui il se contente du reste de r\u00e9p\u00e9ter sans cesse les partis pris qu&#8217;il adore entendre: l&#8217;Am\u00e9rique o\u00f9 tout est possible, et puis les jeans, le rock, et toutes les s\u00e9ries qui monopolisent les \u00e9crans de t\u00e9l\u00e9vision. C&#8217;est \u00e0 peu pr\u00e8s tout. C&#8217;est un peu l\u00e9ger pour refonder la politique \u00e9trang\u00e8re de la France et rompre avec quarante ans de gaullisme.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tAu plus il est d\u00e9taill\u00e9, au plus le pro-am\u00e9ricanisme, ou atlantisme, de Sarko ne semble rien du point de vue politique, au point o\u00f9 Immarigeon remarque avec bonheur (\u00e0 propos de la position de Sarko en cas d&#8217;attaque US de l&#8217;Iran), comme l&#8217;on d\u00e9crit un nageur d\u00e9butant en train de barboter: \u00ab<em>Il est encore perdu quelque part au milieu de l&#8217;atlantisme.<\/em>\u00bb Effectivement, le paradoxe de Sarkozy est qu&#8217;il affirme un engagement f\u00e9roce, presque caricatural \u00e0 force d&#8217;affirmation, et qu&#8217;il semble pourtant flotter comme un bouchon sur les flots d\u00e9cha\u00een\u00e9s, &#8211; justement \u00ab<em>quelque part au milieu de l&#8217;atlantisme<\/em>\u00bb. Les \u00e9tonnements d&#8217;Immarigeon ne cessent de s&#8217;accumuler &#8230; Les n\u00f4tres vont de pair.<\/p>\n<\/p>\n<p><p>\tL&#8217;auteur s&#8217;interroge de cette fa\u00e7on: \u00ab<em>Sarko l&#8217;Am\u00e9ricain? Oui. Mais jusqu&#8217;o\u00f9?<\/em>\u00bb Pas de r\u00e9ponse, on s&#8217;en doute. L&#8217;objet m\u00eame de la passion-Sarko est trop grossi\u00e8rement d\u00e9form\u00e9 pour que cet engagement puisse para\u00eetre autrement que futile et sans substance alors qu&#8217;il est affirm\u00e9 avec tant de pompe et d&#8217;ardeur: \u00ab<em>Son Am\u00e9rique \u00e0 lui est celle qu&#8217;on \u00e9voque dans la presse \u00e9conomique ou dans les \u00e9coles de commerce, un fantasme de r\u00e9ussite mat\u00e9rielle, le &#8220;r\u00eave des familles fran\u00e7aises <\/em>[&#8230;] <em>que les jeunes aillent \u00e9tudier dans des universit\u00e9s am\u00e9ricaines&#8221; puis d\u00e9crochent la fameuse &#8216;Green Card&#8217;&#8230;<\/em>\u00bb Comment l&#8217;identifier et d\u00e9finir son pro-am\u00e9ricanisme autrement que comme \u00ab<em>un r\u00eave de parvenu, celui de la g\u00e9n\u00e9ration Sarko arriv\u00e9e \u00e0 la conscience politique au d\u00e9but de cette r\u00e9volution am\u00e9ricaine que l&#8217;on citait en exemple dans les colonnes du Figaro-Magazine, les ouvrages de Guy Sorman ou les interventions d&#8217;Alain Madelin sur Radio-Solidarit\u00e9<\/em>\u00bb? On sait qu&#8217;en cette mati\u00e8re de l&#8217;admiration emport\u00e9e et enfi\u00e9vr\u00e9e pour l&#8217;Am\u00e9rique, la gauche et la droite en France c&#8217;est la m\u00eame chose. Consid\u00e9r\u00e9 \u00e0 cette lumi\u00e8re, le pro-am\u00e9ricanisme de Sarko c&#8217;est Mai 68 revu fa\u00e7on-Reagan; c&#8217;\u00e9tait une chose moderne en 1985, dont fit grand usage la France de Mitterrand qui d\u00e9couvrait la couleur de l&#8217;argent comme on va aux filles. Par cons\u00e9quent et nous tenant \u00e0 la stricte chronologie, c&#8217;est une chose confondante jusqu&#8217;\u00e0 \u00eatre touchante d&#8217;archa\u00efsme, elle qui se d\u00e9finit par une affirmation de modernit\u00e9. Paradoxe, toujours.<\/p>\n<\/p>\n<p><p>\tLe constat nous laisse toujours plus incertain, de pair avec Immarigeon, &#8211; avec cette interrogation r\u00e9v\u00e9latrice: \u00ab<em>Pourquoi cet attributif d&#8217;Am\u00e9ricain est-il vu par la majorit\u00e9 de ses concitoyens comme une marque d&#8217;infamie alors que lui-m\u00eame ne fait que mettre en musique l&#8217;hypnotique fascination de sa g\u00e9n\u00e9ration?<\/em>\u00bb C&#8217;est effectivement mettre le doigt sur une contradiction fran\u00e7aise remarquable. De ce seul point de vue, on dira que le pro-am\u00e9ricanisme de Sarko est d&#8217;une certaine complexit\u00e9 en rendant compte de la complexit\u00e9 de la consid\u00e9ration fran\u00e7aise de l&#8217;Am\u00e9rique. C&#8217;est le seul moment o\u00f9 l&#8217;on a l&#8217;impression de rencontrer quelque chose de complexe \u00e0 cet \u00e9gard. Au moins, Sarko est-il bien repr\u00e9sentatif de cela, qui s&#8217;exprime par son antienne bien connu, que n&#8217;appr\u00e9cieront pas trop longtemps les amis am\u00e9ricains: \u00ab<em>Je veux leur dire que la France sera toujours \u00e0 leurs c\u00f4t\u00e9s quand ils auront besoin d&#8217;elle. Mais je veux leur dire aussi que l&#8217;amiti\u00e9 c&#8217;est accepter que ses amis puissent penser diff\u00e9remment.<\/em>\u00bb (Sarko le soir de son \u00e9lection.)<\/p>\n<\/p>\n<p><p>\tSur quoi tout cela d\u00e9bouche-t-il? La capitulation, c&#8217;est tr\u00e8s difficile avec les Am\u00e9ricains, tellement elle est sans conditions. Il reste le pari h\u00e9g\u00e9lien (que nos identifierions pour notre compte comme &#8220;le pari maistrien&#8221;): \u00ab[C]<em>eux qui rallient <\/em>[les Am\u00e9ricains] <em>n&#8217;ont qu&#8217;une seule voie: &#8216;unconditionnal surrender&#8217;, la capitulation sans conditions. Sauf \u00e0 s&#8217;y r\u00e9soudre et \u00e0 ouvrir une crise politique majeure en France, Sarko l&#8217;Am\u00e9ricain sera un jour contraint d&#8217;ouvrir une crise non moins majeure avec les Etats-Unis, et de pr\u00e9cipiter sans le vouloir une r\u00e9solution maintes fois remise.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tFinalement, qu&#8217;est-ce qu&#8217;il manque \u00e0 l&#8217;atlantisme de Sarko? De m\u00eame qu&#8217;\u00ab[i]<em>l ne suffit pas de vouloir pour pouvoir<\/em>\u00bb (d\u00e9finition de Sarko par Yasmina Reza selon Immarigeon), il ne suffit pas de croire pour \u00eatre habit\u00e9. Si la croyance est celle du toc, la conviction est en papier m\u00e2ch\u00e9. Sarko n&#8217;arrivera jamais \u00e0 la cheville de Tony Blair \u00e0 cet \u00e9gard. L&#8217;atlantisme de Sarkozy est trop diaphane, trop &#8220;tendance&#8221; et trop r\u00eav\u00e9 \u00e0 la fois, et rien d&#8217;autre, pour pouvoir se transformer en une politique. Il ajoutera au d\u00e9sordre de sa politique en accentuant l&#8217;\u00e9cart\u00e8lement entre ses diff\u00e9rentes pulsions, &#8211; jusqu&#8217;\u00e0 ce que, press\u00e9 par les \u00e9v\u00e9nements, il soit oblig\u00e9 \u00e0 un choix. A ce moment, comme on le comprend bien avec l&#8217;\u00e9nonc\u00e9 de la phrase, les \u00e9v\u00e9nements p\u00e8seront lourdement.<\/p>\n<\/p>\n<p><p>\tLe myst\u00e8re de Sarko l&#8217;Am\u00e9ricain n&#8217;est pas dans la substance de son engagement, puisque de substance il n&#8217;y a point et que l&#8217;engagement est \u00e0 mesure; \u00e0 cet \u00e9gard, l&#8217;exc\u00e8s de bavardage ne cr\u00e9e pas la substance, il en r\u00e9v\u00e8le l&#8217;absence. Le myst\u00e8re est dans ce que cet engagement sans substance puisse en soi \u00eatre un probl\u00e8me, un objet de d\u00e9bat, une cause d&#8217;inqui\u00e9tude, un argument d&#8217;accusation de trahison, &#8211; bref, une question de substance. On en conclut donc que le pro-am\u00e9ricanisme de Sarko, confront\u00e9 \u00e9videmment aux diff\u00e9rences in\u00e9luctables et intangibles qui caract\u00e9risent les deux pays, est plus illustratif de la crise fran\u00e7aise qu&#8217;il ne d\u00e9noue la crise franco-am\u00e9ricaine. Plus que l&#8217;image d&#8217;un engagement convaincu, il est le reflet un peu sommaire d&#8217;une contradiction bien fran\u00e7aise, et aujourd&#8217;hui exacerb\u00e9e. Quelque chose de diablement fran\u00e7ais, en ce sens.<\/p>\n<\/p>\n<p><p>\t(*) <em>Sarko l&#8217;Am\u00e9ricain<\/em>, Bourin Editeur, Paris.<\/p>\n<\/p>\n<p><p>\tSur Amazon : <a href=\"http:\/\/www.amazon.fr\/gp\/product\/2849410780?ie=UTF8&#038;tag=dedefensa-21&#038;linkCode=as2&#038;camp=1642&#038;creative=6746&#038;creativeASIN=2849410780\" class=\"gen\">Sarko l Americain<\/a><\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le vide et la vertu 8 novembre 2007 &#8212; Sarko \u00e0 Washington, on en parle? Et comment&#8230; Avant d&#8217;\u00e9ventuellement aborder le voyage, ses pompes et ses circonstances, et ses r\u00e9sultats \u00e9ventuellement, l&#8217;occasion est bonne de parler du personnage. Le pr\u00e9sident fran\u00e7ais se trouvait, \u00e0 Washington, plac\u00e9 dans une situation o\u00f9 se manifestait le c\u00f4t\u00e9 le&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[6133,3743,5925,4590,5045],"class_list":["post-69392","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-immarigeon","tag-pro-americanisme","tag-sarko","tag-sarkozy","tag-vertu"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69392"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69392\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}