{"id":69406,"date":"2007-11-12T00:00:00","date_gmt":"2007-11-12T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2007\/11\/12\/rumsfeld-demystifie\/"},"modified":"2007-11-12T00:00:00","modified_gmt":"2007-11-12T00:00:00","slug":"rumsfeld-demystifie","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2007\/11\/12\/rumsfeld-demystifie\/","title":{"rendered":"Rumsfeld d\u00e9mystifi\u00e9"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955; font-size:2em\">Rumsfeld d\u00e9mystifi\u00e9<\/h2>\n<\/p>\n<p><p>Voici le <a class=\"gen\" href=\"http:\/\/www.amazon.fr\/gp\/product\/2888920468?ie=UTF8&#038;tag=dedefensa-21&#038;linkCode=as2&#038;camp=1642&#038;creative=6746&#038;creativeASIN=2888920468\">livre<\/a> de Andrew Cockburn (<em>Rumsfeld, His Rise, Fall and Catastrophic Legacy<\/em>) traduit en fran\u00e7ais: <em>Caligula au Pentagone<\/em>, chez Xenia, collection <em>Le cha&icirc;non manquant<\/em>. Il s&rsquo;agit sans aucun doute de bien plus qu'\u00a0\u00bbun livre de plus\u00a0\u00bb sur Rumsfeld et, au-del\u00e0, sur l&rsquo;<em>establishment<\/em> de s\u00e9curit\u00e9 nationale de Washington. Le ton neutre, presque flegmatique dissimule \u00e0 peine une cascade de pr\u00e9cisions et de r\u00e9v\u00e9lation sur l&rsquo;un des personnages les plus myst\u00e9rieux, les plus importants et les plus symboliques du pouvoir du syst\u00e8me de l&rsquo;am\u00e9ricanisme dans notre temps historique.<\/p>\n<\/p>\n<p><p>On conna&icirc;t Cockburn; excellent journaliste et auteur, membre \u00e9minent de la mythique tribu des Cockburn (ses fr\u00e8res Alexander et Patrick, des filles et ni\u00e8ces journalistes et actrices, leur p\u00e8re activiste, communiste et pol\u00e9miste et ainsi de suite); comme les autres Cockburn, Andrew est un Britannique d&rsquo;origine irlandaise travaillant r\u00e9guli\u00e8rement aux USA; comme les autres Cockburn, c&rsquo;est un auteur fondamentalement contestataire, un esprit \u00ab\u00a0dissident\u00a0\u00bb si l&rsquo;on veut. C&rsquo;est une bonne source, Cockburn, c&rsquo;est une \u00ab\u00a0source claire\u00a0\u00bb dans une \u00e9poque encombr\u00e9e de tant d&rsquo;ombres douteuses. Il est int\u00e9ressant de suivre ce qu&rsquo;il nous dit de Rumsfeld, \u00e0 partir d&rsquo;une documentation et d&rsquo;une exp\u00e9rience s\u00e9rieuses, autant que d&rsquo;un point de vue d\u00e9gag\u00e9 de toute pression fondamentale de type conformiste..<\/p>\n<\/p>\n<p><p>L&rsquo;int\u00e9r\u00eat du propos qu&rsquo;on trouve dans <em>Caligula au Pentagone<\/em> se trouve ainsi dans la rencontre de deux tendances.<\/p>\n<\/p>\n<p><p>&bull; La confirmation de notre esp\u00e9rance mentionn\u00e9e plus haut: Cockburn a un bon et gros dossier Rumsfeld. Beaucoup d&rsquo;informations, d&rsquo;appr\u00e9ciations in\u00e9dites.<\/p>\n<\/p>\n<p><p>&bull; Une mise en perspective tr\u00e8s \u00ab\u00a0r\u00e9aliste\u00a0\u00bb de Rumsfeld. Le personnage est ramen\u00e9 \u00e0 des dimensions terrestres, d\u00e9barrass\u00e9 du mythe et de la publicit\u00e9, selon une d\u00e9marche plus naturelle que d\u00e9lib\u00e9r\u00e9e et, par cons\u00e9quent, encore plus convaincante. Pour autant, ses c\u00f4t\u00e9s soi-disant \u00ab\u00a0myst\u00e9rieux\u00a0\u00bb ne sont pas ignor\u00e9s mais eux aussi mis en perspective. Cela fera grincer nombre de dentiers.<\/p>\n<\/p>\n<p><p>Le r\u00e9sultat est, \u00e0 notre sens, d&rsquo;une fa\u00e7on somme toute logique, une d\u00e9mystification de Rumsfeld. Le personnage est descendu, vivement et sans m\u00e9nagement, du pi\u00e9destal o&ugrave; il fut plac\u00e9 le 11 septembre 2001. L&rsquo;int\u00e9r\u00eat de la chose est qu&rsquo;on trouve \u00e9galement une autre entreprise de d\u00e9mystification, &ndash; qui va de soi, certes, qui n&rsquo;a pas \u00e9t\u00e9 n\u00e9cessairement voulue en tant que telle parce qu&rsquo;elle est la cons\u00e9quence \u00e9vidente de la premi\u00e8re d\u00e9mystification. Elle constitue l&rsquo;effet le plus important du livre. Il s&rsquo;agit de la d\u00e9mystification d&rsquo;un Rumsfeld <em>deus ex machina<\/em> conscient, de surcro&icirc;t acteur et complice actif, et manipulateur efficace d&rsquo;une \u00e9norme entreprise mal\u00e9fique de l&rsquo;am\u00e9ricanisme \u00e9labor\u00e9e et programm\u00e9e, et parfaitement contr\u00f4l\u00e9e; un Rumsfeld tireur de ficelles, ricanant et faisant gigoter le monde comme une marionnette dont il tiendrait les fils. Certes, Rumsfeld est compl\u00e8tement une cr\u00e9ature de l&rsquo;am\u00e9ricanisme mais il n&rsquo;en est pas le manipulateur. (Notre conviction est que l&rsquo;am\u00e9ricanisme n&rsquo;a pas besoin de manipulateur. La chose est un syst\u00e8me manipulateur par substance, ses cr\u00e9atures suivent la pente naturelle.)<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Pourquoi Rumsfeld?<\/h3>\n<\/p>\n<p><p>Rumsfeld nous a paru d\u00e8s l&rsquo;origine un acteur essentiel de l&rsquo;administration GW Bush. Cockburn n&rsquo;\u00e9carte certainement pas cette appr\u00e9ciation. Mais, par le tableau qu&rsquo;il fait de la carri\u00e8re du double (1975-1977 et 2001-2006) secr\u00e9taire \u00e0 la d\u00e9fense, il \u00ab\u00a0humanise\u00a0\u00bb ce jugement, &ndash; c&rsquo;est-\u00e0-dire qu&rsquo;il l'\u00a0\u00bbam\u00e9ricanise\u00a0\u00bb, &ndash; pour le meilleur et pour le pire, c&rsquo;est-\u00e0-dire pour le pire essentiellement.<\/p>\n<\/p>\n<p><p>Myst\u00e8re du d\u00e9part de sa carri\u00e8re gouvernementale et de sa v\u00e9ritable carri\u00e8re publique, qui rencontre notre propre interrogation. Comme nous l&rsquo;avons nous-m\u00eame constat\u00e9 \u00e0 partir de divers t\u00e9moignages, c&rsquo;est l&rsquo;\u00e9tonnement, rapport\u00e9 par Cockburn, de ceux qui connurent Rumsfeld \u00e0 l&rsquo;OTAN, \u00e0 Bruxelles, en 1973-74, le retrouvant en 2002, tonitruant contre la \u00ab\u00a0vieille Europe\u00a0\u00bb. Rumsfeld-1973 \u00e9tait un homme charmant, affable, pro-europ\u00e9en; voyez ce qu&rsquo;est devenu Rumsfeld-2002. Ce myst\u00e8re devient alors une sorte de contre-grille de lecture de la personnalit\u00e9 de Rumsfeld. Il va conduire \u00e0 le charger de beaucoup plus d&rsquo;inconnus qu&rsquo;il n&rsquo;est n\u00e9cessaire. Aujourd&rsquo;hui, on interpr\u00e8te ais\u00e9ment le retour de Rumsfeld sur la sc\u00e8ne nationale et internationale, en janvier 2001, comme un des tournants du complot de la prise du pouvoir par la tendance extr\u00e9miste qui emporta l&rsquo;Am\u00e9rique \u00e0 partir de 9\/11. A la lecture du livre, on peut fortement douter de cette interpr\u00e9tation. Cockburn nous rappelle que Rumsfeld fut nomm\u00e9 par raccroc (il \u00e9tait plut\u00f4t pr\u00e9vu pour la CIA) et il nous r\u00e9v\u00e8le que Cheney n&rsquo;avan\u00e7a son nom qu&rsquo;avec r\u00e9ticence :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>\u00ab\u00a0Je me souviens que Cheney m&rsquo;a appel\u00e9 pour me parler de Don dans la perspective du Pentagone\u00a0\u00bb, m&rsquo;a dit un ancien haut fonctionnaire de la S\u00e9curit\u00e9 nationale. \u00ab\u00a0Il n&rsquo;\u00e9tait gu\u00e8re enthousiaste, je n&rsquo;ai vraiment pas l&rsquo;impression qu&rsquo;il faisait cela pour aider un vieil ami\u00a0\u00bb<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Les relations Rumsfeld-Cheney s&rsquo;\u00e9taient consid\u00e9rablement aigries depuis 10 ou 15 ans et n&rsquo;avaient plus rien de commun avec l&rsquo;entente complice du temps de la pr\u00e9sidence Ford. Alors, pas de complot Cheney-Rumsfeld?<\/p>\n<\/p>\n<p><p>Sans doute la r\u00e9alit\u00e9 est-elle plus simple et, finalement, plus logique. Le complot \u00e9tait d\u00e9j\u00e0 en place. Il l&rsquo;est depuis longtemps. Le syst\u00e8me de l&rsquo;am\u00e9ricanisme est complot par substance. Il a toujours m\u00e9caniquement fonctionn\u00e9 dans ce sens et, depuis 1945, le monde entier est son terrain de man&oelig;uvre. Qui devient sa cr\u00e9ature fait partie du complot permanent de l&rsquo;am\u00e9ricanisme.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Rumsfeld, ou la force brute<\/h3>\n<\/p>\n<p><p>La carri\u00e8re de Rumsfeld, surtout depuis son premier passage \u00e0 la d\u00e9fense, laisse une impression \u00e9trange. Il s&rsquo;agit \u00e0 la fois d&rsquo;une r\u00e9ussite assez remarquable (comme chef d&rsquo;entreprise, comme homme d&rsquo;influence dans le monde politique, comme fortune, comme ministre) &ndash; et d&rsquo;une frustration g\u00e9n\u00e9rale. Dans les deux cas, l&rsquo;homme montre une force et une \u00e9nergie exceptionnelles, une compl\u00e8te absence de scrupules (par d\u00e9sint\u00e9r\u00eat et ignorance pour ce qu&rsquo;on nomme \u00ab\u00a0scrupule\u00a0\u00bb plus que par amoralisme). Il est \u00e0 la fois un acteur accompli du syst\u00e8me et un dirigeant incomplet. (Mais n&rsquo;est-ce pas finalement la nouvelle marque de fabrique du syst\u00e8me? GW Bush est, lui aussi \u00e0 sa fa\u00e7on \u00ab\u00a0\u00e0 la fois un acteur accompli du syst\u00e8me et un dirigeant incomplet\u00a0\u00bb, et il a longtemps besoin de Rumsfeld pour \u00eatre lui-m\u00eame, &ndash; ou, disons, un peu plus que lui-m\u00eame.)<\/p>\n<\/p>\n<p><p>L&rsquo;imbrication du service public et du secteur priv\u00e9 est fondamentale dans la vie professionnelle de Rumsfeld; et l&rsquo;on parle du secteur priv\u00e9 \u00ab\u00a0pur\u00a0\u00bb, puisque non li\u00e9 \u00e0 la d\u00e9fense nationale (il est CEO d&rsquo;une grande firme de produits pharmaceutiques apr\u00e8s avoir quitt\u00e9 le Pentagone en 1977). De ce point de vue, il est l&rsquo;homme exemplaire du syst\u00e8me tel qu&rsquo;il a toujours exist\u00e9 peu ou prou. Le syst\u00e8me conforte d\u00e9cisivement cette \u00e9quation \u00e0 partir du <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=353\">Manifeste Powell<\/a> de 1971 et de la prise en main radicale et ouverte du pouvoir, directement ou par la main-mise des organismes f\u00e9d\u00e9raux, par le secteur priv\u00e9.<\/p>\n<\/p>\n<p><p>La carri\u00e8re priv\u00e9e de Rumsfeld, sur plus de 20 ans, qui va lui apporter la fortune, est entrecoup\u00e9e d&rsquo;\u00e9pisode divers de service public ou de retour en politique. Il effectue une mission au Moyen-Orient pour l&rsquo;administration Reagan, avec rencontre chaleureuse de Saddam comme point d&rsquo;orgue. Il songe \u00e0 la pr\u00e9sidence en 1988. Il y a aussi ce fameux (?) passage dans le syst\u00e8me COG (\u00ab\u00a0Continuity Of Government\u00a0\u00bb), sur lequel Cockburn donne un luxe de d\u00e9tails (voir l&rsquo;extrait du livre mis en ligne <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4618\">ce jour<\/a>). L&rsquo;ambigu\u00eft\u00e9 du syst\u00e8me est ici pouss\u00e9e \u00e0 son extr\u00e9mit\u00e9. On ne peut pas parler de \u00ab\u00a0gouvernement secret\u00a0\u00bb, ou de \u00ab\u00a0gouvernement de l&rsquo;ombre\u00a0\u00bb, ni de complot <em>stricto sensu<\/em>; pourtant, beaucoup de choses y font songer et l&rsquo;esprit de la chose n&rsquo;est pas loin de baigner le programme.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Un vrai dur et un faux dictateur<\/h3>\n<\/p>\n<p><p>La brutalit\u00e9 de Rumsfeld est incontestable, son poids \u00e9galement, son influence sans aucun doute. Pour autant, a-t-il de l&rsquo;autorit\u00e9? L&rsquo;une des sp\u00e9cialit\u00e9s de cet homme qui contr\u00f4le tout et voit tout est, en g\u00e9n\u00e9ral, de se d\u00e9fausser sur ses subordonn\u00e9s de responsabilit\u00e9s qui l&#8217;embarrassent. Ainsi fera-t-il du scandale <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=1283\">Boeing-Druyun<\/a>, dont il se d\u00e9charge enti\u00e8rement sur son n&deg;2 Pete Aldrige. Cela nous vaut un \u00e9tonnant interrogatoire confidentiel par un enqu\u00eateur interne sur les circonstances de cette affaire, avec un Rumdsfeld \u00e9bahi ne se rappelant m\u00eame pas les dates de l&rsquo;attaque contre l&rsquo;Irak. Cockburn a obtenu les minutes de cet interrogatoire, ce passage surr\u00e9aliste o&ugrave; l&rsquo;on demande \u00e0 Rumsfeld s&rsquo;il \u00e9tait au courant des tractations&hellip;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<strong><em>Rumsfeld<\/em><\/strong><em>: Nous avions cette guerre en Irak qui a commenc\u00e9 en, euh, mars&hellip;<\/em><\/p>\n<\/p>\n<p><p>&raquo;<strong><em>L&rsquo;enqu\u00eateur<\/em><\/strong><em>: Mars.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<strong><em>Rumsfeld<\/em><\/strong><em>: F\u00e9vrier, mars, avril.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<strong><em>L&rsquo;enqu\u00eateur<\/em><\/strong><em>: Mars 2003.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<strong><em>Rumsfeld<\/em><\/strong>: [Deux mille] <em>deux.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<strong><em>L&rsquo;enqu\u00eateur<\/em><\/strong><em>: Trois.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<strong><em>Rumsfeld<\/em><\/strong><em>: Trois.<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Comme pour le reste, Rumsfeld est un homme d&rsquo;une grande mais fausse autorit\u00e9, qui pr\u00e9tend avoir tout sous son contr\u00f4le et qui ne contr\u00f4le pas grand&rsquo;chose, qui est principalement attentif \u00e0 r\u00e9duire l&rsquo;autorit\u00e9 de ses subordonn\u00e9s et qui s&#8217;emploie constamment \u00e0 peaufiner son \u00ab\u00a0image\u00a0\u00bb publique au travers d&rsquo;une relation pressante et souvent terroriste avec les m\u00e9dias. Au contraire, c&rsquo;est un ma&icirc;tre des relations qui comptent, qui peuvent assurer sa position ou faciliter ses entreprises. Il a bien peu de consid\u00e9ration pour son adjoint Wolfowitz, qui appara&icirc;t dans le livre comme un homme ind\u00e9cis, h\u00e9sitant, le contraire de cet intellectuel id\u00e9ologique tranchant qu&rsquo;on nous a souvent d\u00e9crit. (Au passage, nous apprenons, \u00e9bahis, qu&rsquo;il fut question de nommer Wolfowitz comme \u00ab\u00a0vice-roi\u00a0\u00bb US d&rsquo;Irak avant de choisir Bremer.)<\/p>\n<\/p>\n<p><p>Son grand ami dans cette p\u00e9riode cruciale est Richard Perle, &ndash; mais sans doute devrait-on parler plus pr\u00e9cis\u00e9ment de \u00ab\u00a0complice\u00a0\u00bb. (Ainsi apprend-on que Perle refusa un poste aupr\u00e8s de Rumsfeld, &ndash; peut-\u00eatre celui qui \u00e9chut \u00e0 Wolfowitz? &ndash; parce que le Pentagone ne pouvait pas lui offrir autant qu&rsquo;il gagnait dans le \u00ab\u00a0civil\u00a0\u00bb.) Ce n&rsquo;est pas la moindre des surprises, tant les personnalit\u00e9s de Perle et de Rumsfeld sembleraient peu s&rsquo;assembler. Mais sans doute y a-t-il entre eux une complicit\u00e9 des conceptions, le go&ucirc;t de l&rsquo;intrigue et de la publicit\u00e9, et de l&rsquo;argent \u00e9galement, le m\u00e9lange du priv\u00e9 manipulateur de la puissance publique et de la puissance publique ainsi d\u00e9natur\u00e9e&hellip;<\/p>\n<\/p>\n<p><p>Enfin, il y a les rapports de Rumsfeld et de GW. Sans doute Rumsfeld a-t-il tenu pendant plusieurs ann\u00e9es le pr\u00e9sident sous sa coupe, par l&rsquo;ascendant psychologique. Cockburn le voit comme un p\u00e8re aupr\u00e8s de GW, rempla\u00e7ant le vrai p\u00e8re, le 41\u00e8me Pr\u00e9sident, que GW avait rejet\u00e9. Cockburn juge que Rumsfeld se montra tr\u00e8s fin psychologue vis-\u00e0-vis du Pr\u00e9sident :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>Au Moyen Age on appelait ce genre de personnage \u00ab\u00a0un puissant sujet\u00a0\u00bb. Rumsfeld, ayant \u00e9chou\u00e9 \u00e0 se faire \u00e9lire d\u00e9mocratiquement, restera dans l&rsquo;histoire comme un grand courtisan.<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>L&rsquo;impression qui subsiste est qu&rsquo;\u00e0 cet \u00e9gard, Rumsfeld eut bien plus d&rsquo;influence sur GW que son ex-comp\u00e8re Cheney.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">La force et le d\u00e9sordre<\/h3>\n<\/p>\n<p><p>Il est incontestable que Rumsfeld est un f\u00e9roce guerrier de la bureaucratie et du <em>business<\/em> am\u00e9ricanistes. Son ambition est immense et elle s&rsquo;accorde parfaitement avec les r\u00e8gles du syst\u00e8me qui favorise absolument l&rsquo;individualisme pourvu que l&rsquo;on se conforme \u00e0 ses r\u00e8gles. (Le syst\u00e8me tient les hommes en les divisant entre eux par l&rsquo;affrontement de leurs ambitions, et en r\u00e9unissant leur \u00e9nergie \u00e0 son profit en les encha&icirc;nant \u00e0 ses buts m\u00e9caniques.) On ne retrouve nulle part en lui un certain d\u00e9sint\u00e9ressement, un certain sens du service public, qu&rsquo;on trouvait chez des hommes comme George Marshall ou comme Eisenhower, comme George Keenan, voire m\u00eame comme McNamara. Rumsfeld est l&rsquo;homme individualiste du syst\u00e8me apr\u00e8s la transformation des ann\u00e9es 1970, quand le syst\u00e8me bascula dans une formule o&ugrave; la pr\u00e9pond\u00e9rance des groupes de pression prit le dessus d\u00e9finitivement.<\/p>\n<\/p>\n<p><p>Pour cette raison qu&rsquo;il est parfaitement la cr\u00e9ature du syst\u00e8me dans sa derni\u00e8re phase, Rumsfeld n&rsquo;est pas l&rsquo;homme des grands desseins ni des plans de conqu\u00eate universels. Il adopte certaines \u00ab\u00a0causes\u00a0\u00bb (celle des syst\u00e8mes anti-missiles, par exemple) comme un lobbyiste, \u00e0 la fa\u00e7on d&rsquo;un Perle. Il y voit d&rsquo;abord son int\u00e9r\u00eat, la satisfaction de son orgueil, le moyen d&rsquo;exercer sa brutalit\u00e9 qui lui tient lieu d&rsquo;autorit\u00e9. Est-il utile d&rsquo;ajouter qu&rsquo;apr\u00e8s avoir suivi la carri\u00e8re de Rumsfeld dessin\u00e9e par Cockburn, on doute grandement que le syst\u00e8me soit capable de construire des plans universels, de monter des complots diaboliques de pr\u00e9cision, comme un horloger du diable. Le syst\u00e8me, comme Rumsfeld, c&rsquo;est plut\u00f4t le bulldozer du diable. Puisqu&rsquo;on a la force, on en use. &laquo;<em>Ici, on ne r\u00e9sout pas les probl\u00e8mes, on les \u00e9crase.<\/em>&raquo; Nous serions assez de l&rsquo;avis de Jean-Philippe Immarigeon (P.38-39 de <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4605\">son livre<\/a> <em>Sarko l&rsquo;Am\u00e9ricain<\/em>.) Ceux qui voient dans tous les complots la main impeccablement pr\u00e9cise du syst\u00e8me de l&rsquo;am\u00e9ricanisme ne sont pas loin de partager la fascination grossi\u00e8re d&rsquo;un Sarko pour ce syst\u00e8me-l\u00e0, &ndash; celui qui peut tout en bien ou en mal&hellip; Des mains de boucher, pas des doigts de f\u00e9e (ou de sorci\u00e8re); ce qui caract\u00e9rise ce syst\u00e8me, c&rsquo;est sa grossi\u00e8ret\u00e9 et sa m\u00e9diocrit\u00e9. (Dire qu&rsquo;il se compare lui-m\u00eame \u00e0 l&#8217;empire de Rome! Quelle impudence!)<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Que restera-t-il de Rumsfeld?<\/h3>\n<\/p>\n<p><p>Quelle impression g\u00e9n\u00e9rale subsiste-t-il de Rumsfeld? Quel portrait en gardons-nous? Essayons de r\u00e9sumer: Rumsfeld nous appara&icirc;t comme un personnage typique du pouvoir moderne (postmoderne) aux USA: \u00e0 la fois tr\u00e8s puissant gr\u00e2ce \u00e0 son habilet\u00e9 \u00e0 se servir des avantages du syst\u00e8me et \u00e0 combattre avec violence et bonheur dans les arcanes de cette soci\u00e9t\u00e9 bureaucratique, promotionnelle et corrompue; \u00e0 la fois prisonnier du syst\u00e8me puisque tenu encore plus qu&rsquo;un autre \u00e0 respecter ses r\u00e8gles pour pouvoir mieux les utiliser. Cet homme est-il mauvais, un \u00ab\u00a0m\u00e9chant\u00a0\u00bb selon la terminologie de GW? Pas vraiment, d&rsquo;ailleurs selon l&rsquo;interrogation circonspecte de savoir si cela existe, un \u00ab\u00a0homme mauvais\u00a0\u00bb; un dur par contre, brutal, \u00e0 la fa\u00e7on des \u00ab\u00a0parrains\u00a0\u00bb de la <em>Cosa Nostra<\/em>, cassant dans ses rapports, capable parfois de jugements remarquables (voir <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=201\">son discours<\/a> du 10 septembre 2001) dont il fera des actes catastrophiques; de toutes les fa\u00e7ons, &ndash; l&rsquo;expression revient irr\u00e9sistiblement, &ndash; une cr\u00e9ature du syst\u00e8me, prise dans son engrenage, qui a d\u00e9cid\u00e9 d\u00e8s l&rsquo;origine de ne pas s&rsquo;interroger \u00e0 ce propos.<\/p>\n<\/p>\n<p><p>Sa carri\u00e8re politique est \u00e9galement \u00e9clair\u00e9e par sa personnalit\u00e9. S&rsquo;il faut la d\u00e9finir, on en retient deux grands axes, combinant des traits de caract\u00e8re et des comportements politiques, ou des strat\u00e9gies.<\/p>\n<\/p>\n<p><p>&bull; La violence de Rumsfeld implique la mont\u00e9e aux extr\u00eames ou, dans tous les cas, \u00e0 l&rsquo;extr\u00eame, &ndash; n&rsquo;importe lequel, mais conserv\u00e9 \u00e0 l&rsquo;int\u00e9rieur du syst\u00e8me. Cela explique que cet homme soit conduit \u00e0 recommander et \u00e0 couvrir les pratiques les plus violentes. C&rsquo;est l&rsquo;homme de la torture, recommand\u00e9e, d\u00e9taill\u00e9e, mesur\u00e9e au millim\u00e8tres, etc., assistant m\u00eame selon certaines sources, \u00e0 des \u00ab\u00a0travaux pratiques\u00a0\u00bb. C&rsquo;est aussi l&rsquo;homme de l&#8217;emploi forcen\u00e9 du nucl\u00e9aire dans les exercices du <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4618\">COG<\/a>.<\/p>\n<\/p>\n<p><p>&bull; L&rsquo;obsession du <em>management<\/em>, qui passe par la disposition des technologies avanc\u00e9es. Il semble qu&rsquo;on puisse avancer l&rsquo;hypoth\u00e8se explicative que, dans l&rsquo;esprit de Rumsfeld, l&rsquo;Irak est le champ d&rsquo;application de sa grande th\u00e9orie de la <em>Transformation<\/em> (anglais-fran\u00e7ais dans le texte) et pratiquement rien que cela. Pour lui, toute son action apr\u00e8s 9\/11 s&rsquo;explique par son action avant 9\/11. A c\u00f4t\u00e9 de ses manigances sans nombre, de ses intrigues, de ses man&oelig;uvres, de ses grands projets de conqu\u00eate, sa grande entreprise c&rsquo;est la r\u00e9forme du Pentagone; 9\/11 lui donne l&rsquo;occasion de reprendre la main sur le Congr\u00e8s, devant lequel il se trouvait en tr\u00e8s grandes difficult\u00e9s; les guerres en Afghanistan et en Irak seront \u00e9videmment, il n&rsquo;en doute pas une seconde, les terrains de d\u00e9monstration de la justesse de ses vues. Bien entendu, Rumsfeld a laiss\u00e9 le Pentagone, charg\u00e9 jusqu&rsquo;\u00e0 la gueule de centaines de $milliards, dans un \u00e9tat de d\u00e9sordre bien pire que celui o&ugrave; il le trouva.<\/p>\n<\/p>\n<p><p>Etrange personnage d&rsquo;un temps historique qui n&rsquo;a pas de pr\u00e9c\u00e9dent ; personnage \u00e0 la fois puissant et vain, formidable et d\u00e9risoire. Rumsfeld est l&rsquo;homme fameux en son temps servant \u00e0 son avantage un pouvoir d&rsquo;une puissance sans \u00e9gale et dont, peut-\u00eatre, il ne restera rien. Le syst\u00e8me d\u00e9vore gloutonnement ses enfants. Bon app\u00e9tit.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rumsfeld d\u00e9mystifi\u00e9 Voici le livre de Andrew Cockburn (Rumsfeld, His Rise, Fall and Catastrophic Legacy) traduit en fran\u00e7ais: Caligula au Pentagone, chez Xenia, collection Le cha&icirc;non manquant. Il s&rsquo;agit sans aucun doute de bien plus qu&rsquo;\u00a0\u00bbun livre de plus\u00a0\u00bb sur Rumsfeld et, au-del\u00e0, sur l&rsquo;establishment de s\u00e9curit\u00e9 nationale de Washington. Le ton neutre, presque flegmatique&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[3253,1294,1135,7149,7207,3194,3213,569,3014,1448,7208],"class_list":["post-69406","post","type-post","status-publish","format-standard","hentry","category-analyse","tag-americanisme","tag-cheney","tag-cockburn","tag-cog","tag-editions","tag-pentagone","tag-perle","tag-rumsfeld","tag-systeme","tag-wolfowitz","tag-xenia"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69406"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69406\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}