{"id":69487,"date":"2007-12-10T00:00:00","date_gmt":"2007-12-10T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2007\/12\/10\/une-mission-par-tous-les-temps\/"},"modified":"2007-12-10T00:00:00","modified_gmt":"2007-12-10T00:00:00","slug":"une-mission-par-tous-les-temps","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2007\/12\/10\/une-mission-par-tous-les-temps\/","title":{"rendered":"Une mission par tous les temps"},"content":{"rendered":"<p><h2 class=\"common-article\">Une mission par tous les temps<\/h2>\n<\/p>\n<p><p>\tL&rsquo;intervention du ministre fran\u00e7ais de la d\u00e9fense, le 11 septembre 2007 \u00e0 Toulouse, a soulev\u00e9 officiellement la question importante de l&rsquo;utilit\u00e9 des syst\u00e8mes de hautes technologies. Nous avons fait un premier \u00e9cho \u00e0 cette intervention, dans notre rubrique <em>Journal<\/em>, dans notre num\u00e9ro du 25 septembre. On sait que le ministre mettait en cause le d\u00e9veloppement syst\u00e9matique des hautes technologies en prenant comme exemple l&rsquo;avion de combat <em>Rafale<\/em>.<\/p>\n<\/p>\n<p><p>\tLe ministre Morin expliquait que le <em>Rafale<\/em> est un \u00ab<em>avion tr\u00e8s sophistiqu\u00e9 et difficile \u00e0 vendre<\/em>\u00bb; il disait: \u00ab<em>Je souhaite qu&rsquo;on propose aux politiques la possibilit\u00e9 de choisir un \u00e9quipement un peu moins sophistiqu\u00e9<\/em>\u00bb; il disait encore: \u00ab[Q]<em>uand les Am\u00e9ricains emportent des contrats, c&rsquo;est souvent avec des F-16 d&rsquo;occasion.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tNous rappelions dans notre num\u00e9ro du 25 septembre que ce n&rsquo;\u00e9tait pas la premi\u00e8re fois qu&rsquo;on enregistrait une intervention de cette sorte d&rsquo;un ministre fran\u00e7ais. (Nous citions les remarques radiodiffus\u00e9es du Premier ministre Michel Rocard, en septembre 1988, sur le <em>Rafale<\/em>, \u00ab<em>dossier sinistr\u00e9<\/em>\u00bb, qui contribu\u00e8rent notablement \u00e0 l&rsquo;\u00e9chec de l&rsquo;entr\u00e9e de la Belgique dans le programme <em>Rafale<\/em>.) Les hommes politiques fran\u00e7ais ont un peu en commun cette tendance, \u00e0 l&rsquo;image du monde intellectuel fran\u00e7ais auquel ils sont fort sensibles, \u00e0 l&rsquo;image d&rsquo;un certain esprit fran\u00e7ais auquel ils sacrifient beaucoup, d&rsquo;un penchant au d\u00e9nigrement de leur propre pays.<\/p>\n<\/p>\n<p><p>\tLes circonstances f\u00e2cheuses et l&rsquo;incons\u00e9quence \u00e9tonnante des hommes politiques fran\u00e7ais n&#8217;emp\u00eachent pas que cette d\u00e9claration concerne un probl\u00e8me existant, tr\u00e8s actuel et pressant. Il s&rsquo;agit du r\u00f4le et de la place des hautes technologies dans les syst\u00e8mes d&rsquo;arme. C&rsquo;est un probl\u00e8me auquel nous sommes nous-m\u00eames fort sensibles, que nous avons \u00e9voqu\u00e9 souvent. Nous prenons l&rsquo;argument de ces d\u00e9clarations pour y revenir, mais dans un sens nouveau, comme nous y invite le ministre,  peut-\u00eatre involontairement, peut-\u00eatre pas,  qui sait&#8230;<\/p>\n<h3>De l&rsquo;impossibilit\u00e9 d&rsquo;\u00e9valuer l&rsquo;int\u00e9r\u00eat des hautes technologies  depuis 9\/11<\/h3>\n<\/p>\n<p><p>\tDepuis le 11 septembre 2001, les conditions de la s\u00e9curit\u00e9 internationale ont chang\u00e9 de fa\u00e7on radicale. Ou bien, disons-le diff\u00e9remment: nous avons effectivement act\u00e9 que les conditions de la s\u00e9curit\u00e9 internationale sont bien plus complexes que les strat\u00e8ges le pensaient pr\u00e9c\u00e9demment. La G4G (Guerre de 4\u00e8me G\u00e9n\u00e9ration) a fait irruption sur la sc\u00e8ne de la pens\u00e9e strat\u00e9gique. Pourtant, la G4G n&rsquo;a finalement rien de bien nouveau puisqu&rsquo;elle est le label appliqu\u00e9 au conflit vieux comme le monde entre fort et faible. La G4G implique \u00e9videmment l&#8217;emploi, entre les bellig\u00e9rants, de moyens dits asym\u00e9triques. L\u00e0 \u00e9galement, rien de bien nouveau<\/p>\n<\/p>\n<p><p>\tLa G4G d&rsquo;aujourd&rsquo;hui a une forme tr\u00e8s sp\u00e9cifique comme c&rsquo;est la logique m\u00eame, puisque chaque \u00e9poque donne une forme diff\u00e9rente \u00e0 ce type de conflit. La guerre du faible contre le fort change de figure \u00e0 chaque \u00e9poque, avec l&rsquo;\u00e9volution des moyens du fort et l&rsquo;adaptation du faible \u00e0 ces nouveaux moyens.<\/p>\n<\/p>\n<p><p>\tDeux caract\u00e9ristiques sont propres \u00e0 cette guerre du faible contre le fort telle qu&rsquo;elle s&rsquo;est impos\u00e9e depuis le 11 septembre 2001.<\/p>\n<\/p>\n<p><p>\t Une premi\u00e8re nouveaut\u00e9 sp\u00e9cifique, c&rsquo;est le fait que la G4G fait appel \u00e0 un tr\u00e8s grand nombre d&rsquo;\u00e9l\u00e9ments non militaires, ce qui correspond \u00e0 la diversit\u00e9 de la situation politique. Des facteurs tels que la culture, la souverainet\u00e9, la transnationalit\u00e9, les communications au sens de la circulation de l&rsquo;information, c&rsquo;est-\u00e0-dire au sens social le plus large, jouent un r\u00f4le fondamental.<\/p>\n<\/p>\n<p><p>\t Une seconde nouveaut\u00e9, de non moindre importance sans doute, c&rsquo;est que l&rsquo;existence de la G4G est act\u00e9e et consid\u00e9r\u00e9e comme un \u00e9l\u00e9ment fondamental de la situation strat\u00e9gique, voire m\u00eame comme  la seule forme de conflit probable dans les circonstances actuelles. (La cause principale de cette situation est la crainte des destructions qu&rsquo;engendrerait un conflit classique de haut niveau, incluant probablement l&#8217;emploi du nucl\u00e9aire dont l&#8217;emploi est fortement banalis\u00e9 par la doctrine de frappe pr\u00e9ventive des USA. Toutes les puissances militaires,  sauf peut-\u00eatre les USA,  ont la ferme intention d&rsquo;\u00e9viter un tel conflit. Il en r\u00e9sulte que l&rsquo;essentiel des conflits se r\u00e9sume \u00e0 des guerres de type G4G. On ne voit pas, dans la pr\u00e9vision raisonnable, quelque \u00e9l\u00e9ment que ce soit qui modifie cette situation fondamentalement.)<\/p>\n<\/p>\n<p><p>\tLa G4G occupe donc l&rsquo;essentiel de la sc\u00e8ne strat\u00e9gique. Cette situation conduit \u00e0 des questions \u00e9galement essentielles. On mesure de plus en plus pr\u00e9cis\u00e9ment combien les syst\u00e8mes de hautes technologies sont souvent peu \u00e0 leur place dans un tel type de conflits, souvent inefficaces, parfois contre-performants. Pire encore, la possession de ces syst\u00e8mes entra\u00eene des tactiques peu adapt\u00e9es \u00e0 la G4G et, surtout, influe f\u00e2cheusement sur les psychologies. Le conflit du Liban de l&rsquo;\u00e9t\u00e9 2006, o\u00f9 Isra\u00ebl a \u00e9t\u00e9 humili\u00e9 par le Hezbollah, est l\u00e0 pour nous rappeler d&rsquo;une fa\u00e7on spectaculaire cette r\u00e9alit\u00e9 exp\u00e9riment\u00e9e chaque jour en Irak et en Afghanistan. Par ailleurs et pour emp\u00eacher toute conclusion h\u00e2tive, on sait que si le Hezbollah a fait sa G4G en utilisant des moyens et des tactiques souvent jug\u00e9s d\u00e9pass\u00e9s mais bien r\u00e9adapt\u00e9s, ou des tactiques et des moyens de conflits de basse intensit\u00e9, il a \u00e9galement utilis\u00e9 quand c&rsquo;\u00e9tait opportun des syst\u00e8mes de hautes technologies. Ce dernier point nous interdit de proclamer la fin de l&rsquo;utilit\u00e9 des hautes technologies, notamment pour faire ce qui para\u00eet aujourd&rsquo;hui \u00eatre la forme de conflit qui lui serait la plus \u00e9trang\u00e8re. Le probl\u00e8me se complique.<\/p>\n<\/p>\n<p><p>\tIl se complique d&rsquo;autant plus qu&rsquo;il est, \u00e0 notre sens, singuli\u00e8rement transform\u00e9 par l&rsquo;aspect psychologique. Le plus important, nous semble-t-il, dans les hautes technologies, c&rsquo;est leur effet sur les psychologies de ceux qui les utilisent. L&rsquo;usage des hautes technologies constitue un ph\u00e9nom\u00e8ne non seulement technique (technologique) et militaire, mais \u00e9galement psychologique. Il nourrit un \u00e9tat d&rsquo;esprit fait de certitudes souvent d\u00e9raisonnables, appuy\u00e9es sur une appr\u00e9ciation g\u00e9n\u00e9rale de l&rsquo;absolue sup\u00e9riorit\u00e9 de ce moyen. Ainsi doit-on remarquer que c&rsquo;est \u00e9galement dans l&#8217;emploi qu&rsquo;on fait des hautes technologies que se pose un grave probl\u00e8me d&rsquo;interf\u00e9rence dans leur \u00e9ventuel bon usage.<\/p>\n<\/p>\n<p><p>\tA c\u00f4t\u00e9 de cela, l&rsquo;apparition de la G4G n&rsquo;a pas frein\u00e9 le d\u00e9veloppement d&rsquo;un aspect des hautes technologies li\u00e9 \u00e0 la communication. Il s&rsquo;agit de l&rsquo;aspect de d\u00e9monstration, qui est en g\u00e9n\u00e9ral beaucoup plus destin\u00e9 \u00e0 des concurrents dont on est souvent plus les alli\u00e9s que les adversaires. Ainsi les pays disposant de mat\u00e9riels de hautes technologies ont-ils tendance \u00e0 d\u00e9ployer d\u00e8s qu&rsquo;ils sont disponibles leurs syst\u00e8mes de hautes technologies, \u00e0 des fins d\u00e9monstratives, pour marquer leur diff\u00e9rence avec d&rsquo;autres pays alli\u00e9s et impressionner \u00e9ventuellement des acheteurs potentiels. C&rsquo;est l&rsquo;aspect <em>war-proven<\/em> qui donne au syst\u00e8me une sorte de label de bonne utilisation. Cela explique que les Fran\u00e7ais aient d\u00e9ploy\u00e9 leur <em>Rafale<\/em> en Afghanistan, suivis deux ans plus tard par les Britanniques avec leur <em>Typhoon<\/em>. Ces avions r\u00e9ussissent plus ou moins bien leurs missions, parfois au prix d&rsquo;affirmations bien imprudentes. Il est effectivement imprudent de dire, comme le fait le colonel Parker du IX Squadron de la RAF en partance en ao\u00fbt en Afghanistan, que \u00ab<em>the Typhoon<\/em> [will be] <em>a fantastic close air support machine<\/em>\u00bb. Quoi qu&rsquo;il en soit, il semble \u00e9vident que la volont\u00e9 de d\u00e9montrer l&rsquo;efficacit\u00e9, la valeur et la puissance des hautes technologies joue un r\u00f4le d\u00e9terminant.<\/p>\n<\/p>\n<p><p>\tCet aspect de l&rsquo;utilisation des syst\u00e8mes de hautes technologies \u00e9largit brusquement, et d&rsquo;une fa\u00e7on extr\u00eamement bienvenue, le champ de nos r\u00e9flexions. Il permet de nous \u00e9chapper du cadre restreint des questions militaires, pour mieux envisager la probl\u00e9matique des hautes technologies et aborder d&rsquo;une fa\u00e7on plus compl\u00e8te la question soulev\u00e9e par les remarques du ministre Morin.<\/p>\n<h3>Les hautes technologies et la signification politique de la mission de guerre<\/h3>\n<\/p>\n<p><p>\tCette approche nous invite \u00e0 consid\u00e9rer les hautes technologies dans un champ plus large qu&rsquo;\u00e0 l&rsquo;habitude et, surtout, diff\u00e9rent. Il s&rsquo;agit d&rsquo;appr\u00e9cier ces syst\u00e8mes de hautes technologies hors de leur r\u00e9f\u00e9rence utile (qu&rsquo;est-ce que ces hautes technologies sont capables de faire?) et plut\u00f4t en fonction de leur r\u00e9f\u00e9rence repr\u00e9sentative (quel poids de puissance et de niveau d&rsquo;expertise repr\u00e9sentent-elles?). Notre propos est \u00e9galement d&rsquo;adopter ce point de vue en fonction de la plate-forme consid\u00e9r\u00e9e et en fonction de la mission et de la signification politique de cette mission. Ce dernier point est effectivement l&rsquo;essentiel du propos.<\/p>\n<\/p>\n<p><p>\tCertes, le jugement de l&rsquo;officier de la RAF rel\u00e8ve de la pure relation publique et, par cons\u00e9quent, il est stupide parce que sans substance ni fondement. Nous affirmer que le <em>Typhoon<\/em> est une machine id\u00e9ale pour l&rsquo;appui tactique rapproch\u00e9 repr\u00e9sente une proposition si d\u00e9raisonnable qu&rsquo;elle ne doit m\u00eame pas \u00eatre consid\u00e9r\u00e9e; qui plus est, c&rsquo;est une proposition sans aucun int\u00e9r\u00eat. Le <em>Typhoon<\/em> est en Afghanistan pour figurer, pour affirmer sa pr\u00e9sence en conditions op\u00e9rationnelles, pour dire \u00e0 qui cela importe, \u00e9galement \u00e0 d&rsquo;\u00e9ventuels acheteurs, qu&rsquo;il a quitt\u00e9 le stade du prototype, des essais, de la mise en condition, pour le statut op\u00e9rationnel. C&rsquo;est un message publicitaire qui concerne l&rsquo;affirmation d&rsquo;une puissance technologique autant que sa disposition pour d&rsquo;\u00e9ventuelles ventes (exportation). Notre propos n&rsquo;est pas, ici, de d\u00e9terminer si ce message est juste (on a vu ce qu&rsquo;on en pense) mais de constater que ce message est une cause importante du d\u00e9ploiement de l&rsquo;avion. Nous irions m\u00eame jusqu&rsquo;\u00e0 proposer l&rsquo;id\u00e9e qu&rsquo;il s&rsquo;agit de la cause principale.<\/p>\n<\/p>\n<p><p>\tCela confirme que les hautes technologies ont effectivement une fonction de repr\u00e9sentation, une fonction de communication au niveau de l&rsquo;information. Cette fonction est extr\u00eamement forte et importante. Malgr\u00e9 la d\u00e9raison de pr\u00e9senter le <em>Typhoon<\/em> comme un avion d&rsquo;appui tactique rapproch\u00e9, il reste comme id\u00e9e principale que le <em>Typhoon<\/em> est effectivement entr\u00e9 en service op\u00e9rationnel. On voit bien que le message n&rsquo;a dans ce cas aucun rapport avec l&rsquo;efficacit\u00e9 de l&rsquo;avion. Le cas du <em>Typhoon<\/em> est tr\u00e8s d\u00e9monstratif parce que, justement, le fondement du message dans la r\u00e9alit\u00e9 est tr\u00e8s faible.<\/p>\n<\/p>\n<p><p>\tIl s&rsquo;agit d&rsquo;une situation typique de notre \u00e9poque caract\u00e9ris\u00e9e par des conflits type G4G et par une d\u00e9finition de la puissance extr\u00eamement complexe, o\u00f9 la repr\u00e9sentation tient un r\u00f4le tr\u00e8s important parce que notre \u00e9poque est celle de l&rsquo;information et de ses effets sur la psychologie (l&rsquo;\u00e9poque psychopolitique \u00e0 la place de l&rsquo;\u00e9poque de la g\u00e9opolitique [voir notre rubrique <em>Analyse<\/em>, 10 d\u00e9cembre 2006]). Cette situation typique conduit au premier constat que l&rsquo;importance de ce qu&rsquo;on avait coutume de d\u00e9signer comme une machine de guerre utilisant des hautes technologies ne se mesure plus aux r\u00e9sultats que cette machine obtient dans un conflit, m\u00eame si elle est plong\u00e9e dans un conflit; puis au second constat que son importance d\u00e9pend \u00e9galement de sa puissance en tant que valeur de repr\u00e9sentation, c&rsquo;est-\u00e0-dire de symbole de quelque chose d&rsquo;autre qu&rsquo;elle-m\u00eame.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est avec ces nouveaux param\u00e8tres qu&rsquo;il faut \u00e9tablir une classification de l&rsquo;importance des syst\u00e8mes de hautes technologies et d\u00e9terminer ceux qui sont n\u00e9cessaires, ceux qui sont utiles et ceux qui sont inutiles. C&rsquo;est avec ces nouveaux param\u00e8tres qu&rsquo;il faut examiner \u00e0 la fois ce que sont ces syst\u00e8mes de hautes technologies et ce \u00e0 quoi ils servent, potentiellement et pratiquement.<\/p>\n<\/p>\n<p><p>\t Ce qu&rsquo;ils sont. La question sur la n\u00e9cessit\u00e9 et l&rsquo;utilit\u00e9 des hautes technologies est marqu\u00e9e par un paradoxe qui s&rsquo;explique par la dimension politique et conceptuelle de ces hautes technologies. On veut parler de leur caract\u00e8re souverain, car c&rsquo;est \u00e9videmment en fonction de cette sp\u00e9cificit\u00e9 que nous devons tenter de r\u00e9pondre \u00e0 la question envisag\u00e9e. Aujourd&rsquo;hui, dans un univers soumis \u00e0 des forces d\u00e9structurantes d&rsquo;une puissance inou\u00efe, qui dissolvent les puissances et les capacit\u00e9s autonomes, la souverainet\u00e9 est une des principales forces structurantes. C&rsquo;est un facteur fondamental de la d\u00e9finition de la n\u00e9o-puissance. La capacit\u00e9 souveraine de concevoir et de produire des hautes technologies fournit la d\u00e9monstration qu&rsquo;on dispose \u00e0 la fois de l&rsquo;autonomie politique et des moyens de produire ces technologies. La disposition et l&rsquo;int\u00e9gration de ces hautes technologies dans un syst\u00e8me pr\u00e9sentent l&rsquo;avantage d&rsquo;une affirmation souveraine de puissance et conduisent \u00e0 d\u00e9signer ces technologies comme des technologies de souverainet\u00e9. Il est imp\u00e9ratif de disposer d&rsquo;au moins un syst\u00e8me dans les grands domaines de la puissance pour qu&rsquo;il y d\u00e9montre cette capacit\u00e9 technologique souveraine.<\/p>\n<\/p>\n<p><p>\t Ce \u00e0 quoi ils servent. Comment d\u00e9terminer le choix qu&rsquo;on fera du syst\u00e8me \u00e0 d\u00e9velopper, disposant sans restriction des hautes technologies servant alors de d\u00e9monstration? Le choix doit \u00eatre dirig\u00e9, en toute coh\u00e9rence, vers des syst\u00e8mes remplissant des missions centrales, que nous nommerions des missions de souverainet\u00e9. Il s&rsquo;agit de missions militaires absolument n\u00e9cessaires \u00e0 l&rsquo;int\u00e9grit\u00e9 et \u00e0 la d\u00e9fense d&rsquo;une nation, qui  assurent son int\u00e9grit\u00e9 territoriale et spatiale. Il s&rsquo;agit de missions de souverainet\u00e9 dans la mesure o\u00f9 leur but essentiel est d&rsquo;assurer et d&rsquo;affirmer la souverainet\u00e9 de la nation. C&rsquo;est ce dernier point de la mission souveraine qui est nouveau et r\u00e9volutionnaire dans les nouvelles situations conflictuelles. Ces missions s&rsquo;imposent comme de type dissuasif, en g\u00e9n\u00e9ral non destin\u00e9es \u00e0 \u00eatre effectu\u00e9es parce que la pr\u00e9sence du syst\u00e8me d&rsquo;arme charg\u00e9 de la mener \u00e0 bien doit dissuader tout agresseur potentiel de tenter son agression. Cela revient \u00e0 inclure certains syst\u00e8mes conventionnels de hautes technologies dans la logique de la dissuasion qui, de sa seule composante nucl\u00e9aire, est \u00e9largie au domaine conventionnel par l&rsquo;apport souverain des technologies.<\/p>\n<h3>La mission souveraine, nouvelle dimension de la dissuasion<\/h3>\n<\/p>\n<p><p>\tAinsi en revient-on \u00e0 l&rsquo;intervention du ministre fran\u00e7ais Morin \u00e0 propos de l&rsquo;avion de combat <em>Rafale<\/em>. C&rsquo;est l&rsquo;exemple m\u00eame d&rsquo;une d\u00e9marche compr\u00e9hensible et justifi\u00e9e (l&rsquo;interrogation sur les hautes technologies) qui prend comme exemple le seul cas o\u00f9 cette d\u00e9marche est sans le moindre doute injustifi\u00e9e.<\/p>\n<\/p>\n<p><p>\tNous parlons ici de la mission souveraine qu&rsquo;on d\u00e9signe techniquement avec les expressions de sup\u00e9riorit\u00e9 a\u00e9rienne ou de domination a\u00e9rienne, et qui se d\u00e9finit bien mieux par l&rsquo;expression de contr\u00f4le de l&rsquo;espace souverain; c&rsquo;est-\u00e0-dire, dans tous les cas l&rsquo;espace national et, dans des cas conjoncturels, l&rsquo;un ou l&rsquo;autre espace non-national dont le contr\u00f4le est jug\u00e9 pour un temps d&rsquo;int\u00e9r\u00eat national primordial.<\/p>\n<\/p>\n<p><p>\tCette mission n&rsquo;est pas une mission op\u00e9rationnelle conjoncturelle, comme par exemple la mission d&rsquo;appui qui d\u00e9pend d&rsquo;une situation op\u00e9rationnelle changeante au sol. C&rsquo;est une mission structurelle, qui est op\u00e9rationnelle ou qui ne l&rsquo;est pas c&rsquo;est selon. Son caract\u00e8re principal est qu&rsquo;elle ne d\u00e9pend pas d&rsquo;une situation changeante mais d&rsquo;une r\u00e9alit\u00e9 structurelle p\u00e9renne. L&rsquo;espace a\u00e9rien d&rsquo;une nation est quelque chose de fixe, d\u00e9pendant de la valeur intangible de la souverainet\u00e9. Comme l&rsquo;arme nucl\u00e9aire, le syst\u00e8me assurant le contr\u00f4le de l&rsquo;espace souverain  est \u00e0 la fois une arme de survie et une arme d&rsquo;affirmation de l&rsquo;existence d&rsquo;une nation. Sa modernisation constante, la disposition des plus hautes technologies pour cette modernisation, sont une condition de sa cr\u00e9dibilit\u00e9, exactement comme dans le cas de l&rsquo;arme nucl\u00e9aire. On sait que la modernisation constante de l&rsquo;arsenal nucl\u00e9aire est une n\u00e9cessit\u00e9 \u00e0 peu pr\u00e8s aussi imp\u00e9rative que la disposition m\u00eame de cette arme nucl\u00e9aire. La m\u00eame logique caract\u00e9rise le syst\u00e8me de hautes technologies qui est destin\u00e9 aux missions souveraines; lui aussi doit entretenir sa cr\u00e9dibilit\u00e9, face aux agresseurs potentiels mais aussi, et surtout, pour continuer \u00e0 figurer comme un facteur ad\u00e9quat de l&rsquo;enjeu dont il est l&rsquo;outil \u00e0 la fois d\u00e9terminant et identifiant. Puisque cet outil existe dans la mission souveraine o\u00f9 il intervient, il identifie effectivement cette mission comme souveraine et en avise les agresseurs potentiels. Mettez un <em>Ouragan<\/em>, un <em>Myst\u00e8re<\/em> ou un SPAD-XIII \u00e0 la place du <em>Rafale<\/em> et l&rsquo;on aura du mal \u00e0 croire que la mission dont ce syst\u00e8me est charg\u00e9 est effectivement souveraine, et son effet dissuasif sera proche de z\u00e9ro. Comme l&rsquo;arme nucl\u00e9aire elle-m\u00eame, si le syst\u00e8me n&rsquo;est plus cr\u00e9dible, s&rsquo;il n&rsquo;est plus modernis\u00e9, ce sont l&rsquo;affirmation, la puissance et l&rsquo;identification m\u00eame de la souverainet\u00e9 qui sont mises en question. Il y a un rapport tr\u00e8s \u00e9troit entre la capacit\u00e9 technique et technologique de l&rsquo;outil de souverainet\u00e9 et la repr\u00e9sentation psychologique et politique de la souverainet\u00e9 que cet outil affirme autant qu&rsquo;il la d\u00e9fend.<\/p>\n<\/p>\n<p><p>\tPour bien conceptualiser ce propos en sortant de la caricature facile (le SPAD-XIII \u00e0 la place du <em>Rafale<\/em>), on signalera un autre exemple que celui de l&rsquo;avion fran\u00e7ais mais, cette fois, avec deux avions aussi avanc\u00e9s l&rsquo;un que l&rsquo;autre. C&rsquo;est le cas conjoint du F-22 <em>Raptor<\/em> et du F-35 (JSF). Dans ce cas, on en revient au propos fondamental entre missions conjoncturelles et missions structurelles.<\/p>\n<\/p>\n<p><p>\t Le F-22,  hors des nombreuses et diverses critiques sur son co\u00fbt, ses probl\u00e8mes techniques, etc.  est certainement, selon les conceptions US, l&rsquo;avion de domination a\u00e9rienne par excellence. Il est l&rsquo;avion-type de la mission de souverainet\u00e9. M\u00eame si l&rsquo;USAF en restait \u00e0 ses 183 exemplaires pr\u00e9vus actuellement (ce qui est improbable), le F-22 aurait sa justification simplement parce qu&rsquo;il n&rsquo;y a pas d&rsquo;alternative \u00e0 cet avion. Certains y voient une sorte d&rsquo;avion de mus\u00e9e, ou d&rsquo;exposition, tant le chiffre de sa production est pour l&rsquo;instant r\u00e9duit. Mais c&rsquo;est justement le cas: avion d&rsquo;exposition du niveau de d\u00e9veloppement des hautes technologies, avion d&rsquo;exposition de la capacit\u00e9 d&rsquo;affirmation de la mission de souverainet\u00e9 par excellence, telle que nous l&rsquo;avons d\u00e9crite. Cet avion est un principe, comme dans le cas du <em>Rafale<\/em>. Un principe ne se discute pas et ne se saucissonne pas; il ne se d\u00e9grade pas,  il est, et c&rsquo;est tout.<\/p>\n<\/p>\n<p><p>\t Au contraire, le JSF est, par sa mission conjoncturelle, d\u00e9pendante du reste, un syst\u00e8me essentiellement technologiquement d\u00e9gradable. On y songe d&rsquo;ailleurs. Pour tenter de r\u00e9duire son co\u00fbt incontr\u00f4lable, il existe des projets de r\u00e9duire les hautes technologies qu&rsquo;on a pr\u00e9vu d&rsquo;y int\u00e9grer. Dans ce cas, simplement, le contr\u00f4le d&rsquo;autres syst\u00e8mes sur lui (le F-22 notamment) s&rsquo;agrandit. D&rsquo;autre part, il existe des projets de r\u00e9duire les commandes nationales de F-35 et de les remplacer par des F-16 modernis\u00e9s (mod\u00e8le A-16 pr\u00e9vu dans les ann\u00e9es 1980 et modernis\u00e9). En aucun cas le JSF n&rsquo;est imp\u00e9ratif en tant que tel, parce qu&rsquo;il n&rsquo;est ni structurant ni souverain.<\/p>\n<\/p>\n<p><p>\tUne derni\u00e8re remarque sur cette question concerne l&rsquo;exportation, et plus pr\u00e9cis\u00e9ment le cas fran\u00e7ais. L\u00e0 aussi, il nous faut prendre le contre pied de l&rsquo;intervention du ministre Morin. Ces syst\u00e8mes de hautes technologies ne sont nullement contradictoires avec l&rsquo;exportation, bien au contraire. A partir du moment o\u00f9 ils offrent au pays acheteur le moyen d&rsquo;une mission souveraine, ils renforcent la souverainet\u00e9 de ce pays. Dans une \u00e9poque o\u00f9 le v\u00e9ritable danger est la d\u00e9structuration, et notamment la d\u00e9structuration des nations, tout ce qui renforce la souverainet\u00e9 est sans prix. Ce devrait \u00eatre, aujourd&rsquo;hui, le principal argument de promotion d&rsquo;un syst\u00e8me d&rsquo;arme de hautes technologies offert \u00e0 l&rsquo;exportation. On notera, pour ceux qui cultivent encore la m\u00e9moire, que c&rsquo;\u00e9tait d\u00e9j\u00e0 l&rsquo;argument sous-jacent de la grande politique d&rsquo;exportation des armements de l&rsquo;\u00e9poque gaullienne: le renforcement de la souverainet\u00e9 des autres. La France a tout \u00e0 y gagner, parce que c&rsquo;est la nation par excellence de la souverainet\u00e9. Chaque fois que le principe de souverainet\u00e9 est renforc\u00e9, la France est renforc\u00e9e. Ce constat vaut bien la comptabilit\u00e9 de l&rsquo;\u00e9picier et les airs importants des \u00e9conomistes.<\/p>\n<h3>La souverainet\u00e9, question centrale de notre temps<\/h3>\n<\/p>\n<p><p>\tY a-t-il fa\u00e7on plus moderne, plus r\u00e9formiste, que d&rsquo;aborder les probl\u00e8mes de notre temps historique \u00e0 la lumi\u00e8re du probl\u00e8me central de ce temps historique? Encore faut-il savoir pr\u00e9cis\u00e9ment quel est ce probl\u00e8me central.<\/p>\n<\/p>\n<p><p>\tLaissons les experts et les faiseurs de discours des cabinets de ministres.  Puisque nous sommes dans le temps de la globalisation, autre antienne de la nouvelle pr\u00e9sidence fran\u00e7aise, il faut savoir que \u00ab<em>la globalisation comporte autant de menaces que d&rsquo;atouts<\/em>\u00bb. C&rsquo;est Javier Solana qui nous le dit (le 4 octobre, devant la commission Mallet sur le Livre Blanc de la D\u00e9fense),  un homme qu&rsquo;on ne peut soup\u00e7onner d&rsquo;opinions excentriques et incontr\u00f4lables. La principale menace que fait peser sur nous la globalisation, c&rsquo;est la d\u00e9structuration des forces qui structurent la civilisation. La souverainet\u00e9 des nations est une de ces forces, sans doute la plus fondamentale.<\/p>\n<\/p>\n<p><p>\tIl n&rsquo;y a pas de fa\u00e7on plus constructive, plus r\u00e9formiste, plus moderne de consid\u00e9rer le probl\u00e8me des syst\u00e8mes d&rsquo;arme de hautes technologies que de le consid\u00e9rer \u00e0 la lumi\u00e8re du principal probl\u00e8me de notre temps historique, qui est celui de la souverainet\u00e9. A cette lumi\u00e8re, le diagnostic est vite rendu, et on a vu ce qu&rsquo;il en est.<\/p>\n<\/p>\n<p><p>\tIl est singuli\u00e8rement ironique que ce soit en France, la Grande Nation souveraine par excellence, que ce probl\u00e8me ait \u00e9t\u00e9 involontairement pos\u00e9, dans les termes les plus faussaires qui soient. Mais non apr\u00e8s tout, c&rsquo;est dans la tradition fran\u00e7aise, qui privil\u00e9gie l&rsquo;auto-d\u00e9nigrement comme un signe de la grande intelligence fran\u00e7aise \u00e9clairant le monde depuis des si\u00e8cles. C&rsquo;est dire que la question de l&rsquo;exportation du <em>Rafale<\/em> ne se pose pas principalement sur les march\u00e9s \u00e9trangers. Elle se pose d&rsquo;abord \u00e0 Paris. C&rsquo;est, on l&rsquo;admettra, un trait caract\u00e9ristique de la fameuse exception fran\u00e7aise<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une mission par tous les temps L&rsquo;intervention du ministre fran\u00e7ais de la d\u00e9fense, le 11 septembre 2007 \u00e0 Toulouse, a soulev\u00e9 officiellement la question importante de l&rsquo;utilit\u00e9 des syst\u00e8mes de hautes technologies. Nous avons fait un premier \u00e9cho \u00e0 cette intervention, dans notre rubrique Journal, dans notre num\u00e9ro du 25 septembre. On sait que le&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[5],"tags":[5597,4843,250,2616,7065,7060,3219,2746,3129],"class_list":["post-69487","post","type-post","status-publish","format-standard","hentry","category-de-defensa","tag-exportation","tag-f22","tag-jsf","tag-ministre","tag-mission","tag-morin","tag-rafale","tag-souverainete","tag-typhoon"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69487"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69487\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}