{"id":69619,"date":"2008-01-21T00:00:00","date_gmt":"2008-01-21T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2008\/01\/21\/la-victoire-de-combat-pour-hillary-et-le-sort-de-la-campagne\/"},"modified":"2008-01-21T00:00:00","modified_gmt":"2008-01-21T00:00:00","slug":"la-victoire-de-combat-pour-hillary-et-le-sort-de-la-campagne","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2008\/01\/21\/la-victoire-de-combat-pour-hillary-et-le-sort-de-la-campagne\/","title":{"rendered":"La victoire de combat pour Hillary et le sort de la campagne"},"content":{"rendered":"<p><p>La victoire de Hillary Clinton dans le Nevada ne r\u00e8gle rien, nous confie-t-on. D&rsquo;ailleurs, elle est fort mince (51% contre 45% \u00e0 Obama) et elle rapporte moins de d\u00e9l\u00e9gu\u00e9s \u00e0 la premi\u00e8re qu&rsquo;au second. Michael Tomasky, dans <em>The Guardian<\/em> du <a href=\"http:\/\/commentisfree.guardian.co.uk\/michael_tomasky\/2008\/01\/winning_ugly.html\" class=\"gen\">19 janvier<\/a>, r\u00e9sume la chose par ce mot, qui fait son titre: \u00ab<em>Winning ugly.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tEn effet, la bataille fut rude. Les d\u00e9mocrates ne se firent pas de cadeaux entre eux, et Bill Clinton, \u00e9ventuel futur <em>First Gentleman<\/em>, ne fut pas le dernier dans cette activit\u00e9.<\/p>\n<\/p>\n<p><p>\t\u00ab[Hillary] <em>Clinton may also have paid a price by dint of the fact that this was a dirty, bitter race. Obama didn&rsquo;t completely wrap himself in glory, and he probably erred in praising Ronald Reagan and calling the Republican Party the party of ideas in recent American history. But the Clinton campaign twisted those words and a lot more.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>I don&rsquo;t know who on this planet has the stature to go face-to-face with Bill Clinton and look him in the eye and tell him he behaved in a discreditable fashion. His wife? His buddy Vernon Jordan? Whoever it is, someone had better stop him. He campaigned against a fellow Democrat no differently than if Obama had been Newt Gingrich. The Clinton campaign may conclude that, numerically and on balance, Bill helped. But, trust me, to the thousands of committed progressives who supported him when he really needed it, who went to the mat for him at his moment of (largely self-inflicted) crisis but who now happen to be supporting someone other than his wife, he&rsquo;s done himself a tremendous amount of damage.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The final price of victory is the splintering of base Democratic voters. African Americans solidified behind Obama, 79-18%. Hispanics, behind Clinton, 64-23%. Young voters went heavily for Obama. Old voters heavily for Clinton. These divisions threaten to flower into schisms. There will be plenty of time to put the pieces back together. But if Clinton becomes the nominee and black voters feel that Obama was treated unfairly &#8230; well, let&rsquo;s imagine that black voter turnout in November is down by 10% in Pennsylvania, Michigan and Ohio. That could mean the difference between victory and defeat in those three states.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tIl est vrai que, de son c\u00f4t\u00e9, Obama a pr\u00eat\u00e9 le flanc \u00e0 la critique en faisant des compliments aux mannes de <a href=\"http:\/\/commentisfree.guardian.co.uk\/richard_adams\/2008\/01\/remembering_reagan.html\" class=\"gen\">Reagan<\/a>. Certes, cette d\u00e9marche correspondait \u00e0 sa volont\u00e9 de confirmer le candidat unitaire qu&rsquo;il avait voulu para\u00eetre dans l&rsquo;Ohio. Le r\u00e9sultat dans le Nevada fait encore un peu plus justice de cette ambition.<\/p>\n<\/p>\n<p><p>\tLa primaire du Nevada a dissip\u00e9 d\u00e9finitivement pour les d\u00e9mocrates les vapeurs triomphales du d\u00e9but de la campagne, essentiellement sur l&rsquo;\u00e9ventualit\u00e9 d&rsquo;une grande candidature d&rsquo;union qui donnerait un \u00e9lan unificateur \u00e0 ce m\u00eame parti d\u00e9mocrate et, esp\u00e9rait-on, au pays. Aujourd&rsquo;hui, les pr\u00e9sidentielles sont entr\u00e9es dans une bataille longue, \u00e2pre et sans merci. L&rsquo;aspect remarquable de la situation est que le parti qui semble \u00eatre le mieux \u00e0 m\u00eame pour succ\u00e9der \u00e0 l&rsquo;\u00e8re de division et d&rsquo;affrontement qu&rsquo;est le mandat Bush est d\u00e9sormais menac\u00e9 lui-m\u00eame de graves divisions. Le vote des Noirs dans le Nevada a montr\u00e9 que les divisions raciales renaissaient au sein du parti d\u00e9mocrate \u00e0 l&rsquo;occasion d&rsquo;une candidature qui devrait consacrer l&rsquo;oubli des diff\u00e9rences raciales (79%  et m\u00eame 83% au dernier comptage  des d\u00e9mocrates noirs du Nevada ont vot\u00e9 pour Obama; cela peut difficilement \u00eatre per\u00e7u comme un simple choix politique).<\/p>\n<\/p>\n<p><p>\tLe parti d\u00e9mocrate, donn\u00e9 grand favori, semble en marche vers une bataille fratricide qui va l&rsquo;affaiblir face \u00e0 un parti r\u00e9publicain discr\u00e9dit\u00e9, qui se renforcera \u00e0 cette occasion mais d&rsquo;une fa\u00e7on relative, par simple \u00e9volution des rapports relatifs. Les deux partis principaux pr\u00e9sentent donc des faiblesse marquantes pour cette campagne. Les antagonismes vont \u00eatre exacerb\u00e9s. C&rsquo;est exactement la situation que craignaient les vieux sages de l&rsquo;<em>establishment<\/em>, qui <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4781\" class=\"gen\">envisageaient<\/a> une candidature ind\u00e9pendante (Bloomberg), qui <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4818\" class=\"gen\">crurent<\/a> \u00e0 Obama le temps d&rsquo;une primaire et qui sont ramen\u00e9s \u00e0 leurs angoisses initiales. C&rsquo;est aussi la situation d&rsquo;o\u00f9 peuvent surgir des initiatives ext\u00e9rieures int\u00e9ressantes, comme une vraie candidature ind\u00e9pendante en-dehors du syst\u00e8me.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 22 janvier 2008 \u00e0 06H45<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La victoire de Hillary Clinton dans le Nevada ne r\u00e8gle rien, nous confie-t-on. D&rsquo;ailleurs, elle est fort mince (51% contre 45% \u00e0 Obama) et elle rapporte moins de d\u00e9l\u00e9gu\u00e9s \u00e0 la premi\u00e8re qu&rsquo;au second. Michael Tomasky, dans The Guardian du 19 janvier, r\u00e9sume la chose par ce mot, qui fait son titre: \u00abWinning ugly.\u00bb En&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[6316,6120,3278,5240,6208],"class_list":["post-69619","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-affrontement","tag-campagne","tag-hillary","tag-nevada","tag-obama"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69619"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69619\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}