{"id":69634,"date":"2008-01-25T00:00:00","date_gmt":"2008-01-25T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2008\/01\/25\/les-faux-frais-au-coeur-de-la-crise\/"},"modified":"2008-01-25T00:00:00","modified_gmt":"2008-01-25T00:00:00","slug":"les-faux-frais-au-coeur-de-la-crise","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2008\/01\/25\/les-faux-frais-au-coeur-de-la-crise\/","title":{"rendered":"<strong><em>Les \u201cfaux-frais\u201d au coeur de la crise<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Les faux-frais au coeur de la crise<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t25 janvier 2008  Les Anglo-Saxons sont bien ennuy\u00e9s. Le nom de la soci\u00e9t\u00e9 (banque) fran\u00e7aise Soci\u00e9t\u00e9 G\u00e9n\u00e9rale comporte un nombre consid\u00e9rable d&rsquo;accent, dont ils ne disposent sur leur clavier courant qu&rsquo;au prix d&rsquo;une gymnastique consid\u00e9rable des doigts de la main. Ils ont donc d\u00e9cid\u00e9 d&rsquo;abr\u00e9ger (comme font les Fran\u00e7ais de l&rsquo;OTAN en parlant du SecGen au lieu du Secr\u00e9taire g\u00e9n\u00e9ral) et l&rsquo;affaire est devenue le scandale de la SocGen. Cela n&rsquo;enl\u00e8ve pas le piment de la chose.<\/p>\n<\/p>\n<p><p>\tOn conna\u00eet d\u00e9sormais les p\u00e9rip\u00e9ties abracabrantesques (merci Rimbaud et Chirac) de cette affaire qui lie d&rsquo;une fa\u00e7on \u00e9tonnamment serr\u00e9e les manigances d&rsquo;un individu au sort de la structure financi\u00e8re mondiale, et du syst\u00e8me en g\u00e9n\u00e9ral. Puisque nous savons tous ce qui se colporte dans la presse fran\u00e7aise, ou francophone, voyons rapidement ce qu&rsquo;en dit un journal anglo-saxon. <em>The Independent<\/em> donne d&rsquo;abord un commentaire g\u00e9n\u00e9ral, <a href=\"http:\/\/www.independent.co.uk\/news\/business\/news\/massive-fraud-at-socgen-jolts-credit-markets-773904.html\" class=\"gen\">aujourd&rsquo;hui<\/a> bien s\u00fbr:<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Just when it looked like things couldn&rsquo;t get any worse for the financial world, Soci\u00e9t\u00e9 G\u00e9n\u00e9rale, one of its most respected banks, stunned the market yesterday by announcing a 4.9bn (\u00a33.7bn) loss caused by a rogue trader who evaded the bank&rsquo;s controls to make huge bets on stock markets.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>France&rsquo;s second-biggest bank said the trader, J\u00e9r\u00f4me Kerviel, had secretly set up unauthorised bets on futures linked to European share indices. The Governor of the Bank of France, Christian Noyer, said SocGen was not guilty of wrongdoing and that M. Kerviel&rsquo;s ability as a computer genius had allowed him to escape the bank&rsquo;s internal controls.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>But the news sent shivers through credit markets already living in fear of further shocks from the credit crunch which has battered confidence in the world banking system. The three-month sterling Libor  the rate at which banks lend to each other  jumped as concerns about counterparty risk re-emerged. Risk management controls seem to have failed in an environment where there is already little investor confidence, said Dresdner Kleinwort credit analysts. Fourth-quarter results updates by European banks could bring more negative surprises.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tDans une autre colonne, le m\u00eame <em>Independent<\/em> donne, sous la plume de Jeremy Warner et <a href=\"http:\/\/www.independent.co.uk\/news\/business\/comment\/jeremy-warner-in-davos-socgen-fraud-deepens-crisisb-773935.html\" class=\"gen\">aujourd&rsquo;hui<\/a> encore, un \u00e9cho de la crise de la SocGen vue de Davos. L&rsquo;on y est catastroph\u00e9s et l&rsquo;on y m\u00e9dite l&rsquo;une ou l&rsquo;autre pens\u00e9e du Grand Timonier (l&rsquo;immortel Mao). <\/p>\n<\/p>\n<p><p>\t\u00ab<em>Already reeling from the crisis in credit markets, the banking system needed a major fraud like a hole in the head. News that a rogue trader has almost completely wiped out the profits for last year of Soci\u00e9t\u00e9 G\u00e9n\u00e9rale, prompting France&rsquo;s second-largest bank to seek an emergency injection of 5.5bn (\u00a34.1bn) of new equity, has further heightened the sense of a financial system out of control and no longer able to manage its own risk.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Here in Davos, bankers are beginning to wonder what else might lie in store for their beleaguered industry. One CEO cited Mao Zedong&rsquo;s perversion of the English proverb: Remember, it is always darkest just before it is totally black. In any case, few here are yet betting on an early dawn, despite the series of initiatives being launched by US policymakers to ease the crisis.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Where there&rsquo;s financial crisis there is invariably fraud, and in a way it is remarkable that it has taken a full six months of turmoil in the capital markets for one of this magnitude to come to light. The roots of all banking crises lie in financial excess, and in periods of excess there is nearly always deception and theft.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>In point of fact, there are no direct links between the Soci\u00e9t\u00e9 G\u00e9n\u00e9rale fraud and the sub-prime mortgages meltdown at the heart of the wider banking crisis. The French bank fell victim to a rogue trader dealing outside his authority in equity index futures, not mortgage-backed securities. Yet the debacle seems symbolic of the collapse in traditional banking standards which seems to have engulfed the banking system as a whole. Even accepting that the trader was hiding his positions from his superiors, and that he learned the techniques by which he managed this charade by working in back office compliance, it beggars belief that he could have financed such a wild gamble on the equity markets without anyone noticing.<\/em>\u00bb<\/p>\n<h3>L&rsquo;accident devient substance de la crise syst\u00e9mique<\/h3>\n<\/p>\n<p><p>\tUne fois de plus et fid\u00e8le \u00e0 nos ignorances syst\u00e9matiques (ou ignorances syst\u00e9miques? Cela irait bien dans l&rsquo;air du temps), nous laissons aux sp\u00e9cialistes et observateurs comp\u00e9tents les r\u00e9flexions \u00e9conomiques, financi\u00e8res et techniques concernant l&rsquo;exploit tout \u00e0 fait remarquable de J\u00e9r\u00f4me Kerviel, l&rsquo;homme qui s&rsquo;est pay\u00e9 la SocGen \u00e0 l&rsquo;insu de son plein gr\u00e9.<\/p>\n<\/p>\n<p><p>\tLe fait remarquable de l&rsquo;accident massif de la SocGen est que le monde de la finance l&rsquo;a aussit\u00f4t interpr\u00e9t\u00e9 comme un sympt\u00f4me du mal qui mine le syst\u00e8me, et non pas, justement comme un accident. (Warner : \u00ab<em> Yet the debacle seems symbolic of the collapse in traditional banking standards which seems to have engulfed the banking system as a whole.<\/em>\u00bb) Question d&rsquo;ambiance, dira-t-on. Peut-\u00eatre, et peut-\u00eatre pas, et c&rsquo;est la deuxi\u00e8me option que nous privil\u00e9gions.<\/p>\n<\/p>\n<p><p>\tD&rsquo;une fa\u00e7on assez remarquable, l&rsquo;accident-Kerviel a \u00e9galement \u00e9t\u00e9 aussit\u00f4t identifi\u00e9 \u00e0 un travers du syst\u00e8me, \u00e0 sa vuln\u00e9rabilit\u00e9 technique,  l&rsquo;\u00e9normit\u00e9 de l&rsquo;accident faisant le reste. On y ajoute la vigilance fort affaiblie des banquiers qui vivent, depuis plusieurs ann\u00e9es, dans une atmosph\u00e8re paradisiaque o\u00f9 plus rien ne semble imposer des barri\u00e8res aux ambitions et aux manuvres, o\u00f9 plus rien de la r\u00e9alit\u00e9 ne semble sollicit\u00e9 pour pond\u00e9rer les agissements dans leur monde.<\/p>\n<\/p>\n<p><p>\t(Les banquiers semblent avoir fait leur l&rsquo;hypoth\u00e8se qu&rsquo;Alan Greenspan \u00e9voquait, le 10 juin 1998 devant le <em>Joint Economic Committee<\/em> du Congr\u00e8s, sans l&rsquo;accepter tout \u00e0 fait mais en la mentionnant comme tout \u00e0 fait concevable [soulign\u00e9 en gras par nous \u00e0 l&rsquo;intention des banquiers]: \u00ab<em>La situation ne correspond pas \u00e0 ce que l&rsquo;\u00e9volution historique nous conduisait \u00e0 attendre \u00e0 ce point de l&rsquo;expansion \u00e9conomique, et quoiqu&rsquo;<\/em> <strong><em>il soit possible en un sens que notre \u00e9conomie ait d\u00e9pass\u00e9 l&rsquo;histoire<\/em><\/strong>, <em>nous devons \u00e9galement rester vigilant \u00e0 propos du fait que des relations historiques moins favorables puissent s&rsquo;imposer\u00e0 nous.<\/em>\u00bb) <\/p>\n<\/p>\n<p><p>\tNous proposons, au-del\u00e0 de ces constats, de lier cette affaire \u00e0 d&rsquo;autres faits qui nous semblent significatifs, qui sont consid\u00e9r\u00e9s ici comme exemplaires d&rsquo;attitudes et de pratiques g\u00e9n\u00e9rales.<\/p>\n<\/p>\n<p><p>\t D&rsquo;une part, la questions des bonus et autres <em>golden parachutes<\/em> qui r\u00e9compensent en g\u00e9n\u00e9ral les dirigeants de banques et autres \u00e9tablissements financiers ayant conduit leurs soci\u00e9t\u00e9s \u00e0 une situation catastrophique pour leurs employ\u00e9s (licenciements) ou pour elles-m\u00eames (pertes abyssales). Voir le commentaire grin\u00e7ant de <em>WSWS.org<\/em> sur le sujet, le <a href=\"http:\/\/www.wsws.org\/articles\/2008\/jan2008\/bonu-j21.shtml\" class=\"gen\">21 janvier<\/a>: \u00ab<em>The five largest Wall Street banks doled out a record $39 billion in bonuses last year, according to data collected by the Bloomberg news service. After driving hundreds of thousands of families into foreclosure, causing a financial crisis affecting hundreds of millions, and pushing the US and world economies closer to recession, it appears Wall Street is rewarding itself for a job well done.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t D&rsquo;autre part, la situation du Pentagone telle qu&rsquo;elle appara\u00eet de plus en plus clairement, et notamment l&rsquo;importance consid\u00e9rable des sommes perdues dans des accidents tels que gaspillage, fraude, corruprtion, etc. (Voir notre <em>F&#038;C<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4830\" class=\"gen\">14 janvier<\/a> .)<\/p>\n<\/p>\n<p><p>\tCe qui est remarquable dans le commentaire de Jeremy Warner, c&rsquo;est la fa\u00e7on dont, \u00e0 Davos et dans le texte qu&rsquo;il signe lui-m\u00eame, on place aussit\u00f4t l&rsquo;accident-Kerviel non dans la rubrique accidents mais dans le domaine d\u00e9j\u00e0 encombr\u00e9 des sympt\u00f4mes,  l&rsquo;accident-Kerviel qui, selon les mots de Warner,  \u00ab<em> has further heightened the sense of a financial system out of control and no longer able to manage its own risk<\/em>\u00bb.<\/p>\n<\/p>\n<p><p>\tTous ces constats et divers accidents que nous avons rappel\u00e9s,  et il y en a tellement d&rsquo;autres,  se placent, dans la vision habituelle des choses, dans la rubrique des faux-frais. Il s&rsquo;agit, disons, dans les conceptions classiques des activit\u00e9s \u00e9conomiques et autres, des impond\u00e9rables habituels, des accidents in\u00e9vitables, des probl\u00e8mes conjoncturels n\u00e9s de pratiques douteuses mais qui restaient toujours marginales. Pour ces questions, l&rsquo;habitude \u00e9tait par exemple d&rsquo;avoir des caisses noiresqui permettaient de r\u00e9gler les choses discr\u00e8tement et en douceur; ou bien de pr\u00e9voir le d\u00e9part discret de tel ou tel dirigeant fautif, avec une somme raisonnable \u00e0 la clef, pour \u00e9viter le scandale. Aujourd&rsquo;hui, cela est impossible. Les sommes sont si consid\u00e9rables qu&rsquo;elles interviennent directement dans le sort du syst\u00e8me pour le d\u00e9s\u00e9quilibrer, qu&rsquo;elles semblent prendre le centre de la sc\u00e8ne pour devenir l&rsquo;expression m\u00eame de la crise du syst\u00e8me. La disparition compl\u00e8te de tout ce qui ressemble \u00e0 la conscience professionnelle et la solidarit\u00e9, cons\u00e9quence de l&rsquo;individualisme exacerb\u00e9 impos\u00e9 par le syst\u00e8me, fait le reste.<\/p>\n<\/p>\n<p><p>\tL&rsquo;accident que sont les faux-frais devient l&rsquo;expression de la substance de la crise. En m\u00eame temps apparaissent les ahurissantes conditions pr\u00e9valant dans ces milieux, les capacit\u00e9s de manipulation de l&rsquo;un ou l&rsquo;autre, la disparition de sommes colossales dans une situation \u00e9trange de non-comptabilit\u00e9, un peu comme il existe un <em>no man&rsquo;s land<\/em> \u00e0 la guerre. (C&rsquo;est Rumsfeld qui estimait en 2005, lors de commentaires que la Quadriennal Defense Review, qu&rsquo;il fallait estimer les sommes non comptabilis\u00e9es du d\u00e9partement de la d\u00e9fense des 10 derni\u00e8res ann\u00e9es autour du $trillion. Encore ne pr\u00e9cisait-il pas que l&rsquo;aspect le plus inqui\u00e9tant de cette \u00e9valuation est l&rsquo;acc\u00e9l\u00e9ration exponentielle de ces sommes non-comptabilis\u00e9es, la plus grosse partie du $trillion se regroupant dans les ann\u00e9es depuis 9\/11.)<\/p>\n<\/p>\n<p><p>\tCe que nous montrent ces divers accidents que nous observons, c&rsquo;est que l&rsquo;accident prend de plus en plus la place de la substance, faisant d&rsquo;ailleurs d\u00e9couvrir \u00e0 mesure qu&rsquo;apr\u00e8s tout la substance n&rsquo;existe plus gu\u00e8re. Ce processus ne nous para\u00eet m\u00eame pas accidentel par rapport au syst\u00e8me, \u00e0 cause de ce fait qu&rsquo;un seul domaine (la finance) serait touch\u00e9, mais bien d\u00e9sormais substantiel (!) \u00e0 notre civilisation quand on constate que tous les domaines suivent les m\u00eames pratiques. Il s&rsquo;agit d&rsquo;une mont\u00e9e aux extr\u00eames  des marges du syst\u00e8me, de ce qui \u00e9tait alors jug\u00e9 comme accessoire.<\/p>\n<\/p>\n<p><p>\tNous \u00e9crivons \u00e0 ce propos dans le prochain num\u00e9ro (10 f\u00e9vrier) de notre Lettre d&rsquo;Analyse <em>de defensa &#038; eurostrat\u00e9gie<\/em>, dans la rubrique <em>de defensa<\/em>: \u00ab<em>Effectivement, cette mont\u00e9e aux extr\u00eame est une mont\u00e9e aux marges (ou une descente aux marges?!) en ce sens que l&rsquo;essentiel du motif de l&rsquo;action, effectivement d\u00e9crit ou constat\u00e9 comme essentiel, se trouve dans des domaines accessoires, accidentels, et surtout parasitaire des choses anciennement essentielles: le gaspillage, la corruption, la fraude; mais aussi l&rsquo;Irak d\u00e9crit (en 2002-2003) comme l&rsquo;\u00e9quivalent de la puissance mal\u00e9fique de l&rsquo;Allemagne nazie et de l&rsquo;URSS r\u00e9unie; le terrorisme institu\u00e9 comme une v\u00e9ritable menace m\u00e9taphysique; des pr\u00e9sentateurs-TV ou des sportifs dop\u00e9s pr\u00e9sent\u00e9s comme les h\u00e9ros intellectuels et tragiques de notre temps. Etcetera&#8230;<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tSans aucun doute, nous sommes entr\u00e9s dans la phase aigu\u00eb de la crise syst\u00e9mique de la civilisation. Il y a non seulement le fait de la crise, mais il y a en plus le fait de la forme de cette crise, qui est sans exemple et sans pr\u00e9c\u00e9dent. L&rsquo;\u00e9volution compl\u00e8te dans le virtualisme, autant des sommes manipul\u00e9es que des actions entreprises, surprend m\u00eame ceux qui sont au centre de la crise, les acteurs comme les manipulateurs. Le caract\u00e8re le plus remarquable de la crise est la quasi-impossibilit\u00e9 de l&rsquo;identifier m\u00eame lorsqu&rsquo;elle a \u00e9clat\u00e9, donc la quasi-impossibilit\u00e9 d&rsquo;y apporter un rem\u00e8de efficace. Une seule chose subsiste \u00e0 travers les temps historiques, c&rsquo;est la psychologie. La crise infecte effectivement les psychologies. La r\u00e9action de Davos \u00e0 l&rsquo;accident-Kerviel comme la d\u00e9crit Warner indique que m\u00eame les psychologies des ma\u00eetres du monde de la finance ont incub\u00e9 le fait que nous sommes entr\u00e9s dans la grande crise syst\u00e9mique et sombrent dans la neurasth\u00e9nie de crise.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est original Nous n&rsquo;avons pas besoin des 15 millions de ch\u00f4meurs aux USA (un tiers des salari\u00e9s de l&rsquo;\u00e9poque) ni de la chute de la production industrielle de 12% en 5 mois (novembre 1932-mars 1933) pour comprendre que nous sommes dans une crise qui vaut bien celle de 1929-33, et qui la d\u00e9passera ais\u00e9ment.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les faux-frais au coeur de la crise 25 janvier 2008 Les Anglo-Saxons sont bien ennuy\u00e9s. Le nom de la soci\u00e9t\u00e9 (banque) fran\u00e7aise Soci\u00e9t\u00e9 G\u00e9n\u00e9rale comporte un nombre consid\u00e9rable d&rsquo;accent, dont ils ne disposent sur leur clavier courant qu&rsquo;au prix d&rsquo;une gymnastique consid\u00e9rable des doigts de la main. Ils ont donc d\u00e9cid\u00e9 d&rsquo;abr\u00e9ger (comme font les&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3228,7391,7394,7395,7392,7393,6277],"class_list":["post-69634","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-crise","tag-faux-frais","tag-generale","tag-kerviel","tag-socgen","tag-societe","tag-systemique"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69634"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69634\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}