{"id":69684,"date":"2008-02-16T00:00:00","date_gmt":"2008-02-16T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2008\/02\/16\/en-attendant-saint-malo-ii\/"},"modified":"2008-02-16T00:00:00","modified_gmt":"2008-02-16T00:00:00","slug":"en-attendant-saint-malo-ii","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2008\/02\/16\/en-attendant-saint-malo-ii\/","title":{"rendered":"En attendant Saint-Malo-II"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955;font-size:2em;\">En attendant Saint-Malo-II<\/h2>\n<\/p>\n<p><p>16 f\u00e9vrier 2008 &mdash; Deux hebdomadaires de langue anglaise de la capitale belge et europ\u00e9enne ont repris et d\u00e9velopp\u00e9 l&rsquo;id\u00e9e d&rsquo;une force europ\u00e9enne d&rsquo;intervention structur\u00e9e, d\u00e9velopp\u00e9e sur initiative fran\u00e7aise dans un cadre de contraintes d&rsquo;engagement de d\u00e9fense, avec des objectifs larges d\u00e9passant la seule constitution de cette force. Il s&rsquo;agit de <em>The European Voice<\/em> du <a class=\"gen\" href=\"http:\/\/www.europeanvoice.com\/current\/article.asp?id=29809\">14 f\u00e9vrier<\/a> et de <em>EUObserver<\/em> du <a class=\"gen\" href=\"http:\/\/euobserver.com\/9\/25667\/?rk=1\">15 f\u00e9vrier<\/a>, tous deux \u00e0 Bruxelles. <em>EUOberver<\/em> reprend la substance de l&rsquo;article de son confr\u00e8re. Tous deux se r\u00e9f\u00e8rent \u00e0 un article de Pierre Lellouche, \u00e9crivant \u00e8s-qualit\u00e9 en tant que \u00ab\u00a0d\u00e9l\u00e9gu\u00e9 g\u00e9n\u00e9ral de l&rsquo;UMP pour la d\u00e9fense\u00a0\u00bb, dans <em>Le Figaro<\/em> du <a class=\"gen\" href=\"http:\/\/www.lefigaro.fr\/debats\/2008\/01\/31\/01005-20080131ARTFIG00515--propositions-pour-donner-a-l-union-une-defense-commune.php\">31 janvier<\/a>.<\/p>\n<\/p>\n<p><p>Il est assur\u00e9, \u00e0 cette date et pour ce qui concerne l&rsquo;\u00e9volution politique, que l&rsquo;intervention la plus int\u00e9ressante est celle de <em>The European Voice<\/em>, qui fait partie du <a class=\"gen\" href=\"http:\/\/www.economistgroup.com\/\">groupe<\/a> <em>The Economist<\/em>. Le d\u00e9lai (apr\u00e8s le texte de Lellouche qui est cit\u00e9 comme r\u00e9f\u00e9rence) montre que cette intervention de <em>The European Voice<\/em> est mesur\u00e9e, qu&rsquo;elle a \u00e9t\u00e9 pes\u00e9e \u00e0 la lumi\u00e8re du texte du d\u00e9put\u00e9 fran\u00e7ais per\u00e7u comme une \u00e9vocation informelle des projets fran\u00e7ais pour la pr\u00e9sidence de l&rsquo;UE (juillet-d\u00e9cembre), qu&rsquo;elle r\u00e9pond \u00e0 une r\u00e9alit\u00e9 proche du gouvernement britannique et de la politique britannique (\u00e0 cet \u00e9gard, le groupe <em>The Economist<\/em> est au-dessus de tout soup\u00e7on tant il s&rsquo;impose souvent comme le relais de la pens\u00e9e officielle). L&rsquo;article du 14 f\u00e9vrier apporte des pr\u00e9cisions du c\u00f4t\u00e9 britannique concernant le projet, qui sont r\u00e9v\u00e9latrices autant d&rsquo;une tactique d\u00e9lib\u00e9r\u00e9e des Britanniques que d&rsquo;une appr\u00e9ciation plut\u00f4t favorable de ces m\u00eames Britanniques du projet \u00e9voqu\u00e9. L&rsquo;article est plac\u00e9 en \u00e9vidence (il fait la manchette de la premi\u00e8re page). Il s&rsquo;agit donc d&rsquo;une s\u00e9rie de ballons d&rsquo;essai se r\u00e9pondant, pour explorer la voie d&rsquo;un projet europ\u00e9en \u00e0 lancer durant la pr\u00e9sidence fran\u00e7aise. On pourrait ajouter qu&rsquo;il semble que la pr\u00e9paration soit d\u00e9j\u00e0 politiquement lanc\u00e9e.<\/p>\n<\/p>\n<p><p>Le projet a la particularit\u00e9 essentielle de se faire autour de l&rsquo;id\u00e9e d&rsquo;un \u00ab\u00a0noyau dur\u00a0\u00bb regroupant six pays (Allemagne, Espagne, France, Italie, Pologne, UK) et laiss\u00e9 ouvert aux autres s&rsquo;ils remplissent les crit\u00e8res \u00e9tablis. Lellouche, dans son article du 31 janvier, \u00e9non\u00e7ait huit conditions de base pour un tel projet qu&rsquo;il s&#8217;empresse de baptiser, pour \u00eatre dans l&rsquo;air du temps, du surnom de \u00ab\u00a0G6\u00a0\u00bb. Outre l&rsquo;id\u00e9e du \u00ab\u00a0noyau dur\u00a0\u00bb, on note principalement le niveau requis de d\u00e9penses de d\u00e9fense \u00e0 2% du PIB; l&rsquo;objectif d&rsquo;une force de 60.000 hommes (10.000 hommes par pays du G6); la constitution d&rsquo;un \u00ab\u00a0march\u00e9 commun de l&rsquo;armement\u00a0\u00bb pour le G6 avec cette pr\u00e9cision o&ugrave; un adverbe essentiel est soulign\u00e9 en gras par nous: des commandes d&rsquo;armements donnant lieu \u00e0 &laquo;<em>des march\u00e9s publics europ\u00e9ens ouverts<\/em> <strong><em>prioritairement<\/em><\/strong> <em>aux industries europ\u00e9ennes d&rsquo;armement<\/em>&raquo;; le lancement de \u00ab\u00a0programmes communs structurants\u00a0\u00bb dans des domaines de l&rsquo;espace, des communications et du renseignement, de la d\u00e9fense anti-missile; etc&hellip; Le projet serait mis en place une fois le trait\u00e9 de Lisbonne ratifi\u00e9, dans le cadre de ce trait\u00e9, en 2009.<\/p>\n<\/p>\n<p><p>Lellouche aborde le principal obstacle de cette affaire (la question des relations avec les USA) de cette mani\u00e8re :<\/p>\n<\/p>\n<p><p>&laquo;<em>En r\u00e9conciliant la France avec l&rsquo;Am\u00e9rique d\u00e8s son \u00e9lection et en signalant que d\u00e9fense europ\u00e9enne et Otan sont d\u00e9sormais compatibles du point de vue de la France, le pr\u00e9sident Sarkozy a d&rsquo;ores et d\u00e9j\u00e0 lev\u00e9 le pr\u00e9alable majeur \u00e0 l&rsquo;\u00e9mergence d&rsquo;une d\u00e9fense commune entre Europ\u00e9ens. Tant que, en effet, ces derniers soup\u00e7onnaient la France (et pas toujours \u00e0 tort) de vouloir d\u00e9faire l&rsquo;Otan et bouter dehors le grand alli\u00e9 am\u00e9ricain en proposant une d\u00e9fense europ\u00e9enne alternative \u00e0 l&rsquo;Alliance, l&rsquo;id\u00e9e m\u00eame d&rsquo;une d\u00e9fense europ\u00e9enne commune \u00e9tait de facto condamn\u00e9e. Ce pr\u00e9alable est d\u00e9sormais lev\u00e9, et les Britanniques eux-m\u00eames en Irak comme les Polonais avec l&rsquo;affaire de la d\u00e9fense antimissile, ont compris \u00e0 leurs d\u00e9pens le caract\u00e8re parfois erratique (!) de certaines initiatives strat\u00e9giques am\u00e9ricaines.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Apr\u00e8s avoir \u00e9nonc\u00e9 ces huit propositions-G6, ou \u00ab\u00a0axes propos\u00e9s\u00a0\u00bb, il conclut : &laquo;<em>Une fois adopt\u00e9s, <\/em>[les axes propos\u00e9s] <em>serviront de socle \u00e0 une relation d&rsquo;alliance r\u00e9\u00e9quilibr\u00e9e avec les &Eacute;tats-Unis d&rsquo;Am\u00e9rique, d\u00e8s la seconde moiti\u00e9 de 2009, une fois install\u00e9e la prochaine Administration am\u00e9ricaine.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Maintenant, voyons les passages int\u00e9ressants pour nous de l&rsquo;article de <em>The European Voice<\/em>, qui concernent les r\u00e9actions britanniques (et allemande, accessoirement) \u00e0 l&rsquo;\u00e9vocation d&rsquo;un tel projet.<\/p>\n<\/p>\n<p><p>&laquo;<em>The UK will not support the plan publicly until the new treaty comes into force, but an EU official confirmed that the UK had pushed for the provision when the constitution was being drafted. The possibility of forming a pioneer defence group had been included in the constitution because \u00ab\u00a0the UK and France wanted it in\u00a0\u00bb, an EU official said, adding that the UK saw the initiative as \u00ab\u00a0a way of leveraging extra<\/em> [military]<em> capabilities\u00a0\u00bb from some member states.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Under the Lisbon treaty, membership of the group should be open to any country that meets the qualifying criteria.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>German centre-right MEP Karl von Wogau, chairman of the European Parliament&rsquo;s sub-committee on security and defence, said: \u00ab\u00a0It would be better if there&rsquo;s an openness to small- and medium-sized countries.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Sarkozy wants to boost European defence during his country&rsquo;s presidency of the EU in the second half of this year and create what he describes as a \u00ab\u00a0European pillar\u00a0\u00bb within NATO. He is planning to use an offer to reintegrate France fully into NATO command in 2009 to leverage support from European allies for new initiatives on European defence. A key French aim is to set up a fully fledged EU planning cell.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>The UK and France are also keen to mark the tenth anniversary of the St Malo declaration between the then French president Jacques Chirac and the UK prime minister Tony Blair, which launched a new era of defence co-operation, although the EU has since fallen short of some of its ambitions, including creating a 60,000-strong rapid reaction force. Sarkozy and UK Prime Minister Gordon Brown are to discuss defence co-operation at the Anglo-French summit in London on 27-28 March.<\/em>&raquo;<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">La fonction historique du projet<\/h2>\n<\/p>\n<p><p>Ce projet tel qu&rsquo;il se reconstitue au travers des diverses r\u00e9f\u00e9rences n&rsquo;a rien pour surprendre. Il est principalement l&rsquo;enjeu des deux acteurs principaux, France et UK. La r\u00e9f\u00e9rence comm\u00e9morative au trait\u00e9 de Saint-Malo de d\u00e9cembre 1998 est logique, sinon imp\u00e9rative. Il s&rsquo;agit bien d&rsquo;une ambition de type <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4366\">\u00ab\u00a0Saint-Malo-II\u00a0\u00bb<\/a>.<\/p>\n<\/p>\n<p><p>Les deux partenaires \u00ab\u00a0forc\u00e9s-r\u00e9ticents\u00a0\u00bb (les deux parce qu&rsquo;ils sont indispensables \u00e0 tout projets de d\u00e9fense europ\u00e9enne ambitieux, les Anglais qui soup\u00e7onnent les Fran\u00e7ais d&rsquo;anti-atlantisme, les Fran\u00e7ais qui soup\u00e7onnent les Anglais de pro-am\u00e9ricanisme) sont dans des positions qui correspondent \u00e0 leurs r\u00f4les classiques. C&rsquo;est Saint-Malo-I \u00e0 fronts renvers\u00e9s.<\/p>\n<\/p>\n<p><p>&bull; Les Fran\u00e7ais ont la charge de lancer le projet. Ils s&rsquo;appuient sur une rh\u00e9torique vertueuse consistant \u00e0 dire: nous avons r\u00e9gl\u00e9 notre probl\u00e8me avec les USA, donc le soup\u00e7on principal contre nous n&rsquo;a plus de raison d&rsquo;\u00eatre. D&rsquo;ailleurs, nombre d&rsquo;entre eux (les Fran\u00e7ais) croient \u00e0 cette vertu-l\u00e0. Cela n&#8217;emp\u00eache quelque cynisme de se glisser ici ou l\u00e0, conscient ou non. C&rsquo;est le cas lorsque Lellouche (dans le passage cit\u00e9 ci-dessus), apr\u00e8s avoir fait l&rsquo;apologie convenue du rapprochement franco-US, termine ce passage par cette phrase : &laquo;<em> Ce pr\u00e9alable <\/em>[le processus de d\u00e9fense europ\u00e9enne non per\u00e7u comme une agression par les malheureux USA] <em>est d\u00e9sormais lev\u00e9, et les Britanniques eux-m\u00eames en Irak comme les Polonais avec l&rsquo;affaire de la d\u00e9fense antimissile, ont compris \u00e0 leurs d\u00e9pens le caract\u00e8re parfois erratique (!) de certaines initiatives strat\u00e9giques am\u00e9ricaines.<\/em>&raquo; Lellouche utilise l&rsquo;argument du raccommodage franco-US pour faire remarquer \u00e0 quelques alli\u00e9s les catastrophes strat\u00e9giques o&ugrave; les entra&icirc;ne leur alignement inconditionnel sur les USA. Cette vertu est d&rsquo;autre part utilis\u00e9e pour sugg\u00e9rer quelques am\u00e9nagements qui vont faire fr\u00e9mir plus d&rsquo;un atlantiste. (On pense \u00e0 l&rsquo;adverbe \u00ab\u00a0prioritairement\u00a0\u00bb pour d\u00e9finir l&rsquo;acc\u00e8s des industriels europ\u00e9ens au march\u00e9 commun de l&rsquo;armement, ce qui sugg\u00e8re \u00e9videmment le concept h\u00e9r\u00e9tique de \u00ab\u00a0pr\u00e9f\u00e9rence europ\u00e9enne\u00a0\u00bb.)<\/p>\n<\/p>\n<p><p>&bull; Les Britanniques, selon les bruits que nous rapporte <em>The European Voice<\/em>, joueront cette partie&hellip; \u00ab\u00a0\u00e0 la britannique\u00a0\u00bb. C&rsquo;est le contraire de Saint-Malo-I o&ugrave; ils s&rsquo;\u00e9taient fortement expos\u00e9s aux pressions US puisqu&rsquo;ils \u00e9taient \u00e0 la base des propositions. Ils suivent le projet, ils font savoir leur accord officieusement pour le moment, pour pouvoir dire non officiellement si le temps des g\u00e2te. Bon r\u00e9flexe de navigateur, qui a quelque chose de rassurant, &ndash; il s&rsquo;agit bien des Britanniques \u00e9gaux \u00e0 eux-m\u00eames, avec tous leurs traits de caract\u00e8re. Par ailleurs, l&rsquo;argument principal expos\u00e9 dans l&rsquo;article de <em>The European Voice<\/em> (obtenir des capacit\u00e9s militaires suppl\u00e9mentaires gr\u00e2ce \u00e0 l&rsquo;arrangement europ\u00e9en) est convaincant. Les Britanniques sont dans une situation budg\u00e9taire path\u00e9tique. Leur programmation se d\u00e9place dans un champ de mines, au milieu de projets explosifs dont ils n&rsquo;ont pas toujours la ma&icirc;trise (le programme JSF est l&rsquo;exemple central du propos). La lune de miel hyst\u00e9rique des \u00ab\u00a0<em>sp\u00e9cial relationships<\/em>\u00a0\u00bb Blair-Bush n&rsquo;est plus qu&rsquo;un souvenir dont on se demande s&rsquo;il est bien heureux. Aujourd&rsquo;hui, en mati\u00e8re de d\u00e9fense, avec un Gordon Brown qui ne go&ucirc;te que moyennement les exp\u00e9ditions n\u00e9o-colonialistes \u00e0-la-Blair, les Britanniques ont besoin de toutes les garanties, de toutes les aides possibles. De ce point de vue, un projet europ\u00e9en s\u00e9rieux et n\u00e9cessairement par\u00e9 de la vertu europ\u00e9enne, qui \u00e9carte tout aspect anti-US trop voyant, qui institutionnalise notamment la coop\u00e9ration avec la France, vaut d&rsquo;\u00eatre consid\u00e9r\u00e9.<\/p>\n<\/p>\n<p><p>Le projet G6, comme dit Lellouche, est une approche raisonnable de la question de d\u00e9fense europ\u00e9enne, &ndash; si l&rsquo;on s&rsquo;en tient \u00e0 l&rsquo;analyse strictement born\u00e9e du probl\u00e8me. Si on l&rsquo;\u00e9largit au contexte politique et psychologique, au climat de l&rsquo;\u00e9poque et ainsi de suite, nous dirions simplement que c&rsquo;est une approche explosive, &ndash; et involontairement, ce qu&rsquo;il y a de mieux.<\/p>\n<\/p>\n<p><p>D&rsquo;abord, le projet m\u00e9nage quelques rencontres du plus heureux effet. Inviter la Pologne \u00e0 y participer, au moment o&ugrave; ce pays \u00e9trenne un nouveau gouvernement qui veut faire ses preuves de \u00ab\u00a0bon europ\u00e9en\u00a0\u00bb, c&rsquo;est une bonne id\u00e9e. Assortir cette invitation du projet d&rsquo;\u00e9tudier un r\u00e9seau antimissiles europ\u00e9en au moment o&ugrave; cette m\u00eame Pologne est confront\u00e9e \u00e0 des propositions US pressantes pour participer au r\u00e9seau BMDE d&rsquo;anti-missiles US, c&rsquo;est une riche id\u00e9e qui accroit la charge explosive potentielle du projet.<\/p>\n<\/p>\n<p><p>Mais le principal est ailleurs. Assortir des protestations d&rsquo;amiti\u00e9s pro-US en explorant de l&rsquo;autre c\u00f4t\u00e9 un march\u00e9 commun de l&rsquo;armement o&ugrave; l&rsquo;on voudrait glisser une notion de \u00ab\u00a0pr\u00e9f\u00e9rence europ\u00e9enne\u00a0\u00bb, c&rsquo;est allumer la m\u00e8che pour la poudre pr\u00eate \u00e0 exploser. A partir de l\u00e0, il faut \u00e9largir le propos. L&rsquo;argument (fran\u00e7ais) qui est de dire: nous sommes \u00e0 nouveau amis des US, donc nous allons faire une d\u00e9fense europ\u00e9enne forte \u00e0 laquelle nos amis Am\u00e9ricains n&rsquo;auront plus rien \u00e0 redire, c&rsquo;est se bercer d&rsquo;illusions consid\u00e9rables. Qu&rsquo;importe, &ndash; car c&rsquo;est surtout placer les Europ\u00e9ens, et surtout les pro-US, les vrais, les vassaux de l&rsquo;Am\u00e9rique, face \u00e0 cette \u00e9vidence et par cons\u00e9quent \u00e0 leurs responsabilit\u00e9s: les USA n&rsquo;accepteront jamais de bon gr\u00e9 une d\u00e9fense europ\u00e9enne forte. (Quelle que soit la future administration, &ndash; pour <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4907\">McCain<\/a>, la cause est entendue; pour une administration d\u00e9mocrate, le pr\u00e9c\u00e9dent de Saint-Malo-I, qui se fit du temps de l&rsquo;administration Clinton, est une indication n\u00e9cessaire et suffisante.)<\/p>\n<\/p>\n<p><p>Dans le cas \u00e9tudi\u00e9 ici, il n&rsquo;y a plus l&rsquo;argument sempiternel de la France anti-US qui permettait de se d\u00e9fausser du fond du probl\u00e8me. Cette fois, chacun devra jouer franc-jeu; les Am\u00e9ricains, qui diront leur opposition par principe, parce qu&rsquo;ils veulent conserver une Europe asservie, France anti-US ou pas; les Europ\u00e9ens pro-US, qui devront dire, cette fois, qu&rsquo;ils capitulent devant les USA par pur go&ucirc;t de la servilit\u00e9, ou bien qui devront se r\u00e9volter.<\/p>\n<\/p>\n<p><p>Nous dirons le fond de notre sentiment. Nous ne croyons pas une seconde que ce projet r\u00e9ussira en l&rsquo;\u00e9tat et sans remous consid\u00e9rables qui \u00e9largiront et transformeront n\u00e9cessairement l&rsquo;enjeu. Nous croyons que ce n&rsquo;est pas sa fonction fondamentale, historique, m\u00eame si ceux qui le con\u00e7oivent veulent sinc\u00e8rement parvenir \u00e0 sa r\u00e9alisation dans les conditions qu&rsquo;ils disent, qu&rsquo;ils jugent loyales. (On retrouve ici notre argument sempiternel: les dirigeants politiques ne contr\u00f4lent plus rien, s&rsquo;ils y comprennent encore quelque chose. Passons outre. Ce qu&rsquo;on attend d&rsquo;eux est qu&rsquo;ils allument par inadvertance des m\u00e8ches pour faire exploser les situations contraintes qui nous encha&icirc;nent.)<\/p>\n<\/p>\n<p><p>La fonction historique de ce projet, comme la fonction historique de tout projet s\u00e9rieux de d\u00e9fense europ\u00e9enne, est de faire exploser le cadre europ\u00e9en actuel de dissimulation et de camouflage derri\u00e8re les bouc \u00e9missaires de service (les Fran\u00e7ais anti-US), pour faire appara&icirc;tre la situation europ\u00e9enne dans toute sa duplicit\u00e9 et sa servilit\u00e9. On verra alors les gouvernements europ\u00e9ens \u00e0 la fois satellites des USA par asservissement et soutiens inconditionnels de l&rsquo;id\u00e9e europ\u00e9enne par id\u00e9ologie, plac\u00e9s devant la douloureuse obligation de devoir envisager de faire un choix. La chose secouera de fa\u00e7on salutaire la situation europ\u00e9enne, au moins autant qu&rsquo;un r\u00e9f\u00e9rendum fran\u00e7ais n\u00e9gatif sur la Constitution europ\u00e9enne. Si le trait\u00e9 de Lisbonne, qui rattrape par une entourloupette la Constitution torpill\u00e9e, sert \u00e0 cela, l&rsquo;Histoire lui en sera gr\u00e9.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En attendant Saint-Malo-II 16 f\u00e9vrier 2008 &mdash; Deux hebdomadaires de langue anglaise de la capitale belge et europ\u00e9enne ont repris et d\u00e9velopp\u00e9 l&rsquo;id\u00e9e d&rsquo;une force europ\u00e9enne d&rsquo;intervention structur\u00e9e, d\u00e9velopp\u00e9e sur initiative fran\u00e7aise dans un cadre de contraintes d&rsquo;engagement de d\u00e9fense, avec des objectifs larges d\u00e9passant la seule constitution de cette force. Il s&rsquo;agit de The&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3019,398,5756,3830],"class_list":["post-69684","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-defense","tag-europe","tag-lellouche","tag-saint-malo"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69684"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69684\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}