{"id":69696,"date":"2008-02-20T00:00:00","date_gmt":"2008-02-20T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2008\/02\/20\/la-geriatric-air-force-commence-a-la-trouver-mauvaise\/"},"modified":"2008-02-20T00:00:00","modified_gmt":"2008-02-20T00:00:00","slug":"la-geriatric-air-force-commence-a-la-trouver-mauvaise","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2008\/02\/20\/la-geriatric-air-force-commence-a-la-trouver-mauvaise\/","title":{"rendered":"La \u201c<em>Geriatric Air Force<\/em>\u201d commence \u00e0 la trouver mauvaise"},"content":{"rendered":"<p><p>La crise de l&rsquo;USAF est en train de s&rsquo;installer au cur du paysage washingtonien, comme un grave probl\u00e8me de s\u00e9curit\u00e9 nationale. L&rsquo;article que signale un de nos lecteurs sur notre <em>Forum<\/em> <a href=\"http:\/\/www.dedefensa.org\/forum.php\" class=\"gen\">aujourd&rsquo;hui<\/a>, qu&rsquo;on peut \u00e9galement directement trouver sur <a href=\"http:\/\/ap.google.com\/article\/ALeqM5gRg2AXq8pM4IIlXXwKt0WK7FJ0_gD8UT4PQG0\" class=\"gen\">AP<\/a>, est un signe de l&rsquo;offensive de relations publiques entreprise par l&rsquo;USAF.<\/p>\n<\/p>\n<p><p>\tL&rsquo;organe de pression presque-officiel de l&rsquo;USAF, l&rsquo;Air Force Association, signale la chose dans son <em>Daily Report<\/em> du <a href=\"http:\/\/dc01-cdh-afa03.tranguard.net\/AFA\/Reports\/2008\/Month02\/Day20\/\" class=\"gen\">jour<\/a>:<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The Air Force is beginning to be more vocal in articulating its need for a big shot in the arm to modernize its already geriatric aircraft fleet. More and more senior service officials are coming out on the record and citing the need for an extra $20 billion on average annually for the next 20 years, saying that, without such infusions, the air dominance that the US has enjoyed for decades will erode if not disappear altogether.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLe <em>Daily Report<\/em>, qui mentionne l&rsquo;article de AP d\u00e9j\u00e0 signal\u00e9, annonce en termes pr\u00e9cis les conditions de cette offensive de relations publiques \u00e0 Washington. L&rsquo;USAF se pr\u00e9pare d&rsquo;ores et d\u00e9j\u00e0 \u00e0 mener l&rsquo;assaut de la future administration.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The Air Force has established that, to carry out the national military strategy and protect the homeland, its needs 86 fully modern combat wings, which it refers to collectively as the Required Force. Since existing and projected budget toplines will not get it to that level of fighters, bombers, tankers, rescue helicopters, manned and unmanned intelligence platforms, and satellites, the $20 billion increase is necessary, the senior officials are saying. We expect to hear this consistent message at this week&rsquo;s AFA Air Warfare Symposium in Orlando, during the Congressional hearings on the service&rsquo;s Fiscal 2009 request, and throughout the course of the year as the Fiscal 2010 program objective memorandum takes shape and USAF, like the other services, prepares for a new Administration.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tTr\u00e8s vite, il va appara\u00eetre que le march\u00e9 est des plus simples: ou bien donner au minimum $20 milliards de plus par an \u00e0 l&rsquo;USAF, sans aucune garantie que cette somme soit suffisante pour combler tous les besoins de la force; ou r\u00e9duire les engagements et l&rsquo;utilisation de cette force, notamment et pr\u00e9cis\u00e9ment outre-mer. C&rsquo;est ici que la question de la crise de l&rsquo;USAF pourrait prendre une dimension politique, \u00e0 l&rsquo;heure d&rsquo;une crise \u00e9conomique qui ne cesse de prendre de l&rsquo;ampleur \u00e0 Washington et qui pousse \u00e0 envisager de s\u00e9rieuses \u00e9conomies budg\u00e9taires pour la prochaine administration.<\/p>\n<\/p>\n<p><p>\tL&rsquo;USAF est la premi\u00e8re des armes qui, au Pentagone, est conduite \u00e0 poser \u00e0 plus ou moins court terme son probl\u00e8me budg\u00e9taire selon une vision politique implicite (et involontaire). Selon qui sera le prochain pr\u00e9sident, la crise de l&rsquo;USAF peut \u00eatre un argument de plus pour ceux qui recommandent un certain d\u00e9sengagement des USA des affaires du monde, surtout des engagements agressifs et bellicistes. De ce point de vue, la crise de l&rsquo;USAF nourrit indirectement une pouss\u00e9e pour l&rsquo;instant diffuse et mal identifi\u00e9e, que Justin Raimundo r\u00e9sume dans sa chronique de <a href=\"http:\/\/www.antiwar.com\/justin\/?articleid=12391\" class=\"gen\">ce jour<\/a> selon la formule McCain <em>versus<\/em> Robert A. Taft (le s\u00e9nateur Taft, un des derniers grands politiciens US \u00e0 avoir soutenu l&rsquo;option de l&rsquo;isolationnisme).<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 20 f\u00e9vrier 2008 \u00e0 17H06<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La crise de l&rsquo;USAF est en train de s&rsquo;installer au cur du paysage washingtonien, comme un grave probl\u00e8me de s\u00e9curit\u00e9 nationale. L&rsquo;article que signale un de nos lecteurs sur notre Forum aujourd&rsquo;hui, qu&rsquo;on peut \u00e9galement directement trouver sur AP, est un signe de l&rsquo;offensive de relations publiques entreprise par l&rsquo;USAF. L&rsquo;organe de pression presque-officiel de&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[248,3228,1242,41],"class_list":["post-69696","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-afa","tag-crise","tag-isolationnisme","tag-usaf"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69696"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69696\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}