{"id":69729,"date":"2008-03-05T00:00:00","date_gmt":"2008-03-05T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2008\/03\/05\/le-premier-faux-pas-dobama\/"},"modified":"2008-03-05T00:00:00","modified_gmt":"2008-03-05T00:00:00","slug":"le-premier-faux-pas-dobama","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2008\/03\/05\/le-premier-faux-pas-dobama\/","title":{"rendered":"Le premier faux-pas d&rsquo;Obama?"},"content":{"rendered":"<p><p>Depuis le d\u00e9but de la campagne des primaires, Barack Obama a eu une position qu&rsquo;on qualifierait de naturelle, m\u00eame si cette position nourrit incontestablement des accusations de d\u00e9magogie et d&rsquo;inconsistance. L&rsquo;essentiel pour lui est (\u00e9tait) qu&rsquo;elle donne (donnait) \u00e0 sa candidature un rythme (<em>momentum<\/em>) puissant voire irr\u00e9sistible. En d&rsquo;autres mots, Obama semblait port\u00e9 par une vague populaire et se contentait de traduire cette pouss\u00e9e en s&rsquo;exprimant, en son nom, par des propositions que ses adversaires ont d\u00e9nonc\u00e9es comme vagues, inconsistantes, d\u00e9magogues, etc. Tout cela \u00e9tait de bonne guerre et l&rsquo;ensemble rendait compte finalement d&rsquo;une r\u00e9alit\u00e9 politique puissante \u00e0 l&rsquo;avantage d&rsquo;Obama.<\/p>\n<\/p>\n<p><p>\tIl semble, selon notre estimation, que l&rsquo;un des premiers faux-pas majeurs d&rsquo;Obama soit intervenu peu avant les primaires de mardi, et qu&rsquo;il a pes\u00e9 sur les r\u00e9sultats dans l&rsquo;atmosph\u00e8re survolt\u00e9e de ces \u00e9lections o\u00f9 la principale caract\u00e9ristique est une rapidit\u00e9 de communication extraordinaire par les nouvelles technologies et les r\u00e9seaux disponibles (notamment, tout ce qui est li\u00e9 \u00e0 Internet).  Dans <em>The Independent<\/em> d&rsquo;<a href=\"http:\/\/www.independent.co.uk\/opinion\/commentators\/dominic-lawson\/dominic-lawson-theres-nothing-new-about-barack-obama-790896.html\" class=\"gen\">hier<\/a>, Dominic Lawson rend compte de la chose sous un titre d\u00e9pit\u00e9 (\u00ab<em>There&rsquo;s nothing new about Barack Obama<\/em>\u00bb), impliquant qu&rsquo;avec ce candidat d\u00e9mocrate r\u00e9volutionnaire, on retrouve en r\u00e9alit\u00e9 tous les ingr\u00e9dients habiturels de la bonne vieille politique politicienne US (et non-US, d&rsquo;ailleurs).<\/p>\n<\/p>\n<p><p>\tVoici l&rsquo;affaire expos\u00e9e en cinq paragraphes, avec le paragraphe d&rsquo;introduction sur l&rsquo;image initiale d&rsquo;Obama, et la r\u00e9alit\u00e9 d\u00e9couverte par l&rsquo;affaire du m\u00e9mo d&rsquo;Obama pour les Canadiens. (Obama en campagne dans l&rsquo;Ohio o\u00f9 il d\u00e9nonce l&rsquo;accord de libre-\u00e9change NAFTA, affirmant qu&rsquo;il faut ren\u00e9gocier l&rsquo;accord avec le Mexique et le Canada, envoyant en sous-main aux Canadiens le message que tout cela est simple rh\u00e9torique \u00e9lectorale&#8230;)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Barack Obama is the new, new thing. There&rsquo;s been nothing like him ever before in American politics, apparently. The old style of pork-barrel vote-buying has been cast aside by a man who will appease no special interest groups. In a battle for the presidency with the 71-year-old Republican John McCain, we all know who will represent the decisive break with the old politics&rsquo;. Or do we?<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Over the past fortnight Barack Obama has done whatever it takes to capture Ohio and Texas, and thereby seal the Democrat nomination. In Ohio, where traditional manufacturing jobs have been hit by foreign competition, Obama has savaged the North American Free Trade Agreement, (one of Bill Clinton&rsquo;s signal achievements). He has said that, as President of the United States, he will pull out of the agreement with Mexico and Canada unless those two countries agree to it being rewritten along what the Wall Street Journal describes as Yankee terms.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Yet, according to a memo obtained by the Associated Press, one of Obama&rsquo;s advisors has hastened to reassure anxious Canadian consular officials that while protectionist sentiment has emerged, particularly in the Midwest during the primary campaign, this messaging should be viewed as more about political positioning than a clear articulation of policy plans.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Or, in other words, don&rsquo;t worry, Barack Obama doesn&rsquo;t mean what he says  this is just old-fashioned electioneering. Obama has been relatively silent about Nafta in Texas, which has benefited dramatically from the increased trade with Mexico. On the other hand he has come out specifically against open trucking with Mexico, in which freight lorries would drive across the border instead of unloading onto American trucks. As the Financial Times managed to report with a straight face: Obama&rsquo;s new stance coincided with the endorsement of the Teamsters union, which is opposed to competition in road freight. Ah, politics as usual.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tIl y a sans doute deux aspects d&rsquo;explication du comportement d&rsquo;Obama.<\/p>\n<\/p>\n<p><p>\t D&rsquo;une part, une \u00e9volution normale. L&rsquo;homme est emport\u00e9 par un courant populaire plus qu&rsquo;il ne le suscite. Il s&rsquo;en avise et en arrive \u00e0 tenter, parall\u00e8lement, de reprendre le contr\u00f4le des choses en montrant une certaine responsabilit\u00e9 politique. Il avertit donc les Canadiens qu&rsquo;il ne faut pas trop prendre ses d\u00e9clarations au pied de la lettre. Cela se sait et cela fait bien mauvais effet,  m\u00eame s&rsquo;il s&rsquo;agit, objectivement consid\u00e9r\u00e9e, d&rsquo;une pratique assez courante et normale pour les hommes politiques en campagne.<\/p>\n<\/p>\n<p><p>\t D&rsquo;autre part, peut-\u00eatrer, un p\u00each\u00e9 d&rsquo;arrogance. Obama a agi comme s&rsquo;il \u00e9tait assur\u00e9 de sa nomination, donc sans peser le pour et le contre des effets possibles d&rsquo;une telle d\u00e9marche sur le processus en cours si elle venait \u00e0 \u00eatre connue. P\u00each\u00e9 d&rsquo;arrogance, parce qu&rsquo;Obama n&rsquo;est pas (encore?) assur\u00e9 d&rsquo;\u00eatre d\u00e9sign\u00e9 par le parti d\u00e9mocrate, moins que jamais encore bien s\u00fbr apr\u00e8s les r\u00e9sultats d&rsquo;hier dont une partie peut effectivement \u00eatre consid\u00e9r\u00e9e comme la cons\u00e9quence de cette attitude.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne mle 5 mars 2008 \u00e0 13H08<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depuis le d\u00e9but de la campagne des primaires, Barack Obama a eu une position qu&rsquo;on qualifierait de naturelle, m\u00eame si cette position nourrit incontestablement des accusations de d\u00e9magogie et d&rsquo;inconsistance. L&rsquo;essentiel pour lui est (\u00e9tait) qu&rsquo;elle donne (donnait) \u00e0 sa candidature un rythme (momentum) puissant voire irr\u00e9sistible. En d&rsquo;autres mots, Obama semblait port\u00e9 par une&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3708,7455,7456,6208],"class_list":["post-69729","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-canada","tag-faux-pas","tag-nafta","tag-obama"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69729"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69729\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}