{"id":69735,"date":"2008-03-07T00:00:00","date_gmt":"2008-03-07T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2008\/03\/07\/jsf-fatigue-i-le-cas-de-lus-navy\/"},"modified":"2008-03-07T00:00:00","modified_gmt":"2008-03-07T00:00:00","slug":"jsf-fatigue-i-le-cas-de-lus-navy","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2008\/03\/07\/jsf-fatigue-i-le-cas-de-lus-navy\/","title":{"rendered":"\u201cJSF Fatigue\u201d (I): le cas de l&rsquo;U.S. Navy"},"content":{"rendered":"<p><p>L&rsquo;U.S. Navy est prudente. Le 5 mars, selon <em>Defense News<\/em> du <a href=\"http:\/\/www.defensenews.com\/story.php?i=3407805&#038;c=AME&#038;s=SEA\" class=\"gen\">m\u00eame jour<\/a>, elle est venue t\u00e9moigner devant le S\u00e9nat qu&rsquo;elle envisageait des commandes suppl\u00e9mentaires de F-18E\/F <em>Super Hornet<\/em>, voire une nouvelle version dite 4.75 (pour g\u00e9n\u00e9ration 4.75, chasseur situ\u00e9 entre la quatri\u00e8me g\u00e9n\u00e9ration, comme le F-18 basique, et la cinqui\u00e8me g\u00e9n\u00e9ration, dont le F-35 JSF est le plus beau fleuron).<\/p>\n<\/p>\n<p><p>\tVoici quelques d\u00e9tails&#8230; <\/p>\n<\/p>\n<p><p>\t\u00ab<em>The U.S. Navy is considering buying 69 F\/A-18E\/F Super Hornet fighters to bridge a strike-fighter gap that commanders fear could imperil aviation readiness at a time when older jets are wearing out before new aircraft are ready to take their place, top service officials said March 5.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Chief of Naval Operations Adm. Gary Roughead, who appeared before a Senate panel with Navy Secretary Donald Winter and Marine Corps Commandant Gen. James Conway, mentioned the fighter gap in written testimony submitted to the Senate Appropriations Committee defense subcommittee, which convened to review the Department of the Navy&rsquo;s fiscal 2009 budget request.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>After the hearing, Roughead said Navy planners worried that many of today&rsquo;s Super Hornets would be at the end of their service lives by about 2015, but their scheduled replacement, the F-35 Lighting II, might not be ready to fill the vacancies in carrier air wings. They also worried that the exiting fighters would wear out quicker than planned. Roughead said he doesn&rsquo;t know if the Navy would buy the existing E- or F-variants of the venerable fighter or if planners would be interested in a so-called 4.75 generation Hornet with improved avionics that manufacturer Boeing has mentioned as an option for some defense clients. We&rsquo;re still a ways away from all that, Winter said.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t<em>Lightning II<\/em>, le JSF? Pourquoi pas <em>Godot<\/em> comme nom de bapt\u00eame? On va voir se dessiner et se multiplier les initiatives tendant \u00e0 envisager ce fameux <em>fighter gap<\/em> que le JSF, <em>Godot<\/em> postmoderne qui n&rsquo;en finit pas de ne pas arriver, suscite un peu partout. Son retard, non officiel puisque tout va bien (leit-motiv des communiqu\u00e9s Lockheed Martin), ne cesse de s&rsquo;acccentuer et cr\u00e9e des probl\u00e8mes d&rsquo;effectifs, avec le vieillissement des chasseurs qu&rsquo;il doit remplacer. Les Australiens sont emberlificot\u00e9s dans une commande de 24 <em>Super Hornet<\/em> pour meubler leur attente (JSF pr\u00e9vu pour eux au complet et en ordre de bataille en 2019). L&rsquo;USAF s&rsquo;inqui\u00e8te de savoir jusqu&rsquo;o\u00f9 elle pourra tenir en attendant <em>Godot<\/em>.<\/p>\n<\/p>\n<p><p>\tLa Navy, elle, semble vouloir prendre le probl\u00e8me \u00e0 bras le corps. Une pr\u00e9vision de commande de 69 <em>Super Hortnet<\/em>, cela  commence \u00e0 faire s\u00e9rieux. On pourrait croire qu&rsquo;il s&rsquo;agit d&rsquo;un v\u00e9ritable plan d&rsquo;\u00e9quipement qui est entam\u00e9, qui envisage un retard ind\u00e9fini du JSF, voire plus ou pire. Si le <em>Super Hornet<\/em> 4,75 n&rsquo;est pas encore lanc\u00e9, il est manifestement d\u00e9j\u00e0 dans les cartons. Si son d\u00e9veloppement est d\u00e9cid\u00e9, cela signifierait que la sentence est prononc\u00e9 et que la Navy aurait d\u00e9cid\u00e9 de se passer du JSF,  dont elle n&rsquo;a d&rsquo;ailleurs jamais vraiment raffol\u00e9. Car, bien entendu, tout l&rsquo;argent d\u00e9bloqu\u00e9 pour les <em>Super Hornet<\/em> et la possible version 4,75 sera pris sur le budget JSF de la Navy.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 7 mars 2008 \u00e0 08H27<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;U.S. Navy est prudente. Le 5 mars, selon Defense News du m\u00eame jour, elle est venue t\u00e9moigner devant le S\u00e9nat qu&rsquo;elle envisageait des commandes suppl\u00e9mentaires de F-18E\/F Super Hornet, voire une nouvelle version dite 4.75 (pour g\u00e9n\u00e9ration 4.75, chasseur situ\u00e9 entre la quatri\u00e8me g\u00e9n\u00e9ration, comme le F-18 basique, et la cinqui\u00e8me g\u00e9n\u00e9ration, dont le F-35&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[6517,4711,250,3319,3487],"class_list":["post-69735","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-godot","tag-hornet","tag-jsf","tag-navy","tag-super"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69735"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69735\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}