{"id":69739,"date":"2008-03-08T00:00:00","date_gmt":"2008-03-08T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2008\/03\/08\/en-attendant-le-traite-usa-uk-sur-les-transferts-de-technologies-quelques-precisions-interessantes\/"},"modified":"2008-03-08T00:00:00","modified_gmt":"2008-03-08T00:00:00","slug":"en-attendant-le-traite-usa-uk-sur-les-transferts-de-technologies-quelques-precisions-interessantes","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2008\/03\/08\/en-attendant-le-traite-usa-uk-sur-les-transferts-de-technologies-quelques-precisions-interessantes\/","title":{"rendered":"En attendant le trait\u00e9 USA-UK sur les transferts de technologies, quelques pr\u00e9cisions int\u00e9ressantes\u2026"},"content":{"rendered":"<p><p>Certains attendent Godot (ou bien <em>Godot<\/em>, <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4962\" class=\"gen\">proposition<\/a> d&rsquo;un nouveau nom de bapt\u00eame du F-35\/JSF), d&rsquo;autres une majorit\u00e9 des deux-tiers du S\u00e9nat des Etats-Unis. C&rsquo;est le cas des Britanniques et du mirobolant trait\u00e9 fait en cadeau d&rsquo;adieu par GW Bush \u00e0 <em>Yo Blair<\/em>, en <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4143\" class=\"gen\">juin 2007<\/a>, pour saluer le d\u00e9part glorieux du second. Il s&rsquo;agit d&rsquo;un trait\u00e9 USA-UK sur les transferts de technologies.<\/p>\n<\/p>\n<p><p>\tLe 11 d\u00e9cembre 2007, la commission de la d\u00e9fense de la Chambre des Communes adressait au gouvernement son rapport sur le <em>UK\/US Defence Trade Cooperation Treaty<\/em>. Le gouvernement lui a r\u00e9pondu le 11 f\u00e9vrier 2008 par un document de huit pages qui vient d&rsquo;\u00eatre rendu public (le <a href=\"http:\/\/www.publications.parliament.uk\/pa\/cm200708\/cmselect\/cmdfence\/375\/375.pdf\" class=\"gen\">3 mars<\/a>).<\/p>\n<\/p>\n<p><p>\tLa r\u00e9ponse du gouvernement britannique continent quelques explications et commentaires mirobolants qui situent les conditions o\u00f9 \u00e9volue ce trait\u00e9, lequel trait\u00e9 attend avec patience sa toujours incertaine ratification par le S\u00e9nat US (majorit\u00e9 des deux tiers n\u00e9cessaires). A l&rsquo;heure de l&rsquo;appel aux armes face aux <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4961\" class=\"gen\">envahisseurs<\/a> \u00e9trangers (les Europ\u00e9ens dans le programme KC-45), les Britanniques, qui ont des parts dans EADS, pourraient bien \u00eatre class\u00e9s \u00e9trangers On verra.<\/p>\n<\/p>\n<p><p>\t Dans le document du 11 f\u00e9vrier, le gouvernement britannique admet qu&rsquo;il ne peut \u00eatre tenu pour acquis que le trait\u00e9 sera approuv\u00e9 par la majorit\u00e9 requise des deux tiers du S\u00e9nat , r\u00e9pondant ainsi par l&rsquo;impr\u00e9cision \u00e0 la requ\u00eate pr\u00e9cise de la commission. Aucun contact ne permet au gouvernement Brown d&rsquo;avoir la moindre garantie \u00e0 ce sujet, d&rsquo;autant qu&rsquo;il appara\u00eet que le S\u00e9nat n&rsquo;est gu\u00e8re int\u00e9ress\u00e9 par cette question actuellement,  \u00e0 moins que l&rsquo;affaire EADS\/KC-45 r\u00e9veiller cet int\u00e9r\u00eat, mais dans le sens malencontreux qu&rsquo;on imagine. N\u00e9anmoins, dit le texte du 11 f\u00e9vrier qui fait montre d&rsquo;un optimisme roboratif, \u00ab<em>we are confident that Congressional scrutiny of the Treaty will show that it is as much in the US interest as it is in the interest of the UK<\/em>\u00bb.  <\/p>\n<\/p>\n<p><p>\t Le minist\u00e8re de la d\u00e9fense admet que \u00ab<em> the Treaty appears to be asymmetrical in giving the US more control over UK exports than vice versa<\/em>\u00bb. Comment s&rsquo;en sortir? Simplement en avan\u00e7ant d&rsquo;une fa\u00e7on \u00e9trange \u00ab<em> the practical effect of the Treaty will be to bring US and UK exporting arrangements closer together<\/em>\u00bb. Effectivement, le jour o\u00f9 les Britaniques auront fait toutes les concessions aux USA, et les USA aucune, l&rsquo;accord d&rsquo;exportation entre USA et UK sera encore plus proche, disons avec les deux pays ne faisant plus qu&rsquo;un, et l&rsquo;on devine lequel<\/p>\n<\/p>\n<p><p>\t D\u00e9licieuse cerise sur le g\u00e2teau, il appara\u00eet que le trait\u00e9 ne couvre pas les programmes multi-nationaux o\u00f9 UK et USA sont parties prenantes Qui ne pense alors au JSF, programme multi-national auquel UK et USA sont effectivement parties prenantes, et qui est l&rsquo;une des principales raisons imm\u00e9diates de ce trait\u00e9 UK-USA? Le MoD explique que \u00ab<em>the Treaty has, however, the potential to assist those parts of the JSF programme which are exclusively joint US\/UK collaborative projects. We welcome this benefit. We will continue to monitor the JSF programme closely<\/em>\u00bb Etrange commentaire: comment une partie binationale d&rsquo;un accord multi-national peut-il \u00e9chapper \u00e0 la multi-nationalit\u00e9? Il en a, dans tous les cas, la potentialit\u00e9, explique le MoD. Du coup, oui, on juge bienvenu ce qui est potentiellement un b\u00e9n\u00e9fice du trait\u00e9. Cela permet d&rsquo;affirmer d&rsquo;une fa\u00e7on potentiellement martiale qu&rsquo;on continuera \u00e0 suivre avec attention le programme JSF Nous aussi.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 8 mars 2008 \u00e0 16H52<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Certains attendent Godot (ou bien Godot, proposition d&rsquo;un nouveau nom de bapt\u00eame du F-35\/JSF), d&rsquo;autres une majorit\u00e9 des deux-tiers du S\u00e9nat des Etats-Unis. C&rsquo;est le cas des Britanniques et du mirobolant trait\u00e9 fait en cadeau d&rsquo;adieu par GW Bush \u00e0 Yo Blair, en juin 2007, pour saluer le d\u00e9part glorieux du second. Il s&rsquo;agit d&rsquo;un&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[5224,2969,6517,250,4096,4495,4095,6863],"class_list":["post-69739","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-communes","tag-f-35","tag-godot","tag-jsf","tag-technologies","tag-traite","tag-transferts","tag-usa-uk"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69739"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69739\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}