{"id":69770,"date":"2008-03-21T00:00:00","date_gmt":"2008-03-21T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2008\/03\/21\/hagel-il-faut-un-nouveau-parti-politique-aux-usa\/"},"modified":"2008-03-21T00:00:00","modified_gmt":"2008-03-21T00:00:00","slug":"hagel-il-faut-un-nouveau-parti-politique-aux-usa","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2008\/03\/21\/hagel-il-faut-un-nouveau-parti-politique-aux-usa\/","title":{"rendered":"Hagel: il faut un nouveau parti politique aux USA"},"content":{"rendered":"<p><p>On a d\u00e9j\u00e0 vu combien, \u00e0 l&rsquo;int\u00e9rieur d&rsquo;un syst\u00e8me dont il est certes comptable (ce qui implique des limites \u00e0 la critique, sans aucun doute), le s\u00e9nateur r\u00e9publicain Chuck Hagel repr\u00e9sente une des personnalit\u00e9s les plus proches de la lucidit\u00e9 critique et de l&rsquo;honn\u00eatet\u00e9 intellectuelle. Le livre (<em>America: Our Next Chapter<\/em>) que vient d&rsquo;\u00e9crire Hagel et qui sera en vente le 25 mars nous donne ses r\u00e9flexions sur l&rsquo;\u00e9tat de l&rsquo;Am\u00e9rique. <\/p>\n<\/p>\n<p><p>\t<em>Raw Story<\/em> (Associated Press) nous en fait rapport le <a href=\"http:\/\/www.rawstory.com\/news\/mochila\/Hagel_US_may_need_new_political_par_03202008.html\" class=\"gen\">20 mars<\/a>:<\/p>\n<\/p>\n<p><p>\t\u00ab<em>U.S. Sen. Chuck Hagel writes in a new book that the United States needs independent leadership and possibly another political party, while suggesting the Iraq war might be remembered as one of the five biggest blunders in history.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>In the current impasse, an independent candidate for the presidency, or a bipartisan unity ticket &#8230; could be appealing to Americans, Hagel writes in America: Our Next Chapter, due in stores Tuesday. The Associated Press obtained an advance copy.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLa d\u00e9p\u00eache d&rsquo;AP donne certains d\u00e9tails sur les d\u00e9marches d&rsquo;Hagel avant la guerre en Irak. Opposant d\u00e9termin\u00e9 \u00e0 cette guerre depuis son d\u00e9clenchement, Hagel avait pourtant vot\u00e9 les pouvoirs de guerre au pr\u00e9sident. Dans son livre, selon le rapport qu&rsquo;en fait AP, il donne les explications suivantes :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>During visits to the Middle East in December 2002, Hagel said, Israel&rsquo;s top security officials asked, Do you really understand what you are getting yourselves into?<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Hagel said Bush personally assured him that he would exhaust diplomatic avenues before committing troops to Iraq. The senator said he voted for the war resolution based on those assurances, but regrets the vote because it&rsquo;s now clear that lawmakers were presented with lies and wishful thinking.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tCes explications montrent bien que Hagel a eu avant le conflit une position ambigu\u00eb. On peut lui reprocher d&rsquo;avoir vot\u00e9 les pouvoirs de guerre mais on doit \u00e9galement observer qu&rsquo;il l&rsquo;a fait sur certaines assurances du pr\u00e9sident. Ces pr\u00e9cisions sont in\u00e9dites et compl\u00e8tent bien l&rsquo;id\u00e9e d&rsquo;une manipulation g\u00e9n\u00e9rale dans le chef de l&rsquo;administration Bush pour obtenir le soutien le plus large possible \u00e0 cette attaque, y compris aupr\u00e8s de parlementaires r\u00e9publicains (cela n&rsquo;\u00e9tait pas connu). Elles montrent que le pr\u00e9sident lui-m\u00eame \u00e9tait partie prenante dans cette manipulation; si la guerre a sembl\u00e9 \u00eatre essentiellement au d\u00e9part une entreprise des n\u00e9o-conservateurs, il appara\u00eet de plus en plus qu&rsquo;il s&rsquo;est agi d\u00e8s l&rsquo;origine de l&rsquo;action d&rsquo;un parti de la guerre d\u00e9bordant largement cette seule faction.<\/p>\n<\/p>\n<p><p>\tD&rsquo;une certaine fa\u00e7on, ces conditions de d\u00e9part en plus de ce qui a suivi (l&rsquo;opposition d\u00e9cid\u00e9e \u00e0 la guerre en Irak de Hagel depuis 2003, l&rsquo;aventure irakienne tournant en catastrophe, les menaces d&rsquo;attaque de l&rsquo;Iran) expliquent que Hagel, homme d&rsquo;attitude mod\u00e9r\u00e9e, envisage la possibilit\u00e9 de r\u00e9formes en profondeur du syst\u00e8me US pour tenter de sortir de la p\u00e9riode actuelle. Il confirme ainsi <em>in fine<\/em> qu&rsquo;il existe une tendance au sein de l&rsquo;<em>establishment<\/em>, d\u00e9j\u00e0 perceptible lorsqu&rsquo;on \u00e9voquait une <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4792\" class=\"gen\">candidature ind\u00e9pendante<\/a> de Michael Bloomberg, pr\u00eate \u00e0 pr\u00f4ner des mesures tr\u00e8s importantes de restructuration du syst\u00e8me politique. On ignore \u00e9videmment si ces id\u00e9es peuvent encore \u00eatre d&rsquo;application dans la campagne pr\u00e9sidentielle actuelle.<\/p>\n<\/p>\n<p><p>\tHagel a de toutes les fa\u00e7ons un r\u00f4le important \u00e0 jouer dans un mouvement de cette sorte. On le pressentait comme un \u00e9ventuel vice-pr\u00e9sident d&rsquo;une candidature Bloomberg. D&rsquo;autre part, il y aurait des contacts entre <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4952\" class=\"gen\">Obama et lui<\/a>, ce qui impliquerait une autre sorte de rupture puisqu&rsquo;il est r\u00e9publicain et que Obama est d\u00e9mocrate. Dans le climat actuel, beaucoup d&rsquo;hypoth\u00e8ses restent possibles. Exemple r\u00e9cent, on commence \u00e0 envisager celle o\u00f9, dans le cas o\u00f9 Clinton serait d\u00e9sign\u00e9e comme candidate par des manuvres au congr\u00e8s de d\u00e9signation du parti d\u00e9mocrate, Obama pourrait \u00eatre tent\u00e9 lui-m\u00eame par une candidature ind\u00e9pendante. Dans ce cas, Hagel pourrait \u00eatre de la f\u00eate.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 21 mars 2008 \u00e0 09H13<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>On a d\u00e9j\u00e0 vu combien, \u00e0 l&rsquo;int\u00e9rieur d&rsquo;un syst\u00e8me dont il est certes comptable (ce qui implique des limites \u00e0 la critique, sans aucun doute), le s\u00e9nateur r\u00e9publicain Chuck Hagel repr\u00e9sente une des personnalit\u00e9s les plus proches de la lucidit\u00e9 critique et de l&rsquo;honn\u00eatet\u00e9 intellectuelle. Le livre (America: Our Next Chapter) que vient d&rsquo;\u00e9crire Hagel&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3009,4841,6813,857,6208,5623,3686],"class_list":["post-69770","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-democrates","tag-hagel","tag-independant","tag-irak","tag-obama","tag-parti","tag-republicain"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69770"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69770\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}