{"id":69785,"date":"2008-03-26T00:00:00","date_gmt":"2008-03-26T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2008\/03\/26\/lhistoire-sous-nos-yeux\/"},"modified":"2008-03-26T00:00:00","modified_gmt":"2008-03-26T00:00:00","slug":"lhistoire-sous-nos-yeux","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2008\/03\/26\/lhistoire-sous-nos-yeux\/","title":{"rendered":"L&rsquo;Histoire sous nos yeux"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955;font-size:2em;\">L&rsquo;Histoire sous nos yeux<\/h2>\n<\/p>\n<p><p>26 mars 2008 &mdash; Nous commen\u00e7ons \u00e0 regarder autour de nous, et \u00e0 nous regarder nous-m\u00eames dans les d\u00e9combres de nos illusions. L&rsquo;unanimit\u00e9 est en train de se faire sur l&rsquo;importance historique et symbolique de ce 14 mars 2008, ce jour o&ugrave;, selon <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=5010\">Martin Wolf<\/a>, &laquo;<em>the dream of global free-market capitalism died<\/em>&raquo;. (Martin Wolf encore, avec ces mots de contrition, dont il faut mesurer le poids, &ndash; un commentateur de ce calibre n&rsquo;\u00e9crit pas cela, dans le <em>Financial Times<\/em> en plus, \u00e0 la l\u00e9g\u00e8re: &laquo;<em>Once upon a time, I had hoped that securitisation would shift a substantial part of the risk-bearing outside the regulated banking system, where governments would no longer need to intervene. That has proved a delusion.<\/em>&raquo;)<\/p>\n<\/p>\n<p><p>On conna&icirc;t les d\u00e9tails de ce jour historique du 14 mars 2008 et l&rsquo;on commence \u00e0 en mesurer la signification: Bear Stearns sur le point de s&rsquo;effondrer en une banqueroute extraordinaire, l&rsquo;intervention du pouvoir public (Bernanke et la Federal Reserve), le flot d&rsquo;argent du contribuable ($30 milliards de ligne de cr\u00e9dit) mis \u00e0 la disposition de JP Morgan pour qu&rsquo;il rach\u00e8te Bear Stearns en une solde incroyable (depuis r\u00e9\u00e9valu\u00e9e parce qu&rsquo;on l&rsquo;a trouv\u00e9e saum\u00e2tre), &ndash; et vogue le syst\u00e8me sauv\u00e9 <em>in extremis<\/em>. Nous vivons des temps historiques.<\/p>\n<\/p>\n<p><p>&#8230; D&rsquo;autre part, rien n&rsquo;est fini. On s&rsquo;en doutait. Les temps historiques, cela ne d\u00e9croche pas aussi simplement, sous pr\u00e9texte que la Fed a ouvert une ligne de cr\u00e9dit de $30 milliards pour JP Morgan. Le sentiment de l&rsquo;in\u00e9luctable catastrophe est plus que jamais parmi nous, alors qu&rsquo;on apprend que le moral des m\u00e9nages US, notre r\u00e9f\u00e9rence inoxydable, continue \u00e0 s&rsquo;effondrer, au plus bas niveau depuis d\u00e9cembre et janvier 1974, en ces jours terribles du scandale du Watergate<\/p>\n<\/p>\n<p><p>(Selon <em>WSWS.org<\/em> <a class=\"gen\" href=\"http:\/\/www.wsws.org\/articles\/2008\/mar2008\/econ-m26.shtml\">aujourd&rsquo;hui<\/a>: &laquo;<em>The Conference Board, a business-backed research group in New York, reported that its index of consumer confidence fell to a five-year low in March, to 64.5 from a revised 76.4 in February. The reading was far below Wall Street expectations of 73.0.<\/em>[&#8230;] <em>The Conference Board noted that there was a particularly sharp drop in the index measuring expected future confidence, to 47.9 from 58.0. \u00ab\u00a0The Expectations Index, in fact, is now at a 35-year low (Dec. 1973, 45.2), levels not seen since the Oil Embargo and Watergate,\u00a0\u00bb a press release noted.<\/em>&raquo;)<\/p>\n<\/p>\n<p><p>Le <em>Financial Times<\/em>, <a class=\"gen\" href=\"http:\/\/www.ft.com\/cms\/s\/0\/2f9ab320-fa66-11dc-aa46-000077b07658.html\">aujourd&rsquo;hui<\/a> dans ses colonnes, nous entretient du sentiment g\u00e9n\u00e9ral:<\/p>\n<\/p>\n<p><p>&laquo;<em>Central banks&rsquo; efforts to ease strains in the money markets are failing to stop financial institutions from hoarding cash, stoking fears that the recent respite in equity markets may not signal the end of the credit crisis.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Banks&rsquo; borrowing costs &ndash; a sign of their willingness to lend to each other &ndash; in the US, eurozone and the UK rose again even after the Federal Reserve&rsquo;s unprecedented activity in lending to retail and investment banks against weaker than usual collateral and similar action in Europe.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>The continued friction in the money markets came even as stock markets were showing new signs of optimism in spite of fresh data from the US showing consumers at their most pessimistic for 35 years and house prices falling at the fastest rate on record.<\/em>&raquo;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Leur foi est en crise<\/h3>\n<\/p>\n<p><p>Reportons-nous aux explications enfi\u00e9vr\u00e9es et curieusement jubilatoires de Gerard Baker, que nous signalons <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=5011\">par ailleurs<\/a>. Il nous dit toute sa confiance parce que monsieur Bernanke, le patron de la Fed, est un sp\u00e9cialiste de la Grande D\u00e9pression:<\/p>\n<\/p>\n<p><p>&laquo;<em>Mr Bernanke, who had made something of a life&rsquo;s work of studying the Great Depression and its causes, addressed the central contention in one of Professor Friedman&rsquo;s analyses &mdash; that the economic disaster of the 1930s was essentially the result of an unforced policy error, a terrible series of mistakes by the Federal Reserve.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Mr Bernanke&rsquo;s conclusion was surprisingly blunt: \u00ab\u00a0You&rsquo;re right. We did it. We&rsquo;re very sorry. But thanks to you, we won&rsquo;t do it again.\u00a0\u00bb<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Effectivement, \u00e0 temps historiques r\u00e9f\u00e9rences historiques. Aujourd&rsquo;hui, nous dansons au bord de la Grande D\u00e9pression-II, r\u00e9f\u00e9rence \u00e0 la Grande D\u00e9pression originelle en sautoir. Savoir que Bernanke en est un sp\u00e9cialiste, un \u00ab\u00a0historien-\u00e9conomiste\u00a0\u00bb si vous voulez, est devenu un argument imp\u00e9ratif (voir Baker). Cela ne nous rassure pas pour autant. Face \u00e0 l&rsquo;expertise historico-\u00e9conomique de Bernanke, il y a le chiffre de l&rsquo;effondrement poursuivi de la confiance du consommateur US. Comme d&rsquo;habitude, conform\u00e9ment \u00e0 la pens\u00e9e moderniste, on confond cause et moyen. L&rsquo;effondrement du syst\u00e8me bancaire US durant la Grande D\u00e9pression (9.000 faillites en trois ans) ne fut pas la cause de la Grande D\u00e9pression, mais le moyen technique de la Grande D\u00e9pression. La cause, ce fut la confiance tr\u00e9pass\u00e9e du citoyen dans le syst\u00e8me. Aujourd&rsquo;hui, ce n&rsquo;est pas la sauvegarde <em>in extremis<\/em>, avec l&rsquo;argent de ce m\u00eame citoyen et sans lui demander son avis, d&rsquo;une banque v\u00e9n\u00e9rable et aussi inconsciente que les autres, qui va changer l&rsquo;humeur de ce m\u00eame citoyen.<\/p>\n<\/p>\n<p><p>La psychologie du printemps glac\u00e9 et lugubre de 2008 (crise climatique oblige) se rapproche \u00e0 grande vitesse de la psychologie de la Grande D\u00e9pression. Pas besoin de la trag\u00e9die affich\u00e9e comme dans les rues sordides des villes, aux USA dont nous r\u00eavons tant, dans les ann\u00e9es 1932-33 pour cela. M\u00eame si notre syst\u00e8me continue \u00e0 mouliner pour dissimuler la r\u00e9alit\u00e9 (plut\u00f4t notre vigueur morale face \u00e0 la Chine et \u00e0 son Tibet que l&rsquo;\u00e9croulement en temps r\u00e9el de notre syst\u00e8me capitaliste pour l&rsquo;\u00e9dification du citoyen), la r\u00e9alit\u00e9 est d\u00e9j\u00e0 dans la psychologie du citoyen. Nous avons trop jou\u00e9 le virtualisme, sans prendre garde que la r\u00e9alit\u00e9 persistait et qu&rsquo;ainsi elle avait le champ libre. &laquo;<em>That has proved a delusion.<\/em>&raquo;<\/p>\n<\/p>\n<p><p><a class=\"gen\" href=\"http:\/\/www.europe2020.org\/spip.php?article530=fr\">Certains<\/a> nomment cette Grande D\u00e9pression-II \u00ab\u00a0la Tr\u00e8s Grande D\u00e9pression\u00a0\u00bb (tout cela pour les USA, moteur d\u00e9sormais incontestable et incontest\u00e9e de ce qui pourrait \u00eatre aussi bien vue comme la Tr\u00e8s Grande Crise du syst\u00e8me). Ils n&rsquo;ont pas tort. Le contexte qui est une part essentielle de la crise, &ndash; la situation internationale et la vigueur du syst\u00e8me am\u00e9ricaniste, &ndash; est dans un \u00e9tat infiniment plus grave qu&rsquo;en 1930-33. La psychologie, particuli\u00e8rement aux USA, est infiniment plus affaiblie depuis 9\/11 qu&rsquo;elle ne l&rsquo;\u00e9tait alors, et sans la moindre estime ni confiance pour la direction \u00e0 laquelle son sort est confi\u00e9. (Voyez, dans le chapitre 2 du &laquo;<em>Soleil noir de la Beat Generation<\/em>&raquo;, sur <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4392\">ce site<\/a>, la fi\u00e8vre enthousiaste et presque paradisiaque qui accueillit la prise de fonction de Hoover, au printemps 1929. Comparez cela avec l&rsquo;atmosph\u00e8re faussaire, trompeuse et d\u00e9sesp\u00e9r\u00e9e autour de la r\u00e9\u00e9lection de Bush, qui correspond \u00e0 peu pr\u00e8s en valeur chronologique.)<\/p>\n<\/p>\n<p><p>L&rsquo;article de Martin Wolf, comme celui d&rsquo;un nombre grandissant de commentateurs, montre \u00e9galement que cette attaque de la psychologie par la crise touche les \u00ab\u00a0croyants\u00a0\u00bb les plus indispensables au syst\u00e8me, ceux qui, durant des d\u00e9cennies, servirent la messe et r\u00e9cit\u00e8rent la th\u00e9ologie du syst\u00e8me. Il s&rsquo;agit bien d&rsquo;une \u00ab\u00a0crise de la foi\u00a0\u00bb, comme l&rsquo;observait <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4913\">Paul Krugman<\/a> il y a un peu plus d&rsquo;un mois: &laquo;<em>Because, ultimately, it&rsquo;s a crisis of faith.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Le syst\u00e8me s&rsquo;\u00e9tait consid\u00e9rablement renforc\u00e9 depuis la Grande D\u00e9pression, pour se prot\u00e9ger d&rsquo;une Grande D\u00e9pression-II. Pourtant, la Grande D\u00e9pression-II est \u00e0 nos portes. Cela mesure la fragilit\u00e9 incroyable du syst\u00e8me, qui tient d\u00e9sormais bien plus \u00e0 la psychologie des gens, \u00e0 leur croyance devenue incroyance furieuse dans le syst\u00e8me, qu&rsquo;au sort des d\u00e9risoires banques aux centaines de $milliards d&rsquo; \u00ab\u00a0actif\u00a0\u00bb devenu \u00ab\u00a0passif\u00a0\u00bb qui s&rsquo;\u00e9croulent comme fait un ch\u00e2teau de cartes. Bernanke le churchillien est \u00e0 la barre, \u00e0 la grande joie de Gerard Baker, mais plus grand&rsquo;monde n&rsquo;y croit (sauf Baker, bien s&ucirc;r), &ndash; dans ce temps sacril\u00e8ge d&rsquo;incroyance. La Grande D\u00e9pression-II arrive \u00e0 la mani\u00e8re de la catastrophe irakienne, selon les m\u00eames normes, dans le m\u00eame apparat virtualiste. \u00ab\u00a0<em>Mission accomplished<\/em>\u00ab\u00a0, a dit Bernanke le 14 mars 2008, comme Bush le 1er mai 2003. Pour l&rsquo;Irak, on conna&icirc;t la suite.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;Histoire sous nos yeux 26 mars 2008 &mdash; Nous commen\u00e7ons \u00e0 regarder autour de nous, et \u00e0 nous regarder nous-m\u00eames dans les d\u00e9combres de nos illusions. L&rsquo;unanimit\u00e9 est en train de se faire sur l&rsquo;importance historique et symbolique de ce 14 mars 2008, ce jour o&ugrave;, selon Martin Wolf, &laquo;the dream of global free-market capitalism&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[6936,3083,7224,2891,3715,7025],"class_list":["post-69785","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-bernanke","tag-depression","tag-foi","tag-grande","tag-marche","tag-wolf"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69785"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69785\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}