{"id":69800,"date":"2008-04-02T00:00:00","date_gmt":"2008-04-02T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2008\/04\/02\/une-evolution-psychologique-decisive\/"},"modified":"2008-04-02T00:00:00","modified_gmt":"2008-04-02T00:00:00","slug":"une-evolution-psychologique-decisive","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2008\/04\/02\/une-evolution-psychologique-decisive\/","title":{"rendered":"<strong><em>Une \u00e9volution psychologique d\u00e9cisive?<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Une \u00e9volution psychologique d\u00e9cisive?<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t2 avril 2008  Le sommet qui s&rsquo;ouvre \u00e0 Bucarest est une rencontre essentielle et peut-\u00eatre d\u00e9cisive pour l&rsquo;OTAN. Notons aussit\u00f4t que la m\u00eame chose est dite de tous les sommets de l&rsquo;OTAN, depuis 1990-91.<\/p>\n<\/p>\n<p><p>\tLa m\u00eame chose \u00e9tait dite pour le sommet de l&rsquo;OTAN \u00e0 Rome, \u00e0 l&rsquo;automne 1991. Au cours d&rsquo;une des s\u00e9ances, le pr\u00e9sident des USA George Bush-p\u00e8re s&rsquo;\u00e9tait lev\u00e9 et avait pos\u00e9 une question inattendue. Il avait demand\u00e9 \u00e0 tous les autres chefs d&rsquo;Etat et de gouvernement s&rsquo;ils d\u00e9siraient que les USA restent en Europe. Certains comprirent effectivement la question dans son sens le plus large: d\u00e9siraient-ils que les USA restent membres de l&rsquo;OTAN et que l&rsquo;OTAN continue \u00e0 exister? On se r\u00e9cria et l&rsquo;incident fut clos. L&rsquo;OTAN continua \u00e0 exister, et les Am\u00e9ricains \u00e0 demeurer en Europe. Puisque c&rsquo;\u00e9tait le cas, Richard Holbrooke, l&rsquo;adjoint de la secr\u00e9taire d&rsquo;Etat Madeleine Albright, mit les choses au point en signant dans <em>Foreign Affairs<\/em>, en 1996, un article dont le titre suffisait \u00e0 r\u00e9sumer l&rsquo;esprit: \u00ab<em>American Is an European Power<\/em>\u00bb. Les conditions de la survie de l&rsquo;OTAN \u00e9taient clairement r\u00e9affirm\u00e9es puisqu&rsquo;en \u00e9tant pr\u00e9sent\u00e9s comme <em>an European Power<\/em> de cette fa\u00e7on qui en prend lestement \u00e0 son aise avec la g\u00e9ographie et l&rsquo;histoire, les USA ne pouvaient \u00eatre que la premi\u00e8re.<\/p>\n<\/p>\n<p><p>\tUne fois de plus, comme dans le cas de tous les sommets de l&rsquo;OTAN au moins depuis la fin de la Guerre froide, la r\u00e9union de Bucareste est effectivement pr\u00e9sent\u00e9e comme essentielle, voire existentielle. A mesure que le temps passe, que les probl\u00e8mes s&rsquo;accumulent sans \u00eatre r\u00e9solus, que les d\u00e9s\u00e9quilibres de l&rsquo;Organisation ne cessent de s&rsquo;affirmer, le caract\u00e8re essentiel, voire existentiel de ces r\u00e9unions ne cesse de se confirmer. Il n&rsquo;y a rien d&rsquo;original l\u00e0-dedans. Aujourd&rsquo;hui, tous les probl\u00e8mes qu&rsquo;affronte l&rsquo;OTAN, qui ne sont pas nouveaux mais n&rsquo;ont cess\u00e9 de se d\u00e9velopper, apparaissent de plus en plus insolubles,  comme \u00e0 chaque r\u00e9union,  mais \u00e0 celle de Bucarest un peu plus que lors des pr\u00e9c\u00e9dentes&#8230;<\/p>\n<\/p>\n<p><p>\tLa r\u00e9union de Bucarest a lieu dans le palais de m\u00e9galomane qu&rsquo;avait fait construire Ceaucescu, nomm\u00e9 <em>Casa Poporului<\/em> (traduction inutile), et qui n&rsquo;\u00e9tait pas termin\u00e9 \u00e0 la chute du dictateur communiste. Un choix \u00e9trange pour une r\u00e9union de l&rsquo;OTAN, remarque l&rsquo;\u00e9ditorial du <em>Guardian<\/em> de <a href=\"http:\/\/www.guardian.co.uk\/commentisfree\/2008\/apr\/02\/nato\" class=\"gen\">ce jour<\/a>. Le titre de l&rsquo;\u00e9ditorial est: \u00ab<em>In search of a mission<\/em>\u00bb (A la recherche d&rsquo;une mission). Il concerne l&rsquo;OTAN et aurait pu \u00eatre \u00e9crit pour le sommet de Rome de l&rsquo;automne 1991, comme pour tous les autres qui suivirent.<\/p>\n<\/p>\n<p><p>\tLes deux probl\u00e8mes les plus pressants que ce sommet doit envisager sont: la situation en Afghanistan et la volont\u00e9 des Am\u00e9ricains d&rsquo;\u00e9largir l&rsquo;Alliance \u00e0 l&rsquo;Ukraine et \u00e0 la G\u00e9orgie, \u00e0 laquelle s&rsquo;opposent la Russie (hors de l&rsquo;OTAN mais qui sera pr\u00e9sente \u00e0 la r\u00e9union de Bucarest), mais aussi nombre de membres europ\u00e9ens de l&rsquo;Alliance (Allemagne et France en t\u00eate). D&rsquo;autres probl\u00e8mes, moins visibles \u00e0 Bucarest, sont tout aussi pressants et tout aussi diviseurs de l&rsquo;OTAN. L&rsquo;intention US de mettre en place un r\u00e9seau anti-missiles en Europe (Tch\u00e9quie et Pologne) en est un. Derni\u00e8re nouvelle en date \u00e0 ce propos: les Anglais sont de plus en plus furieux que cette question soit trait\u00e9e en bilat\u00e9ral (USA d&rsquo;une part, Tch\u00e9quie et Pologne de l&rsquo;autre). Du c\u00f4t\u00e9 allemand, l&rsquo;atmosph\u00e8re n&rsquo;est pas meilleure, toujours \u00e0 cause de ces n\u00e9gociations bilat\u00e9rales impliquant les seules Tch\u00e9quie et Pologne alors que le dossier concerne la s\u00e9curit\u00e9 europ\u00e9enne dans sa globalit\u00e9, et les relations de la Russie avec l&rsquo;Europe dans son int\u00e9gralit\u00e9,  point d&rsquo;une sensibilit\u00e9 extr\u00eame pour l&rsquo;Allemagne. <\/p>\n<\/p>\n<p><p>\tL&rsquo;\u00e9ditorial du <em>Guardian<\/em> d\u00e9j\u00e0 cit\u00e9 ne fait que reprendre le catalague de quelques impasses qui affectent l&rsquo;OTAN. Il ne propose aucune solution, sinon de repousser l&rsquo;une ou l&rsquo;autre d\u00e9cision \u00e0 d&rsquo;autres temps o\u00f9 il sera encore plus difficile d&rsquo;y r\u00e9pondre sinon par une rupture, cela pour \u00e9viter <strong>au moins<\/strong> la rupture \u00e0 ce sommet-l\u00e0&#8230; La seule phrase qui tranche par sa nettet\u00e9 sur le reste, et contient donc une hypoth\u00e8se claire et une psychologie en pleine \u00e9volution, est ce membre de phrase: \u00ab<em>If Nato survives&#8230;<\/em>\u00bb Le reste est de la litt\u00e9rature convenue et, pour cette raison paradoxale, elle vaut citation lorsqu&rsquo;elle est compar\u00e9e \u00e0 la r\u00e9alit\u00e9 des choses.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>&#8230;While the building they are meeting in had a clear purpose, the leaders of the 26 Nato countries and the thousands of officials accompanying them have no clear idea what the alliance is about.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Geared to defend Europe from a land attack during the cold war, Nato has no agreed mission, doctrine or strategy with which to define itself. Is it a bulwark against a re-emergent authoritarian Russia? The Baltic and east European member states regard Nato as the cornerstone of their independence. For them membership is not a choice but an existential issue. For Germany, keen to forge a workable strategic relationship with Russia, it is anything but.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Some members see it as a global organisation to combat global threats, but others are deeply sceptical. Nato&rsquo;s response to its difficulties in Afghanistan contains all of these elements. The French president, Nicolas Sarkozy, will buy goodwill at the Bucharest conference by announcing the deployment of 1,000 French combat troops in the east of Afghanistan. However, his quid pro quo is a greater role for civil and economic agencies. But is Nato best suited to perform the function of a muscular aid agency?<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The wisest decision Nato will take at this summit will be to defer, for at least a year, a decision on whether to set Ukraine and Georgia on the path to membership. If Nato had a hard time in the Balkans, it should think several times before involving itself in the Caucasus, where oil, religion and centuries of conflict meet, explosively, in the mountains. And it should be wary of becoming entangled in the identity problems of Ukraine, a significant portion of whose population is hostile to Nato  unless, of course, it wants to guarantee that the next president of Russia remains a hardline nationalist. If Nato survives it will need to blur its edges, not recreate lines of division in terrain with which it is deeply unfamiliar.<\/em>\u00bb<\/p>\n<h3>Une \u00e9volution psychologique<\/h3>\n<\/p>\n<p><p>\tA c\u00f4t\u00e9 de ces divers constats qui n&rsquo;ont l&rsquo;air d&rsquo;\u00eatre que des r\u00e9p\u00e9titions de choses sempiternelles depuis des ann\u00e9es, voire de bien plus d&rsquo;une d\u00e9cennie sans que la gravit\u00e9 en soit pour autant absente, il y a l&rsquo;observation que ce sommet de Bucarest conna\u00eet un climat nouveau d&rsquo;urgence. Peut-\u00eatre est-ce la premi\u00e8re fois que cette affirmation, jusque-l\u00e0 r\u00e9p\u00e9t\u00e9e pour r\u00e9pondre au jeu des pressions m\u00e9diatiques,  p\u00e9n\u00e8tre les psychologies: le sort de l&rsquo;OTAN est d\u00e9sormais en jeu, et c&rsquo;est maintenant la principale pr\u00e9occupation de l&rsquo;Organisation.<\/p>\n<\/p>\n<p><p>\tJusqu&rsquo;ici, c&rsquo;\u00e9taient les diverses questions pressantes qui affectent l&rsquo;Organisation qui constituaient l&rsquo;essentiel des sommets. Les esprits se refusaient d&rsquo;aller \u00e0 la conclusion in\u00e9vitable. Aujourd&rsquo;hui, cette conclusion in\u00e9vitable est pr\u00e9sente sous forme de question dans les esprits: l&rsquo;OTAN peut-elle survivre longtemps dans les conditions chaotiques qui la caract\u00e9risent? M\u00eame le double, voire triple langage qui caract\u00e9rise autant les manifestations officielles de l&rsquo;OTAN que les entretiens eux-m\u00eames ne suffira plus \u00e0 dissiper ce poids psychologique qui p\u00e8se d\u00e9sormais sur tous. La cause conjoncturelle imm\u00e9diate de cette \u00e9volution est certainement la position extr\u00eame prise par les USA sur la question de l&rsquo;adh\u00e9sion de l&rsquo;Ukraine et de la G\u00e9oergie, s&rsquo;ajoutant \u00e0 la pression constante de la situation en Afghanistan.<\/p>\n<\/p>\n<p><p>\tMais ce sont en v\u00e9rit\u00e9 tous les probl\u00e8mes de l&rsquo;OTAN qui viennent \u00e0 maturit\u00e9, ceux qu&rsquo;on a d\u00e9j\u00e0 \u00e9voqu\u00e9s et aussi les autres, ceux qu&rsquo;on avait l&rsquo;habitude d&rsquo;escamoter ou de d\u00e9layer. L&rsquo;un de ceux-ci est la question des rapports de la France avec l&rsquo;OTAN. <em>Le Monde<\/em> de <a href=\"http:\/\/www.lemonde.fr\/organisations-internationales\/article\/2008\/04\/01\/debat-sur-le-retour-complet-de-la-france-dans-l-otan_1029612_3220.html#ens_id\" class=\"gen\">ce jour<\/a> note qu&rsquo;un d\u00e9bat sur le retour complet de la France dans l&rsquo;OTAN s&rsquo;est ouvert en France,  d\u00e9bat bien risqu\u00e9 pour l&rsquo;orthodoxie des pens\u00e9es, car il risque de mettre \u00e0 jour tant de choses non-dites,  d\u00e9bat <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4402\" class=\"gen\">nouveau et bienvenu<\/a> dans un pays qui a v\u00e9cu pendant quarante ans derri\u00e8re une apparence d&rsquo;indiff\u00e9rence publique sur la question, comme si la question \u00e9tait r\u00e9gl\u00e9e et la r\u00e9ponse entendue. Cela permettait \u00e0 chacun d&rsquo;imaginer \u00e0 son go\u00fbt de quelle r\u00e9ponse il s&rsquo;agissait. Le quotidien fran\u00e7ais de r\u00e9f\u00e9rence observe \u00e0 propos des diverses propositions et intentions fran\u00e7aises (envoi de 1.000 hommes en Afghanistan, retour conditionnel de la France dans l&rsquo;OTAN, d\u00e9fense europ\u00e9enne):<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Le pr\u00e9sident am\u00e9ricain devrait remercier le chef de l&rsquo;Etat fran\u00e7ais de son geste de solidarit\u00e9 envers l&rsquo;OTAN, et souligner que Washington ne voit que des avantages aux progr\u00e8s de la politique europ\u00e9enne de s\u00e9curit\u00e9 et de d\u00e9fense (PESD), autrement dit de la d\u00e9fense europ\u00e9enne, comme le demande Paris. Les termes du marchandage qui se poursuit depuis plusieurs mois entre les deux capitales seront ainsi officiellement pos\u00e9s. Le reste d\u00e9pendra de nombreux facteurs, dont les moindres ne sont pas la volont\u00e9 des Am\u00e9ricains de traduire des promesses verbales en actes, et la capacit\u00e9 de M. Sarkozy \u00e0 convaincre les Fran\u00e7ais  et leur classe politique  qu&rsquo;il n&rsquo;a pas l\u00e2ch\u00e9 la proie pour l&rsquo;ombre.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Si, au cours du semestre de la pr\u00e9sidence fran\u00e7aise de l&rsquo;Union europ\u00e9enne, qui commence le 1er juillet, Washington n&rsquo;a pas favoris\u00e9 le d\u00e9blocage d&rsquo;un v\u00e9ritable Centre de planification et de conduite des op\u00e9rations militaires europ\u00e9ennes, cela voudra dire que Paris n&rsquo;a aucun int\u00e9r\u00eat \u00e0 reprendre toute sa place au sein de l&rsquo;OTAN, comme le souhaite Nicolas Sarkozy.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tEn d&rsquo;autres termes: le d\u00e9bat technique et politique est pos\u00e9, tout le monde fait bonne mine mais rien, absolument rien n&rsquo;est r\u00e9solu et le plus dur commence. D&rsquo;un point de vue technique et politique, il n&rsquo;y a aucune garantie de r\u00e9ussite de cette op\u00e9ration et, au contraire, bien des possibilit\u00e9s du contraire. C&rsquo;est un langage inhabituel de r\u00e9alisme pour <em>Le Monde<\/em>, qui montre l&rsquo;intensit\u00e9 du climat (psychologie l\u00e0 aussi) \u00e0 Paris.<\/p>\n<\/p>\n<p><p>\tPour autant et pour cette fois, la question des rapports de la France avec l&rsquo;OTAN pourtant en pleine crise n&rsquo;est pas un point central de crise de l&rsquo;OTAN mais une crise parmi d&rsquo;autres. Cela mesure l&rsquo;\u00e9volution de la situation dont, soudain, le sommet de Bucarest appara\u00eet comme un point de r\u00e9v\u00e9lation et de fixation.<\/p>\n<\/p>\n<p><p>\tAinsi en va-t-il de toutes les crises aujourd&rsquo;hui au coeur de l&rsquo;OTAN, qui, toutes, atteignent leur point de fusion, celui-l\u00e0 o\u00f9 elles ne peuvent plus \u00eatre ignor\u00e9es. De cette fa\u00e7on atteint-on l&rsquo;essentiel que nous signalions plus haut: le sort de l&rsquo;OTAN est d\u00e9sormais en jeu, et c&rsquo;est maintenant la principale pr\u00e9occupation de l&rsquo;Organisation. Cet \u00e9tat d&rsquo;esprit est sans aucun doute la caract\u00e9ristique la plus remarquable, et la plus inattendue par rapport \u00e0 ce qu&rsquo;on en pensait il y a quelques semaines, du sommet de Bucarest.<\/p>\n<\/p>\n<p><p>\tIl n&rsquo;en sera pas fait mention dans le communiqu\u00e9 final parce que sommes dans le domaine de la psychologie. C&rsquo;est l&rsquo;habitude, les communiqu\u00e9s n&rsquo;ont pas pour fonction de nous faire part des \u00e9tats d&rsquo;\u00e2me en cours. Mais, apr\u00e8s Bucarest, on peut raisonnablement avancer l&rsquo;hypoth\u00e8se que les choses seront diff\u00e9rentes,  quelque chose d&rsquo;essentiel aura chang\u00e9 dans la perception de la question (de la crise) de l&rsquo;OTAN. Cela n&rsquo;est que logique. L&rsquo;environnement g\u00e9n\u00e9ral de crise syst\u00e9mique qui bouleverse toutes les grandes interrogations de la civilisation occidentale ne peut \u00e9viter \u00e0 cette alliance que commence le stade supr\u00eame de la crise permanente qu&rsquo;elle est devenue depuis la fin de la Guerre froide.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une \u00e9volution psychologique d\u00e9cisive? 2 avril 2008 Le sommet qui s&rsquo;ouvre \u00e0 Bucarest est une rencontre essentielle et peut-\u00eatre d\u00e9cisive pour l&rsquo;OTAN. Notons aussit\u00f4t que la m\u00eame chose est dite de tous les sommets de l&rsquo;OTAN, depuis 1990-91. La m\u00eame chose \u00e9tait dite pour le sommet de l&rsquo;OTAN \u00e0 Rome, \u00e0 l&rsquo;automne 1991. Au cours&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[7509,3228,584,3099],"class_list":["post-69800","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-bucarest","tag-crise","tag-otan","tag-psychologie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69800"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69800\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}