{"id":69822,"date":"2008-04-11T00:00:00","date_gmt":"2008-04-11T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2008\/04\/11\/la-loi-contre-attaque\/"},"modified":"2008-04-11T00:00:00","modified_gmt":"2008-04-11T00:00:00","slug":"la-loi-contre-attaque","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2008\/04\/11\/la-loi-contre-attaque\/","title":{"rendered":"<strong><em>La Loi contre-attaque<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">La Loi contre-attaque<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t11 avril 2008  Le <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=5048\" class=\"gen\">jugement<\/a> de la Haute Cour de Londres sur l&rsquo;arr\u00eat, en <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3479\" class=\"gen\">d\u00e9cembre 2006<\/a>, de l&rsquo;enqu\u00eate du SFO dans le scandale <em>Yamamah<\/em>-BAE est \u00e9videmment un important \u00e9v\u00e9nement pour le cours de cette affaire. Des prolongements \u00e9galement importants sont \u00e0 pr\u00e9voir.<\/p>\n<\/p>\n<p><p>\tLe <em>Financial Times<\/em> d\u00e9signe la d\u00e9cision de la Haute Cour sous l&rsquo;expression de \u00ab[t]<em>hursday&rsquo;s explosive court ruling<\/em>\u00bb. Ce jugement (explosif) est en g\u00e9n\u00e9ral partag\u00e9. La couverture m\u00e9diatique de l&rsquo;affaire est tr\u00e8s variable et les commentaires restent extr\u00eamement prudents. L&rsquo;on sent bien que l&rsquo;on est pass\u00e9 du sensationnel qui am\u00e8ne des r\u00e9v\u00e9lations croustillantes au fondamental qui rec\u00e8le des risques graves de d\u00e9stabilisation d&rsquo;un syst\u00e8me. Dans le premier cas, la presse aime bien, dans le second elle est plus prudente,  ou bien, elle a fait son choix, comme le montre la premi\u00e8re page (papier) du FT, v\u00e9ritablement sensationnelle; le FT a depuis longtemps pris partie <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3507\" class=\"gen\">avec fougue<\/a> contre les agissements de BAE au nom de la d\u00e9fense d&rsquo;un capitalisme qu&rsquo;il voudrait vertueux.<\/p>\n<\/p>\n<p><p>\tLa prudence sur le fond signal\u00e9e plus haut est partag\u00e9e par tous les acteurs, comme le note encore le FT: \u00ab<em>The near-silence of BAE on Thursday and the other main parties was a sign of how much they all had to think about on a day when Lord Justice Moses&rsquo;s voice rang out uncomfortably loud and clear.<\/em>\u00bb (Silence d&rsquo;autant plus remarquable que le gouvernement et les autres parties impliqu\u00e9es avaient \u00e9t\u00e9 notifi\u00e9es plusieurs jours avant du sens de la d\u00e9cision de la Haute Cour. On n&rsquo;a pourtant rien \u00e0 dire, ce qui en dit long.)<\/p>\n<\/p>\n<p><p>\tOn le comprend, beaucoup de gens, beaucoup de groupes, attendent la suite des \u00e9v\u00e9nements Le <em>Guardian<\/em> d&rsquo;<a href=\"http:\/\/www.guardian.co.uk\/world\/2008\/apr\/11\/bae.armstrade\" class=\"gen\">aujourd&rsquo;hui<\/a> apporte ces diverses pr\u00e9cisions :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Pressure was mounting last night on the government to allow the reopening of the criminal investigation into secret payments by arms company BAE to Saudi Arabia following a high court judgment that made clear the inquiry should never have been dropped.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Ministers have to decide in the next two weeks over what to do about the ruling from Lord Justice Moses, who with Lord Justice Sullivan, delivered a damning verdict on the behaviour of the former prime minister, Tony Blair, and his government in forcing a halt to the long-running investigation.<\/em><\/p>\n<\/p>\n<p><p>\t(&#8230;)<\/p>\n<\/p>\n<p><p>\t\u00bb<em>The high court will reconvene in a fortnight to decide what remedy to award the two groups of anti-corruption campaigners who brought the judicial review of the Serious Fraud Office decision to end the inquiry.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Among those waiting to see what Gordon Brown will do is the anti-bribery committee of the OECD, who spent last week in London grilling British officials about the apparent flouting of an international treaty. Investigators in Switzerland and the US Department of Justice, who took up the Saudi case when Britain abandoned it, will also be awaiting the government&rsquo;s next move. Ministers have so far refused to assist the US which has made requests for documents under a mutual legal assistance treaty.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Campaigners and MPs yesterday called for Brown to distance himself from his predecessor and allow the BAE inquiry to restart.<\/em> [&#8230;] >MI>Labour backbencher Bob Marshall-Andrews said the judgment meant a new inquiry is inevitable, a view backed by Sir Menzies Campbell, the former Liberal Democrat leader. These rulings will be a test for Baroness Scotland in her new role<D> [as attorney general] <em>on whether the government will take the case forward, he said. It is also a test for the PM on whether he will take a different line from his predecessor, who intervened to halt the investigation in the first place.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tD&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, les perspectives juridiques, de la part de la Haute Cour qui doit se prononcer encore sur les mesures qu&rsquo;elle d\u00e9cidera, restent assez n\u00e9buleuses. On admet que la Haute Cour pourrait difficilement faire autrement que de recommander tr\u00e8s fermement la r\u00e9ouverture de l&rsquo;enqu\u00eate par le SFO, ce qui ne d\u00e9plairait pas \u00e0 nombre de fonctionnaires de cet organisme, frustr\u00e9s par l&rsquo;ordre du gouvernement d&rsquo;abandonner l&rsquo;enqu\u00eate. La presse devrait \u00e9galement soutenir une telle option, comme elle le recommande d\u00e9j\u00e0, et une partie importante du monde politique. (Il y aurait bien s\u00fbr des possibilit\u00e9s de blocage temporaire, par exemple si le SFO fait appel. Mais le rem\u00e8de temporaire pourrait \u00eatre pire que le mal, tant la Haute Cour a exprim\u00e9 une attitude g\u00e9n\u00e9rale dans la magistrature britannique.)<\/p>\n<\/p>\n<p><p>\tBien entendu, cette perspective (r\u00e9ouverture de l&rsquo;enqu\u00eate) est potentiellement radicale, ou  explosive selon le terme d\u00e9j\u00e0 cit\u00e9. Elle le serait pour les suites au Royaume-Uni autant qu&rsquo;\u00e0 cause de toutes les autres enqu\u00eates en cours (OCDE, d\u00e9partement US de la justice, gouvernement suisse). Ces divers organismes et enqu\u00eateurs devraient consid\u00e9rer une r\u00e9ouverture de l&rsquo;enqu\u00eate du SFO comme un feu vert pour acc\u00e9l\u00e9rer leurs propres actions, tandis que les r\u00e9sistances internes \u00e0 la bureaucratie oppos\u00e9es \u00e0 ces diff\u00e9rentes enqu\u00eates devraient s&rsquo;affaiblir radicalement.<\/p>\n<h3><strong><em>Gunfight<\/em><\/strong> au coeur du syst\u00e8me<\/h3>\n<\/p>\n<p><p>\tC&rsquo;est d&rsquo;un autre point de vue que le cas imm\u00e9diat de BAE,  qui mettra un certain temps avant de s&rsquo;\u00e9claircir \u00e0 la lumi\u00e8re de la d\u00e9cision de la Haute Cour,  que nous allons envisager cette d\u00e9cision du tribunal de Londres. Nous allons la mettre notamment en parall\u00e8le avec le cas du GAO \u00e0 Washington, qui se trouve d\u00e9sormais au centre de deux pol\u00e9miques br\u00fblantes concernant deux importantes affaires touchant le complexe militaro-industriel (CMI): le <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4976\" class=\"gen\">programme JSF<\/a> et <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4999\" class=\"gen\">le choix<\/a> de l&rsquo;USAF de EADS\/Northrop Grumman pour le programme KC-45.<\/p>\n<\/p>\n<p><p>\tDans tous ces cas, avec plus ou moins de nuances, les organismes juridiques impliqu\u00e9s n&rsquo;ont pas un pouvoir discr\u00e9tionnaire total (encore moins pour le GAO, qui est un organe consultatif). Mais leur prestige, autant que la publicit\u00e9 faite \u00e0 leurs prises de position, leur donnent un poids qui doit \u00eatre consid\u00e9r\u00e9 hors du seul formalisme juridique. En termes d&rsquo;influence pesant sur les d\u00e9cisions possibles des autres pouvoirs, les d\u00e9cisions de ces organismes ont plus de poids que leur seule valeur juridique et ils ont m\u00eame un poids consid\u00e9rable lorsqu&rsquo;on consid\u00e8re le relais m\u00e9diatique (voir le FT aujourd&rsquo;hui pour le cas BAE). On peut dire que les affaires \u00e9voqu\u00e9es ont beaucoup plus d&rsquo;importance qu&rsquo;elles n&rsquo;en auraient si l&rsquo;on s&rsquo;en tenait \u00e0 la lettre de la loi.<\/p>\n<\/p>\n<p><p>\tLe constat que l&rsquo;on peut alors proposer est que les circonstances paraissent indiquer qu&rsquo;il existe d\u00e9sormais une dynamique de fond, plut\u00f4t qu&rsquo;un mouvement g\u00e9n\u00e9ral qui ferait croire \u00e0 une concertation en fait totalement absente, de l&rsquo;appareil juridique anglo-saxon contre ce qui pouvait \u00eatre consid\u00e9r\u00e9 jusqu&rsquo;ici comme une v\u00e9ritable impunit\u00e9 du complexe militaro-industriel. (Le CMI indique bien la chose am\u00e9ricaniste qu&rsquo;on conna\u00eet, et nous y incluons sans h\u00e9sitation <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=3609\" class=\"gen\">BAE<\/a>, parce que cette firme est am\u00e9ricanis\u00e9e, qu&rsquo;elle s&rsquo;inscrit dans le r\u00e9seau g\u00e9n\u00e9ral d&rsquo;influence et de corruption de l&rsquo;armement anglo-saxon, qu&rsquo;elle s&rsquo;appuie notamment sur les liens avec l&rsquo;Arabie Saoudite qui fait elle-m\u00eame partie de ce r\u00e9seau g\u00e9n\u00e9ral.)  Cette impunit\u00e9 n&rsquo;\u00e9tait pas gratuite, elle s&rsquo;appuyait sur ce que nous avons d\u00e9sign\u00e9 comme un <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4965\" class=\"gen\">contrat<\/a>. (Dans le texte r\u00e9f\u00e9renc\u00e9, il est question de la probl\u00e9matique de l&rsquo;apport pour le syst\u00e8me des guerres que m\u00e8ne le CMI. Ici, nous parlons d&rsquo;autres domaines. Ce que nous voulons mettre en \u00e9vidence, c&rsquo;est la notion de contrat entre le syst\u00e8me et le CMI.) <\/p>\n<\/p>\n<p><p>\tIl nous para\u00eet justifi\u00e9, plut\u00f4t que de r\u00e9pandre quelques couches de confiture sur les tartines \u00e9crites \u00e0 la gloire des vertus de la justice et du reste, d&rsquo;avancer l&rsquo;hypoth\u00e8se que les difficult\u00e9s grandissantes jusqu&rsquo;au d\u00e9sordre complet du CMI \u00e0 tenir les termes du contrat sont la cause de l&rsquo;\u00e9volution de cette situation dans le sens qu&rsquo;on voit. L&rsquo;hypoth\u00e8se a d&rsquo;autant plus de sens qu&rsquo;elle concerne des affaires diff\u00e9rentes en essence, qui refl\u00e8tent le d\u00e9sordre g\u00e9n\u00e9ral du CMI plut\u00f4t que son manquement \u00e0 une sorte d&rsquo;apparence de vertu minimale impos\u00e9e (ce qui pourrait \u00eatre le cas s&rsquo;il n&rsquo;y avait eu que des affaires de corruption). On n&rsquo;a jamais demand\u00e9 au CMI d&rsquo;\u00eatre vraiment vertueux, par contre on exige de lui qu&rsquo;il montre un certain ordre, une certaine efficacit\u00e9 et une certaine retenue d&rsquo;apparence dans ses agissements. Un cas comme BAE montre un d\u00e9sordre et une absence de responsabilit\u00e9 fort dommageables; c&rsquo;est \u00e9galement le cas pour le programme JSF, bien que le fond de l&rsquo;affaire soit diff\u00e9rent.<\/p>\n<\/p>\n<p><p>\tNous ne proposons nullement une graduation dans l&rsquo;\u00e9chelle de la vertu hypoth\u00e9tique caract\u00e9risant le syst\u00e8me (par exemple, entre la justice et le CMI). Nous proposons un constat,  il n&rsquo;exclue par ailleurs ni les \u00e9tats d&rsquo;\u00e2me ni les bonnes intentions, ni m\u00eame des vertus plus nobles,  qui importe dans sa forme r\u00e9aliste sinon cynique pour notre propos, dans la situation de pure r\u00e9alit\u00e9 et de rapport de forces qu&rsquo;il d\u00e9crit.<\/p>\n<\/p>\n<p><p>\tCe que nous nommons le syst\u00e8me est fait de divers centres de pouvoir et de comp\u00e9tence qui ont chacun leur mot \u00e0 dire et leur r\u00f4le \u00e0 jouer. L&rsquo;appareil de la justice fait partie du syst\u00e8me, comme le CMI en fait partie. Dans le cas \u00e9voqu\u00e9 ici, il y a cet autre constat que le pouvoir politique,  autre \u00e9l\u00e9ment du syst\u00e8me,  ne semble plus vouloir, ou pouvoir r\u00e9agir face \u00e0 ces incartades du CMI qui commencent \u00e0 ressembler \u00e0 une d\u00e9g\u00e9n\u00e9rescence du sens de la responsabilit\u00e9 collective. (On remarquera que, dans ce cas, la remarque vaut aussi bien pour le scandale BAE que pour le programme JSF, qui a \u00e9chapp\u00e9 depuis longtemps \u00e0 tout contr\u00f4le du pouvoir politique, voire m\u00eame \u00e0 l&rsquo;affaire du programme KC-45 qui est d\u00e9nonc\u00e9e par certains \u00e0 Washington comme une atteinte, hors du contr\u00f4le du pouvoir politique, port\u00e9e \u00e0 la puissance strat\u00e9gique des USA.)<\/p>\n<\/p>\n<p><p>\tLa justice,  ou, dit plus pompeusement, la Loi,  s&rsquo;estime alors charg\u00e9e de la mission de jouer ce r\u00f4le que le pouvoir politique a abdiqu\u00e9, quitte \u00e0 impliquer au passage (cas de BAE et de Blair) ce m\u00eame pouvoir politique. On peut voir dans ce d\u00e9ballage aussi bien un sursaut de certains centres de pouvoir plus conscients que d&rsquo;autres de la n\u00e9cessit\u00e9 de maintenir un certain \u00e9quilibre d&rsquo;ordre et une certaine apparence de bonne conduite,  qu&rsquo;un r\u00e9glement de compte entre familles concurrentes. On peut m\u00eame y voir \u00e9galement, dans le chef de certains, des vertus dont l&rsquo;origine remonte \u00e0 une histoire qui pr\u00e9c\u00e9da l&rsquo;installation de ce syst\u00e8me qui r\u00e9git notre civilisation. Tout cela n&rsquo;\u00f4te rien au fond de l&rsquo;affaire telle que nous la d\u00e9crivons.<\/p>\n<\/p>\n<p><p>\tL&rsquo;affaire BAE n&rsquo;est nullement un \u00e9piph\u00e9nom\u00e8ne. C&rsquo;est un signe s\u00e9rieux de la crise du syst\u00e8me. C&rsquo;est un signe \u00e9galement convaincant que le complexe militaro-industriel n&rsquo;est pas seulement une sombre affaire de comploteurs industriels et militaristes mais \u00e9galement, et surtout, et en pleine lumi\u00e8re d\u00e9sormais, l&rsquo;un des \u00e9l\u00e9ments constitutifs fondamentaux du syst\u00e8me. Sa crise refl\u00e8te la crise du syst\u00e8me comme elle l&rsquo;alimente.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Loi contre-attaque 11 avril 2008 Le jugement de la Haute Cour de Londres sur l&rsquo;arr\u00eat, en d\u00e9cembre 2006, de l&rsquo;enqu\u00eate du SFO dans le scandale Yamamah-BAE est \u00e9videmment un important \u00e9v\u00e9nement pour le cours de cette affaire. Des prolongements \u00e9galement importants sont \u00e0 pr\u00e9voir. Le Financial Times d\u00e9signe la d\u00e9cision de la Haute Cour&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3792,3806,3228,2851,6254,3014,2852,4364],"class_list":["post-69822","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-bae","tag-cmi","tag-crise","tag-financial","tag-justice","tag-systeme","tag-times","tag-yamamah"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69822"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69822\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}