{"id":69824,"date":"2008-04-12T00:00:00","date_gmt":"2008-04-12T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2008\/04\/12\/lusaf-pire-que-la-navy\/"},"modified":"2008-04-12T00:00:00","modified_gmt":"2008-04-12T00:00:00","slug":"lusaf-pire-que-la-navy","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2008\/04\/12\/lusaf-pire-que-la-navy\/","title":{"rendered":"L&rsquo;USAF pire que la Navy"},"content":{"rendered":"<p><p>Les divers services des forces arm\u00e9es US ne cessent de d\u00e9filer au Congr\u00e8s pour exposer leur horrible situation. Apr\u00e8s <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=4962\" class=\"gen\">la Navy<\/a>, qui est venue se plaindre de <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=5046\" class=\"gen\">la difficult\u00e9<\/a> de ses perspectives en dotation d&rsquo;avions de combat, c&rsquo;est le tour de l&rsquo;USAF. Les conditions sont bien pires que celles de la Navy.<\/p>\n<\/p>\n<p><p>\tVoici ce qu&rsquo;en dit le <em>Daily Report<\/em> de l&rsquo;Air Force Association, du <a href=\"http:\/\/www.airforce-magazine.com\/DRArchive\/Pages\/default.aspx\" class=\"gen\">11 avril<\/a>:<\/p>\n<\/p>\n<p><p>\t\u00ab<strong><em>Fighter Gap&rsquo; Now a Problem:<\/em><\/strong> <em>Testifying before a Senate panel April 9, two Air Force generals said the service faces a fighter gap in the years ahead that could leave it drastically short of its requirement for 2,250 fighters in its force structure. Based on the current program of record, the Air Force anticipates a shortage of over 800 aircraft, beginning in 2017 and running through 2024, Lt. Gen. Daniel Darnell, deputy chief of staff for air, space, and information operations, plans and requirements, told the Senate Armed Services Committee&rsquo;s AirLand Subcommittee. Darnell noted, for example, that the F-35 does not go into full production until 2015reaching rates of 48 per yearyet the Air Force already is retiring F-15s and F-16s and will continue to do so through the out years. And before the JSF achieves full production, manufacture of the F-22 will be over, based on the current production cap that limits USAF to 183 Raptors. Following the hearing, Lt. Gen. Donald Hoffman, the Air Force&rsquo;s senior uniformed acquisition official, told reporters that the current cap on F-22 production, which falls far short of the 381 F-22s that it maintains it needs, is a big part of the problem. But the real issue, he said, is the production rate for F-35s and how fast the new fighters can replace retiring iron. Aircraft, such as older F-16s, F-15s, and even some A-10s, may not last as long as it takes to get enough F-35s on the ramp, Hoffman said. ..<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tAinsi d\u00e9filent au Congr\u00e8s les \u00e9valuations de la situation catastrophique de la structure de forces qui n&rsquo;ont pourtant pas \u00e9t\u00e9 affect\u00e9es directement par les guerres en cours en Irak et en Afghanistan. L&rsquo;U.S. Army et le Marine Corps ont \u00e9t\u00e9 directement touch\u00e9s par ces conflits et r\u00e9duits \u00e0 des conditions extr\u00eamement d\u00e9licates pour seulement soutenir le rythme des combats que ces deux services m\u00e8nent. Leur soutien logistique et autre effectue une ponction \u00e9norme sur le budget de la d\u00e9fense, au d\u00e9triment du financement courant des deux autres forces (USAF et Navy).<\/p>\n<\/p>\n<p><p>\tCes deux forces sont elles-m\u00eames dans une position difficile \u00e0 cause de l&rsquo;\u00e9volution structurelle des forces arm\u00e9es depuis la fin de la Guerre froide (\u00e9norme extension de leurs activit\u00e9s, engagements divers, \u00e0 partir d&rsquo;une masse consid\u00e9rable constitu\u00e9e dans les ann\u00e9es de 1979 \u00e0 1990, mais tr\u00e8s peu ou pas modernis\u00e9e depuis, ce qui conduit \u00e0 des mat\u00e9riels aujourd&rsquo;hui dans un \u00e9tat de vieillissement avanc\u00e9,  24-25 ans d&rsquo;\u00e2ge moyen pour les avions de l&rsquo;Air Force). Les ponctions en faveur de l&rsquo;Army et des Matines et en leur d\u00e9faveur aggravent chaque jour cette situation. A l&rsquo;autre bout du dilemme, les programmes de modernisation (F-22 et F-35) rencontrent des difficult\u00e9s sans nombre qui font repousser leur arriv\u00e9e en escadres, et d&rsquo;ailleurs \u00e0 un rythme qui sera r\u00e9duit par rapport aux n\u00e9cessit\u00e9s (48 F-35 par an pour l&rsquo;Air Force au lieu des 110 jug\u00e9s n\u00e9cessaires avant m\u00eame que des d\u00e9lais suppl\u00e9mentaires aient encore recul\u00e9 l&rsquo;entr\u00e9e en service).<\/p>\n<\/p>\n<p><p>\tOn observera combien le JSF (F-35) est le pivot de toute cette affaire. Le programme ne cesse de prendre du retard et la Navy et l&rsquo;USAF ne cessent de r\u00e9clamer son entr\u00e9e en service acc\u00e9l\u00e9r\u00e9e, sous peine de chercher des solutions alternatives (repli sur la production de mod\u00e8les anciens modernis\u00e9s). Le trou possible de plus de 800 avions de combat pour l&rsquo;USAF entre 2017 et 2024 repr\u00e9sente une \u00e9norme r\u00e9duction de plus du tiers des capacit\u00e9s de l&rsquo;USAF. On peut consid\u00e9rer que l&rsquo;USAF agite cette possibilit\u00e9 pour obtenir des cr\u00e9dits suppl\u00e9mentaires mais il appara\u00eet \u00e9vident depuis quelques temps que cette crise n&rsquo;est pas un montage de relations publiques. Il est vrai que les forces arm\u00e9es US sont entr\u00e9s dans une crise qui devrait d\u00e9passer celle de la <em>Hollow Army<\/em> qui a suivi le Vietnam, qui n&rsquo;a pas de pr\u00e9c\u00e9dent depuis la d\u00e9mobilisation acc\u00e9l\u00e9r\u00e9e de septembre-d\u00e9cembre 1945.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 12 avril 2008 \u00e017H22<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les divers services des forces arm\u00e9es US ne cessent de d\u00e9filer au Congr\u00e8s pour exposer leur horrible situation. Apr\u00e8s la Navy, qui est venue se plaindre de la difficult\u00e9 de ses perspectives en dotation d&rsquo;avions de combat, c&rsquo;est le tour de l&rsquo;USAF. Les conditions sont bien pires que celles de la Navy. Voici ce qu&rsquo;en&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[249,2969,7526,7527,250,3319,41],"class_list":["post-69824","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-f-22","tag-f-35","tag-fighter","tag-gap","tag-jsf","tag-navy","tag-usaf"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69824"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69824\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}