{"id":69827,"date":"2008-04-14T00:00:00","date_gmt":"2008-04-14T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2008\/04\/14\/le-surge-cote-sombre\/"},"modified":"2008-04-14T00:00:00","modified_gmt":"2008-04-14T00:00:00","slug":"le-surge-cote-sombre","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2008\/04\/14\/le-surge-cote-sombre\/","title":{"rendered":"Le \u201c<em>surge<\/em>\u201d, c\u00f4t\u00e9 sombre"},"content":{"rendered":"<p><p>Il y a eu l&rsquo;audition du g\u00e9n\u00e9ral Petraeus, sans grand tralalas publicitaire et spectaculaire. La performance, r\u00e9p\u00e9t\u00e9e de six mois en six mois, commence \u00e0 lasser, d&rsquo;autant que le cat\u00e9chisme est une succession de lieux communs et d&rsquo;affirmations vides. La philosophie de la chose est que le <em>surge<\/em> marche, que la situation en Irak s&rsquo;am\u00e9liore, mais qu&rsquo;il faut \u00eatre patient, qu&rsquo;il faut garder toujours autant de soldats l\u00e0-bas, tout cela sur fond d&rsquo;explosions et de recrudescence des troubles divers en Irak.<\/p>\n<\/p>\n<p><p>\tUne \u00e9ditorialiste du groupe <em>North Star Writers<\/em> a eu l&rsquo;id\u00e9e de baser sa chronique du <a href=\"http:\/\/www.northstarwriters.com\/ct089.htm\" class=\"gen\">10 avril<\/a> sur le t\u00e9moignage que le lieutenant g\u00e9n\u00e9ral William E. Odom, un g\u00e9n\u00e9ral de l&rsquo;U.S. Army \u00e0 la retraite, ancien directeur de la NSA et aujourd&rsquo;hui l&rsquo;un des critiques les plus incisifs de la guerre en Irak, a fait devant les m\u00eames s\u00e9nateurs qui se pr\u00e9paraient \u00e0 \u00e9couter Petraeus. Candace Talmadge a donc d\u00e9cid\u00e9 de nous faire entendre le t\u00e9moignage d&rsquo;un autre g\u00e9n\u00e9ral.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The surge is prolonging instability, not creating the conditions for unity as the president claims, his testimony began.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The decline in violence reflects a dispersion of power to dozens of local strong men who distrust the government and occasionally fight among themselves, Odom explained. Thus the basic military situation is far worse because of the proliferation of armed groups under local military chiefs who follow a proliferating number of political bosses.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em> This can hardly be called greater military stability, much less progress toward political consolidation, and to call it fragility that needs more time to become success is to ignore its implications.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Persuading the Sunnis not to shoot at U.S. troops comes at a high financial toll.  . . . Our new Sunni friends insist on being paid for their loyalty, Odom pointed out. I have heard, for example, a rough estimate that the cost of in one area of about 100 square kilometers is $250,000 per day. And periodically they threaten to defect unless their fees are increased.<\/em><\/p>\n<\/p>\n<p><p>\t(&#8230;)<\/p>\n<\/p>\n<p><p>\t\u00bb<em>Odom also made hash of claims that Al Qaeda will have a staging area in Iraq for further attacks against the United States if we withdraw our entire military presence.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em> The Sunnis will soon destroy Al Qaeda if we leave Iraq, Odom said. The Kurds do not allow them in their region, and the Shiites, like the Iranians, detest Al Qaeda. To understand why, one need only take note of the Al Qaeda public diplomacy campaign over the past year or so on Internet blogs. They implore the United States to bomb and invade Iran and destroy this apostate Shiite regime.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em> As an aside, it gives me pause to learn that our vice president and some members of Congress are aligned with Al Qaeda on spreading the war to Iran.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tOn peut trouver l&rsquo;int\u00e9gralit\u00e9 du t\u00e9moignage du g\u00e9n\u00e9ral Odom sur le site <em>Information Clearing House<\/em>, \u00e0 la date du <a href=\"http:\/\/www.informationclearinghouse.info\/article19671.htm\" class=\"gen\">2 avril<\/a>. Le th\u00e8me essentiel implicite de ce t\u00e9moignage est effectivement que le ph\u00e9nom\u00e8ne de d\u00e9stabilisation qui frappe l&rsquo;Irak et qui entretient la guerre est la pr\u00e9sence des forces US dans ce pays, et la politique qui est conduite autant que la guerre qui y est men\u00e9e. (Ce qui est dit pour le <em>surge<\/em> lui-m\u00eame vaut pour toute l&rsquo;aventure: \u00ab<em>The surge is prolonging instability, not creating the conditions for unity as the president claims.<\/em>\u00bb) Dans le sens restreint des r\u00e9alit\u00e9s op\u00e9rationnelles, tactiques mais aussi avec une dimension psychologique \u00e9vidente, l&rsquo;analyse du g\u00e9n\u00e9ral Odom renforce l&rsquo;id\u00e9e qu&rsquo;on \u00e9voque dans notre <em>F&#038;C<\/em> d&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=5053\" class=\"gen\">aujourd&rsquo;hui<\/a>, selon laquelle le vrai malaise vient de l&rsquo;Am\u00e9rique elle-m\u00eame, que c&rsquo;est l&rsquo;Am\u00e9rique qui suscite et provoque les crises dont elle pr\u00e9tend \u00eatre ensuite la victime.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 14 avril 2008 \u00e0 09H39<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il y a eu l&rsquo;audition du g\u00e9n\u00e9ral Petraeus, sans grand tralalas publicitaire et spectaculaire. La performance, r\u00e9p\u00e9t\u00e9e de six mois en six mois, commence \u00e0 lasser, d&rsquo;autant que le cat\u00e9chisme est une succession de lieux communs et d&rsquo;affirmations vides. La philosophie de la chose est que le surge marche, que la situation en Irak s&rsquo;am\u00e9liore,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[857,4771,6264,6263],"class_list":["post-69827","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-irak","tag-odom","tag-petraeus","tag-surge"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69827"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69827\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}