{"id":69835,"date":"2008-04-17T00:00:00","date_gmt":"2008-04-17T00:00:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2008\/04\/17\/observations-sur-le-malaise-americain\/"},"modified":"2008-04-17T00:00:00","modified_gmt":"2008-04-17T00:00:00","slug":"observations-sur-le-malaise-americain","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2008\/04\/17\/observations-sur-le-malaise-americain\/","title":{"rendered":"<strong><em>Observations sur le \u201cmalaise am\u00e9ricain\u201d<\/em><\/strong>"},"content":{"rendered":"<p><h2 class=\"common-article\">Observations sur le malaise am\u00e9ricain<\/h2>\n<\/p>\n<p><\/p>\n<p><p>\t17 avril 2008  Pour un \u00e9conomiste (qu&rsquo;on nous pardonne l&rsquo;aspect restrictif de ce d\u00e9but), Paul Krugman montre une remarquable propension pour la psychologie. Il aborde (\u00e0 nouveau pour lui, qui le fait souvent) le probl\u00e8me de la psychologie des Am\u00e9ricains, qu&rsquo;il juge manifestement \u00e9puis\u00e9e et en crise. (Voir son article du <a href=\"http:\/\/www.iht.com\/articles\/2008\/04\/14\/opinion\/edkrugman.php\" class=\"gen\">14 avril<\/a> dans l&rsquo;International <em>Herald Tribune<\/em>, avec comme question, ou titre en forme de question: pourquoi l&rsquo;Am\u00e9rique se sent-elle si mal?)<\/p>\n<\/p>\n<p><p>\t(Ce texte de Krugman avec notre commentaire sont \u00e0 rapprocher du texte de Herbert \u00e9galement avec notre commentaire, dans notre <em>F&#038;C<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=5053\" class=\"gen\">14 avril<\/a>. Signe que la psychologie am\u00e9ricaniste ou des Am\u00e9ricains est aujourd&rsquo;hui un grand sujet de l&rsquo;ordre du jour.)<\/p>\n<\/p>\n<p><p>\tKrugman remarque notamment, avec un certain \u00e9tonnement d&rsquo;abord, que les indices statistiques sur la tr\u00e8s forte d\u00e9pression psychologique des Am\u00e9ricains n&rsquo;a pas de rapport \u00e9vident, automatique, avec la gravit\u00e9 de la situation \u00e9conomique et surtout sociale (ch\u00f4mage),  dans tous les cas, pour le moment. A d&rsquo;autres p\u00e9riodes o\u00f9 les conditions \u00e9conomiques et sociales \u00e9taient plus mauvaises que celles qu&rsquo;on conna\u00eet, l&rsquo;humeur des Am\u00e9ricains \u00e9tait moins d\u00e9pressive. Krugman \u00e9crit notamment:<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The Survey Research Center of the University of Michigan has been tracking American economic perceptions since the 1950s. On Friday the center released its latest estimate of the consumer sentiment index &#8211; and it was a stunner. Americans are more pessimistic about their situation than they have been for more than a quarter century.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Meanwhile, a recent Pew report found that the percentage of Americans saying that they&rsquo;re better off than they were five years ago is at its lowest level in 44 years of polling.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>What&rsquo;s striking about this bleak mood is that by the usual measures the economy isn&rsquo;t doing that badly  at least not yet. In particular, the official unemployment rate of 5.1 percent, though rising, is still fairly low by historical standards.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Yet economic attitudes are worse now than they were in 1992, when the average unemployment rate was 7.5 percent.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tQuelle est la suggestion de Krugman? Il revient sur une hypoth\u00e8se qu&rsquo;il avait faite au d\u00e9but de 2002, \u00e0 l&rsquo;occason du scandale Enron. Le <a href=\"http:\/\/query.nytimes.com\/gst\/fullpage.html?res=9807E2DF133AF93AA15752C0A9649C8B63\" class=\"gen\">29 janvier 2002<\/a>, il \u00e9crivait que le scandale Enron pourrait avoir une importance plus grande que 9\/11 et ses cons\u00e9quences sur la psychologie am\u00e9ricaniste. Cette chronique avait fait sensation, dans le sens du sacril\u00e8ge \u00e9videmment; 9\/11 \u00e9tait d\u00e9j\u00e0 un \u00e9v\u00e9nement sacr\u00e9 selon les normes officielles. Le <a href=\"http:\/\/query.nytimes.com\/gst\/fullpage.html?res=9404E0DC133EF93BA15755C0A9649C8B63\" class=\"gen\">28 juin 2002<\/a>, il revenait sur ce sujet pour commenter les avalanches de r\u00e9v\u00e9lations et \u00e9v\u00e9nements dramatiques dans le scandale Enron depuis janvier. Il \u00e9crivait: \u00ab<em>&#8230; Meanwhile the revelations keep coming. Six months ago, in a widely denounced column, I suggested that in the end the Enron scandal would mark a bigger turning point for America&rsquo;s perception of itself than Sept. 11 did. Does that sound so implausible today?<\/em>\u00bb (Nous-m\u00eames avions \u00e0 cette \u00e9poque comment\u00e9 l&rsquo;hypoth\u00e8se Krugman dans un <em>F&#038;C<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=277\" class=\"gen\">29 juin 2002<\/a>. Nous la jugions tout \u00e0 fait acceptable, alors qu&rsquo;\u00e0 cette \u00e9poque la premi\u00e8re phase de la guerre en Afghanistan \u00e9tait \u00e0 son terme et que les rumeurs d&rsquo;attaque contre l&rsquo;Irak n&rsquo;\u00e9taient nullement insistantes.)<\/p>\n<\/p>\n<p><p>\tAujourd&rsquo;hui (le 14 avril 2008), Krugman revient donc sur cette hypoth\u00e8se en observant que les Am\u00e9ricains ont perdu toute confiance dans leurs institutions financi\u00e8res.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Early this decade, when the great corporate scandals broke &#8211; Enron, WorldCom, and so on  I expected big-business corruption to become a major political issue.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>It didn&rsquo;t, partly because the march to war had the effect of changing the subject, partly, perhaps, because Americans weren&rsquo;t ready to take a broadly negative view of the system that brought them the previous decade&rsquo;s boom.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>But my impression is that the subprime crisis  with its revelation that titans of finance were dealing in funny money and its tales of failed executives receiving hundred-million-dollar going-away presents  has resurrected the sense that something is rotten in the state of our economy.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>And this sense is adding to the general gloom.<\/em>\u00bb<\/p>\n<h3>La r\u00e9flexion politique est dans une prison psychologique<\/h3>\n<\/p>\n<p><p>\tNous discuterons moins le fond de l&rsquo;hypoth\u00e8se que le fait qu&rsquo;elle apparaisse et qu&rsquo;elle soit aussit\u00f4t assimil\u00e9e \u00e0 ce que Krugman d\u00e9signe comme un <em>an American malaise<\/em>. En 2002, l&rsquo;important \u00e9tait bien plus le scandale Enron que ses effets psychologiques directs, qui \u00e9taient difficiles \u00e0 d\u00e9montrer \u00e0 cause du climat g\u00e9n\u00e9ral n\u00e9 de 9\/11, brouillant toutes les analyses psychologiques \u00e0 cet \u00e9gard. Krugman partait du scandale pour dire: la psychologie US (la confiance des Am\u00e9ricains) est plus touch\u00e9e par ce scandale que par 9\/11. Aujourd&rsquo;hui, il fait la d\u00e9marche inverse: il part du constat de la psychologie atteinte pour en chercher les causes; et il revient sur son hypoth\u00e8se en l&rsquo;assimilant \u00e0 celle qu&rsquo;il fait aujourd&rsquo;hui.<\/p>\n<\/p>\n<p><p>\tLa chose (la psychologie US) est en ce moment largement exploit\u00e9e. Rappelons cette remarque que nous faisions plus haut&#8230; Ce texte de Krugman avec notre commentaire sont \u00e0 rapprocher du texte de Herbert \u00e9galement avec notre commentaire, dans notre <em>F&#038;C<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article.php?art_id=5053\" class=\"gen\">14 avril<\/a>. Signe que la psychologie am\u00e9ricaniste ou des Am\u00e9ricains est aujourd&rsquo;hui un grand sujet de l&rsquo;ordre du jour. C&rsquo;est-\u00e0-dire que nous avons tendance \u00e0 moins consid\u00e9rer l&rsquo;hypoth\u00e8se Krugman dans la cause qu&rsquo;il envisage (\u00ab[Americans]<em> lost confidence in the integrity of our economic institutions<\/em>\u00bb) que dans son objet m\u00eame: le malaise psychologique am\u00e9ricain. Comme Herbert, Krugman constate le m\u00eame ph\u00e9nom\u00e8ne du malaise; mais les deux commentateurs donnent deux explications diff\u00e9rentes; il nous appara\u00eet alors fond\u00e9 d&rsquo;observer que l&rsquo;important est bien le malaise lui-m\u00eame.<\/p>\n<\/p>\n<p><p>\tIl y a bien s\u00fbr une crise psychologique profonde des Am\u00e9ricains, et c&rsquo;est le principal ph\u00e9nom\u00e8ne. En 2002, des \u00e9v\u00e9nements brutaux et en rapide succession pouvaient en constituer une cause premi\u00e8re et l&rsquo;on pouvait juger que l&rsquo;attitude psychologique en \u00e9tait la cons\u00e9quence. Aujourd&rsquo;hui, l&rsquo;ordre des choses a bascul\u00e9. La crise centrale, structurelle, est la psychologie elle-m\u00eame et l&rsquo;on cherche les \u00e9v\u00e9nements qui peuvent en donner une explication conjoncturelle.<\/p>\n<\/p>\n<p><p>\tPourquoi un tel int\u00e9r\u00eat, un tel penchant pour la psychologie? Il nous appara\u00eet \u00e9vident, aux USA plus qu&rsquo;ailleurs, que les interrogations des commentateurs, lorsqu&rsquo;ils se concentrent dans le domaine des \u00e9v\u00e9nements, essentiellement politiques avec leurs cons\u00e9quences \u00e9conomiques et sociales, sont aujourd&rsquo;hui moins dans une impasse que dans une <strong>prison<\/strong>. Ces \u00e9v\u00e9nements catastrophiques et sans autre perspectives que l&rsquo;aggravation sans fin de la situation se succ\u00e8dent depuis sept ans et n&rsquo;apportent plus rien de nouveau.<\/p>\n<\/p>\n<p><p>\t&#8230; Et ainsi le lien est-il fait: la politique est aujourd&rsquo;hui dans une prison <strong>psychologique<\/strong>, dans la prison de la crise psychologique, aux USA bien plus qu&rsquo;ailleurs. La psychologie (la crise psychologique) a pris le premier rang, elle est centrale, elle r\u00e8gle tout. C&rsquo;est elle qui d\u00e9clenche la r\u00e9flexion et non, comme dans le cas d&rsquo;Enron-Krugman en 2002, un \u00e9v\u00e9nement donn\u00e9, interpr\u00e9t\u00e9 politiquement, qui donne la clef de la r\u00e9flexion pour appr\u00e9cier un \u00e9tat psychologique. La situation est tr\u00e8s diff\u00e9rente de 2002 (Enron vu par Krugman, avec l&rsquo;hypoth\u00e8se que Enron est plus grave que 9\/11). La crise n&rsquo;est plus dans les \u00e9v\u00e9nements mais dans la psychologie, les \u00e9v\u00e9nements donnent diversement l&rsquo;occasion \u00e0 cette crise de se manifester, et, en g\u00e9n\u00e9ral, d&rsquo;une fa\u00e7on extr\u00eame et \u00e9ventuellement inattendue par rapport \u00e0 ces \u00e9v\u00e9nements. <\/p>\n<\/p>\n<p><p>\tPour cette raison, nous renfor\u00e7ons notre avis selon lequel la situation est aujourd&rsquo;hui d&rsquo;une instabilit\u00e9 potentielle extr\u00eame aux USA. La psychologie elle-m\u00eame est par d\u00e9finition un facteur incontr\u00f4lable et irrationnel, aux prolongements impr\u00e9visibles. La psychologie \u00e9tant au centre de la crise, comme cause et moteur de la crise \u00e0 la fois, il est absolument impossible d&rsquo;appr\u00e9hender l&rsquo;orientation, le rythme et l&rsquo;ampleur de l&rsquo;\u00e9volution de cette crise. La seule certitude c&rsquo;est ce mot mille fois r\u00e9p\u00e9t\u00e9: crise.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Observations sur le malaise am\u00e9ricain 17 avril 2008 Pour un \u00e9conomiste (qu&rsquo;on nous pardonne l&rsquo;aspect restrictif de ce d\u00e9but), Paul Krugman montre une remarquable propension pour la psychologie. Il aborde (\u00e0 nouveau pour lui, qui le fait souvent) le probl\u00e8me de la psychologie des Am\u00e9ricains, qu&rsquo;il juge manifestement \u00e9puis\u00e9e et en crise. (Voir son article&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[898,3446,3099],"class_list":["post-69835","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-krugman","tag-malaise","tag-psychologie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=69835"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/69835\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=69835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=69835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=69835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}